{"id":404333,"date":"2025-06-06T17:22:45","date_gmt":"2025-06-06T15:22:45","guid":{"rendered":"https:\/\/sostariffe-internal.gruppomol.lcl\/news\/?p=404333"},"modified":"2025-06-12T16:01:44","modified_gmt":"2025-06-12T14:01:44","slug":"fusione-tim-e-iliad-operazione-piu-vicina-il-ruolo-di-poste","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/fusione-tim-e-iliad-operazione-piu-vicina-il-ruolo-di-poste-404333\/","title":{"rendered":"Fusione TIM e Iliad, operazione pi\u00f9 vicina? Il ruolo di Poste"},"content":{"rendered":"<p><strong>Poste Italiane<\/strong> potrebbe avere un ruolo importante nella possibile <strong>fusione TIM Iliad<\/strong>, un&#8217;operazione valutata fino a <strong>25 miliardi di euro<\/strong>. Scopri come cambier\u00e0 il settore delle telecomunicazioni in Italia<!--more--><\/p>\n<p><strong>Poste Italiane<\/strong> con l&#8217;acquisizione del <strong>15%<\/strong> delle quote di <strong>TIM<\/strong> da <strong>Vivendi<\/strong> per la cifra di <strong>648 milioni di euro <\/strong>\u00e8 diventata la prima azionista della Telco, con una quota del <strong>24,81%<\/strong>, soglia che non prevede l&#8217;obbligo di\u00a0<strong>OPA<\/strong> (Offerta Pubblica di Acquisto). L&#8217;azienda francese ha visto quindi scendere la sua partecipazione a solo il 2,5%. A partire dal 2026 i clienti di <strong>PosteMobile<\/strong> verranno invece <a href=\"https:\/\/www.sostariffe.it\/news\/postemobile-cambia-rete-il-futuro-e-con-tim-403708\/\"><strong>migrati sulla rete di TIM<\/strong><\/a>.<\/p>\n<p><strong>TIM<\/strong> \u00e8 tornata a essere pianamente italiana ma <strong>Poste Italiane<\/strong>, secondo quanto riporta La Stampa, potrebbe essere l&#8217;artefice dell&#8217;ingresso in societ\u00e0 di<strong> Iliad<\/strong>, che a fine maggio ha festeggiato il suo settimo anno dall&#8217;arrivo nel nostro Paese.<\/p>\n<p>Se state cercando un&#8217;<strong>offerta mobile conveniente<\/strong>, cliccando sul tasto di seguito potete confrontare gratuitamente le soluzioni pi\u00f9 interessanti dei principali operatori tramite il <strong>comparatore di SOStariffe.it<\/strong> e poi attivare comodamente online la promozione perfetta per le vostre esigenze e abitudini di consumo.<\/p>\n<p>[WIDGET-MOBILE]<\/p>\n<h2>Fusione TIM Iliad: il ruolo di Poste Italiane e le prospettive per il mercato Tlc<\/h2>\n<p>La Stampa afferma che <strong>Iliad<\/strong> sarebbe disponibile a un ingresso in minoranza nel capitale di <strong>TIM<\/strong> ma vorrebbe la guida industriale della societ\u00e0. <strong>Poste Italiane<\/strong> si sarebbe gi\u00e0 messa a lavoro per valutare la fattibilit\u00e0 della fusione tra i due gruppi. L&#8217;obiettivo \u00e8 quello di arrivare a costruire un operatore con il 37,5% di quote del mercato mobile dal valore di 25 miliardi di euro.<\/p>\n<p>La prospettiva di una <strong>fusione TIM Iliad<\/strong> non \u00e8 comunque una novit\u00e0. Su questa possibilit\u00e0 di era proprio espresso nelle ultime settimane lo stesso AD di <strong>Telecom, Pietro Labriola<\/strong>, che in una call indetta lo scorso aprile per commentare con gli analisi i conti del gruppo aveva dichiarato di essere &#8220;<em>a favore di un consolidamento in Italia<\/em>&#8220;. Il dirigente aveva comunque precisato di non aver &#8220;<em>mai nascosto che<strong> Iliad<\/strong> potrebbe essere un possibile deal<\/em>&#8221; e aveva aggiunto che &#8220;<em>non sarebbe un incubo per noi se ci fosse invece un consolidamento tra <strong>Wind <\/strong>e<strong> Iliad<\/strong><\/em>\u201d. &#8220;<em>Continueremo a seguire la possibilit\u00e0 di seguire un deal con<strong> Iliad<\/strong> ma allo stesso tempo anche con Wind potrebbe esserci un dea<\/em>l&#8221;, era stata la precisazione&#8221;, aveva chiarito Labriola.<\/p>\n<p>L&#8217;AD di <strong>Telecom<\/strong> aveva anche spiegato le differente tra un eventuale accordo con <strong>Iliad<\/strong> o con <strong>WindTre<\/strong>:\u00a0&#8220;<em>Un deal potential tra <strong>TIM <\/strong>e<strong> WindTre<\/strong> \u00e8 molto complesso perch\u00e9 la somma dei due pi\u00f9 \u00e8 pi\u00f9 alta del 40%-50% della quota mercato sia sul fisso che sul mobile. Quindi non posso chiedere miracoli anche se non sono troppo aggressivi sull\u2019Antitrust<\/em>&#8220;. Lo stesso manager comunque non aveva escluso anche questa possibilit\u00e0.<\/p>\n<p>Per quanto riguarda <strong>Iliad<\/strong>, invece, l&#8217;amministratore delegato<strong> Benedetto Levi<\/strong> durante un incontro con i giornalisti a Milano in cui \u00e8 stata anche presentata la <strong>nuova offerta fibra<\/strong> chiamata <strong>IliadBox Super<\/strong> ha confermato che non \u00e8 in corso alcuna trattativa concreta con <strong>TIM<\/strong>. Allo stesso tempo, per\u00f2, il numero uno della divisione italiana dell&#8217;azienda di <b>Xavier Niel <\/b>ha sottolineato che &#8220;<em>sicuramente il consolidamento del mercato porterebbe valore al mercato<\/em>&#8221; delle telecomunicazioni ma anche che questo tipo di operazione non sarebbe &#8220;<em>una necessit\u00e0<\/em>&#8220;. Levi ha poi ricordato i punti di forza dell&#8217;azienda francese con\u00a0&#8220;<em>un <strong>Ebitda<\/strong> in crescita del 24% nel primo trimestre su quello di un anno fa<\/em>&#8220;.<\/p>\n<p>La possibile <strong>fusione TIM Iliad<\/strong> passa anche dalla politica. La telco a ragione viene considerata un asset strategico per il Paese ed \u00e8 forte il desiderio che resti italiana. Dall&#8217;altro lato, per\u00f2, il ministro delle Imprese e del Made in Italy, <strong>Adolfo Urso<\/strong>, durante un tavolo sulle telco dello scorso aprile al Mimit in cui \u00e8 stato approvato un <a href=\"https:\/\/www.sostariffe.it\/news\/telecomunicazioni-gli-obiettivi-del-governo-per-il-futuro-del-settore-403516\/\"><strong>piano di rilancio<\/strong><\/a> per il settore aveva dichiarato che, anche alla luce della fusione tra <strong>Fastweb <\/strong>e<strong> Vodafone Italia<\/strong>, &#8220;<em>il consolidamento non \u00e8 pi\u00f9 un&#8217;opzione: \u00e8 una necessit\u00e0, per colmare il divario competitivo che esiste in Italia rispetto agli altri Paesi europei<\/em>&#8220;. Urso aveva poi sottolineato che &#8220;<em>cinque operatori in Italia sono troppi<\/em>&#8220;.<\/p>\n<h2>Le migliori offerte mobile di TIM, Iliad e PosteMobile a giugno 2025<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 352px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 33.3333%; height: 24px; text-align: center;\"><strong>Offerte mobile<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px; text-align: center;\"><strong>Costi<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px; text-align: center;\"><strong>Minuti, SMS e Gigabyte<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\"><strong>Promo Creami EXTRA WOW 50 di PosteMobile<br \/>\n<\/strong><\/td>\n<td style=\"width: 33.3333%;\">\n<ul>\n<li><strong>5,99<\/strong> <strong>\u20ac\/mese<\/strong><\/li>\n<li>Attivazione a <strong>10<\/strong> <strong>\u20ac + 10 \u20ac<\/strong><\/li>\n<\/ul>\n<\/td>\n<td style=\"width: 33.3333%;\">\n<ul>\n<li>minuti e SMS illimitati +<strong> 50 GB in 4G+ <\/strong>fino a 300 Mbps<\/li>\n<li><strong>opzione 5G<\/strong> a <strong>3<\/strong>\u00a0<strong>\u20ac\/mese<\/strong><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\"><strong>TIM Power Iron<br \/>\n<\/strong><\/td>\n<td style=\"width: 33.3333%;\">\n<ul>\n<li><strong>primo mese e attivazione gratis<\/strong>, poi <strong>6,99 \u20ac\/mese<\/strong><\/li>\n<li>SIM\/eSIM a <strong>10 \u20ac<\/strong><\/li>\n<\/ul>\n<\/td>\n<td style=\"width: 33.3333%;\">\n<ul>\n<li>minuti illimitati e 200 SMS + <strong>150 GB in 5G<\/strong><\/li>\n<li><strong>Giga illimitati in 5G Ultra<\/strong> con <strong>TIM Unica Power<\/strong><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 33.3333%; height: 24px;\"><strong>Giga 200 di Iliad<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px;\">\n<ul>\n<li><strong>9,99<\/strong> <b>\u20ac\/mese per sempre<\/b><\/li>\n<li>Attivazione a <strong>9,99 \u20ac<\/strong><\/li>\n<\/ul>\n<\/td>\n<td style=\"width: 33.3333%; height: 24px;\">\n<ul>\n<li>minuti e SMS illimitati + <strong style=\"font-family: inherit; font-size: inherit;\">200 GB in 5G<\/strong><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>In attesa di scoprire se effettivamente la <strong>fusione TIM Iliad<\/strong> avr\u00e0 un seguito e se avverr\u00e0 un ulteriore consolidamento del mercato, di seguito sono descritte alcune delle migliori offerte dei tre operatori coinvolti nell&#8217;operazione. Con <strong>meno di 10 euro al mese<\/strong> \u00e8 possibile attivare un piano con <strong>minuti illimitati<\/strong> e fino a <strong>200 GB in 5G<\/strong>, anche con <strong>attivazione gratuita<\/strong>.<\/p>\n<p>Vi ricordiamo poi che per non perdere il <strong>numero di telefono<\/strong> nel cambio di gestore basta richiedere la <strong>portabilit\u00e0 <\/strong>o<strong> MNP<\/strong> (Mobile Number Portability), che verr\u00e0 eseguita gratuitamente entro un massimo di tre giorni lavorativi.<\/p>\n<p>Tra le migliori offerte disponibili a giugno potete quindi scegliere tra:<\/p>\n<h3>Promo Creami EXTRA WOW 50 di PosteMobile<\/h3>\n<ul>\n<li>minuti e SMS illimitati<\/li>\n<li><strong>50 GB in 4G+<\/strong> fino a 300 Mbps sulla rete di Vodafone<\/li>\n<li>\u00a07,55 GB per navigare in roaming in Ue<\/li>\n<\/ul>\n<p>L&#8217;offerta di <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/postemobile\/\"><strong>PosteMobile<\/strong><\/a> costa <strong>5,99 euro al mese<\/strong>. Il contributo per l&#8217;attivazione \u00e8 di <strong>10 euro<\/strong> pi\u00f9 una ricarica di<strong> 10 euro<\/strong> comprensiva del primo canone. La tariffa \u00e8 disponibile solo online per i nuovi clienti.<\/p>\n<p>Potete <strong>passare al 5G<\/strong> c&#8217;\u00e8\u00a0l&#8217;apposita opzione da <strong>3 euro al mese<\/strong>.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=1&amp;id=11695\" target=\"_blank\" rel=\"noopener\">Attiva Creami EXTRA WOW 50 <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h3><strong>TIM Power Iron<\/strong><\/h3>\n<ul>\n<li>minuti illimitati e 200 SMS<\/li>\n<li><strong>150 GB in 5G <\/strong>fino a 250 Mbps<\/li>\n<li>8 GB per navigare il roaming in Ue<\/li>\n<\/ul>\n<p>Il <b>primo mese e attivazione sono gratis <\/b>per i nuovi clienti che l&#8217;acquistano online l&#8217;offerta di <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/tim\/\"><strong>TIM<\/strong><\/a>, che poi si rinnova a <strong>6,99 euro al mese<\/strong>. La SIM costa <strong>10 euro<\/strong> con 5 euro di traffico incluso. In alternativa potete richiedere anche online un&#8217;<strong>eSIM<\/strong> allo stesso prezzo. Per effettuare la verifica dell&#8217;identit\u00e0 potete utilizzare anche pi\u00f9 comodamente lo <strong>SPID<\/strong>.<\/p>\n<p>Questa offerta \u00e8 riservata a chi richiede la <strong>portabilit\u00e0 del numero<\/strong> da <strong>Iliad<\/strong> o alcuni operatori virtuali selezionati come <strong>PosteMobile, CoopVoce, Fastweb Mobile<\/strong> e altri.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/tim\/\" target=\"_blank\" rel=\"noopener\">Confronta le offerte TIM mobile <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Se siete clienti di <strong>TIM<\/strong> per la connessione Internet di casa potete poi aggiungere <strong>TIM Unica Power<\/strong> per avere <strong>Giga illimitati in 5G Ultra fino a 6 SIM<\/strong> (anche se non intestati al titolare dalla linea fissa) e navigare fino a <strong>2 Gbps<\/strong> in download e 200 Mbps in upload con accesso prioritario alla rete dell&#8217;operatore. <strong>TIM Unica Power \u00e8 gratis<\/strong>, invece di 1,90 euro al mese, abbinando almeno 3 SIM entro il 28\/6\/25.<\/p>\n<h3><strong>Giga 200 di Iliad<\/strong><\/h3>\n<ul>\n<li>minuti e SMS illimitati<\/li>\n<li><b>200 GB in 5G <\/b>in oltre 7.000 Comuni<\/li>\n<li>13 GB per navigare in roaming in Ue e Uk<\/li>\n<\/ul>\n<p>L&#8217;offerta di <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/iliad\/\"><strong>Iliad<\/strong><\/a> costa <b>9,99 euro al mese<\/b> con<b> prezzo <\/b><b>fisso per sempre<\/b>. Il contributo per l&#8217;attivazione \u00e8 di <strong>9,99 euro <\/strong>mentre SIM e spedizione sono gratis. Altrimenti potete acquistare un&#8217;<strong>eSIM<\/strong> a<strong>\u00a09,99 euro <\/strong>anche online.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=2&amp;id=11827\" target=\"_blank\" rel=\"noopener\">Attiva Giga 200 di Iliad <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Attivando <strong>Giga 200 con pagamento automatico<\/strong> su conto corrente o carta di credito avete accesso a uno <strong>sconto sulla rete fissa<\/strong> e acquistare <strong>IliadBox<\/strong> <strong>Super<\/strong> con inclusi una connessione senza limiti fino a 5 Gbps in download in FTTH EPON, chiamate illimitate, modem Wi-Fi 7, saponetta Wi-Fi da 350 GB in 4G e 2 Wi-Fi 7 Extender a <strong>29,99 euro al mese per sempre<\/strong>. Per ottenere il vantaggio fisso e mobile dovrete prima attivare la fibra e poi aggiungere la SIM\/eSIM dall&#8217;<strong>Area Personale Fibra<\/strong>. L&#8217;offerta convergente ha un costo totale di <strong>39,98 euro al mese<\/strong> pi\u00f9 <strong>39,99 euro<\/strong> una tantum per l&#8217;installazione della linea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poste Italiane potrebbe avere un ruolo importante nella possibile fusione TIM Iliad, un&#8217;operazione valutata fino a 25 miliardi di euro. Scopri come cambier\u00e0 il settore delle telecomunicazioni in Italia<\/p>\n","protected":false},"author":72,"featured_media":404344,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[20744,9,4],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/404333"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=404333"}],"version-history":[{"count":17,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/404333\/revisions"}],"predecessor-version":[{"id":404446,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/404333\/revisions\/404446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/404344"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=404333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=404333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=404333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}