{"id":398913,"date":"2024-12-20T11:48:44","date_gmt":"2024-12-20T10:48:44","guid":{"rendered":"https:\/\/sostariffe-internal.gruppomol.lcl\/news\/?p=398913"},"modified":"2024-12-22T23:32:48","modified_gmt":"2024-12-22T22:32:48","slug":"iliad-estero-ancora-piu-giga-inclusi-da-dicembre-2024","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/iliad-estero-ancora-piu-giga-inclusi-da-dicembre-2024-398913\/","title":{"rendered":"Iliad estero: ancora pi\u00f9 Giga inclusi da dicembre 2024"},"content":{"rendered":"<p><strong>Iliad<\/strong> ha aumentato la quantit\u00e0 di <strong>Gigabyte disponibili per il roaming in Ue<\/strong> inclusi nelle sue offerte e abbassato i costi <strong>extrasoglia<\/strong>. Scopri cosa \u00e8 cambiato e le opzioni <strong>Iliad estero<\/strong> disponibili<!--more--><\/p>\n<p><a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/iliad\/\"><strong>Iliad<\/strong><\/a> come altri operatori di <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/\"><strong>telefonia mobile<\/strong><\/a> ha scelto di anticipare l&#8217;adeguamento previsto per l&#8217;inizio del 2025 per quanto riguarda il roaming. Il gestore low cost ha aumento i Giga inclusi nelle sue offerte dedicati alla navigazione in Unione Europea e ridotto i <strong>costi extasoglia<\/strong>. Nelle scorse settimane anche <strong>TIM <\/strong>e<strong> WindTre<\/strong> avevano seguito la stessa strada.<\/p>\n<p>Vi ricordiamo che con il<strong> comparatore di SOStariffe.it<\/strong> potete confrontare gratuitamente le offerte di <strong>Iliad<\/strong> con quelle di altri operatori per trovare quella pi\u00f9 conveniente per voi. Basta cliccare sul tasto di seguito per avviare la comparazione e, una volta trovata la soluzione pi\u00f9 adatta alla vostre esigenze, attivarla comodamente online.<\/p>\n<p>[WIDGET-MOBILE]<\/p>\n<h2>Iliad estero: pi\u00f9 Giga per il roaming in Ue da dicembre 2024<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 120px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\"><strong>Iliad e il roaming in Ue<\/strong><\/td>\n<td style=\"width: 50%; height: 24px;\"><strong>Tutti i dettagli<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td style=\"width: 50%; height: 48px;\"><strong>Cosa \u00e8 cambiato dal 12\/12\/24?<\/strong><\/td>\n<td style=\"width: 50%; height: 48px;\"><strong>Iliad<\/strong> anticipa le modifiche per il <strong>roaming in Ue<\/strong> previste dal primo gennaio 2025<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\"><strong>Quanti Giga ho per il roaming in Ue?<\/strong><\/td>\n<td style=\"width: 50%; height: 24px;\">I Giga disponibili in Ue in base alla propria offerta ora si calcolano come segue: <strong>Volume di GB = [importo della propria spesa mensile (IVA esclusa) \/ 1,30] x 2<\/strong>.<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\"><strong>Cosa succede quando finisco i Giga in roaming?<\/strong><\/td>\n<td style=\"width: 50%; height: 24px;\">La nuova <strong>tariffa extrasoglia<\/strong>, che si attiva quando si esauriscono i Giga per il roaming in Ue, \u00e8 di <strong>0,154 cent per MB<\/strong> (IVA inclusa)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Con il <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/guide\/abolizione-roaming-in-europa-guida-ai-cambiamenti-da-luglio-2022\"><strong>Roaming Like at Home<\/strong><\/a> \u00e8 possibile navigare in Unione Europea alle stesse condizioni previste dalla propria offerta nazionale, anche se entro una soglia determinata di traffico dati che viene calcolata in funzione del costo mensile della stessa tariffa. Il calo graduale dei prezzi in roaming all&#8217;ingrosso costringer\u00e0 gli operatori, che sono tenuti ad adeguare annualmente le condizioni dei piani mobili per quanto riguarda la navigazione in Ue, ad aumentare la quantit\u00e0 di Gigabyte utilizzabili in Europea e ridurre anche il <strong>costo extrasoglia<\/strong> applicato una volta consumato il traffico dati disponibile. Al momento le stesse regole si applicano anche al <strong>Regno Unito<\/strong>.<\/p>\n<p>L&#8217;adeguamento entrer\u00e0 in vigore a partire dal primo gennaio 2025 ma <strong>Iliad<\/strong> ha deciso di anticipare i tempi. Prima del 12 dicembre 2024 la formula per calcolare i Giga utilizzabili in Ue era la seguente: Volume di GB = [importo della propria spesa mensile (IVA esclusa) \/ 1,55] x 2. Ora invece si deve fare riferimento a questa formula: <strong>Volume di GB = [importo della propria spesa mensile (IVA esclusa) \/ 1,30] x 2<\/strong>.\u00a0Per quanto riguarda invece il <strong>costo extrasoglia<\/strong>, la tariffazione si \u00e8 ridotta da 0,189 cent per MB (IVA inclusa) a <strong>0,159 cent per MB<\/strong> (IVA inclusa).<\/p>\n<p>L&#8217;adeguamento dei Giga disponibili in Ue, valido anche per i <strong>gi\u00e0 clienti <\/strong>con tariffe oggi non pi\u00f9 disponibili, nel dettaglio quindi prevede:<\/p>\n<ul>\n<li><strong>8 GB<\/strong> per offerte da <strong>5,99 euro al mese<\/strong><\/li>\n<li><strong>9 GB<\/strong> per offerte da <strong>6,99 euro al mese<\/strong><\/li>\n<li><strong>11 GB<\/strong> per offerte da 7<strong>,99 euro al mese<\/strong><\/li>\n<li><strong>12 GB<\/strong> per offerte da <strong>8,99 euro al mese<\/strong><\/li>\n<li><strong>13 GB<\/strong> per offerte da <strong>9,99 euro al mese<\/strong><\/li>\n<li><strong>16 GB<\/strong> per offerte da <strong>11,99 euro al mese<\/strong><\/li>\n<li><strong>18 GB<\/strong> per offerte da <strong>13,99 euro al mese<\/strong><\/li>\n<li><strong>19 GB<\/strong> per offerte da <strong>14,99 euro al mese<\/strong><\/li>\n<\/ul>\n<p>Vi ricordiamo che state <strong>pianificando un viaggio (<a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/guide\/iliad-estero-guida-ai-costi-offerte-e-attivazione-dei-servizi-fuori-confine\">qui alcuni consigli utili<\/a>)<\/strong>, sono disponibili alcune opzioni <strong>Iliad estero<\/strong> per avere:<\/p>\n<ul>\n<li><strong>5 GB in roaming in Ue <\/strong>per un mese a <strong>3,99 euro<\/strong><\/li>\n<li><strong>5 GB in roaming in Svizzera <\/strong>per un mese a <strong>4,99 euro<\/strong><\/li>\n<li><strong>5 GB in roaming in USA e Canada <\/strong>per un mese a <strong>4,99 euro<\/strong><\/li>\n<\/ul>\n<h2><b>Le altre offerte di Iliad a dicembre 2024<\/b><\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 144px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 33.3333%; height: 24px; text-align: center;\"><strong>Offerte mobile<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px; text-align: center;\"><strong>Costo mensile<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px; text-align: center;\"><strong>Minuti, SMS e Gigabyte<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 33.3333%; height: 24px;\"><strong>Voce<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px;\"><strong><b>4,99 \u20ac\/mese per sempre<\/b><\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px;\"><strong>minuti e SMS illimitati <\/strong>+ 20 MB in 4G\/4G+<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 33.3333%; height: 24px;\"><strong>Giga 120<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px;\"><b>7,99 \u20ac\/mese per sempre<\/b><\/td>\n<td style=\"width: 33.3333%; height: 24px;\">minuti e SMS illimitati + <strong>120 GB in 4G\/4G+<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\"><strong>Flash 210<\/strong><\/td>\n<td style=\"width: 33.3333%;\"><b>9,99 \u20ac\/mese per sempre<\/b><\/td>\n<td style=\"width: 33.3333%;\">minuti e SMS illimitati + <strong>210 GB in 5G<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 33.3333%; height: 24px;\"><strong>Giga 250<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px;\"><b>11,99 \u20ac\/mese per sempre<\/b><\/td>\n<td style=\"width: 33.3333%; height: 24px;\">minuti e SMS illimitati + <strong>250 GB in 5G<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 33.3333%; height: 24px;\"><strong>Dati 350<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px;\"><b>14,99 \u20ac\/mese per sempre<\/b><\/td>\n<td style=\"width: 33.3333%; height: 24px;\">minuti e SMS a consumo + <strong>350 GB in 4G\/4G+<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Tutte le offerte di <strong>Iliad<\/strong> sono senza vincoli n\u00e9 costi nascosti. Se non siete soddisfatti del piano mobile potete richiedere in qualsiasi momento il recesso senza penali o costi aggiuntivi per la disattivazione della linea. L&#8217;operatore low cost include nelle sue offerte tutti i servizi di base e reperibilit\u00e0, a partire dalla segreteria telefonica fino all&#8217;Hotspot per condividere la connessione a Internet con altri dispositivi, e dato che non applica rimodulazioni il prezzo \u00e8 fisso per sempre.<\/p>\n<p>Con <strong>Iliad<\/strong> potete navigare in <strong>4G\/4G+<\/strong> potendo contare su una copertura superiore al 99% del territorio italiano. Per le sue <strong>offerte 5G<\/strong>, che integrano la tecnologia <strong>VoLTE<\/strong> per effettuare chiamate con audio di altissima qualit\u00e0 anche mentre si utilizzano le app e si naviga su Internet in contemporanea, la copertura \u00e8 invece garantita in oltre 3.000 Comuni. A dicembre potete quindi scegliere tra le seguenti tariffe:<\/p>\n<h3>Voce<\/h3>\n<ul>\n<li>minuti e SMS illimitati<\/li>\n<li><strong>20 MB<\/strong>\u00a0<strong>in 4G\/4G+ <\/strong>da utilizzare anche in roaming in Ue<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di <strong>9,99 euro al mese per sempre<\/strong>.<\/p>\n<h3>Giga 120<\/h3>\n<ul>\n<li>minuti e SMS illimitati<\/li>\n<li><strong>120 GB in 4G\/4G+<\/strong><\/li>\n<li>9 GB per il roaming in Ue<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di <strong>7,99 euro al mese per sempre<\/strong>.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=1&amp;id=11203\" target=\"_blank\" rel=\"noopener\">Attiva Giga 120 di Iliad <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h3>Flash 210<\/h3>\n<ul>\n<li>minuti e SMS illimitati<\/li>\n<li><strong>210 GB in 5G<\/strong><\/li>\n<li>13 GB per il roaming in Ue<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di <strong>9,99 euro al mese per sempre<\/strong>.\u00a0L&#8217;offerta, salvo proroghe, \u00e8 disponibile fino alle ore <strong>14<\/strong> del <strong>30 dicembre 2024<\/strong>.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=2&amp;id=11770\" target=\"_blank\" rel=\"noopener\">Attiva Flash 210 di Iliad <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h3>Giga 250<\/h3>\n<ul>\n<li>minuti e SMS illimitati<\/li>\n<li><strong>250 GB in 5G<\/strong><\/li>\n<li>16 GB per il roaming in Ue<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di <strong>11,99 euro al mese per sempre<\/strong>.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=3&amp;id=11648\" target=\"_blank\" rel=\"noopener\">Attiva Giga 250 di Iliad <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h3>Dati 350<\/h3>\n<ul>\n<li>chiamate a 28 cent al minuto e SMS a 28 cent<\/li>\n<li><strong>350 GB in 4G\/4G+<\/strong><\/li>\n<li>19 GB per il roaming in Ue<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di <strong>14,99 euro al mese per sempre<\/strong>.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=5&amp;id=10097\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva Dati 350 di Iliad <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Per tutte le offerte il contributo per l&#8217;attivazione \u00e8 di<strong> 9,99 euro<\/strong> una tantum. SIM e spedizione sono invece gratuite. Potete altrimenti richiedere un&#8217;<strong>eSIM<\/strong> anche online al costo di <strong>9,99 euro<\/strong>. Per l&#8217;attivazione dell&#8217;offerta dovrete poi effettuare la <strong>video identificazione<\/strong>, che servir\u00e0 all&#8217;operatore per verificare l&#8217;identit\u00e0 dell&#8217;intestatario del piano mobile. In tutto vi basteranno solo pochi minuti.<\/p>\n<p>Accedendo all&#8217;Area Personale da mobile o web potete gestire comodamente la vostra offerta. Il login avviene poi in automatico se connessi alla rete dell&#8217;operatore low cost. Dall&#8217;<strong>Area Personale<\/strong> si possono effettuare diverse operazioni come monitorare il traffico e il credito residui, cambiare offerta, gestire le deviazioni di chiamata e molte altre ancora.<\/p>\n<p><strong>Iliad<\/strong> blocca la navigazione quando si esaurisce il traffico dati incluso nelle sue offerte per evitare spese inutili. Potete per\u00f2 continuare a navigare in Italia, una volta superati i 200 MB e solo previo consenso, al costo di <strong>90 cent ogni 100 MB<\/strong>.<\/p>\n<p>Alle offerte di <strong>Iliad<\/strong> potete abbinare anche uno <strong>smartphone a rate senza anticipo<\/strong> con pagamento tramite un <strong>finanziamento a tasso zero<\/strong> (salvo approvazione) e <strong>spedizione gratuita<\/strong>. In base al modello sono disponibili rateizzazione fino a 24 mesi. Tra gli smartphone disponibili, ad esempio, potete scegliere tra <strong>iPhone 16<\/strong> a partire da <strong>39,16 euro al mese per 20 rate<\/strong> o <strong>Samsung Galaxy S24 FE<\/strong> a partire da <strong>32,04 euro al mese per 24 rate<\/strong>. Dando poi in permuta un vecchio dispositivo di Apple potete ricevere uno sconto sul finanziamento e avere <strong>iPhone 16 Pro<\/strong> a partire da <strong>21 euro al mese<\/strong>. Iliad comunque mette a disposizione anche <strong>smartphone rigenerati<\/strong> a partire da<strong> 179 euro<\/strong>.<\/p>\n<p>Non solo, chi attiva un&#8217;<strong>offerta da 9,99 euro o 11,99 euro al mese<\/strong> e sceglie il <strong>pagamento automatico<\/strong> su conto corrente o carta di credito pu\u00f2 usufruire di uno sconto sulla rete fissa e attivare <strong>IliadBox<\/strong> al prezzo di <strong>21,99 euro al mese per sempre<\/strong>, invece di 25,99 euro al mese. L&#8217;<a href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-fibra-ottica\/\"><strong>offerta fibra<\/strong><\/a> include:<\/p>\n<ul>\n<li>navigazione senza limiti fino a 5 Gbps in download e 700 Mbps in upload (suddivisi tra porte Ethernet e Wi-Fi) in FTTH EPON o fino a 2,5 Gbps in download e 500 Mbps in upload in FTTH GPON<\/li>\n<li>chiamate illimitate anche verso 60 destinazioni internazionali<\/li>\n<li>attivazione<\/li>\n<li>modem con supporto al Wi-Fi 7 in comodato d&#8217;uso gratuito<\/li>\n<\/ul>\n<p>Il contributo per l&#8217;installazione della linea \u00e8 di <strong>39,99 euro<\/strong>. Si possono aggiungere fino a 4 Wi-Fi 7 Extender per ampliare la copertura e raggiungere ogni angolo della casa (1,99 euro al mese per ogni dispositivo) e McAfee Multi Access per la protezione di tutti i terminali connessi alla rete fissa (2,99 euro al mese).<\/p>\n<p>Se avete bisogno di assistenza potete contattare gratuitamente il<strong>\u00a0Servizio Clienti<\/strong> al <strong>177 <\/strong>dal luned\u00ec alla domenica, inclusi i giorni festivi, dalle ore 8.00 alle 22.00. Altrimenti potete consultare la sezione &#8220;<strong>Assistenza<\/strong>&#8221; sul sito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iliad ha aumentato la quantit\u00e0 di Gigabyte disponibili per il roaming in Ue inclusi nelle sue offerte e abbassato i costi extrasoglia. Scopri cosa \u00e8 cambiato e le opzioni Iliad estero disponibili<\/p>\n","protected":false},"author":72,"featured_media":398940,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[20744,9],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/398913"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=398913"}],"version-history":[{"count":9,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/398913\/revisions"}],"predecessor-version":[{"id":398943,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/398913\/revisions\/398943"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/398940"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=398913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=398913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=398913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}