{"id":397830,"date":"2024-11-26T12:00:02","date_gmt":"2024-11-26T11:00:02","guid":{"rendered":"https:\/\/sostariffe-internal.gruppomol.lcl\/news\/?p=397830"},"modified":"2024-11-27T00:33:06","modified_gmt":"2024-11-26T23:33:06","slug":"unicredit-lancia-offerta-di-scambio-di-azioni-per-acquisire-banco-bpm","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/unicredit-lancia-offerta-di-scambio-di-azioni-per-acquisire-banco-bpm-397830\/","title":{"rendered":"UniCredit lancia offerta di scambio di azioni per acquisire Banco BPM"},"content":{"rendered":"<p><b>UniCredit <\/b>alla conquista di <b>Banco BPM<\/b>, con un&#8217;offerta pubblica di scambio volontaria. Dalle nozze nascerebbe la terza banca europea, con al suo interno anche gli istituti 100% digitali di<b> buddybank UniCredit <\/b>e <b>Webank di Banco BPM<\/b>, che offrono conti correnti online zero spese.<b> <\/b>Ecco i dettagli sulla maxi operazione e come trovare un<b> conto conveniente <\/b>a novembre 2024 con il <b>comparatore di SOStariffe.it.<\/b><\/p>\n<p><!--more--><\/p>\n<p><b>UniCredit <\/b>presenta<b> <\/b>un&#8217;offerta pubblica di scambio volontaria sulla totalit\u00e0 delle azioni di <b>Banco BPM <\/b>per un controvalore complessivo di oltre 10 miliardi di euro.<span class=\"Apple-converted-space\"> \u00a0<\/span>Dopo aver lanciato a settembre 2024 l\u2019operazione per la fusione con la tedesca <b>Commerzbank<\/b>, il gigante bancario guidato da<b> Andrea Orcel <\/b>si muove anche per unirsi con il Banco BPM: \u201c<em>Tre anni fa abbiamo definito la nostra ambizione di costruire la Banca per il futuro dell\u2019Europa. Oggi facciamo un passo avanti molto importante, estendendo un\u2019offerta agli stakeholder di Banco BPM affinch\u00e9 si uniscano a noi e al nostro viaggio<\/em>\u201d, ha scritto su LinkedIn il ceo di UniCredit.<\/p>\n<p>Una mossa che per\u00f2 ha immediatamente provocato le reazioni della politica. \u00c8 subito scesa in campo la <b>Lega<\/b>, con i ministri <b>Matteo Salvini<\/b> e <b>Giancarlo Giorgetti<\/b> che frenano sull\u2019operazione in quanto non concordata con il Governo e chiedono alla Banca d&#8217;Italia di esprimersi in merito all&#8217;offerta fatta da UniCredit.<\/p>\n<p>In attesa di sapere se nascer\u00e0 o meno la terza banca europea, se stai cercando un conto corrente zero spese, il comparatore di <b>SOStariffe.it<\/b> pu\u00f2 aiutarti nella ricerca di un\u2019offerta conveniente a novembre 2024. Per avere una fotografia delle varie proposte, clicca sul pulsante verde qui sotto:<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/conto-corrente\/\" target=\"\u201c_blank&quot;\" rel=\"noopener\"> CONFRONTA I CONTI CORRENTI <span style=\"\u201ctext-align: right\u201d;\">\u00bb<\/span><\/a><\/p>\n<p>Tra le banche partner del comparatore di SOStariffe.it sono presenti le due banche 100% digitali dei due istituti protagonisti dell&#8217;operazione: <strong><a href=\"https:\/\/www.sostariffe.it\/conto-corrente\/buddy-unicredit\/\">buddybank di UniCredit<\/a><\/strong>\u00a0e <strong><a href=\"https:\/\/www.sostariffe.it\/conto-corrente\/webank\/\">Webank<\/a><\/strong> di Banco BPM, le quali offrono conti correnti online zero spese.<\/p>\n<p>Con il conto <strong>Genius buddy<\/strong> puoi approfittare della promozione per ottenere<strong> fino a 650 euro in buoni regalo Amazon.it<\/strong> riservata ai nuovi clienti che aprono il conto entro il 1\u00b0 dicembre 2024. Il conto di buddybank UniCredit \u00e8 a <strong>canone gratuito<\/strong> se lo richiedi entro il <strong>28 febbraio 2025<\/strong> (anzich\u00e9 2,90 euro\/mese), con carta di debito internazionale MyOne inclusa. Per conoscere maggiori dettagli dell&#8217;offerta del conto <strong>Genius buddy<\/strong> di buddybank UniCredit e aprirlo, clicca sul link qui sotto:<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=rate_widget&amp;id=9651&amp;sos_api_key=\" target=\"_blank\" rel=\"noopener\">SCOPRI IL CONTO DI BUDDYBANK UNICREDIT <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Con apertura entro il 10 dicembre 2024, il <strong>conto corrente online di Webank<\/strong> \u00e8 a <strong>canone zero<\/strong> e offre il<strong> 3% lordo annuo di remunerazione sul saldo fino al 30 giugno 2025<\/strong> sulle giacenze dai 3.000 euro a 100.000 euro. \u00a0Carta di credito, debito e prepagata sono gratuite. Per saperne di pi\u00f9 dell&#8217;offerta del <strong>conto Webank <\/strong>e aprire il conto premi il bottone verde che trovi qui di seguito:<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=rate_widget&amp;id=415&amp;sos_api_key=NrdLvsXdv1Y4PhIgZ9xJF5p0QIW4rfkgbsuFu9xuPIuGzoJS\" target=\"_blank\" rel=\"noopener\">SCOPRI CONTO WEBANK <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h2>UniCredit e Banco BPM: dalla fusione nascer\u00e0 una super banca<\/h2>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><b>NOZZE UNICREDIT E BANCO BPM<\/b><\/td>\n<td style=\"width: 50%;\"><b>LE CIFRE<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">Numero totale dei clienti<\/td>\n<td style=\"width: 50%;\"><b> 19 milioni<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">Numero complessivo delle filiali<\/td>\n<td style=\"width: 50%;\"><b>4.763 sportelli<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">Numero totale dei dipendenti<\/td>\n<td style=\"width: 50%;\"><b>97.000 impiegati<\/b><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Se andasse in porto il matrimonio tra UniCredit e Banco BPM nascerebbe la<b> seconda banca d\u2019Italia, <\/b>dopo<b> Intesa Sanpaolo, <\/b>ma la prima per<b> capitalizzazione<\/b>.<b> <\/b>E il nuovo gruppo bancario che nascerebbe dall\u2019unione di UniCredit e Banco BPM diventerebbe ancor pi\u00f9 grande e solido se andasse a buon fine anche la fusione con Commerzbank, la quarta banca tedesca.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>I numeri riportati nella tabella qui sopra, danno un\u2019idea delle dimensioni del nuovo gigante bancario italiano che potrebbe ridisegnare lo scenario del credito e della finanza non solo nel nostro Paese, ma anche in Europa.<\/p>\n<p>Commentando il via all\u2019operazione lanciata da UniCredit, l\u2019<b>amministratore delegato Orcel<\/b>, in un post sul social network <b>LinkedIn<\/b>, scrive che \u201c<i>rafforzare la nostra presenza nel Paese unendo le forze con Banco BPM consolider\u00e0 la nostra posizione di seconda banca pi\u00f9 grande in Italia, aumentando cos\u00ec la concorrenza all\u2019interno del Paese e <\/i><b><i>creando una banca ancora pi\u00f9 forte nel mercato italiano<\/i><\/b><i>, in grado di investire e competere sulla scena europea<\/i>\u201d.<\/p>\n<p>Il banchiere Orcel spiega che \u201c<i>al momento, <\/i><b><i>l&#8217;offerta che abbiamo presentato non \u00e8 vincolante<\/i><\/b>\u201d. Il ceo di UniCredit chiarisce che spetter\u00e0 al Consiglio di amministrazione di Banco BPM accettare o meno la proposta. Cos\u00ec come saranno chiamati ad esprimersi anche gli azionisti di entrambi gli istituti di credito. Orcel poi conferma che l\u2019operazione Banco BPM \u201c<i>non ha alcun impatto sul <\/i><b><i>nostro investimento in corso in Commerzbank<\/i><\/b><i>, una banca che opera in un altro dei nostri mercati principali<\/i>\u201d.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Allargando lo scenario a un discorso pi\u00f9 di prospettiva, UniCredit mira a \u201c<i>impiegare i prossimi tre-cinque anni per accelerare ulteriormente la nostra crescita, in termini di profitto, sostenibilit\u00e0 e capacit\u00e0 di gestire gli imprevisti e le sfide<\/i>\u201d, fa notare ancora Orcel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>UniCredit alla conquista di Banco BPM, con un&#8217;offerta pubblica di scambio volontaria. Dalle nozze nascerebbe la terza banca europea, con al suo interno anche gli istituti 100% digitali di buddybank UniCredit e Webank di Banco BPM, che offrono conti correnti online zero spese. Ecco i dettagli sulla maxi operazione e come trovare un conto conveniente [&hellip;]<\/p>\n","protected":false},"author":108,"featured_media":397831,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1104,22310,1278],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/397830"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=397830"}],"version-history":[{"count":7,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/397830\/revisions"}],"predecessor-version":[{"id":397878,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/397830\/revisions\/397878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/397831"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=397830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=397830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=397830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}