{"id":389319,"date":"2024-05-20T12:00:23","date_gmt":"2024-05-20T10:00:23","guid":{"rendered":"https:\/\/www.sostariffe.it\/news\/?p=389319"},"modified":"2024-05-21T08:23:42","modified_gmt":"2024-05-21T06:23:42","slug":"promozione-selfyconto-banca-mediolanum-apertura-conto-fino-a-6-premi-a-scelta-a-maggio-2024","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/promozione-selfyconto-banca-mediolanum-apertura-conto-fino-a-6-premi-a-scelta-a-maggio-2024-389319\/","title":{"rendered":"Promozione SelfyConto Banca Mediolanum apertura conto: fino a 6 premi a scelta a maggio 2024"},"content":{"rendered":"<p>Scopri la promozione <b>SelfyConto <\/b>riservata ai nuovi clienti che aprono il conto corrente online entro il<b> 31 maggio 2024<\/b>. Accreditando stipendio\/pensione o addebitando spese per 500 euro al mese per tre mesi, c&#8217;\u00e8 la possibilit\u00e0 di avere a scelta un premio fra i sei in palio. Trova su SOStariffe.it le altre offerte vantaggiose di <b>maggio 2024<\/b>.<\/p>\n<p><!--more--><\/p>\n<p>Per i nuovi clienti che aprono <b>SelfyConto <\/b>entro il 31 maggio 2024, il conto corrente online di Banca Mediolanum, in via promozionale c\u2019\u00e8 la possibilit\u00e0 di ricevere in regalo uno <strong>smartphone Samsung Galaxy A25 5G<\/strong>, oppure sostituirlo con un altro dei cinque premi in palio<span class=\"Apple-converted-space\">. SelfyConto \u00e8 gratuito sempre per gli under 30, mentre per tutti gli altri il canone \u00e8 gratis solo per i primi 12 mesi, poi 3,75 euro al mese, ma azzerabili.\u00a0<\/span><\/p>\n<p>Per scoprire altre soluzioni convenienti a maggio 2024, c\u2019\u00e8 il comparatore per <b>conti correnti <\/b>di <b>SOStariffe.it<\/b> che mette a confronto le proposte pi\u00f9 vantaggiose fra le banche partner. Clicca sul pulsante verde per avere una panoramica delle offerte:<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/conto-corrente\/\" target=\"_blank\" rel=\"noopener noreferrer\">SCOPRI I CONTI CORRENTI DI MAGGIO 2024<span style=\"\u201ctext-align: right\u201d;\">\u00bb<\/span><\/a><\/p>\n<h2>Promozione SelfyConto: fino a 6 premi in palio a maggio 2024<\/h2>\n<p>Per ricevere uno dei premi previsti dalla promozione SelfyConto, \u00e8 necessario aprire entro il 31 maggio 2024 ed effettuare entro il 7 settembre 2024 l&#8217;<strong>accredito dello stipendio o della pensione<\/strong> sul conto, oppure con addebiti sul conto corrente, per tre mesi, di un importo complessivo pari almeno a <strong>500 euro al mese per ciascun mese<\/strong>, relativi a:<\/p>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<ul>\n<li>carte di credito o carte di debito, oltre alle ricariche disposte a favore di carte prepagate distribuite da Banca Mediolanum;<\/li>\n<li>addebiti diretti attivi sul conto corrente (SDD -SEPA Direct Debit).<\/li>\n<\/ul>\n<p>Soddisfacendo una di queste condizioni, si ricever\u00e0 uno <strong>smartphone Samsung Galaxy A25 5G<\/strong>. Il cliente avra\u0300 la possibilita\u0300, entro 7 giorni, di <strong>sostituire questo premio<\/strong> scegliendo in alternativa uno tra i seguenti:<\/p>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<ul>\n<li>Microsoft Xbox Serie S 512Gb;<\/li>\n<li>Samsung Smart Monitor M5 &#8211; M50C da 27\u201d;<\/li>\n<li>Apple AirPods 3\u00b0 Generazione;<\/li>\n<li>Garmin Smartwatch Forerunner 55;<\/li>\n<li>buono regalo Amazon.it del valore di 150 euro.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<h2>Promozione SelfyConto: conto corrente online conveniente a maggio 2024<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 48px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px; text-align: center;\"><strong>NOME DELL&#8217;OFFERTA<\/strong><\/td>\n<td style=\"width: 50%; height: 24px; text-align: center;\"><strong>DETTAGLI DELL&#8217;OFFERTA<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\"><strong>SelfyConto di Banca Mediolanum<\/strong><\/td>\n<td style=\"width: 50%; height: 24px;\">\n<ul>\n<li><strong>canone zero al primo anno<\/strong>, poi 3,75 \u20ac ma azzerabile in via promozionale<\/li>\n<li>possibilit\u00e0 di ricevere un <strong>premio tecnologico<\/strong> a scelta aprendo il conto entro il<strong> 31\/5\/2024<\/strong> e soddisfacendo alcune condizioni poste dalla banca<\/li>\n<li><strong>carta di debito <\/strong>inclusa nel conto<\/li>\n<li>prelievi di contanti gratuiti in area Euro<\/li>\n<li>bonifici ordinari senza costi<\/li>\n<li>carta di credito <strong>Mediolanum Credit Card <\/strong>(facoltativa): 12 \u20ac\/anno di canone e fido a partire da 1.500 \u20ac\/mese<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Banca Mediolanum\u00a0offre <b>SelfyConto<\/b>, un conto corrente online a <strong>canone gratuito per il primo anno<\/strong>, poi \u00e8 previsto un costo di 3,75 euro al mese, ma <strong>azzerabile fino al 31 dicembre 2024 <\/strong>rispettando una delle seguenti condizioni:<\/p>\n<ul>\n<li>attivare un prestito o un mutuo o un prodotto assicurativo di protezione;<\/li>\n<li>essere titolari di un patrimonio gestito pari ad almeno 15.000 euro;<\/li>\n<li>effettuare 48 operazioni di compravendita titoli.<\/li>\n<\/ul>\n<p>C&#8217;\u00e8 da osservare che per gli <strong>under 30,<\/strong> SelfyConto \u00e8 sempre <b>a canone gratuito<\/b>.<\/p>\n<p>L&#8217;apertura di questo conto di Banca Mediolanum \u00e8 pi\u00f9 veloce con lo SPID. Per aprire <b>online SelfyConto<\/b>, c\u2019\u00e8 solo bisogno di:<\/p>\n<ul>\n<li>documento di identit\u00e0 e codice fiscale;<\/li>\n<li>tenere a portata di mano il cellulare;<\/li>\n<li>avere un indirizzo email.<\/li>\n<\/ul>\n<p>Questo conto corrente online di Banca Mediolanum si caratterizza per:<\/p>\n<ul>\n<li><strong>carta di debito Mediolanum Card <\/strong>(circuito Mastercard) a canone gratuito;<\/li>\n<li>prelievi di contanti da ATM dalla stessa banca e anche da altra banca gratuiti in area Euro;<\/li>\n<li><b>bonifici online senza commissioni<\/b>;<\/li>\n<li>domiciliazione delle bollette gratuita;<\/li>\n<li>pagamento gratuito di F23, F24, MAV, RAV;<\/li>\n<li>ricariche telefoniche a costo zero;<\/li>\n<li>possibilit\u00e0 di trading online con 24 mercati nel mondo.<\/li>\n<\/ul>\n<p>C&#8217;\u00e8, infine, da notare che con SelfyConto puoi anche avere a richiesta la <b>carta di credito Mediolanum Credit Card\u00a0<\/b>(circuito Visa o Mastercard). Questa carta ha un canone di 12 euro l&#8217;anno (pari a 1 euro al mese), un fido a partire da 1.500 euro mese e prevede un collegamento a Google Pay, Apple Pay e Samsung Pay. Puoi anche ottenere una carta prepagata <b>Mediolanum Prepaid Card<\/b> abbinata al conto corrente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scopri la promozione SelfyConto riservata ai nuovi clienti che aprono il conto corrente online entro il 31 maggio 2024. Accreditando stipendio\/pensione o addebitando spese per 500 euro al mese per tre mesi, c&#8217;\u00e8 la possibilit\u00e0 di avere a scelta un premio fra i sei in palio. Trova su SOStariffe.it le altre offerte vantaggiose di maggio [&hellip;]<\/p>\n","protected":false},"author":108,"featured_media":389324,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1104],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/389319"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=389319"}],"version-history":[{"count":9,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/389319\/revisions"}],"predecessor-version":[{"id":389459,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/389319\/revisions\/389459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/389324"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=389319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=389319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=389319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}