{"id":386515,"date":"2024-03-22T14:53:57","date_gmt":"2024-03-22T13:53:57","guid":{"rendered":"https:\/\/www.sostariffe.it\/news\/?p=386515"},"modified":"2024-03-25T19:06:23","modified_gmt":"2024-03-25T18:06:23","slug":"offerte-fastweb-tutto-compreso-per-vecchi-clienti-le-promozioni-di-marzo-2024","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/offerte-fastweb-tutto-compreso-per-vecchi-clienti-le-promozioni-di-marzo-2024-386515\/","title":{"rendered":"Offerte Fastweb tutto compreso per vecchi clienti: le promozioni di Marzo 2024"},"content":{"rendered":"<p>Scopri le offerte<strong> Fastweb tutto compreso <\/strong>per gi\u00e0 clienti di marzo. Al giusto prezzo avrete una connessione senza limiti fino a <strong>2,5 Gbps in FTTH<\/strong> anche con chiamate incluse<!--more--><\/p>\n<p><a href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-adsl-fibra-fastweb\/\"><strong>Fastweb Casa<\/strong><\/a> premia i suoi clienti con tanti vantaggi e promozioni, in particolare quelli che gli sono stati fedeli negli anni. Le offerte <strong>Fastweb tutto compreso<\/strong> sono pensate per soddisfare le esigenze di connessione di qualsiasi categoria di utenti, anche quelli che richiedono il massimo della propria rete domestica. L&#8217;operatore poi vi permette di provare la nuova tariffa per trenta giorni. Scaduto il periodo promozionale potete decidere se continuare con <strong>Fastweb<\/strong> oppure richiedere online il recesso senza costi aggiuntivi o penali insieme al rimborso di tutte le spese sostenute durante il mese.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-adsl-fibra-fastweb\/\" target=\"_blank\" rel=\"noopener\">Scopri le migliori offerte fisso <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h2>Fastweb tutto compreso: le offerte per la rete fissa di marzo 2024<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 120px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 25%; text-align: center; height: 24px;\"><strong>Le offerte Internet Casa di Fastweb<\/strong><\/td>\n<td style=\"width: 25%; text-align: center; height: 24px;\"><strong>Navigazione<\/strong><\/td>\n<td style=\"width: 25%; text-align: center; height: 24px;\"><strong>Chiamate<\/strong><\/td>\n<td style=\"width: 25%; text-align: center; height: 24px;\"><strong>Costo mensile<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 25%; height: 24px;\"><strong>Fastweb Casa Light FWA<\/strong><\/td>\n<td style=\"width: 25%; height: 24px;\">fino a 1 Gbps in Ultra FWA<\/td>\n<td style=\"width: 25%; height: 24px;\">non incluse<\/td>\n<td style=\"width: 25%; height: 24px;\"><strong>24,95 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 25%; height: 24px;\"><strong>Fastweb Casa Light<\/strong><\/td>\n<td style=\"width: 25%; height: 24px;\">fino a 2,5 Gbps in FTTH GPON<\/td>\n<td style=\"width: 25%; height: 24px;\">a consumo<\/td>\n<td style=\"width: 25%; height: 24px;\"><strong>27,95 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 25%; height: 24px;\"><strong>Fastweb Casa<\/strong><\/td>\n<td style=\"width: 25%; height: 24px;\">fino a 2,5 Gbps in FTTH GPON<\/td>\n<td style=\"width: 25%; height: 24px;\">illimitate<\/td>\n<td style=\"width: 25%; height: 24px;\"><strong>29,95 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 25%; height: 24px;\"><strong>Fastweb Casa Plus<\/strong><\/td>\n<td style=\"width: 25%; height: 24px;\">fino a 2,5 Gbps in FTTH GPON<\/td>\n<td style=\"width: 25%; height: 24px;\">illimitate<\/td>\n<td style=\"width: 25%; height: 24px;\"><strong>36,95 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Con le <strong>offerte Fastweb tutto compreso<\/strong> i gi\u00e0 clienti dell&#8217;operatore hanno la possibilit\u00e0 di passare a una tipologia di connessione superiore, se \u00e8 disponibile adeguata copertura. Le condizioni delle <a href=\"https:\/\/www.sostariffe.it\/internet-casa\/\"><strong>offerte Internet Casa<\/strong><\/a> sono le stesse di quelle proposte a chi attiva per la prima volta una linea con <strong>Fastweb Casa<\/strong>.<\/p>\n<p>Le <strong>offerte Fastweb tutto compreso<\/strong> per la fibra prevedono una connessione su rete <strong>FTTH<\/strong> (Fiber to the Home) con l&#8217;integrazione della tecnologia <strong>GPON<\/strong> (Gigabit Passive Optical Network) per navigare alla massima velocit\u00e0 in tutte le principali citt\u00e0 italiane. In alternativa si pu\u00f2 richiedere l&#8217;attivazione di una linea fissa in <strong>fibra misto rame<\/strong> o <strong>FTTC<\/strong> (Fiber to the Cabinet) fino a 300 Mbps in download a seconda della distanza tra la vostra abitazione e la cabina stradale. Per sapere se siete gi\u00e0 raggiunti dalla fibra, potete <a href=\"https:\/\/www.sostariffe.it\/internet-casa\/verifica-copertura\/\"><strong>verificare gratis la copertura<\/strong><\/a> con <strong>SOStariffe.it<\/strong>.<\/p>\n<h3><strong>Fastweb Casa Light<\/strong><\/h3>\n<ul>\n<li>navigazione senza limiti fino a 2,5 Gbps in download in FTTH<\/li>\n<li>chiamate a 15 cent al minuto + 15 cent di scatto alla risposta<\/li>\n<li>attivazione inclusa<\/li>\n<li>modem FASTGate incluso<\/li>\n<li>i corsi e workshop della Fastweb Digital Academy per apprendere nuove competenze digitali richieste dalle aziende<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di <strong>27,95 euro al mese<\/strong> senza vincoli.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=rate_widget&amp;id=9711&amp;sos_api_key=\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva Fastweb Casa Light <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h3><strong>Fastweb Casa<\/strong><\/h3>\n<ul>\n<li>navigazione senza limiti fino a 2,5 Gbps in download in FTTH<\/li>\n<li>chiamate illimitate<\/li>\n<li>attivazione inclusa<\/li>\n<li>modem Internet Box NeXXt inclusa<\/li>\n<li>assicurazione Assistenza Casa o Assistenza Pet di Quixa inclusa<\/li>\n<li>i corsi e workshop della Fastweb Digital Academy<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di <strong>29,95 euro al mese<\/strong> senza vincoli.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=rate_widget&amp;id=1785&amp;sos_api_key=\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva Fastweb Casa <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Se non siete raggiunti dalla fibra o abitate in un piccolo Comune, avete a disposizione un&#8217;<a href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-internet-wireless\/\"><strong>offerta FWA<\/strong><\/a> (Fixed Wireless Access) per navigare sulla<strong> fibra misto radio<\/strong>:<\/p>\n<h3><strong>Fastweb Casa Light FWA<\/strong><\/h3>\n<ul>\n<li>navigazione fino a 1 Gbps in download in Ultra FWA<\/li>\n<li>modem Internet Box NeXXt incluso<\/li>\n<li>installazione antenna<\/li>\n<li>i corsi e workshop della Fastweb Digital Academy<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di <strong>24,95 euro al mese<\/strong> senza vincoli.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=rate_widget&amp;id=10145&amp;sos_api_key=\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva Fastweb Casa Light FWA<span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Con il modem <strong>Internet Box NeXXt<\/strong> incluso in comodato d&#8217;uso gratuito avete la garanzia di un segnale sempre stabile e veloce grazie al supporto al Wi-Fi 6 di ultima generazione. Il router poi integra l&#8217;assistente personale <strong>Alexa<\/strong> di Amazon per gestire le diverse funzioni del dispositivo tramite i comandi vocali. Si pu\u00f2, ad esempio, chiedere di riprodurre un brano musicale e informazioni su meteo, news, etc. Per la sicurezza di tutta la famiglia si possono poi impostare diversi profili di sicurezza personalizzati. Il <strong>Parental Control<\/strong> garantisce la protezione dei minori contro le principali minacce sul web.<\/p>\n<p>Alle <strong>offerte<\/strong> <strong>Fastweb tutto compreso <\/strong>si pu\u00f2 anche aggiungere al costo di<strong>\u00a03 euro al mese<\/strong> un <strong>Wi-Fi Extender<\/strong> per ampliare la portata del segnale (soprattutto se la vostra casa \u00e8 grande o su pi\u00f9 piani) e allo stesso prezzo l&#8217;<strong>opzione Plus<\/strong> con inclusi <strong>Assistenza Plus<\/strong> e tutti i vantaggi di <strong>FastwebUP Plus<\/strong>, che ogni mese vi regala:<\/p>\n<ul>\n<li>un mese di film e le serie tv in streaming in omaggio su Infinity+<\/li>\n<li>due biglietti al prezzo di uno nei cinema UCI<\/li>\n<li>un mese di abbonamento digitale a La Repubblica e La Stampa del gruppo GEDI<\/li>\n<li>un mese di abbonamento a BuddyFit<\/li>\n<\/ul>\n<p><strong>Assistenza Plus<\/strong> \u00e8 il servizio che vi permette di richiedere l&#8217;intervento di un tecnico specializzato, che \u00e8 sempre gratuito anche nel caso in cui il problema alla connessione non sia riconducibile a Fastweb, come nel caso di un non corretto collegamento dei cavi. I gi\u00e0 clienti poi con <strong>FastwebUp<\/strong> possono poi accedere a vantaggi dedicati e tante opportunit\u00e0 di risparmio che aumentano insieme al proprio livello. Si accumulano punti in base agli anni passati con l&#8217;operatore ma anche completando le Azioni come rispondere ad alcuni quiz. Con il concorso <strong>UP is Fun<\/strong> si possono poi vincere premi esclusivi ogni mese.<\/p>\n<p>Con<strong> Fastweb Casa<\/strong> potete scegliere se avere inclusa un&#8217;<strong>assicurazione con Quixa<\/strong> che si rinnova annualmente insieme all&#8217;offerta per la rete fissa:<\/p>\n<ul>\n<li><strong>Assistenza Casa<\/strong> con incluso supporto h24 per la sicurezza della propria casa in caso di danni o imprevisti<\/li>\n<li><strong>Assistenza Pet<\/strong> con incluso supporto h24 da parte di un veterinario tramite il servizio di telemedicina, consegna a domicilio dei farmaci e rimborso delle spese di ricerca in caso di smarrimento. Il cane o il gatto devono avere un&#8217;et\u00e0 compresa tra 3 mesi e 10 anni compiuti<\/li>\n<\/ul>\n<h2>Fastweb tutto compreso: come aggiungere una SIM mobile a marzo 2024<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 128px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 25%; height: 24px; text-align: center;\"><strong>Le offerte mobile di Fastweb<\/strong><\/td>\n<td style=\"width: 25%; height: 24px; text-align: center;\"><strong>Minuti, SMS e Gigabyte<\/strong><\/td>\n<td style=\"width: 25%; height: 24px; text-align: center;\"><strong>Costo mensile<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 25%; height: 24px;\"><strong>Fastweb Mobile<\/strong><\/td>\n<td style=\"width: 25%; height: 24px;\">minuti illimitati, 100 SMS +<strong> 150 GB anche in 5G<\/strong><\/td>\n<td style=\"width: 25%; height: 24px;\"><strong>7,95 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 55px;\">\n<td style=\"width: 25%; height: 55px;\"><strong>Fastweb Mobile Full<\/strong><\/td>\n<td style=\"width: 25%; height: 55px;\">minuti illimitati, 100 SMS + <strong>200 GB anche in 5G<\/strong><\/td>\n<td style=\"width: 25%; height: 55px;\"><strong>9,95 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 25%; height: 25px;\"><strong>Fastweb Mobile Maxi<\/strong><\/td>\n<td style=\"width: 25%; height: 25px;\">minuti illimitati, 100 SMS + <strong>300 GB anche in 5G<\/strong><\/td>\n<td style=\"width: 25%; height: 25px;\"><strong>11,95 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Alle <strong>offerte Fastweb tutto compreso<\/strong>\u00a0per la rete fissa potete anche abbinare una SIM di <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/\"><strong>telefonia mobile<\/strong><\/a> scegliendo tra le diverse proposte dell&#8217;operatore. Di recente la rete cellulare \u00e8 stata premiata come la <strong>pi\u00f9 veloce in Italia<\/strong> dalla societ\u00e0 di analisi indipendente <strong>Ookla<\/strong>. A marzo sono disponibili tra le <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/5g\/\"><strong>offerte 5G<\/strong><\/a> pi\u00f9 economiche sul mercato con cui navigare alla massima velocit\u00e0 in tutte le grandi citt\u00e0 come Milano, Torino e Roma. L&#8217;obiettivo dell&#8217;operatore \u00e8 quello di raggiungere una copertura del 90% del territorio italiano entro il 2025.<\/p>\n<p>Le offerte di <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/fastweb\/\"><strong>Fastweb Mobile<\/strong><\/a> sono tutte senza vincoli n\u00e9 costi nascosti. Se non siete soddisfatti potete quindi richiedere il recesso senza il pagamento di penali o spese per la disattivazione della linea. A marzo sono quindi disponibili le seguenti tariffe:<\/p>\n<h3><strong>Fastweb Mobile<\/strong><\/h3>\n<ul>\n<li>minuti illimitati e 100 SMS<\/li>\n<li><strong>150 GB anche in 5G<\/strong><\/li>\n<li>9 GB per navigare in roaming in Ue<\/li>\n<li>i corsi e workshop della Fastweb Digital Academy<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di <strong>7,95 euro al mese<\/strong> senza vincoli.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=1&amp;id=10009&amp;sos_api_key=NrdLvsXdv1Y4PhIgZ9xJF5p0QIW4rfkgbsuFu9xuPIuGzoJS\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva Fastweb Mobile <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h3><strong>Fastweb Mobile Full<\/strong><\/h3>\n<ul>\n<li>minuti illimitati e 100 SMS<\/li>\n<li><strong>200 GB<\/strong> <strong>anche in 5G<\/strong><\/li>\n<li>11 GB per navigare in roaming in Ue<\/li>\n<li>FastwebUP Plus Mobile<\/li>\n<li>i corsi e workshop della Fastweb Digital Academy<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di <strong>9,95 euro al mese<\/strong> senza vincoli.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=2&amp;id=11305\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva Fastweb Mobile Full <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h3><strong>Fastweb Mobile Maxi<\/strong><\/h3>\n<ul>\n<li>minuti illimitati e 100 SMS<\/li>\n<li><strong>300 GB<\/strong> per navigare anche in 5G<\/li>\n<li>13 GB per navigare in roaming in Ue<\/li>\n<li>FastwebUP Plus Mobile<\/li>\n<li>Assistenza Pet con Quixa inclusa<\/li>\n<li>i corsi e workshop della Fastweb Digital Academy<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di <strong>11,95 euro al mese<\/strong> senza vincoli.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=3&amp;id=11128\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva Fastweb Mobile Maxi <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p><strong>Fastweb Mobile<\/strong> per tutte le sue offerte non prevede un contributo per l&#8217;attivazione mentre la <strong>SIM<\/strong> costa <strong>10 euro<\/strong>. La <strong>spedizione \u00e8 gratuita<\/strong> e la riceverete direttamente a casa nella cassetta delle lettere entro un massimo di cinque giorni lavorativi. In negozio si pu\u00f2 invece richiedere un&#8217;<strong>eSIM<\/strong> al costo di <strong>10 euro<\/strong>. Per attivare la vostra offerta potrete poi effettuare la verifica dell&#8217;identit\u00e0 tramite\u00a0<strong>SPID<\/strong> o <strong>CIE<\/strong> (Carta d&#8217;Identit\u00e0 Elettronica) oltre alla <strong>video identificazione<\/strong>.<\/p>\n<p>Nel caso in cui abbiate esaurito gli SMS o i Giga inclusi nelle offerte si possono attivare le seguenti opzioni:<\/p>\n<ul>\n<li>5 cent per ogni SMS inviato<\/li>\n<li>1 GB extra al costo di 6 euro (massimo 10 volte al mese)<\/li>\n<li>10 GB al mese a 6 euro con 10 Giga+. Si pu\u00f2 disattivare quando si vuole<\/li>\n<\/ul>\n<p>Per confrontare le offerte di <strong>Fastweb Mobile<\/strong> con quelle di altri operatori potete utilizzare gratuitamente il <strong>comparatore di SOStariffe.it<\/strong>. Vi basteranno pochi clic per avere tutte le informazioni che vi servono per scegliere la proposta pi\u00f9 economica in base alle vostre reali esigenze ed abitudini di consumo. Potrete poi attivarla con la massima comodit\u00e0 cliccando sul tasto &#8220;Scopri&#8221;, che vi re-indirizzer\u00e0 verso il sito dell&#8217;operatore da cui completare l&#8217;acquisto.<\/p>\n<p>[WIDGET-MOBILE]<\/p>\n<h2>Offerte per uno smartphone a rate a marzo 2024<\/h2>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%; text-align: center;\"><strong>Modelli disponibili<\/strong><\/td>\n<td style=\"width: 25%; text-align: center;\"><strong>Prezzo a rate<\/strong><\/td>\n<td style=\"width: 25%; text-align: center;\"><strong>Prezzo di listino<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>iPhone 15<\/strong><\/td>\n<td style=\"width: 25%;\"><strong>44,45 \u20ac\/mese per 20 rate<\/strong><\/td>\n<td style=\"width: 25%;\"><strong>979 \u20ac<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>iPhone 15 Plus<\/strong><\/td>\n<td style=\"width: 25%;\"><strong>52,15 \u20ac\/mese per 20 rate<\/strong><\/td>\n<td style=\"width: 25%;\"><strong>1.129 \u20ac<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>iPhone 15 Pro<\/strong><\/td>\n<td style=\"width: 25%;\"><strong>59,30 \u20ac\/mese per 20 rate<\/strong><\/td>\n<td style=\"width: 25%;\"><strong>1.239 \u20ac<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>iPhone 15 Pro Max<\/strong><\/td>\n<td style=\"width: 25%;\"><strong>71,70 \u20ac\/mese per 20 rate<\/strong><\/td>\n<td style=\"width: 25%;\"><strong>1.489<\/strong> <strong style=\"font-family: inherit; font-size: inherit;\">\u20ac<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>Samsung Galaxy S24 Ultra 256 GB<\/strong><\/td>\n<td style=\"width: 25%;\"><strong>68,45 \u20ac\/mese per 20 rate<\/strong><\/td>\n<td style=\"width: 25%;\">a partire da <strong>1.499,99 \u20ac<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><em>Nota: i prezzi si riferiscono al taglio base da 128 GB (256 GB per iPhone 15 Pro Max e Samsung Galaxy S4 Ultra)<\/em><\/p>\n<p>A tutte le offerte di <strong>Fastweb Mobile<\/strong> potete aggiungere anche l&#8217;acquisto di uno <strong>smartphone a rate<\/strong>, nella maggior parte dei casi senza anticipo, pagando con un\u00a0<strong>finanziamento Findomestic a tasso zero <\/strong>(salvo approvazione). Dando in permuta un vecchio cellulare tramite il servizio di <strong>trade-in<\/strong> dell&#8217;operatore riceverete poi un acconto pari alla valutazione fatta dall&#8217;operatore direttamente sul conto corrente. Potrete ritirare comodamente il vostro telefono in un negozio di <strong>Fastweb<\/strong>. A marzo potete scegliere tra <strong>iPhone 15<\/strong> a partire da <strong>44,45 euro al mese per 20 rate<\/strong> o <strong>Samsung Galaxy S24 Ultra<\/strong> da <strong>256 GB<\/strong> a partire da <strong>68,45 euro al mese per 20 rate<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scopri le offerte Fastweb tutto compreso per gi\u00e0 clienti di marzo. Al giusto prezzo avrete una connessione senza limiti fino a 2,5 Gbps in FTTH anche con chiamate incluse<\/p>\n","protected":false},"author":72,"featured_media":386517,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[22,22322],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/386515"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=386515"}],"version-history":[{"count":11,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/386515\/revisions"}],"predecessor-version":[{"id":386692,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/386515\/revisions\/386692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/386517"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=386515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=386515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=386515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}