{"id":385165,"date":"2024-02-28T15:38:14","date_gmt":"2024-02-28T14:38:14","guid":{"rendered":"https:\/\/www.sostariffe.it\/news\/?p=385165"},"modified":"2024-04-11T10:02:55","modified_gmt":"2024-04-11T08:02:55","slug":"internet-casa-e-ue-addio-alle-connessioni-adsl-in-rame","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/internet-casa-e-ue-addio-alle-connessioni-adsl-in-rame-385165\/","title":{"rendered":"Internet casa e UE: addio alle connessioni ADSL in rame?"},"content":{"rendered":"<p>La <strong>Commissione Ue<\/strong> spinge per l&#8217;<strong>addio ADSL rame<\/strong> e la totale sostituzione di questa tecnologia con la <strong>fibra ottica<\/strong> o <strong>FWA<\/strong> basata sul <strong>5G <\/strong>entro il 2030<!--more--><\/p>\n<p>La <strong>Commissione europea<\/strong> ormai da diverso tempo spinge per una maggiore diffusione della <strong>banda ultralarga<\/strong> nel Vecchio Continente. In quest&#8217;ottica quindi si deve leggere il white paper dal titolo &#8220;<em>Come padroneggiare le esigenze di infrastrutture digitali dell&#8217;Europa?<\/em>&#8221; in cui sostanzialmente si propone di eliminare le connessioni in <strong>ADSL<\/strong> (Asymmetric Digital Subscriber Line) non solo per adottare una tecnologia superiore a livello di prestazioni ma anche per portare ai cittadini europei nuovi servizi e raggiungere gli obiettivi climatici grazie a un minore consumo energetico. <a href=\"https:\/\/www.sostariffe.it\/news\/tim-iniziera-a-chiudere-le-centrali-solo-rame-dal-25-maggio-2024-387352\/\"><strong>TIM inizier\u00e0 lo spegnimento delle centrali solo rame a fine maggio<\/strong><\/a>.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-adsl\/\" target=\"_blank\" rel=\"noopener\">Scopri le migliori offerte fisso <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h2>Addio ADSL rame: i piani della Commissione Ue<\/h2>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><\/td>\n<td style=\"width: 50%; text-align: center;\"><strong>I piani della Commissione Ue per la rete in rame<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">1<\/td>\n<td style=\"width: 50%;\">La <strong>Commissione Ue<\/strong> si pone l&#8217;obiettivo di <strong>spegnere<\/strong> completamente le<strong> reti in rame entro il 2030<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">2<\/td>\n<td style=\"width: 50%;\">Dove possibile l&#8217;<strong>ADSL<\/strong> sar\u00e0 sostituita dalla <strong>fibra ottica<\/strong>, altrimenti, si garantir\u00e0 la copertura in <strong>FWA 5G<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Nel documento della <strong>Commissione Ue<\/strong> si dichiara nero su bianco l&#8217;obiettivo di dismettere l&#8217;80% delle reti in rame entro il 2028 fino ad arrivare a uno spegnimento totale dell&#8217;ADSL e il passaggio definitivo alla <strong>fibra ottica<\/strong> entro il 2030. La banda ultralarga permetter\u00e0 di implementare tecnologie che &#8220;<em>ci porteranno nel mondo di domani: telemedicina, guida automatizzata, manutenzione predittiva degli edifici o agricoltura di precisione<\/em>&#8220;. Dove non \u00e8 possibile la copertura in fibra, invece, si lavorer\u00e0 sui collegamenti in <strong>fibra misto radio<\/strong> per una connessione wireless basata sul <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/5g\/\"><strong>5G<\/strong><\/a>.<\/p>\n<p>La <strong>Commissione Ue<\/strong> sottolinea poi che per salutare per sempre l&#8217;<strong>ADSL<\/strong> serve il coordinamento di tutte le parti interessate, compresi gli enti regolatori come l&#8217;<strong>Autorit\u00e0 delle Comunicazioni<\/strong>. In Italia per\u00f2, come spesso accade, siamo ancora molto indietro. Ne 2023 i principali operatori di rete fissa in Europa hanno annunciato i piani per la dismissione delle reti in rame e il processo \u00e8 effettivamente iniziato in 10 Paesi dell&#8217;Unione. Tra questi per\u00f2 non c&#8217;\u00e8 l&#8217;Italia.<\/p>\n<p>Nel documento sono anche presentati dodici scenari per attirare investimenti, promuovere l&#8217;innovazione, aumentare i livelli di sicurezza e arrivare a un reale mercato unico digitale. La <strong>Commissione Ue<\/strong> ha quindi avviato una consultazione pubblica sul tema che si concluder\u00e0 il 30\/6\/24. Le osservazioni finali verranno pubblicate e contribuiranno a decidere le future azioni a livello politico.<\/p>\n<h2>Le differenze tra ADSL, FTTH, FTTC e FWA<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 120px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px; text-align: center;\"><strong>Tipologia di connessione<\/strong><\/td>\n<td style=\"width: 50%; height: 24px; text-align: center;\"><strong>Velocit\u00e0 di connessione<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\"><strong>ADSL &#8211; rame<\/strong><\/td>\n<td style=\"width: 50%; height: 24px;\"><strong>20 Mbps<\/strong> in download e<strong> 1 Mbps<\/strong> in upload<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\"><strong>FTTC &#8211; fibra misto rame<\/strong><\/td>\n<td style=\"width: 50%; height: 24px;\"><strong>200 Mbps<\/strong> in download e <strong>20 Mbps<\/strong> in upload<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\"><strong>FTTH &#8211; fibra ottica<\/strong><\/td>\n<td style=\"width: 50%; height: 24px;\"><strong>1 Gbps<\/strong> in download e <strong>100 Mbps<\/strong> in upload<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\"><strong>FWA &#8211; fibra misto radio<\/strong><\/td>\n<td style=\"width: 50%; height: 24px;\"><strong>1 Gbps <\/strong>in download in<strong> 5G<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Con una connessione in <strong>ADSL<\/strong> l&#8217;utente viene raggiunto dal segnale utilizzando la rete telefonica fissa tradizionale. La velocit\u00e0 dipende quindi dalle caratteristiche del <strong>doppino in rame<\/strong> e pu\u00f2 arrivare al massimo fino a <strong>20 Mbps in download<\/strong>.<\/p>\n<p>Con la <strong>fibra FTTH<\/strong> (Fiber to the Home), invece, la trasmissione avviene pi\u00f9 velocemente ed \u00e8 immune a interferenze ed eventi atmosferici, oltre a non essere influenzata alla distanza tra l&#8217;abitazione e la stazione di trasmissione di base n\u00e9 dal numero di clienti connessi alla rete. Con la fibra si pu\u00f2 arrivare anche fino a <strong>2,5 Gbps<\/strong> in download con l&#8217;integrazione di altre tecnologie come <strong>GPON<\/strong> (Gigabit Passive Optical Network). <a href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-adsl-fibra-tim\/\"><strong>TIM<\/strong><\/a> con una connessione <strong>FTTH XGS-PON <\/strong>garantisce una connessione anche fino a <strong>10 Gbps<\/strong> in download in un numero limitato di Comuni.<\/p>\n<p>Qual \u00e8 la <a href=\"https:\/\/www.sostariffe.it\/internet-casa\/guide\/ftth-e-fttc-differenze-e-come-funzionano\"><strong>differenza tra FTTH e fibra misto rame<\/strong><\/a> o <strong>FTTC<\/strong> (Fiber to the Cabinet)? Nel secondo caso solo la prima parte del collegamento \u00e8 previsto in fibra ottica mentre il cosiddetto &#8220;ultimo miglio&#8221; \u00e8 coperto tramite il doppino in rame. La velocit\u00e0 quindi dipende dalla distanza tra l&#8217;abitazione e la cabina stradale ma pu\u00f2 arrivare fino a <strong>300 Mbps<\/strong> in download. Per <a href=\"https:\/\/www.sostariffe.it\/internet-casa\/faq\/come-capire-se-sto-navigando-con-fibra-o-adsl\"><strong>sapere se siete raggiunti dalla fibra<\/strong><\/a>, potete <a href=\"https:\/\/www.sostariffe.it\/internet-casa\/verifica-copertura\/\"><strong>verificare gratuitamente la copertura<\/strong><\/a> su<strong> SOStariffe.it<\/strong>.<\/p>\n<p>Infine abbiamo la <strong>fibra misto radio<\/strong> o <strong>FWA<\/strong> (Fixed Wireless Access). Con questa tecnologia i dati viaggiano sulla rete mobile in <strong>4G\/4G+<\/strong> ma gi\u00e0 diversi operatori sfruttano anche le <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/faq\/cosa-si-intende-per-fwa-5g\"><strong>frequenze del 5G<\/strong><\/a> per offrire una connessione fino a <strong>1 Gbps in download<\/strong>. L&#8217;operatore vi fornir\u00e0 un apparato in base alla copertura un apparato da interno o da estero per ricevere il segnale.<\/p>\n<h2>Le migliori offerte per la fibra di febbraio 2024<\/h2>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 20%;\"><strong>Caratteristiche della fibra<\/strong><\/td>\n<td style=\"width: 20%;\"><strong>Internet Unlimited di Vodafone<\/strong><\/td>\n<td style=\"width: 20%;\"><strong>Sky Wi-Fi<\/strong><\/td>\n<td style=\"width: 20%;\"><strong>IliadBox<\/strong><\/td>\n<td style=\"width: 20%;\"><strong>Super Fibra Unlimited di WindTre<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 20%;\"><strong>Navigazione<\/strong><\/td>\n<td style=\"width: 20%;\">fino a 2,5 Gbps in FTTH<\/td>\n<td style=\"width: 20%;\">fino a 1 Gbps in FTTH<\/td>\n<td style=\"width: 20%;\">fino a 5 Gbps in FTTH EPON<\/td>\n<td style=\"width: 20%;\">fino a 2,5 Gbps in FTTH<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 20%;\"><strong>Chiamate<\/strong><\/td>\n<td style=\"width: 20%;\">illimitate<\/td>\n<td style=\"width: 20%;\">a consumo<\/td>\n<td style=\"width: 20%;\">illimitate<\/td>\n<td style=\"width: 20%;\">illimitate<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 20%;\"><strong>Costo mensile<\/strong><\/td>\n<td style=\"width: 20%;\">\n<ul>\n<li><strong>24,90<\/strong> <b>\u20ac\/mese<\/b><\/li>\n<li><strong>22,90<\/strong> <b>\u20ac\/mese <\/b>per i gi\u00e0 clienti mobile<\/li>\n<\/ul>\n<\/td>\n<td style=\"width: 20%;\">\n<ul>\n<li><strong>24,90<\/strong> <b>\u20ac\/mese per 12 mesi<\/b><\/li>\n<\/ul>\n<\/td>\n<td style=\"width: 20%;\">\n<ul>\n<li><strong>24,99<\/strong>\u00a0<b>\u20ac\/mese per sempre<\/b><\/li>\n<li><strong>19,99\u00a0<\/strong><b>\u20ac\/mese per sempre <\/b>con attiva un&#8217;offerta dati da 9,99 \u20ac\/mese<\/li>\n<\/ul>\n<\/td>\n<td style=\"width: 20%;\">\n<ul>\n<li><strong>24,99<\/strong> <b>\u20ac\/mese<\/b><\/li>\n<li><strong>22,99<\/strong> <b>\u20ac\/mese <\/b>per i gi\u00e0 clienti mobile<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 20%;\"><strong>Attivazione<\/strong><\/td>\n<td style=\"width: 20%;\"><strong>Gratis fino al 29\/2\/24<\/strong><\/td>\n<td style=\"width: 20%;\"><strong>Gratis per i gi\u00e0 clienti Sky<\/strong><\/td>\n<td style=\"width: 20%;\">39,99 \u20ac per l&#8217;installazione<\/td>\n<td style=\"width: 20%;\">39,99 \u20ac<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Si pu\u00f2 dire che l&#8217;<strong>ADSL<\/strong> sia ormai una tecnologia del tutto obsoleta e che difficilmente \u00e8 in grado di rispondere in modo soddisfacente alle esigenze degli utenti. Ad esempio, con questa tipologia di connessione \u00e8 pi\u00f9 complicato guardare un film o una serie TV in <strong>streaming<\/strong>, anche non in altissima qualit\u00e0, senza che il segnale rallenti o si interrompi. In pi\u00f9 oggi \u00e8 possibile trovare facilmente <a href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-fibra-ottica\/\"><strong>offerte fibra ottica<\/strong><\/a> a un prezzo comparabile se non addirittura inferiore a quello dell&#8217;<strong>ADSL<\/strong>. Tra le migliori proposte di febbraio abbiamo:<\/p>\n<h3><strong>Internet Unlimited di Vodafone<\/strong><\/h3>\n<ul>\n<li>navigazione senza limiti fino a 2,5 Gbps in download in FTTH<\/li>\n<li>chiamate illimitate<\/li>\n<li>modem con Wi-Fi Optimizer<\/li>\n<li>attivazione inclusa (5 euro al mese per 24 rate)<\/li>\n<li><strong>buono Amazon da 100 euro fino al 29\/2\/24<\/strong><\/li>\n<\/ul>\n<p>L&#8217;offerta di <a href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-adsl-fibra-vodafone\/\"><strong>Vodafone<\/strong><\/a> costa <strong>24,90 euro al mese<\/strong>, invece di 27,90 euro al mese. Il contributo iniziale per l&#8217;<strong>attivazione \u00e8 gratis<\/strong>, invece di 39,90 euro, acquistandola online entro il <strong>29\/2\/24<\/strong>.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=rate_widget&amp;id=3029&amp;sos_api_key=\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva Internet Unlimited di Vodafone <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Se siete <strong>gi\u00e0 clienti di Vodafone<\/strong> per la <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/\"><strong>telefonia mobile<\/strong><\/a> il prezzo della fibra senza chiamate incluse \u00e8 invece di <strong>22,90 euro al mese<\/strong>. Se poi avete una SIM e la rete fissa con la promozione<strong> Infinito Insieme<\/strong> avrete senza costi aggiuntivi <strong>Giga illimitati in 5G per tutta la famiglia<\/strong> (massimo 6 SIM). Si pu\u00f2 pagare con\u00a0domiciliazione in bolletta o addebito su borsellino, carta di credito e conto corrente.<\/p>\n<h3><strong>Sky Wi-Fi<\/strong><\/h3>\n<ul>\n<li>navigazione senza limiti fino a 1 Gbps in download in FTTH e Wi-Fi sferico<\/li>\n<li>chiamate a consumo (19 cent di scatto alla risposta verso fissi pi\u00f9 altri 19 cent al minuto verso mobili)<\/li>\n<li>modem Sky Wi-Fi hub<\/li>\n<li>opzione Voce Unlimited con chiamate illimitate gratuite per 18 mesi, poi 5 euro al mese<\/li>\n<\/ul>\n<p>L&#8217;offerta di <a href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-adsl-fibra-sky-wifi\/\"><strong>Sky WiFi<\/strong><\/a> costa <strong>24,90 euro al mese per 12 mesi<\/strong>, poi 29,90 euro al mese. Il contributo per l&#8217;<strong>attivazione \u00e8 gratis<\/strong>, invece di 49 euro,\u00a0per i gi\u00e0 clienti di<strong> Sky <\/strong>acquistandola online tramite<strong>\u00a0Sky Extra<\/strong>.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=rate_widget&amp;id=10035&amp;sos_api_key=\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva Sky Wi-Fi <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Alla rete fissa potete anche abbinare i pacchetti <strong>Sky TV e Sky Cinema<\/strong> per la <strong>pay TV<\/strong> al costo totale di\u00a0<strong>35,80 euro al mese per 18 mesi<\/strong>, poi 69,90 euro al mese. Il contributo per l&#8217;attivazione \u00e8 di 19 euro, invece di 99 euro.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=rate_widget&amp;id=9317&amp;sos_api_key=\" target=\"_blank\" rel=\"noopener\">Attiva Sky WiFi + Sky TV + Sky Cinema <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h3><strong>IliadBox<\/strong><\/h3>\n<ul>\n<li>navigazione senza limiti fino a 5 Gbps in download e 700 Mbps in upload in FTTH EPON (suddivisi tra porte Ethernet e Wi-Fi) o fino a 2,5 Gbps in download e 500 Mbps in upload in FTTH GPON<\/li>\n<li>chiamate illimitate<\/li>\n<li>attivazione inclusa<\/li>\n<li>modem IliadBox in comodato d&#8217;uso gratuito<\/li>\n<\/ul>\n<p>L&#8217;offerta di <a href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-adsl-fibra-iliad\/\"><strong>Iliad<\/strong><\/a> costa <strong>24,99 euro al mese<\/strong><strong> per sempre <\/strong>o<strong> 19,99 euro al mese per sempre <\/strong>per i clienti Iliad mobile\u00a0con un&#8217;<strong>offerta da 9,99 euro al mese e pagamento automatico<\/strong> su conto corrente o carta di credito. Lo sconto \u00e8 ottenibile anche in una fase successiva all&#8217;attivazione dell&#8217;abbonamento in fibra, andando ad attivare una SIM Iliad e richiedendolo tramite l&#8217;Area Personale del sito Iliad.<\/p>\n<p>Il contributo per l&#8217;installazione della linea \u00e8 di 39,99 euro. Potete aggiungere alla fibra fino a <strong>4 WiFi Extender<\/strong> (1,99 euro al mese per ogni dispositivo) e la protezione di <strong>McAfee Multi Access<\/strong> (2,99 euro al mese).<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?id=11143&amp;area=adsl\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva l&#8217;offerta fibra di Iliad <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Se ancora non siete clienti di Iliad per il mobile e volete accedere allo <strong>sconto di 5 euro al mese sulla fibra<\/strong> potete oggi attivare:<\/p>\n<p><strong>Flash 200<\/strong><\/p>\n<ul>\n<li>minuti e SMS illimitati<\/li>\n<li><strong>200 GB<\/strong> <strong>anche in 5G<\/strong> in oltre 3.000 Comuni in tutta Italia<\/li>\n<li>11 GB per navigare in roaming in Ue<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di <strong>9,99 euro al mese per sempre<\/strong>. Il contributo per l&#8217;attivazione \u00e8 di 9,99 euro mentre SIM e spedizione sono gratuite. In alternativa potete richiedere online un&#8217;<strong>eSIM <\/strong>al costo di<strong>\u00a09,99 euro<\/strong>. L&#8217;offerta, salvo proroghe, \u00e8 disponibile solo fino al <strong>29\/2\/24<\/strong>.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=3&amp;id=9733\" target=\"_blank\" rel=\"noopener\">Attiva Flash 200 di Iliad <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h3><strong>Super Fibra Unlimited di WindTre<\/strong><\/h3>\n<ul>\n<li>navigazione illimitata fino a 2,5 Gbps in download in FTTH<\/li>\n<li>chiamate illimitate<\/li>\n<li>modem Wi-Fi 6 incluso<\/li>\n<li><strong>Giga illimitati fino a 3 SIM della famiglia<\/strong><\/li>\n<li>possibilit\u00e0 di attivare <strong>Unlimited Special<\/strong> con <strong>minuti e Giga illimitati<\/strong> al costo di <strong>7,99 euro al mese<\/strong><\/li>\n<\/ul>\n<p>Dopo aver <strong>verificato la copertura<\/strong> con <strong>SOStariffe.it<\/strong> potrete attivare l&#8217;offerta di\u00a0<a href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-adsl-fibra-windtre-infostrada\/\"><strong>WindTre<\/strong><\/a> al costo di\u00a0<strong>24,99 euro al mese<\/strong>. Il prezzo per i gi\u00e0 clienti mobile dell&#8217;operatore \u00e8 invece di<strong>\u00a022,99 euro al mese <\/strong>senza chiamate incluse ma con <strong>12 mesi di Amazon Prime<\/strong>. Il contributo per l&#8217;attivazione \u00e8 di 39,99 euro.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=rate_widget&amp;id=8695&amp;sos_api_key=\" target=\"_blank\" rel=\"noopener\">Attiva Super Fibra di WindTre <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h2>Le migliori offerte FWA di febbraio 2024<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 120px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\"><strong>Caratteristica offerta FWA<\/strong><\/td>\n<td style=\"width: 50%; height: 24px;\"><strong>Fastweb Casa Light FWA<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\">Navigazione<\/td>\n<td style=\"width: 50%; height: 24px;\">fino a 1 Gbps in Ultra FWA<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\">Chiamate<\/td>\n<td style=\"width: 50%; height: 24px;\">non incluse<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\">Costo mensile<\/td>\n<td style=\"width: 50%; height: 24px;\"><strong>24,95<\/strong> <b style=\"font-family: inherit; font-size: inherit;\">\u20ac\/mese<\/b><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\">Attivazione<\/td>\n<td style=\"width: 50%; height: 24px;\"><strong>Gratis<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Se non siete raggiunti dalla fibra, perch\u00e9 ad esempio abitate in un piccolo Comune, non dovete rassegnarvi a una connessione lenta. Oggi infatti diversi operatori permettono di scegliere tra <a href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-internet-wireless\/\"><strong>offerte FWA<\/strong><\/a> davvero convenienti. Tra le migliori del mese abbiamo:<\/p>\n<h3><strong>Fastweb Casa Light FWA<\/strong><\/h3>\n<ul>\n<li>navigazione fino a 1 Gbps in download in Ultra FWA<\/li>\n<li>modem Internet Box NeXXt incluso<\/li>\n<li>installazione antenna<\/li>\n<li>i corsi e workshop della Fastweb Digital Academy<\/li>\n<\/ul>\n<p>L&#8217;offerta di <a href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-adsl-fibra-fastweb\/\"><strong>Fastweb Casa<\/strong><\/a> costa <strong>24,95 euro al mese<\/strong> senza vincoli. L&#8217;operatore vi permette di provarla per trenta giorni. Poi, se non siete soddisfatti del servizio, avete la possibilit\u00e0 di richiedere online il recesso senza costi aggiuntivi o penali e ricevere il rimborso di tutte le spese sostenute.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=rate_widget&amp;id=10145&amp;sos_api_key=\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva Fastweb Casa Light FWA<span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Commissione Ue spinge per l&#8217;addio ADSL rame e la totale sostituzione di questa tecnologia con la fibra ottica o FWA basata sul 5G entro il 2030<\/p>\n","protected":false},"author":72,"featured_media":385168,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[22322],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/385165"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=385165"}],"version-history":[{"count":18,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/385165\/revisions"}],"predecessor-version":[{"id":387448,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/385165\/revisions\/387448"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/385168"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=385165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=385165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=385165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}