{"id":383040,"date":"2024-01-29T10:00:17","date_gmt":"2024-01-29T09:00:17","guid":{"rendered":"https:\/\/www.sostariffe.it\/news\/?p=383040"},"modified":"2024-01-30T09:44:01","modified_gmt":"2024-01-30T08:44:01","slug":"auto-elettriche-e-freddo-intenso-problemi-e-fake-news","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/auto-elettriche-e-freddo-intenso-problemi-e-fake-news-383040\/","title":{"rendered":"Auto elettriche e freddo intenso: problemi e fake news"},"content":{"rendered":"<p>Il freddo intenso mette fuori uso le stazioni pubbliche di ricarica dei veicoli Tesla nell\u2019area di Chicago, in Usa, lasciando in panne gli automobilisti. Scoppia il caso <strong>auto elettriche nel clima gelido<\/strong> e le fake news si moltiplicano. Eppure, esistono <strong>tecnologie e buone prassi<\/strong> per evitare problemi nei mesi invernali. Ecco un\u2019analisi di quanto successo e un focus su come trovare la <strong>miglior assicurazione auto<\/strong> a gennaio 2024 con il <strong>comparatore di SOStariffe.it<\/strong>. <!--more--><\/p>\n<p><strong>Freddo intenso nemico delle auto elettriche<\/strong>? In America scoppia la polemica sull\u2019affidabilit\u00e0 dei veicoli full electric dopo che l\u2019ondata di gelo che si \u00e8 abbattuta sull\u2019hinterland di Chicago ha messo fuori uso diverse stazioni pubbliche di ricarica Supercharger di Tesla, il brand di Elon Musk.<\/p>\n<p>Dai media locali ai social network, il caso ha fatto il giro del mondo, diventando, per alcuni detrattori dell\u2019auto elettrica, un pretesto per diffondere fake news su questo tipo di mobilit\u00e0 sostenibile. Eppure, per quanto sia vero che le prestazioni delle batterie al litio peggiorino con il freddo intenso, \u00e8 altrettanto vero che <strong>esistono tecnologie e comportamenti virtuosi<\/strong> per garantirne buone performance anche in inverno.<\/p>\n<p>Prima di analizzare cosa sia successo a Chicago e i rimedi che i proprietari di veicoli BEV (Battery Electric Vehicle) possono mettere in campo quando la colonnina di mercurio scende, ricordiamo che il <strong>comparatore di SOStariffe.it <\/strong>per <strong>assicurazioni auto<\/strong> (accessibile dal link qui sotto) \u00e8 un valido alleato nella ricerca del miglior <strong>preventivo RC Auto<\/strong> a gennaio 2024.<\/p>\n<p><a class=\"green-cta\" style=\"width: 300px; height: 30px; line-height: 30px; font-size: 15px;\" href=\"https:\/\/www.sostariffe.it\/assicurazioni\/assicurazione-auto\/preventivo1.html\">Trova la migliore polizza auto a gennaio 2024<span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Nel tool (che \u00e8 gratuito) \u00e8 possibile, inserendo i propri dati anagrafici, assicurativi e le caratteristiche del veicolo da assicurare, avere un confronto online dei preventivi. L\u2019utilizzo dei propri dati consente infatti di avere un confronto \u201csu misura\u201d dei costi reali proposti dalle compagnie assicurative. Si tratta di un aspetto importante per determinare sia la copertura della polizza RC pi\u00f9 vantaggiosa sia le varie garanzie accessorie. SOStariffe.it offre anche un\u2019assistenza gratuita al <strong>numero verde 800 99 95 65<\/strong>.<\/p>\n<h2>Freddo intenso e auto elettrica: cosa \u00e8 successo a Chicago a Gennaio 2024<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 288px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; text-align: center; height: 24px;\"><strong>LE DOMANDE<\/strong><\/td>\n<td style=\"width: 50%; text-align: center; height: 24px;\"><strong>LE: RISPOSTE<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 72px;\">\n<td style=\"width: 50%; height: 72px;\"><strong>Cosa \u00e8 successo nell&#8217;interland di Chicago?<\/strong><\/td>\n<td style=\"width: 50%; height: 72px;\">Le temperature rigide hanno <strong>messo fuori uso diverse stazioni pubbliche di ricarica per veicoli Tesla<\/strong>, lasciando in panne gli automobilisti<\/td>\n<\/tr>\n<tr style=\"height: 96px;\">\n<td style=\"width: 50%; height: 96px;\"><strong>Qual \u00e8 stato il problema?<\/strong><\/td>\n<td style=\"width: 50%; height: 96px;\">In assenza di una spiegazione ufficiale di Tesla, si ipotizza che il freddo estremo abbia avuto un impatto su<strong> cavi di ricarica, connettori e altri componenti<\/strong> delle colonnine Supercharger<\/td>\n<\/tr>\n<tr style=\"height: 96px;\">\n<td style=\"width: 50%; height: 96px;\"><strong>\u00c8 vero che il freddo intenso peggiora le prestazione di una batteria al litio?<\/strong><\/td>\n<td style=\"width: 50%; height: 96px;\"><strong>S\u00ec, \u00e8 vero<\/strong>, ma \u00e8 altrettanto vero che <strong>esistono tecnologie e comportamenti virtuosi<\/strong> per garantire <strong>buone prestazioni<\/strong> delle batterie elettriche anche nei mesi invernali<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Sull\u2019hinterland di Chicago, negli Usa, <strong>si \u00e8 abbattuta un\u2019ondata di gelo<\/strong> a gennaio 2024, con la colonnina di mercurio scesa in picchiata fino a raggiungere punte di 20 gradi sottozero in alcune zone del Midwest. Freddo intenso<strong> che ha messo fuori uso diverse colonnine di ricarica pubbliche Supercharger di Tesla<\/strong>. Il risultato? Centinaia di automobilisti sono rimasti in panne e \u201c<em>le stazioni di ricarica pubbliche si sono trasformate <strong>in cimiteri di automobili<\/strong><\/em>\u201d, si legge in un articolo pubblicato sul sito dell\u2019emittente televisiva statunitense Fox32 con sede a Chicago.<\/p>\n<p>Dal momento che Tesla non ha rilasciato alcun commento ufficiale, si ipotizza che il malfunzionamento delle colonnine sia stato provocato dall&#8217;impatto che il freddo estremo ha avuto su<strong> cavi di ricarica, connettori e altri componenti<\/strong> di un Supercharger.<\/p>\n<p>Il \u201ccaso Tesla\u201d ha per\u00f2 scatenato le reazioni degli utenti, diventando anche il pretesto per diffondere fake news su questo tipo di mobilit\u00e0 sostenibile. Ma gli esperti invitano a non cadere nelle \u201cbufale\u201d: \u201c<em>Il fenomeno segnalato a Chicago \u00e8 legato a un malfunzionamento delle stazioni di ricarica, non alle auto\u201d, <\/em>scrive il giornalista informatico e cacciatore di fake news, <strong>Paolo Attivissimo<\/strong>, sul suo blog &#8220;Il Disinformatico&#8221;: \u201c<em>Usare questa storia per criticare le auto elettriche in generale e dire che non reggono il freddo \u00e8 come dire che le auto a carburante sono un fallimento perch\u00e9 si \u00e8 gelata la pompa di una stazione di servizio<\/em>\u201d.<\/p>\n<p>Del resto, tutte le auto perdono efficienza quando fa freddo. \u201c<em>Tuttavia, gli automobilisti se ne preoccupano davvero solo quando si tratta di auto elettriche, poich\u00e9 la minore efficienza si traduce direttamente in una minore autonomia<\/em>\u201d, spiegano gli esperti di <strong>Recurrent<\/strong>, una startup americana che si occupa di ricerca e consulenza sui veicoli elettrici. Eppure ci sono una serie di accorgimenti e comportamenti quotidiani che i proprietari di veicoli full electric possono mettere in campo per garantire alle batterie <strong>buone performance anche nei mesi invernali<\/strong>.<\/p>\n<p>Il primo \u201ccomandamento\u201d, secondo Paolo Attivissimo \u00e8 molto semplice: \u201c<em>N<\/em><i>on lasciare che l\u2019auto si scarichi cos\u00ec tanto<\/i>. <em>Un po\u2019 come la soluzione per non restare a secco con un\u2019auto a carburante \u00e8 andare a fare rifornimento prima che il serbatoio sia vuoto\u201d<\/em>.<\/p>\n<h2>Freddo intenso e auto elettriche: le buone prassi a Gennaio 2024<\/h2>\n<p>Qui di seguito, invece, ecco alcuni consigli messi a punto dagli esperti di \u201cRecurrent\u201d per garantire l&#8217;ottimale funzionamento delle batterie al litio anche durante la stagione fredda:<\/p>\n<ul>\n<li><strong>preriscaldare l\u2019auto quando \u00e8 ancora in carica<\/strong>. Il cosiddetto \u201cpre-condizionamento\u201d \u00e8 disponibile nella maggior parte dei veicoli elettrici utilizzando l\u2019app del telefono o impostando un orario di partenza. Alcuni veicoli, scrivono gli esperti di Recurrent sul loro sito, offrono anche un pacchetto \u201cclima invernale\u201d appositamente progettato per mantenere la temperatura della batteria in una zona ideale in modo che siano sempre pronte all\u2019uso;<\/li>\n<li>una volta che si \u00e8 in viaggio, <strong>abbassare il riscaldamento dell\u2019abitacolo<\/strong> e utilizzare piuttosto i sedili riscaldati e il volante riscaldato. Queste funzionalit\u00e0 consumano meno energia e forniscono calore mirato, garantendo una maggior disponibilit\u00e0 di batteria per viaggiare;<\/li>\n<li>adottare <strong>comportamenti di guida efficienti<\/strong>, evitando brusche accelerazioni o decelerazioni, perch\u00e9 questo pu\u00f2 compromettere la durata della batteria;<\/li>\n<li><strong>evitare di lasciare scaricare troppo la batteria dell\u2019auto <\/strong>e valutare la possibilit\u00e0 di ricaricare la batteria dell\u2019auto quando \u00e8 ancora calda poich\u00e9 una batteria fredda non pu\u00f2 caricarsi tanto velocemente quanto una batteria calda;<\/li>\n<li>valutare l\u2019acquisto di un <strong>modello dotato di pompa di calore<\/strong>: questa nuova tecnologia pu\u00f2 aiutare a preservare la portata quando fa freddo.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Il freddo intenso mette fuori uso le stazioni pubbliche di ricarica dei veicoli Tesla nell\u2019area di Chicago, in Usa, lasciando in panne gli automobilisti. Scoppia il caso auto elettriche nel clima gelido e le fake news si moltiplicano. Eppure, esistono tecnologie e buone prassi per evitare problemi nei mesi invernali. Ecco un\u2019analisi di quanto successo [&hellip;]<\/p>\n","protected":false},"author":108,"featured_media":383043,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4028],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/383040"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=383040"}],"version-history":[{"count":11,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/383040\/revisions"}],"predecessor-version":[{"id":383159,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/383040\/revisions\/383159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/383043"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=383040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=383040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=383040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}