{"id":381782,"date":"2024-01-08T13:00:55","date_gmt":"2024-01-08T12:00:55","guid":{"rendered":"https:\/\/www.sostariffe.it\/news\/?p=381782"},"modified":"2024-01-09T18:00:41","modified_gmt":"2024-01-09T17:00:41","slug":"tutte-le-offerte-very-mobile-di-gennaio-2024","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/tutte-le-offerte-very-mobile-di-gennaio-2024-381782\/","title":{"rendered":"Tutte le offerte Very Mobile di Gennaio 2024"},"content":{"rendered":"<p>Scopri le migliori<strong> offerte Very Mobile<\/strong> di gennaio per avere <strong>minuti e SMS illimitati<\/strong> e fino a <strong>270 GB in 4G<\/strong> a <strong>meno di 10 euro al mese<\/strong> pi\u00f9 <strong>un mese di ricarica in omaggio<\/strong><!--more--><\/p>\n<p><a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/very-mobile\/\"><strong>Very Mobile<\/strong><\/a> \u00e8 un operatore di <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/\"><strong>telefonia mobile<\/strong><\/a> che rientra nella categoria dei <strong>MVNO<\/strong> (Mobile Virtual Network Operator) in quanto si appoggia alla rete di <strong>WindTre<\/strong>. Questo particolare gestore punta forte sulla trasparenza e i prezzi bassi. Le <strong>offerte Very Mobile<\/strong> sono infatti senza vincoli n\u00e9 costi nascosti. Se non siete soddisfatti potete richiedere il recesso quando volete, senza il pagamento di penali o ulteriori spese per la disattivazione della linea. Le tariffe poi si rinnovano sempre lo stesso giorno del mese, che potete verificare in qualsiasi momento dell&#8217;<strong>app Very<\/strong>.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/very-mobile\/\" target=\"_blank\" rel=\"noopener\">Scopri le offerte di Very Mobile <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h2>Offerte Very Mobile: le migliori di gennaio 2024<\/h2>\n<p>Le <strong>offerte Very Mobile<\/strong> si differenziano in tre categorie in base alle modalit\u00e0 di attivazione:<\/p>\n<ul>\n<li>portabilit\u00e0 da Iliad o un operatore virtuale selezionato<\/li>\n<li>portabilit\u00e0 da TIM, WINDTRE, Vodafone e alcuni operatori virtuali selezionati<\/li>\n<li>attivazione di un nuovo numero di cellulare<\/li>\n<\/ul>\n<h3>Offerte con portabilit\u00e0 da Iliad o alcuni operatori virtuali<\/h3>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 25%; text-align: center;\"><strong>OFFERTE<\/strong><\/td>\n<td style=\"width: 25%; text-align: center;\"><strong>MINUTI, SMS E GIGA<\/strong><\/td>\n<td style=\"width: 25%; text-align: center;\"><strong>COSTO MENSILE<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 25%;\"><strong>Very 4,99<\/strong><\/td>\n<td style=\"width: 25%;\"><strong>minuti e SMS illimitati<\/strong> + 1 GB in 4G fino a 30 Mbps<\/td>\n<td style=\"width: 25%;\"><strong>4,99 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 25%;\"><strong>Very 5,99<\/strong><\/td>\n<td style=\"width: 25%;\">minuti e SMS illimitati + <strong>120 GB in 4G<\/strong> fino a 30 Mbps<\/td>\n<td style=\"width: 25%;\"><strong>5,99 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 25%;\"><strong>Very 6,99<\/strong><\/td>\n<td style=\"width: 25%;\">minuti e SMS illimitati +<strong> 150 GB in 4G<\/strong> fino a 30 Mbps<\/td>\n<td style=\"width: 25%;\"><strong>6,99 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 25%;\"><strong>Very 7,99<\/strong><\/td>\n<td style=\"width: 25%;\">minuti e SMS illimitati +<strong> 200 GB in 4G<\/strong> fino a 30 Mbps<\/td>\n<td style=\"width: 25%;\"><strong>7,99 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 25%;\"><strong>Very 9,99<\/strong><\/td>\n<td style=\"width: 25%;\">minuti e SMS illimitati + <strong>270 GB in 4G<\/strong> fino a 30 Mbps<\/td>\n<td style=\"width: 25%;\"><strong>9,99 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Per chi richiede la <strong>portabilit\u00e0 del numero<\/strong>, che viene eseguita gratuitamente da<strong> Very Mobile<\/strong> entro un massimo di tre giorni lavorativi, arrivando da<strong> Iliad<\/strong> o da alcuni operatori virtuali selezionati come <strong>Fastweb Mobile, Coop Voce, PosteMobile<\/strong> e altri sono disponibili:<\/p>\n<p><strong>Very 4,99<\/strong><\/p>\n<ul>\n<li><strong>minuti e SMS illimitati<\/strong><\/li>\n<li>1 GB in 4G fino a 30 Mbps per navigare anche in roaming in Ue<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di<strong> 4,99 euro al mese<\/strong>. Attivazione, SIM e spedizione sono gratuite.<\/p>\n<p><strong>Very 5,99<\/strong><\/p>\n<ul>\n<li>minuti e SMS illimitati<\/li>\n<li><strong>120 GB in 4G<\/strong> fino a 30 Mbps<\/li>\n<li>6,4 GB per navigare in roaming in Ue<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di<strong> 5,99 euro al mese<\/strong>. Attivazione, SIM e spedizione sono gratuite. Acquistandola entro il <strong>15\/1\/24<\/strong> con la <strong>Promo Flashback<\/strong> avete incluso<strong> un mese di ricarica gratis<\/strong>.<\/p>\n<p><strong>Very 6,99<\/strong><\/p>\n<ul>\n<li>minuti e SMS illimitati<\/li>\n<li><strong>150 GB in 4G<\/strong> fino a 30 Mbps (invece di 100 GB)<\/li>\n<li>7,4 GB per navigare in roaming in Ue<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di<strong> 6,99 euro al mese<\/strong>. Attivazione, SIM e spedizione sono gratuite. Acquistandola entro il <strong>15\/1\/24<\/strong> con la <strong>Promo Flashback<\/strong> avete incluso<strong> un mese di ricarica gratis<\/strong>.<\/p>\n<p><strong>Very 7,99<\/strong><\/p>\n<ul>\n<li>minuti e SMS illimitati<\/li>\n<li><strong>200 GB in 4G<\/strong> fino a 30 Mbps (invece di 150 GB)<\/li>\n<li>8,5 GB per navigare in roaming in Ue<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di<strong> 6,99 euro al mese<\/strong>. Attivazione, SIM e spedizione sono gratuite. Acquistandola entro il <strong>15\/1\/24<\/strong> con la <strong>Promo Flashback<\/strong> avete incluso<strong> un mese di ricarica gratis<\/strong>.<\/p>\n<p><strong>Very 9,99<\/strong><\/p>\n<ul>\n<li>minuti e SMS illimitati<\/li>\n<li><strong>270 GB in 4G<\/strong> fino a 30 Mbps (invece di 220 GB)<\/li>\n<li>10,6 GB per navigare in roaming in Ue<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di<strong> 9,99 euro al mese<\/strong>. Attivazione, SIM e spedizione sono gratuite. Acquistandola entro il <strong>15\/1\/24<\/strong> con la <strong>Promo Flashback<\/strong> avete incluso<strong> un mese di ricarica gratis<\/strong>.<\/p>\n<h3>Offerte con portabilit\u00e0 da Vodafone, TIM, Windtre e alcuni MVNO<\/h3>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 25%; text-align: center;\"><strong>OFFERTE<\/strong><\/td>\n<td style=\"width: 25%; text-align: center;\"><strong>MINUTI, SMS E GIGA<\/strong><\/td>\n<td style=\"width: 25%; text-align: center;\"><strong>COSTO MENSILE<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 25%;\"><strong>Very 12,99<\/strong><\/td>\n<td style=\"width: 25%;\">minuti e SMS illimitati + <strong>200 GB in 4G<\/strong> fino a 30 Mbps<\/td>\n<td style=\"width: 25%;\"><strong>12,99 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 25%;\"><strong>Very 13,99<\/strong><\/td>\n<td style=\"width: 25%;\">minuti e SMS illimitati + <strong>270 GB in 4G<\/strong> fino a 30 Mbps<\/td>\n<td style=\"width: 25%;\"><strong>13,99 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Chi invece richiede la <strong>portabilit\u00e0 gratuita del numero<\/strong> da <strong>ho. Mobile, Kena Mobile, Spusu, TIM, Vodafone <\/strong>e<strong> WindTre<\/strong> pu\u00f2 attivare:<\/p>\n<p><strong>Very 12,99<\/strong><\/p>\n<ul>\n<li>minuti e SMS illimitati<\/li>\n<li><strong>200 GB in 4G<\/strong> fino a 30 Mbps (invece di 150 GB)<\/li>\n<li>13,8 GB per navigare in roaming in Ue<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di<strong> 12,99 euro al mese<\/strong>. Attivazione, SIM e spedizione sono gratuite. Acquistandola entro il <strong>15\/1\/24<\/strong> con la <strong>Promo Flashback<\/strong> avete incluso<strong> un mese di ricarica gratis<\/strong>.<\/p>\n<p><strong>Very 13,99<\/strong><\/p>\n<ul>\n<li>minuti e SMS illimitati<\/li>\n<li><strong>270 GB in 4G<\/strong> fino a 30 Mbps (invece di 220 GB)<\/li>\n<li>14,8 GB per navigare in roaming in Ue<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di<strong> 13,99 euro al mese<\/strong>. Attivazione, SIM e spedizione sono gratuite. Acquistandola entro il <strong>15\/1\/24<\/strong> con la <strong>Promo Flashback<\/strong> avete incluso<strong> un mese di ricarica gratis<\/strong>.<\/p>\n<h3>Offerte per chi richiede un nuovo numero<\/h3>\n<table style=\"border-collapse: collapse; width: 100%; height: 312px;\">\n<tbody>\n<tr>\n<td style=\"width: 25%; text-align: center;\"><strong>OFFERTE<\/strong><\/td>\n<td style=\"width: 25%; text-align: center;\"><strong>MINUTI, SMS E GIGA<\/strong><\/td>\n<td style=\"width: 25%; text-align: center;\"><strong>COSTO MENSILE<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td style=\"width: 25%; height: 48px;\"><strong>Very 6,99<\/strong><\/td>\n<td style=\"width: 25%; height: 48px;\">minuti e SMS illimitati +<strong> 150 GB in 4G<\/strong> fino a 30 Mbps<\/td>\n<td style=\"width: 25%; height: 48px;\"><strong>6,99 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td style=\"width: 25%; height: 48px;\"><strong>Very 7,99<\/strong><\/td>\n<td style=\"width: 25%; height: 48px;\">minuti e SMS illimitati +<strong> 200 GB in 4G<\/strong> fino a 30 Mbps<\/td>\n<td style=\"width: 25%; height: 48px;\"><strong>7,99 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td style=\"width: 25%; height: 48px;\"><strong>Very 9,99<\/strong><\/td>\n<td style=\"width: 25%; height: 48px;\">minuti e SMS illimitati + <strong>270 GB in 4G<\/strong> fino a 30 Mbps<\/td>\n<td style=\"width: 25%; height: 48px;\"><strong>9,99 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td style=\"width: 25%; height: 48px;\"><strong>Very 300 Giga<\/strong><\/td>\n<td style=\"width: 25%; height: 48px;\"><strong>300 GB in 4G<\/strong> <strong>Full Speed<\/strong><\/td>\n<td style=\"width: 25%; height: 48px;\"><strong>11,99 \u20ac\/mese<\/strong>, invece di 13,99 \u20ac\/mese entro il 15\/1\/24<\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td style=\"width: 25%; height: 48px;\"><strong>Very 500 Giga<\/strong><\/td>\n<td style=\"width: 25%; height: 48px;\"><strong>500 GB in 4G<\/strong> <strong>Full Speed<\/strong><\/td>\n<td style=\"width: 25%; height: 48px;\"><strong>13,99 \u20ac\/mese<\/strong>, invece di 15,99 \u20ac\/mese entro il 15\/1\/24<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Se invece preferite attivare una <strong>SIM con un nuovo numero<\/strong> potete attivare:<\/p>\n<p><strong>Very 6,99<\/strong><\/p>\n<ul>\n<li>minuti e SMS illimitati<\/li>\n<li><strong>150 GB in 4G<\/strong> fino a 30 Mbps (invece di 100 GB)<\/li>\n<li>7,4 GB per navigare in roaming in Ue<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di<strong> 6,99 euro al mese<\/strong>. Il contributo per l&#8217;attivazione \u00e8 di 1,99 euro mentre SIM e spedizione sono gratuite.<\/p>\n<p><strong>Very 7,99<\/strong><\/p>\n<ul>\n<li>minuti e SMS illimitati<\/li>\n<li><strong>200 GB in 4G<\/strong> fino a 30 Mbps (invece di 150 GB)<\/li>\n<li>8,5 GB per navigare in roaming in Ue<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di<strong> 7,99 euro al mese<\/strong>. Il contributo per l&#8217;attivazione \u00e8 di 1,99 euro mentre SIM e spedizione sono gratuite.<\/p>\n<p><strong>Very 9,99<\/strong><\/p>\n<ul>\n<li>minuti e SMS illimitati<\/li>\n<li><strong>270 GB in 4G<\/strong> fino a 30 Mbps (invece di 220 GB)<\/li>\n<li>10,6 GB per navigare in roaming in Ue<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di<strong> 7,99 euro al mese<\/strong>. Il contributo per l&#8217;attivazione \u00e8 di 1,99 euro mentre SIM e spedizione sono gratuite.<\/p>\n<p><strong>Very 300 Giga<\/strong><\/p>\n<ul>\n<li><strong>300 GB in 4G<\/strong> <strong>Full Speed<\/strong><\/li>\n<li>14,8 GB per navigare in roaming in Ue<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di<strong> 11,99 euro al mese<\/strong>, invece di 13,99 euro al mese, con la promo <strong>Very Giga Special! <\/strong>acquistandola entro il <strong>15\/1\/24<\/strong>. Il contributo per l&#8217;attivazione \u00e8 di 9,99 euro mentre SIM e spedizione sono gratuite.<\/p>\n<p><strong>Very 500 Giga<\/strong><\/p>\n<ul>\n<li><strong>500 GB in 4G<\/strong> <strong>Full Speed<\/strong><\/li>\n<li>17 GB per navigare in roaming in Ue<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di<strong> 13,99 euro al mese<\/strong>, invece di 15,99 euro al mese, con la promo <strong>Very Giga Special! <\/strong>acquistandola entro il <strong>15\/1\/24<\/strong>. Il contributo per l&#8217;attivazione \u00e8 di 9,99 euro mentre SIM e spedizione sono gratuite.<\/p>\n<p>Vi ricordiamo che <strong>Very Mobile<\/strong> vi permette di cambiare offerta, passando a una con pi\u00f9 Giga inclusa, senza costi aggiuntivi in qualsiasi momento. Per farlo potete effettuare la richiesta sull&#8217;<strong>app Very<\/strong> o chiamando il <strong>Servizio Clienti<\/strong> al <strong>1929<\/strong>.<\/p>\n<p>Alle <strong>offerte Very Mobile<\/strong> potete anche aggiungere uno <strong>smartphone ricondizionato con refurbed<\/strong> e pagare in <strong>tre rate senza interessi<\/strong> n\u00e9 vincoli sulla SIM. \u00c8 incluso anche un voucher per l&#8217;acquisto di <strong>caseable.com<\/strong> di una <strong>cover eco-friendly<\/strong>. Per ogni acquisto verr\u00e0 poi piantanto un albero a sostegno dell&#8217;ambiente. Tra i migliori modelli disponibili abbiamo:<\/p>\n<ul>\n<li><strong>iPhone 13<\/strong> a <strong>592 euro<\/strong>, invece di 1.019 euro<\/li>\n<li><strong>iPhone 12 Pro Max<\/strong> a <strong>569,99 euro<\/strong>, invece di 1.149 euro<\/li>\n<li><strong>Samsung Galaxy S21 Ultra 5G<\/strong> a <strong>439 euro<\/strong>, invece di 1.299 euro<\/li>\n<li><strong>Samsung Galaxy S20<\/strong> a <strong>299,99 euro<\/strong>, invece di 999 euro<\/li>\n<\/ul>\n<h3>Le caratteristiche delle offerte Very Mobile<\/h3>\n<p>Le <strong>offerte Very Mobile<\/strong> si differenziano in base al proprio operatore di provenienza. Se avete uno smartphone compatibile potete per\u00f2 richiedere direttamente online un&#8217;<strong>eSIM senza costi aggiuntiv<\/strong>i. Per confrontare le sue tariffe con quelle di altri operatori potete utilizzare gratis il <strong>comparatore di SOStariffe.it<\/strong>.<\/p>\n<p>Basteranno pochi clic per avere la certezza di attivare la soluzione pi\u00f9 economica in base alle proprie reali esigenze ed abitudini di consumo. Potrete poi attivarla comodamente online cliccando sul tasto &#8220;Scopri&#8221;, che vi re-indirizzer\u00e0 verso il sito dell&#8217;operatore da cui completare l&#8217;acquisto.<\/p>\n<p>[WIDGET-MOBILE]<\/p>\n<p>Le <strong>offerte Very Mobile<\/strong> includono tutti i servizi di base pi\u00f9 richiesti come Ti Ho Cercato, Ringme e Hotspot per condividere la connessione con altri dispositivi. L&#8217;operatore poi blocca in automatico l&#8217;attivazione di servizi a sovrapprezzo come oroscopi, suonerie, sfondi, etc. oltre alle chiamate internazionale, che potete comune abilitare dall&#8217;<strong>app Very<\/strong>. Gli SMS bancari, invece, sono autorizzati.<\/p>\n<p>Con le <strong>offerte Very Mobile<\/strong> poi potete navigare fino a<strong> 30 Mbps<\/strong> in download e upload sul 99,7% del territorio italiano. Su tutte le SIM \u00e8 attivo in automatico il servizio <strong>Protezione Minori<\/strong>, che blocca l&#8217;accesso a siti e contenuti potenzialmente pericoli per i bambini.<\/p>\n<p><strong>Very Mobile<\/strong> se avete esaurito il traffico dati incluso nell&#8217;offerta blocca in automatico la connessione per evitare spese inutile. Potete per\u00f2 riprendere a navigare in qualsiasi momento dall&#8217;<strong>app Very<\/strong> cliccando sul tasto &#8220;<strong>Rinnova<\/strong>&#8221; per aprire un nuovo ciclo mensile del piano allo stesso prezzo.<\/p>\n<h2>Come passare alle offerte Very Mobile a gennaio 2024<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 168px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px; text-align: center;\"><strong>Come acquistare online le offerte di Very Mobile<\/strong><\/td>\n<td style=\"width: 50%; height: 24px; text-align: center;\"><strong>I dettagli<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\"><strong>SIM<\/strong><\/td>\n<td style=\"width: 50%; height: 24px;\">\n<ul>\n<li>Consegna entro 5 giorni lavorativi direttamente nella cassetta delle lettere<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\"><strong>eSIM<\/strong><\/td>\n<td style=\"width: 50%; height: 24px;\">\n<ul>\n<li>Il <strong>QR Code<\/strong> per scaricarla viene inviato via email<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr style=\"height: 96px;\">\n<td style=\"width: 50%; height: 96px;\"><strong>Attivazione<\/strong><\/td>\n<td style=\"width: 50%; height: 96px;\">\n<ul>\n<li>Seguire la procedura su <strong>verymobile\/attiva<\/strong><\/li>\n<li>Effettuare l&#8217;identificazione anche tramite <strong>SPID<\/strong> o <strong>video identificazione<\/strong><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Per attivare le <strong>offerte Very Mobile<\/strong> vi basta collegarvi al sito dell&#8217;operatore e premere il tasto &#8220;Scegli&#8221;. Fatto questo vi verr\u00e0 richiesto di inserire alcuni dati personali per la registrazione. La SIM fisica vi verr\u00e0 consegnata direttamente a casa gratuitamente e imbucata nella cassetta delle lettere.<\/p>\n<p>Non c&#8217;\u00e8 quindi bisogno di essere presenti personalmente per il ritiro. Chi ha scelto l&#8217;eSIM, invece, ricever\u00e0 l&#8217;apposito QR Code per scaricarla via email. Per attivare la vostra offerta dovrete collegarvi a <strong>verymobile.it\/attiva<\/strong> e inserire i dati richiesti. Potrete effettuare poi la verifica dell&#8217;identit\u00e0 non solo tramite <strong>video identificazione<\/strong> ma anche autenticandovi tramite<strong> SPID<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scopri le migliori offerte Very Mobile di gennaio per avere minuti e SMS illimitati e fino a 270 GB in 4G a meno di 10 euro al mese pi\u00f9 un mese di ricarica in omaggio<\/p>\n","protected":false},"author":72,"featured_media":381783,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[9,21807],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/381782"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=381782"}],"version-history":[{"count":18,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/381782\/revisions"}],"predecessor-version":[{"id":381951,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/381782\/revisions\/381951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/381783"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=381782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=381782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=381782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}