{"id":381065,"date":"2023-12-18T18:53:49","date_gmt":"2023-12-18T17:53:49","guid":{"rendered":"https:\/\/www.sostariffe.it\/news\/?p=381065"},"modified":"2023-12-19T22:49:46","modified_gmt":"2023-12-19T21:49:46","slug":"optima-italia-nuova-promo-natale-2023","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/optima-italia-nuova-promo-natale-2023-381065\/","title":{"rendered":"Optima Italia: nuova promo Natale 2023"},"content":{"rendered":"<p>A dicembre con <strong>Super Mobile Smart<\/strong> di <strong>Optima Italia<\/strong> potete avere minuti illimitati e<strong> 100 GB in 4G<\/strong> e <strong>12 mesi di Amazon Prime<\/strong> inclusi a <strong>meno di 5 euro al mese<\/strong><!--more--><\/p>\n<p><a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/optima\/\"><strong>Optima Italia<\/strong><\/a> \u00e8 tra i migliori operatori di <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/\"><strong>telefonia mobile<\/strong><\/a> in termini di convenienza e con l&#8217;arrivo del Natale ha deciso di proporre una versione festiva della sua tariffa di punta <strong>Super Mobile Smart<\/strong> che prevede <strong>un anno di Amazon Prime incluso<\/strong> (dal valore di ben 49,90 euro). La promozione mette a disposizione ben 100 GB di traffico dati con un prezzo inferiore a 5 euro al mese. L&#8217;offerta \u00e8 attivabile fino al <strong>24 di dicembre<\/strong> ed \u00e8 disponibile in esclusiva online.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/optima\/\" target=\"_blank\" rel=\"noopener\">Scopri l&#8217;offerta di Optima<span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h2>Optima Italia: la nuova offerta di Natale con Amazon Prime incluso di dicembre 2023<\/h2>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><\/td>\n<td style=\"width: 50%;\"><strong>Super Mobile Smart<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>Chiamate e SMS<\/strong><\/td>\n<td style=\"width: 50%;\">minuti illimitati e 200 SMS<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>Gigabyte<\/strong><\/td>\n<td style=\"width: 50%;\"><strong>100 GB in 4G<\/strong> fino a 60 Mbps<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>Costo mensile<\/strong><\/td>\n<td style=\"width: 50%;\"><strong>4,95 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>Attivazione<\/strong><\/td>\n<td style=\"width: 50%;\">non prevista ma la SIM costa 9,90 euro<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>Optima Italia<\/strong> ha quindi aggiornato la sua offerta <strong>Super Mobile Smart<\/strong> senza vincoli n\u00e9 costi nascosti. Chi l&#8217;attiva entro il <strong>24\/12\/23<\/strong> tramite e-commerce o digital sales e richiede la portabilit\u00e0 del numero, che verr\u00e0 eseguita gratuitamente da qualsiasi operatore entro un massimo di tre giorni lavorativi, avr\u00e0 <strong>incluso un anno di Amazon Prime<\/strong> per avere non solo consegna rapide su centinaia di prodotti selezionati sul sito di e-commerce ma anche le serie TV, film e produzioni originali di <strong>Prime Video<\/strong>.<\/p>\n<p>Con <strong>Optima Italia<\/strong> potete navigare fino a<strong> 60 Mbps<\/strong> in download sulla rete di <strong>Vodafone<\/strong> su tutto il territorio italiano e se non siete soddisfatti dell&#8217;offerta potete sempre disattivarla in qualsiasi momento senza il pagamento di penali o costi di recesso.<\/p>\n<p><strong>Super Mobile Smart<\/strong><\/p>\n<ul>\n<li>minuti illimitati e 200 SMS<\/li>\n<li><strong>100 GB in 4G<\/strong><\/li>\n<li><strong>in regalo 12 mesi di Amazon Prime <\/strong>fino al<strong> 24\/12\/23<\/strong><\/li>\n<li>1 GB per navigare in roaming in Ue<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di <strong>4,95 euro al mese<\/strong>. Non c&#8217;\u00e8 contributo per l&#8217;attivazione mentre la SIM costa 9,90 euro, invece di 19,90 euro.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=1&amp;id=11240\" target=\"_blank\" rel=\"noopener\">Attiva Super Mobile Smart di Optima <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h2>Altre offerte interessanti con 100 GB inclusi a dicembre 2023<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 457px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 2.12041%; text-align: center; height: 72px;\"><strong>\u00a0<\/strong><\/td>\n<td style=\"width: 31.213%; height: 72px; text-align: center;\"><b>Altre offerte mobile interessanti<\/b><\/td>\n<td style=\"width: 33.3333%; height: 72px; text-align: center;\"><strong>Minuti, SMS e Giga<\/strong><\/td>\n<td style=\"width: 16.6667%; height: 72px; text-align: center;\"><strong>Prezzo mensile<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 2.12041%; height: 24px;\"><strong>1<\/strong><\/td>\n<td style=\"width: 31.213%; height: 24px;\"><strong>Spusu 100 di Spusu<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px;\">2000 minuti e 500 SMS + <strong>100 GB<\/strong> in 4G+<\/td>\n<td style=\"width: 16.6667%; height: 24px;\"><strong>5,98 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 2.12041%;\"><strong>2<\/strong><\/td>\n<td style=\"width: 31.213%;\"><strong>Kena 5,99 100GB Promo Top<\/strong><\/td>\n<td style=\"width: 33.3333%;\">minuti illimitati e 200 SMS + <strong>100 GB<\/strong> in 4G fino a 60 Mbps + <strong>50 GB<\/strong> con autoricarica +<strong> 50 GB al mese per 12 mesi<\/strong><\/td>\n<td style=\"width: 16.6667%;\"><strong>5,99 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 2.12041%; height: 24px;\"><strong>3<\/strong><\/td>\n<td style=\"width: 31.213%; height: 24px;\"><strong>ho. 5,99 di ho. Mobile<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px;\">minuti e SMS illimitati + <strong>100 GB<\/strong> in 4G fino a 30 Mbps<\/td>\n<td style=\"width: 16.6667%; height: 24px;\"><strong>5,99 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 2.12041%;\"><strong>4<\/strong><\/td>\n<td style=\"width: 31.213%;\"><strong>Giga 100 di Iliad<\/strong><\/td>\n<td style=\"width: 33.3333%;\">minuti e SMS illimitati + <strong>100 GB<\/strong> in 4G\/4G+<\/td>\n<td style=\"width: 16.6667%;\"><strong>7,99 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 2.12041%;\"><strong>5<\/strong><\/td>\n<td style=\"width: 31.213%;\"><strong>TIM Young<\/strong><\/td>\n<td style=\"width: 33.3333%;\">minuti illimitati e 200 SMS + <strong>100 GB<\/strong> anche in 5G con TIM Ricarica Automatica<\/td>\n<td style=\"width: 16.6667%;\"><strong>9,99 \u20ac\/mese<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>La proposta di <strong>Optima Italia<\/strong> \u00e8 certamente interessante ma si possono trovare proposte altrettanto convenienti confrontandole tra loro gratuitamente con il <strong>comparatore di SOStariffe.it<\/strong>. Grazie al nostro strumento avrete la certezza di attivare la soluzione pi\u00f9 economica in base alle vostre reali esigenze ed abitudini di consumo. Potrete poi attivarla comodamente online cliccando sul tasto &#8220;Scopri&#8221;, che vi re-indirizzer\u00e0 verso il sito dell&#8217;operatore da cui completare l&#8217;acquisto.<\/p>\n<p>[WIDGET-MOBILE]<\/p>\n<p>Tra le offerte pi\u00f9 convenienti di dicembre abbiamo:<\/p>\n<p><strong>1. Spusu 100<\/strong><\/p>\n<ul>\n<li>2000 minuti e 500 SMS<\/li>\n<li><strong>100 GB<\/strong>\u00a0<strong>in 4G+<\/strong> fino a 300 Mbps in download e 50 Mbps in upload<\/li>\n<li><strong>200 GB di riserva<\/strong> da utilizzare quando si finiscono i Giga inclusi<\/li>\n<li><strong>Riserva dati<\/strong> per trasformare i minuti, SMS e Giga non consumati durante il mese in traffico dati aggiuntivo da utilizzare a partire primo rinnovo e che non ha scadenza<\/li>\n<li>5,45 GB per navigare in roaming in Ue<\/li>\n<\/ul>\n<p>L&#8217;offerta di <a title=\"Tariffe Spusu mobile\" href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/spusu\/\"><strong>Spusu<\/strong><\/a> costa <strong>5,98 euro<\/strong> <strong>al mese<\/strong> <strong>per sempre<\/strong>. Il contributo per l&#8217;attivazione \u00e8 di 9,90 euro mentre SIM e spedizione sono gratuite. Senza costi aggiuntivi potete anche richiedere online un&#8217;<strong>eSIM<\/strong> o cambiare tariffa in qualsiasi momento.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=4&amp;id=9822\" target=\"_blank\" rel=\"noopener noreferrer\">Confronta le offerte di Spusu <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p><strong>2. Kena 5,99 100GB Promo Top<\/strong><\/p>\n<ul>\n<li>minuti illimitati e 200 SMS<\/li>\n<li><strong>100 GB<\/strong>\u00a0<strong>in 4G<\/strong><\/li>\n<li><strong>50 GB in pi\u00f9 al mese<\/strong> con autoricarica attivandola entro il 24\/1\/24<\/li>\n<li>5 GB per navigare in roaming in Ue<\/li>\n<\/ul>\n<p>L&#8217;offerta di <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/kena-mobile\/\"><strong>Kena Mobile<\/strong><\/a> costa <strong>5,99 euro al mese<\/strong>. Attivazione, SIM e spedizione sono gratis. La promozione \u00e8 riservata a chi richiede la <strong>portabilit\u00e0 del numero<\/strong> da <strong>Iliad<\/strong> o alcuni operatori virtuali selezionati come <strong>PosteMobile, CoopVoce, Fastweb Mobile<\/strong> e altri.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=2&amp;id=10007\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva Kena 5,99 100GB Promo Top <\/a><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=2&amp;id=11163\" target=\"_blank\" rel=\"noopener noreferrer\"> <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p><strong>3. ho. 5,99<\/strong><\/p>\n<ul>\n<li>minuti e SMS illimitati<\/li>\n<li><strong>100 GB\u00a0in 4G<\/strong> fino a 30 Mbps<\/li>\n<li>5,5 GB per navigare in roaming in Ue<\/li>\n<\/ul>\n<p>L&#8217;offerta di <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/ho-mobile\/\"><strong>ho. Mobile<\/strong><\/a> costa<strong>\u00a05,99 euro al mese <\/strong>pi\u00f9 una ricarica di 6 euro da cui verr\u00e0 scalato il costo del primo rinnovo. Attivazione, SIM e spedizione sono gratis. La promozione \u00e8 riservata a chi richiede la <strong>portabilit\u00e0 del numero<\/strong> da <strong>Iliad<\/strong> o alcuni operatori virtuali selezionati come <strong>PosteMobile, CoopVoce, Fastweb Mobile<\/strong> e altri.<\/p>\n<p>Grazie all&#8217;iniziativa <strong>Soddisfatti ho. Rimborsati<\/strong> provarla per un mese e decidere poi se continuare con ho. o richiedere online il recesso con due clic senza costi aggiuntivi o penali insieme al rimborso di tutte le spese ottenute. Attivando l&#8217;opzione <strong>ho. Il Turbo<\/strong> potete navigare fino a 60 Mbps in download a <strong>1,49 euro al mese<\/strong>. L&#8217;opzione \u00e8 inclusa in<strong> ho+<\/strong> insieme ad altri vantaggi a <strong>1,99 euro al mese<\/strong>.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=1&amp;id=11404\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva ho, 5,99 <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p><b>4. Giga 100 di Iliad<\/b><\/p>\n<ul>\n<li>minuti e SMS illimitati<\/li>\n<li><strong>100 GB<\/strong> per navigare in 4G\/4G+<\/li>\n<li>8 GB per navigare in roaming in Ue<\/li>\n<\/ul>\n<p>L&#8217;offerta di <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/iliad\/\"><strong>Iliad<\/strong><\/a> costa <strong>7,99 euro al mese<\/strong><strong>\u00a0per sempre<\/strong>. Il contributo per l&#8217;attivazione \u00e8 di 9,99 euro mentre SIM e spedizione sono gratuite. Potete anche richiedere online un&#8217;<strong>eSIM<\/strong> a <strong>9,99 euro<\/strong>.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=2&amp;id=11232\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva qui Giga 100 di Iliad <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>All&#8217;offerta di <strong>Iliad<\/strong> potete aggiungere anche <strong>iPhone 15 a rate senza anticipo<\/strong> a partire da <strong>40,84 euro al mese per 20 rate<\/strong> e pagare con un <strong>finanziamento Younited<\/strong> (salvo approvazione) e pagamento su carta di credito o debito. Potete ottenere una rateizzazione pi\u00f9 conveniente restituendo il telefono alla fine del finanziamento o dare in permuta un vecchio iPhone, Apple Watch o MacBook per ricevere uno <strong>sconto fino a 825 euro<\/strong> per avere <strong>iPhone 15 Pro<\/strong>.<\/p>\n<p><strong>5. TIM Young 5G<\/strong><\/p>\n<ul>\n<li>minuti illimitati e 200 SMS<\/li>\n<li><strong>100 GB in 5G<\/strong> con TIM Ricarica Automatica (altrimenti 50 GB con addebito su credito residuo)<\/li>\n<li>20 GB per il roaming nei Paesi Ue<\/li>\n<\/ul>\n<p>L&#8217;offerta di <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/tim\/\"><strong>TIM<\/strong><\/a> costa <strong>9,99 euro al mese<\/strong> ma il <strong>primo mese \u00e8 gratis per i nuovi clienti<\/strong> che l&#8217;acquistano online, cos\u00ec come l&#8217;attivazione. La SIM costa 10 euro con 5 euro di traffico incluso. In alternativa potete richiedere un&#8217;<strong>eSIM<\/strong> in negozio allo stesso prezzo e attivarla effettuando la video identificazione tramite <strong>SPID<\/strong>. Pu\u00f2 attivarla solo chi ha meno di 25 anni. Potete poi personalizzarla acquistando una o pi\u00f9 delle seguenti opzioni:<\/p>\n<ul>\n<li><strong>50 GB in pi\u00f9 al mese<\/strong> a 99 cent in pi\u00f9 al mese<\/li>\n<li><strong>100 GB su Google One per 3 mesi<\/strong> a 1,99 euro in pi\u00f9 al mese<\/li>\n<li><strong>TIM Games<\/strong> per avere giochi per console su smartphone e TV a 5 euro in pi\u00f9 al mese<\/li>\n<li><strong>TIM One Number<\/strong> per avere lo stesso numero di telefono su smartphone e smartwatch a 99 cent in pi\u00f9 al mese<\/li>\n<\/ul>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=4&amp;id=9827&amp;sos_api_key=NrdLvsXdv1Y4PhIgZ9xJF5p0QIW4rfkgbsuFu9xuPIuGzoJS\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva TIM Young 5G <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>All&#8217;offerta di TIM potete aggiungere anche<strong> iPhone 15 a rate senza anticipo<\/strong> a partire da <strong>33 euro al mese per 30 rate<\/strong> e pagamento con <strong>finanziamento TIMFin a tasso zero<\/strong>, salvo approvazione, con addebito su conto corrente o carta di credito. I clienti di TIM per la rete fissa possono addebitare le rate in bolletta. La consegna \u00e8 gratuita ma \u00e8 previsto anche il ritiro in negozio per alcuni modelli. Potete anche dare in permuta un vecchio cellulare con <strong>TIM Rivaluta Smartphone<\/strong>\u00a0per acquistare <strong>iPhone 15 anche a 7 euro al mese per 3o rate<\/strong>. Fino al 7\/1\/24 avrete poi <strong>2 mesi gratis di TIMFIN Assicura Smartphone Full<\/strong> della durata di 30 mesi. Poi il costo \u00e8 di 11,90 euro al mese per 28 rate.<\/p>\n<p>Attivando <strong>TIM Young <\/strong>potete poi usufruire di uno<strong> sconto di 6 euro al mese <\/strong>sull<a href=\"https:\/\/www.sostariffe.it\/internet-casa\/\">&#8216;<\/a><a href=\"https:\/\/www.sostariffe.it\/internet-casa\/\"><strong>offerta Internet Casa <\/strong><\/a>di TIM:<\/p>\n<p><strong>TIM WiFi Power Smart<\/strong><\/p>\n<ul>\n<li>connessione senza limiti fino a 2,5 Gbps in download in FTTH<\/li>\n<li>chiamate illimitate per 24 mesi (solo con acquisto online)<\/li>\n<li>modem TIM Hub+ Executive<\/li>\n<li>TIM Navigazione Sicura<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di <strong>24,90 euro al mese<\/strong> con domiciliazione e conto online, invece di 30,90 euro al mese, con attiva una SIM con offerta dati a partire da 9,99 euro al mese. L&#8217;<strong>attivazione \u00e8 gratis<\/strong> entro il <strong>21\/12\/23<\/strong>, invece di 39,90 euro.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=rate_widget&amp;id=11255&amp;sos_api_key=\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva TIM WiFi Power Smart <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>In clienti di TIM per la rete fissa e mobile possono avere <strong>Giga illimitati in 5G fino a 6 SIM<\/strong>, anche se non intestate al titolare della connessione di casa, con <strong>TIM Unica Power<\/strong>. Il prezzo \u00e8 di\u00a0<strong>1,90 euro al mese<\/strong>, che vi verranno addebitati direttamente in bolletta, ma se si abbinano alla promozione almeno 3 SIM entro il 27\/1\/24 il <strong>prezzo \u00e8 azzerato<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A dicembre con Super Mobile Smart di Optima Italia potete avere minuti illimitati e 100 GB in 4G e 12 mesi di Amazon Prime inclusi a meno di 5 euro al mese<\/p>\n","protected":false},"author":72,"featured_media":381078,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[9],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/381065"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=381065"}],"version-history":[{"count":13,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/381065\/revisions"}],"predecessor-version":[{"id":381189,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/381065\/revisions\/381189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/381078"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=381065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=381065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=381065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}