{"id":375587,"date":"2023-09-20T10:00:08","date_gmt":"2023-09-20T08:00:08","guid":{"rendered":"http:\/\/www.sostariffe.it\/news\/?p=375587"},"modified":"2023-09-21T08:49:02","modified_gmt":"2023-09-21T06:49:02","slug":"disney-a-199-euro-al-mese-per-3-mesi-fino-al-20-settembre-2023","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/disney-a-199-euro-al-mese-per-3-mesi-fino-al-20-settembre-2023-375587\/","title":{"rendered":"Disney + a 1,99 euro al mese per 3 mesi fino al 20 settembre 2023"},"content":{"rendered":"<p>Scopri come avere <strong>Disney+<\/strong> a <strong>1,99 euro al mese per 3 mesi<\/strong>. Hai tempo fino ad oggi <strong>20 settembre<\/strong> per attivare l&#8217;offerta. Ecco tutti i dettagli su come cambiano gli abbonamenti all&#8217;app<!--more--><\/p>\n<p>Fino ad <strong>oggi mercoled\u00ec 20\/9\/23<\/strong> avete tempo per attivare un abbonamento a <strong>Disney+ a 1,99 euro al mese per 3 mesi<\/strong>, ovvero con uno sconto del 75% del prezzo attuale. L&#8217;offerta \u00e8 valida per i nuovi clienti e per chi riattiva un precedente abbonamento.<\/p>\n<p>Sulla piattaforma di <strong>Disney<\/strong> potete vedere gli ultimi successi live action e di animazione come <strong>Raya e l&#8217;Ultimo Drago<\/strong>, le storie di <strong>Pixar<\/strong> come <strong>Luca<\/strong>, tutti i film del <strong>Marvel<\/strong> <strong>Cinematic Universe<\/strong> e le serie originali (WandaVision, The Falcon and The Winter Soldier e Loki 2 a partire dal 6\/10\/23), l&#8217;intero universo di <strong>Star Wars<\/strong> con le serie live action (Mandalorian, Kenobi, Ashoka), i documentari di <strong>National Geographic<\/strong> e le serie TV di <strong>Star<\/strong>.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=rate_widget&amp;id=8975&amp;sos_api_key=\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva un abbonamento a Disney+ <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h2>Disney+ a 1,99 euro al mese per 3 mesi: come attivarla a settembre 2023<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 264px;\">\n<tbody>\n<tr style=\"height: 96px;\">\n<td style=\"width: 33.3333%; text-align: center; height: 96px;\"><strong>Caratteristiche<\/strong><\/td>\n<td style=\"width: 33.3333%; text-align: center; height: 96px;\"><strong>Promo attuale<\/strong><\/td>\n<td style=\"width: 16.6667%; text-align: center; height: 96px;\"><strong>Disney+ (dall&#8217;1\/11\/23 diventa Disney+ Standard senza pubblicit\u00e0)<\/strong><\/td>\n<td style=\"width: 8.33335%; text-align: center; height: 96px;\"><strong>Disney+ Standard con pubblicit\u00e0<\/strong><\/td>\n<td style=\"width: 8.33335%; text-align: center; height: 96px;\"><strong>Disney+ Premium<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td style=\"width: 33.3333%; height: 48px;\"><strong>Costo abbonamento<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 48px;\"><strong>1,99 <\/strong><b>\u20ac\/mese <\/b><strong>per 3 mesi fino al 20\/9\/23<\/strong>, poi 11,99 \u20ac\/mese<\/td>\n<td style=\"width: 16.6667%; height: 48px;\"><strong>8,99<\/strong> <b>\u20ac\/mese <\/b>o <strong>89,90<\/strong> <b>\u20ac\/anno<\/b><\/td>\n<td style=\"width: 8.33335%; height: 48px;\"><strong>5,99<\/strong> <b>\u20ac\/mese<\/b><\/td>\n<td style=\"width: 8.33335%; height: 48px;\"><strong>11,99<\/strong> <b>\u20ac\/mese <\/b>o <strong>119,90<\/strong> <b>\u20ac\/anno<\/b><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 33.3333%; height: 24px;\"><strong>Pubblicit\u00e0<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px;\">no<\/td>\n<td style=\"width: 16.6667%; height: 24px;\">no<\/td>\n<td style=\"width: 8.33335%; height: 24px;\">s\u00ec<\/td>\n<td style=\"width: 8.33335%; height: 24px;\">no<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 33.3333%; height: 24px;\"><strong>Dispositivi per la visione in contemporanea<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px;\">2<\/td>\n<td style=\"width: 16.6667%; height: 24px;\">2<\/td>\n<td style=\"width: 8.33335%; height: 24px;\">2<\/td>\n<td style=\"width: 8.33335%; height: 24px;\">4<\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td style=\"width: 33.3333%; height: 48px;\"><strong>Qualit\u00e0 video<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 48px;\">1080p Full HD<\/td>\n<td style=\"width: 16.6667%; height: 48px;\">1080p Full HD<\/td>\n<td style=\"width: 8.33335%; height: 48px;\">1080p Full HD<\/td>\n<td style=\"width: 8.33335%; height: 48px;\">4K HDR<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 33.3333%; height: 24px;\"><strong>Qualit\u00e0 audio<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px;\">5.1 e Stereo<\/td>\n<td style=\"width: 16.6667%; height: 24px;\">5.1 e Stereo<\/td>\n<td style=\"width: 8.33335%; height: 24px;\">5.1 e Stereo<\/td>\n<td style=\"width: 8.33335%; height: 24px;\">Dolby Atmos<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>L&#8217;offerta per avere <strong>Disney+ a 1,99 euro al mese per 3 mesi<\/strong>, salvo recesso prima della scadenza del periodo promozionale senza penali o costi aggiuntivi, si rinnova poi a<strong> 11,99 euro al mese<\/strong>. A partire dall&#8217;1\/11\/23 infatti <strong>Disney<\/strong> proporr\u00e0 nuove forme di abbonamento:<\/p>\n<ul>\n<li><strong>Disney+ Standard<\/strong> <strong>con pubblicit\u00e0<\/strong> a <strong>5,99 euro al mese<\/strong> con possibilit\u00e0 di vedere contenuti in qualit\u00e0 Full HD su 2 dispositivi in contemporanea. Sono previsti 4 minuti di annunci pubblicitari per ogni ora di streaming<\/li>\n<li><strong>Disney+ Standard<\/strong> <strong>senza pubblicit\u00e0<\/strong> a <strong>8,99 euro al mese<\/strong> o <strong>89,90 euro l&#8217;anno<\/strong> (circa il 15% di riduzione sul prezzo) con possibilit\u00e0 di vedere contenuti in qualit\u00e0 Full HD su 2 dispositivi in contemporanea. \u00c8 previsto il download dei contenuti per la visione offline<\/li>\n<li><strong>Disney+ Premium<\/strong> a <strong>11,99 euro al mese<\/strong> o <strong>119,90 euro l&#8217;anno<\/strong> (circa il 15% di riduzione sul prezzo) con possibilit\u00e0 di vedere contenuti in qualit\u00e0 fino a 4K HDR con audio Dolby Atmos su 4 dispositivi in contemporanea. \u00c8 previsto il download dei contenuti per la visione offline<\/li>\n<\/ul>\n<p>Potete pagare con carta di credito (Visa, Mastercard o American Express) o PayPal. Per ogni abbonamento si possono creare fino a 7 diversi profili. <strong>Disney +<\/strong> \u00e8 compatibile con diversi dispositivi tra cui Amazon Fire TV, Apple TV, Chromecast e Smart TV di LG, Samsung e Android TV oltre a Chrome OS, Mac e PC Windows, iPhone e iPad, telefoni e tablet Android, tablet Amazon Fire e console (PS4, PS5, Xbox One, Xbox Serie S e Xbox Serie X).<\/p>\n<h2>Altre offerte con Disney+ incluso a settembre 2023<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 328px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 33.3333%; text-align: center; height: 24px;\"><strong>Le offerte TIMVISION<\/strong><\/td>\n<td style=\"width: 33.3333%; text-align: center; height: 24px;\"><strong>Cosa vedere<\/strong><\/td>\n<td style=\"width: 33.3333%; text-align: center; height: 24px;\"><strong>Costo mensile<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 104px;\">\n<td style=\"width: 33.3333%; height: 104px;\"><strong>TIMVISION con Disney+<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 104px;\">\n<ul>\n<li>TIMVISION<\/li>\n<li>Disney+<\/li>\n<li>6 mesi di Amazon Prime (solo clienti fisso)<\/li>\n<\/ul>\n<\/td>\n<td style=\"width: 33.3333%; height: 104px;\"><strong>primi 3 mesi gratis<\/strong> entro il 23\/9\/23, poi <strong>9,99 <b>\u20ac\/mese<\/b><\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 33.3333%; height: 24px;\"><strong>TIMVISION Calcio e Sport con Disney+<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px;\">\n<ul>\n<li>TIMVISION<\/li>\n<li>Disney+<\/li>\n<li>DAZN Standard<\/li>\n<li>Infinity+<\/li>\n<li>6 mesi di Amazon Prime (solo clienti fisso)<\/li>\n<\/ul>\n<\/td>\n<td style=\"width: 33.3333%; height: 24px;\"><strong>24,99 <b>\u20ac\/mese<\/b><\/strong> fino al 31\/12\/23, poi 29,99 \u20ac\/mese<\/td>\n<\/tr>\n<tr style=\"height: 176px;\">\n<td style=\"width: 33.3333%; height: 176px;\"><strong>TIMVISION Gold<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 176px;\">\n<ul>\n<li>TIMVISION<\/li>\n<li>Disney+<\/li>\n<li>DAZN Standard<\/li>\n<li>Infinity+<\/li>\n<li>Netflix Standard<\/li>\n<li>6 mesi di Amazon Prime (solo clienti fisso)<\/li>\n<\/ul>\n<\/td>\n<td style=\"width: 33.3333%; height: 176px;\"><strong>40,99 <b>\u20ac\/mese<\/b><\/strong> fino al 31\/12\/23, poi 45,99 \u20ac\/mese<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>Disney+<\/strong> si trova incluso anche in alcune delle offerte di <strong>TIM<\/strong> per l&#8217;intrattenimento televisivo. Potete scegliere se abbinarle a una delle tariffe di <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/\"><strong>telefonia mobile<\/strong><\/a> dell&#8217;operatore o per la rete fissa. In alternativa si pu\u00f2 acquistare una SIM che verr\u00e0 utilizzata solo per l&#8217;addebito del costo mensile della promozione.<\/p>\n<p><strong>TIMVISION con Disney+<\/strong><\/p>\n<ul>\n<li>TIMVISION con film, serie TV, documentari e produzioni originali oltre al meglio della programmazione di Mediaset dell&#8217;ultima settimana e Discovery<\/li>\n<li>Disney+<\/li>\n<li>6 mesi di Amazon Prime (solo per i nuovi clienti TIMVISION con linea fissa)<\/li>\n<\/ul>\n<p><strong>I primi 3 mesi sono gratis<\/strong>, poi si rinnova a <strong>9,99 euro al mese<\/strong> invece di 15,98 euro al mese acquistandola entro il 23\/9\/23.<\/p>\n<p><strong>TIMVISION Calcio e Sport con Disney+<\/strong><\/p>\n<ul>\n<li>DAZN Standard con tutte le partite di Serie A (10 su 10 per giornata), Serie BTK, Europa League, i migliori incontri di conference League e altri sport su Eurosport 1 HD ed Eurosport 2 HD<\/li>\n<li>TIMVISION<\/li>\n<li>Infinity+ con 104 partite di Champions League<\/li>\n<li>Disney+<\/li>\n<li>6 mesi di Amazon Prime (solo per i nuovi clienti TIMVISION con linea fissa)<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di <strong>24,99 euro al mese<\/strong> fino al 31\/12\/23 per i clienti fisso o fino al 27\/1\/24 per quelli mobile, poi si rinnova a 29,99 euro al mese.<\/p>\n<p>Il <strong>piano Standard di DAZN<\/strong> permette di guardare lo sport su 2 dispositivi in contemporanea connessi alla stessa rete e di collegare all&#8217;abbonamento fino a 6 terminali. Si pu\u00f2 passare al piano <strong>DAZN Plus<\/strong> con visione in contemporanea su 2 dispositivi anche connessi a reti diverse a <strong>5 euro al mese per 5 mesi<\/strong>, poi 15 euro al mese. Con questo abbonamento si possono associare fino a 7 terminali.<\/p>\n<p><strong>TIMVISION Gold<\/strong><\/p>\n<ul>\n<li>DAZN Standard<\/li>\n<li>TIMVISION<\/li>\n<li>Infinity+<\/li>\n<li>Disney+<\/li>\n<li>Netflix Standard (visione in HD su 2 dispositivi in contemporanea)<\/li>\n<li>6 mesi di Amazon Prime (solo per i nuovi clienti TIMVISION con linea fissa)<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di <strong>40,99 euro al mese<\/strong> fino al 31\/12\/23 per i clienti fisso o fino al 27\/1\/24 per quelli mobile, poi si rinnova a 45,99 euro al mese.<\/p>\n<p>Se acquistate online le offerte TIMVISION <strong>non c&#8217;\u00e8 costo di attivazione<\/strong>, altrimenti il contributo \u00e8 di 19,99 euro una tantum o 9,99 euro se gi\u00e0 si dispone del decoder <strong>TIMVISION Box<\/strong>. Il TV box \u00e8 incluso in comodato d&#8217;uso gratuito e dispone della ottimizzazione automatica della connessione per un segnale stabile e veloce e una visione in altissima qualit\u00e0, comandi vocali tramite Google Assistant per trovare i propri programmi preferiti, Chromecast integrata per trasmettere i contenuti sul telefono sullo schermo della TV e accesso a tutte le app di Google Play. In alternativa \u00e8 disponibile il <strong>TIMVISION Box Atmosphere<\/strong> con visione 4K e sistema audio integrato Bang &amp; Olufsen. I <strong>primi 3 mesi sono gratis<\/strong>, poi si rinnova a 5 euro al mese.<\/p>\n<h3>Le offerte fisso e mobile di TIM<\/h3>\n<p>Se ancora non siete clienti di <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/tim\/\"><strong>TIM<\/strong><\/a> per la telefonia mobile potete confrontare le offerte dell&#8217;operatore gratuitamente con il <strong>comparatore di SOStariffe.it<\/strong>. Bastano pochi clic per costruire il proprio profilo di consumo e trovare la proposta pi\u00f9 economica in base alle vostre reali esigenze. Potrete poi attivarla comodamente online cliccando sul tasto &#8220;Scopri&#8221;, che vi re-indirizzer\u00e0 verso il sito dell&#8217;operatore da cui completare l&#8217;acquisto.<\/p>\n<p>[WIDGET-MOBILE]<\/p>\n<p>Tra le migliori offerte di TIM per il cellulare potete attivare<\/p>\n<p><strong>TIM 5G Power Smart<\/strong><\/p>\n<ul>\n<li>minuti e SMS illimitati<\/li>\n<li><strong>100 GB<\/strong> per navigare in <strong>5G<\/strong> fino a 2 Gbps in download e 150 Mbps in upload con TIM Ricarica Automatica (altrimenti 50 GB a 16,99 euro al mese con addebito su credito residuo)<\/li>\n<li>14 GB per navigare in roaming in Ue<\/li>\n<li>Accesso prioritario alla rete di TIM<\/li>\n<li>100 GB di backup su Google One per 3 mesi (poi 1,99 euro al mese)<\/li>\n<li>TIM Navigazione Sicura<\/li>\n<\/ul>\n<p>Il costo \u00e8 di <strong>14,99 euro al mese<\/strong> ma il <strong>primo mese \u00e8 gratis per i nuovi clienti<\/strong> che l&#8217;acquistano online, cos\u00ec come l&#8217;attivazione. La SIM costa 25 euro con 20 euro di traffico incluso.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=5&amp;id=9745&amp;sos_api_key=NrdLvsXdv1Y4PhIgZ9xJF5p0QIW4rfkgbsuFu9xuPIuGzoJS\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva TIM 5G Power Smart<\/a><\/p>\n<p>Vi ricordiamo che oggi potete attivare le <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/telefono-incluso\/\"><strong>offerte smartphone incluso<\/strong><\/a>\u00a0per avere <strong>iPhone 15 a partire da 33 euro al mese<\/strong> per 30 rate, pagamento con <strong>finanziamento TIMFin<\/strong> (TAEG 0,00%, salvo approvazione) e consegna gratuita. Con <strong>TIM Rivaluta Smartphone <\/strong>si pu\u00f2 dare in permuta un vecchio smartphone per ottenere uno sconto sulle rate di un nuovo modello. Le spedizioni inizieranno dal 22\/9\/23.<\/p>\n<p>Se invece state cercando un&#8217;<a href=\"https:\/\/www.sostariffe.it\/internet-casa\/\"><strong>offerta Internet Casa<\/strong><\/a> con <a href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-adsl-fibra-tim\/\"><strong>TIM<\/strong> <\/a>in base alla copertura potete accedere a una connessione in<strong> fibra ottica FTTH<\/strong> (Fiber to the Home) in oltre 1.500 Comuni in tutta Italia e navigare alla massima velocit\u00e0 con una latenza inferiore ai 6 ms. In alternativa \u00e8 disponibile la <strong>fibra misto rame<\/strong> o <strong>FTTC<\/strong> (Fiber to the Cabinet) fino a 300 Mbps in download a seconda della distanza tra l&#8217;abitazione e la cabina stradale. Potete<a href=\"https:\/\/www.sostariffe.it\/internet-casa\/verifica-copertura\/\"><strong> verificare gratis la copertura<\/strong><\/a> su <strong>SOStariffe.it<\/strong>.<\/p>\n<p><strong>Premium Base<\/strong><\/p>\n<ul>\n<li>navigazione senza limiti fino a 1 Gbps in download e 300 Mbps in upload in FTTH<\/li>\n<li>chiamate a 19 cent al minuto + 19 cent di scatto alla risposta<\/li>\n<li>attivazione inclusa (10 euro al mese per 24 rate)<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di <strong>25,90 euro al mese<\/strong> con domiciliazione e conto online.<\/p>\n<p><strong>TIM WiFi Power Smart<\/strong><\/p>\n<ul>\n<li>navigazione senza limiti fino a 2,5 Gbps in download e 1 Gbps in upload (suddivisi tra porte Ethernet e Wi-Fi) in FTTH<\/li>\n<li>chiamate illimitate (solo con acquisto online)<\/li>\n<li>modem TIM Hub+ Executive (10 euro al mese per 24 rate)<\/li>\n<li>TIM Navigazione Sicura<\/li>\n<\/ul>\n<p>Il prezzo \u00e8 di <strong>30,90 euro al mese<\/strong> con domiciliazione e conto online ma per i <strong>gi\u00e0 clienti mobile di TIM<\/strong> diventa di <strong>24,90 euro al mese<\/strong>. L&#8217;<strong>attivazione \u00e8 gratuita<\/strong> se la si acquista entro il 23\/9\/23.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=rate_widget&amp;id=11255&amp;sos_api_key=\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva una delle offerte fibra TIM <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Chi ha una vecchia ADSL e decide di rottamarla insieme al modem riceve uno <strong>sconto di 120 euro<\/strong>, suddiviso in 5 euro al mese in 24 rate, per passare alla fibra fino a 2,5 Gbps.<\/p>\n<p>I clienti di TIM per mobile e fisso poi possono attivare <strong>TIM Unica Power<\/strong> a <strong>1,90 euro al mese<\/strong>, che vi verranno addebitati direttamente in bolletta, per avere ogni mese <strong>Giga illimitati in 5G fino a 6 SIM<\/strong> (anche se non intestate al titolare della connessione di casa. Se per\u00f2 si associano alla promozione almeno 3 SIM entro il 23\/9\/23 <strong>il prezzo di TIM Unica Power \u00e8 azzerato<\/strong>. Sono inclusi anche altri vantaggi come sconti su alcuni modelli di smartphone a rate con vincolo di 24 mesi, una seconda SIM con un&#8217;offerta TIM 5G Power a partire da 9,99 euro al mese ma soprattutto <strong>3 mesi gratis di TIMVISION con Disney+<\/strong> e 6 mesi di Amazon Prime (poi 9,99 euro al mese).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scopri come avere Disney+ a 1,99 euro al mese per 3 mesi. Hai tempo fino ad oggi 20 settembre per attivare l&#8217;offerta. Ecco tutti i dettagli su come cambiano gli abbonamenti all&#8217;app<\/p>\n","protected":false},"author":72,"featured_media":375593,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[21911,1087],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/375587"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=375587"}],"version-history":[{"count":12,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/375587\/revisions"}],"predecessor-version":[{"id":375616,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/375587\/revisions\/375616"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/375593"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=375587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=375587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=375587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}