{"id":375572,"date":"2023-09-20T11:00:20","date_gmt":"2023-09-20T09:00:20","guid":{"rendered":"http:\/\/www.sostariffe.it\/news\/?p=375572"},"modified":"2023-09-21T08:48:09","modified_gmt":"2023-09-21T06:48:09","slug":"il-conto-deposito-delle-poste-conviene-davvero-le-novita-di-settembre-2023","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/il-conto-deposito-delle-poste-conviene-davvero-le-novita-di-settembre-2023-375572\/","title":{"rendered":"Il conto deposito delle Poste conviene davvero? Le novit\u00e0 di Settembre 2023"},"content":{"rendered":"<p><b>Conto deposito Poste<\/b> sono una serie di prodotti finanziari per un investimento sicuro e un rendimento garantito nel corso del tempo. Ma sono davvero vantaggiosi a settembre 2023? La risposta ai risparmiatori su <b>SOStariffe.it<\/b>.<\/p>\n<p><!--more--><\/p>\n<p>Conto deposito Poste permette di <b>far fruttare<\/b> i propri risparmi: infatti Poste Italiane propone <b>soluzioni sicure di investimento<\/b>. Ma sono offerte anche convenienti? Analizziamo di seguito che cosa prevedono le varie alternative messe a disposizione dalle Poste e quali rendimenti metto sul piatto.<\/p>\n<p>Prima di scoprire maggiori dettagli sulle soluzioni di Poste Italiane, c\u2019\u00e8 da notare che altre forme di investimento con un tasso garantito sono i <strong>Conti Deposito<\/strong>, i quali pagano un<strong> interesse lordo annuo superiore al 5%<\/strong> anche per investimenti di breve durata. Tutti i dettagli in merito sono disponibili tramite il <strong>comparatore di SOStariffe.it<\/strong>, tramite il link qui sotto:<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/conto-deposito\/\" target=\"_blank\" rel=\"noopener noreferrer\">SCOPRI IL MIGLIOR CONTO DEPOSITO <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h2>Buoni fruttiferi postali: le proposte di Settembre 2023<\/h2>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><b>NOME DELL\u2019OFFERTA<\/b><\/td>\n<td style=\"width: 50%;\"><strong>SPIEGAZIONE DELL&#8217;OFFERTA<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><b>Buono 3 anni Plus<\/b><\/td>\n<td style=\"width: 50%;\">Investimento di 3 anni al <b>2%<\/b> lordo annuo<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><b>Buono 3&#215;2 <\/b><\/td>\n<td style=\"width: 50%;\">Rendimento lordo annuo del <b>2,75%<\/b> per 6 anni<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><b>Buono Risparmio Sostenibile<\/b><\/td>\n<td style=\"width: 50%;\">Investimento di 7 anni all\u2019<b>1,50%<\/b> con premio finale<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><b>Buono 3&#215;4<\/b><\/td>\n<td style=\"width: 50%;\">Durata di 12 anni e offre il<b> 3% <\/b>di rendimento<span class=\"Apple-converted-space\">\u00a0<\/span>lordo annuo<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><b>Buono 4 anni risparmiosemplice<\/b><\/td>\n<td style=\"width: 50%;\">Rendimento annuo standard dell\u2019<strong>1,50%<\/strong> per 4 anni<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><b>Buono ordinario<\/b><\/td>\n<td style=\"width: 50%;\">Rendimento lordo annuo del <b>3%<\/b> per una durata di 20 anni<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><b>Buono soluzione Eredit\u00e0<\/b><\/td>\n<td style=\"width: 50%;\">Tasso del <b>3%<\/b> lordo annuo per un investimento di 4 anni<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><b>Buono dedicato minori<\/b><\/td>\n<td style=\"width: 50%;\">Rendimento del <strong>4,50%<\/strong> annuo lordo fino alla maggiore et\u00e0 del minore<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Emessi da Cassa Depositi e Prestiti e garantiti dallo Stato, i <strong>Buoni fruttiferi postali<\/strong> non hanno <b>costi di apertura, gestione e chiusura<\/b>. Sono un investimento sicuro. Inoltre, si pu\u00f2 richiedere in ogni momento il rimborso del capitale investito entro il termine di prescrizione. Non meno importante:<\/p>\n<ul>\n<li>i Buoni fruttiferi postali hanno una <b>tassazione agevolata al 12,50%<\/b>;<\/li>\n<li>sono esenti da imposta di successione;<\/li>\n<li>con Libretto Smart o un conto BancoPosta \u00e8 possibile aprirli online, altrimenti occorre andare in un ufficio postale;<\/li>\n<li>per tutti questi prodotti finanziari, l\u2019importo minimo \u00e8 50 euro.<\/li>\n<\/ul>\n<p>Sono facili da sottoscrivere: \u00e8 possibile scegliere la <b>classica forma cartacea<\/b> di emissione dei buoni (Buoni cartacei), oppure la formula pi\u00f9 moderna dei <b>Buoni dematerializzati<\/b>. Si possono acquistare negli uffici postali e, per i soli Buoni dematerializzati, \u00e8 possibile aprirli anche grazie ai canali online (www.poste.it e App BancoPosta).<\/p>\n<h3>Buono 3 anni Plus<\/h3>\n<p>Con un rendimento del <strong>2%<\/strong> lordo annuo, il <b>Buono 3 anni Plus<\/b> ha una durata di <b>3 anni<\/b>. Capitale e interessi maturati sono liquidati alla scadenza dei 3 anni. \u00c8 possibile chiedere il rimborso del Buono in qualsiasi momento, ma perdendo gli interessi maturati.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<h3>Buono 3&#215;2<\/h3>\n<p>Con un tasso di interesse del <strong>2,75%<\/strong> lordo annuo e una durata di 6 anni, il <b>Buono 3&#215;2<\/b>\u00a0 prevede la liquidazione degli interessi alla scadenza. Offre la possibilit\u00e0 di rimborsarlo anche dopo 3 anni (tasso dell\u20191,25%) con il riconoscimento degli interessi maturati.<\/p>\n<h3>Buono Risparmio Sostenibile<\/h3>\n<p>Il <b>Buono Risparmio<\/b> <strong>Sostenibile<\/strong> ha una durata fino a <b>7 anni<\/b> con un rendimento annuo dell\u2019<b>1,50%<\/b>, con liquidazione degli interessi alla scadenza. Alla scadenza permette di conseguire un eventuale <b>premio<\/b> abbinato all\u2019andamento, se positivo, dell\u2019indice STOXX Europe 600 ESG-X.<\/p>\n<h3>Buono 3&#215;4<\/h3>\n<p>Il <strong>Buono 3&#215;4<\/strong> offre un rendimento sicuro nel lungo periodo. Questa soluzione si contraddistingue per:<\/p>\n<ul>\n<li>durata fino a <b>12 anni<\/b>;<\/li>\n<li><b>3%<\/b> di rendimento lordo\u00a0annuo;<\/li>\n<li>liquidazione alla scadenza.<\/li>\n<\/ul>\n<p>Consente una flessibilit\u00e0 di rimborso in qualsiasi momento e, dopo <b>3, 6 e 9 anni<\/b>, anche con il riconoscimento degli interessi maturati.<\/p>\n<h3>Buono 4 anni risparmiosemplice<\/h3>\n<p>Con liquidazione alla scadenza, il <b>Buono 4 anni risparmiosemplice<\/b> \u00e8 disponibile solo nell\u2019ambito del <b>Piano di Risparmio risparmiosemplice<\/b>. Prevede:<\/p>\n<ul>\n<li>durata di <b>4 anni<\/b>;<\/li>\n<li>tasso annuo lordo dell\u2019<b>1,50%<\/b>;<\/li>\n<li>possibilit\u00e0 di rendimento premiale a scadenza al raggiungimento minimo di 24 sottoscrizioni periodiche nel Piano.<\/li>\n<\/ul>\n<h3>Buono ordinario<\/h3>\n<p>Il Buono ordinario offre il <b>3% di rendimento lordo<\/b> a fronte di un investimento fino a <b>20 anni<\/b>. Si caratterizza per:<\/p>\n<ul>\n<li>interessi riconosciuti dopo un anno dalla sottoscrizione;<\/li>\n<li>dopo il primo anno gli interessi sono riconosciuti ogni bimestre e corrisposti al rimborso del Buono;<\/li>\n<li>possibilit\u00e0 di rientrare in possesso della somma investita in qualsiasi momento, ma perdendo gli interessi maturati.<\/li>\n<\/ul>\n<h3>Buono soluzione Eredit\u00e0<\/h3>\n<p>Il <b>Buono soluzione Eredit\u00e0<\/b> eroga un rendimento del <strong>3%<\/strong> annuo lordo per un investimento di<b> 4 anni<\/b>. Con rimborso prima della scadenza dei 4 anni, si ha diritto solo alla restituzione del capitale investito e non degli interessi maturati.\u00a0 \u00c8 dedicato ai beneficiari di un procedimento successorio concluso in Poste Italiane.<\/p>\n<h3>Buono dedicato ai minori<\/h3>\n<p>Il <b>Buono dedicato ai minori<\/b> si caratterizza per un tasso annuale lordo fino al <b>4,50%<\/b>. \u00c8 un investimento dedicato ai pi\u00f9 piccoli e Poste Italiane permette ai titolari di maturare gli interessi fino alla maggiore et\u00e0 del minore. \u00c8 attivabile tanto da un genitore quanto da un nonno.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<h2>Libretto di risparmio postale: le alternative di Settembre 2023<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 96px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px; text-align: center;\"><strong>NOME DELL&#8217;OFFERTA<\/strong><\/td>\n<td style=\"width: 50%; height: 24px; text-align: center;\"><strong>DETTAGLI DELL&#8217;OFFERTA<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>Libretto ordinario<\/strong><\/td>\n<td style=\"width: 50%;\">\n<ul>\n<li>canone annuo gratuito<\/li>\n<li>tasso di interesse dello <strong>0,001%<\/strong><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\"><strong>Libretto Smart<\/strong><\/td>\n<td style=\"width: 50%; height: 24px;\">\n<ul>\n<li>canone annuo gratuito<\/li>\n<li>rendimento annuo lordo dell&#8217;<strong>1,5%<\/strong><\/li>\n<li><strong>Supersmart 360 giorni<\/strong> con tasso del <strong>2,50%<\/strong><\/li>\n<li>promozione <strong>Supersmart Premium 366 giorni <\/strong>con tasso del<strong> 3,50%<\/strong><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\"><strong>Libretto dedicato ai minori<\/strong><\/td>\n<td style=\"width: 50%; height: 24px;\">\n<ul>\n<li>canone annuo gratuito<\/li>\n<li><strong>tre differenti formule<\/strong> in base alla fascia di et\u00e0 del minore: da 0 a 12 anni, da 12 a 14 anni, da 14 anni a 18 anni<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Con possibilit\u00e0 di <b>versare e prelevare<\/b> in tutti gli uffici postali, i <b>Libretti di risparmio postale <\/b>sono garantiti dallo Stato e non prevedono costi di apertura e di gestione. Inoltre\u00a0con la \u201c<b>Carta Libretto<\/b>\u201d oppure con l\u2019App BancoPosta si pu\u00f2 prelevare gratis a tutti gli sportelli ATM Postamat.<\/p>\n<h3>Libretto ordinario<\/h3>\n<p>Con versamenti e prelievi in tutti gli uffici postali, anche con Carta Libretto, \u00a0il <b>Libretto ordinario<\/b> permette di attivare (allo sportello) sia Buoni fruttiferi postali dematerializzati che di accreditare il cedolino della pensione dell&#8217;INPS e dell&#8217;INPDAP. C&#8217;\u00e8 poi da notare che il Libretto Ordinario assicura un tasso nominale annuo lordo dello<b> 0,001%<\/b>.<\/p>\n<h3>Libretto Smart<\/h3>\n<p>Attivabile dal sito www.poste.it, da app BancoPosta e in ufficio postale, il<b> Libretto Smart <\/b>consente di beneficiare di un tasso di interesse annuo dell\u2019<b>1,50%<\/b>. Pi\u00f9 vantaggioso \u00e8 <strong>Supersmart 360 giorni<\/strong>, grazie al quale \u00e8 possibile beneficiare di un rendimento annuo del <b>2,50%<\/b>. Mentre con la promozione <strong>Supersmart Premium 366 giorni<\/strong> \u00e8 possibile ottenere un tasso del<strong><strong> 3,50% <\/strong><\/strong>annuo lordo a scadenza sulla nuova liquidit\u00e0 accantonata. Quest&#8217;ultima offerta \u00e8 attivabile entro il 6 novembre 2023. In caso di estinzione anticipata, il tasso sar\u00e0 quello base dell\u20191,50%.<\/p>\n<p>Inoltre, presso tutti gli uffici postali e gli sportelli ATM del circuito Postamat \u00e8 possibile:<\/p>\n<ul>\n<li>prelevare contanti;<\/li>\n<li>eseguire operazioni di girofondi da o verso il proprio Libretto Smart.<\/li>\n<li>monitorare il saldo e la lista movimenti.<\/li>\n<\/ul>\n<h3>Libretto dedicato ai minori<\/h3>\n<p>Il <b>Libretto dedicato ai minori<\/b> \u00e8 suddiviso in tre fasce d&#8217;et\u00e0 con tre diversi livelli di autonomia. In promozione fino al 31 ottobre 2023, c\u2019\u00e8 anche la possibilit\u00e0 di vincere un soggiorno di due notti al Gardaland Resort, aprendo online da app uno dei conti sottostanti. Nel dettaglio l&#8217;offerta per gli under 18 di Poste Italiane prevede:<\/p>\n<ul>\n<li>\u201c<b>Io cresco<\/b>\u201d, dedicato ai bambini tra 0 e 12 anni permette di fare versamenti e prelievi consentiti al genitore e al tutore. I risparmi crescono tranquilli in attesa che il minore possa gestirli in modo autonomo;<\/li>\n<li>\u201c<b>Io conosco<\/b>\u201d, dedicato ai ragazzi tra 12 e 14 anni, permette di effettuare versamenti e prelievi anche al minore fino a 30 euro al giorno e 250 euro al mese. Il genitore o il tutore possono richiedere la \u201cCarta IO\u201d, intestata al minore;<\/li>\n<li><b>\u201cIo capisco<\/b>\u201d, dedicato ai ragazzi tra 14 e 18 anni, consente di eseguire versamenti e prelievi anche al minore fino a 50 euro al giorno e 500 euro al mese. Il genitore o il tutore possono richiedere la \u201cCarta IO\u201d, intestata al minore.<\/li>\n<\/ul>\n<h2>Conti deposito: i migliori rendimenti delle banche a Settembre 2023<\/h2>\n<p>Per un investimento sicuro e con un rendimento garantito non ci sono soltanto le offerte proposte da Poste Italiane, ci sono anche i <b>conti deposito <\/b>che, negli ultimi mesi, hanno innalzato il tasso di interesse a percentuali che non si vedevano da anni. Tra le alternative<b> pi\u00f9 remunerative di settembre 2023 <\/b>ci sono:<\/p>\n<ul>\n<li>conto deposito a <strong>12 mesi<\/strong> con rendimento fino al <strong>5% lordo annuo<\/strong>. Con un investimento di 20.000 euro, il guadagno netto \u00e8 di<strong> 701,92 euro<\/strong>;<\/li>\n<li>conto deposito a <strong>24<\/strong> <strong>mesi<\/strong> con rendimento fino <strong>5% <\/strong>lordo annuo. Con un investimento di 20.000 euro, il guadagno netto \u00e8 di<strong> 1.401,92 euro<\/strong>;<\/li>\n<li>conto deposito a <strong>60 mesi<\/strong> con rendimento fino a<strong> 5,4% <\/strong>lordo annuo. Con un investimento di 20.000 euro, il guadagno netto \u00e8 di<strong> 3.800,16 euro<\/strong>.<\/li>\n<\/ul>\n<p>Per una fotografia delle offerte pi\u00f9 vantaggiose di<b> settembre 2023<\/b>, c\u2019\u00e8 il comparatore per <b>conti deposito<\/b> di <b>SOStariffe.it<\/b> che mette a confronto le proposte pi\u00f9 redditizie per far fruttare i propri risparmi.<\/p>\n<p>C&#8217;\u00e8 infine da evidenziare che il conto deposito \u00e8 un <b>investimento sicuro <\/b>poich\u00e9, con la garanzia del Fondo Interbancario di Tutela dei Depositi ai risparmiatori ha garantito il risarcimento della somma investita fino a un massimo di <b>100.000 mila euro<\/b> nel caso di default della banca.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conto deposito Poste sono una serie di prodotti finanziari per un investimento sicuro e un rendimento garantito nel corso del tempo. Ma sono davvero vantaggiosi a settembre 2023? La risposta ai risparmiatori su SOStariffe.it.<\/p>\n","protected":false},"author":108,"featured_media":375577,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1465],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/375572"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=375572"}],"version-history":[{"count":10,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/375572\/revisions"}],"predecessor-version":[{"id":375710,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/375572\/revisions\/375710"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/375577"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=375572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=375572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=375572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}