{"id":375392,"date":"2023-09-18T10:00:53","date_gmt":"2023-09-18T08:00:53","guid":{"rendered":"http:\/\/www.sostariffe.it\/news\/?p=375392"},"modified":"2023-09-19T07:40:45","modified_gmt":"2023-09-19T05:40:45","slug":"nuove-norme-rca-in-arrivo-per-il-codice-delle-assicurazioni-private","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/nuove-norme-rca-in-arrivo-per-il-codice-delle-assicurazioni-private-375392\/","title":{"rendered":"Nuove norme RCA in arrivo per il codice delle assicurazioni private"},"content":{"rendered":"<p><b>Nuove norme RCA<\/b>: la scadenza del 31 dicembre 2023 per recepire la direttiva UE sull\u2019<b>assicurazione della responsabilit\u00e0 civile dell&#8217;auto<\/b> si avvicina. L\u2019Italia \u00e8 al lavoro per adeguarsi, garantendo pi\u00f9 sicurezza e trasparenza. Le novit\u00e0 in arrivo sul <b>codice delle assicurazioni private<\/b> e le <b>migliori offerte<\/b> di settembre 2023 per una polizza auto su <b>SOStariffe.it<\/b>.<\/p>\n<p><!--more--><\/p>\n<p>Semaforo verde del governo alle nuove norme RCA. Il Consiglio dei ministri ha approvato in via preliminare un decreto legislativo per recepire una serie di <b>norme europee<\/b> concernenti l&#8217;<b>assicurazione della responsabilit\u00e0 civile <\/b>delle auto. L&#8217;obiettivo della direttiva UE \u00e8 quello di:<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<ul>\n<li>garantire la parit\u00e0 di tutela minima delle persone lese a seguito di incidenti derivanti dalla circolazione stradale in tutto il territorio dell&#8217;Unione europea;<span class=\"Apple-converted-space\">\u00a0<\/span><\/li>\n<li>assicurare la loro protezione in caso di insolvenza delle imprese di assicurazione;<span class=\"Apple-converted-space\">\u00a0<\/span><\/li>\n<li>garantire parit\u00e0 di trattamento da parte degli assicuratori delle attestazioni di sinistralit\u00e0 pregressa dei potenziali assicurati che attraversano le frontiere interne dell\u2019Unione.<\/li>\n<\/ul>\n<p>Dopo il via libera di Palazzo Chigi, adesso il testo \u00e8 all\u2019esame delle <b>commissioni parlamentari<\/b>. Le modifiche riguardano tanto il codice delle assicurazioni private nella sezione concernente le norme RCA, quanto il Codice della strada.<\/p>\n<p>Prima di analizzare nei dettagli quali sono le nuove norme RCA, \u00e8 opportuno ricordare che gli automobilisti che desiderino <b>tagliare i costi<\/b> della polizza auto possono avere un aiuto dal comparatore per <b>assicurazioni auto<\/b> di <b>SOStariffe.it<\/b>, il quale permette di avere un confronto tra le offerte pi\u00f9 convenienti e, inserendo i propri dati, di avere un <b>preventivo<\/b> del premio assicurativo pi\u00f9 economico. Inoltre, \u00e8 possibile ricevere assistenza gratuita chiamando il <strong>numero verde 800 999 565 <\/strong>sia per scegliere che per attivare la polizza.<\/p>\n<p>Per saperne di pi\u00f9, clicca sul bottone verde qui sotto:<\/p>\n<p><a class=\"green-cta\" style=\"width: 300px; height: 30px; line-height: 30px; font-size: 15px;\" href=\"https:\/\/www.sostariffe.it\/assicurazioni\/assicurazione-auto\/preventivo1.html\">Scopri la migliore polizza auto di Settembre 2023<span style=\"text-align: right;\">\u00bb<\/span><\/a><span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<h2>Nuove norme RCA: che cosa cambia con la direttiva UE<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 96px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\"><\/td>\n<td style=\"width: 50%; height: 24px;\"><strong>RCA: CHE COSA CAMBIA<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\">1<\/td>\n<td style=\"width: 50%; height: 24px;\">Armonizzare la normativa sull&#8217;assicurazione auto nei Paesi dell&#8217;Unione europea su:<\/p>\n<ul>\n<li><b>tutela delle persone lese<\/b><\/li>\n<li>indennizzo in tutti i casi di insolvenza di compagnie straniere<\/li>\n<li><b>aumento dei massimali<\/b><\/li>\n<li>rafforzamento dei controlli sui veicoli degli Stati membri<\/li>\n<li>riconoscimento transfrontaliero degli attestati di rischio<\/li>\n<li>sistema di calcolo e controllo dei premi RCA mediante sistema informatizzato<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\">2<\/td>\n<td style=\"width: 50%; height: 24px;\">Estendere l&#8217;<strong>obbligo di copertura assicurativa<\/strong> a nuove categorie di veicoli<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\">3<\/td>\n<td style=\"width: 50%; height: 24px;\">Rendere obbligatorio e omogeneo dei Stati membri l&#8217;<b>intervento risarcitorio del Fondo di garanzia<\/b> in caso d&#8217;insolvenza di un assicuratore RCA<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Il recepimento della direttiva europea 2021\/2118 del Parlamento europeo e del Consiglio, recante modifica della direttiva 2009\/103\/CE concernente l&#8217;assicurazione della responsabilit\u00e0 civile per la circolazione di autoveicoli e il controllo dell&#8217;obbligo di assicurare tale responsabilit\u00e0 sono i due pilastri che la normativa italiana \u00e8 chiamata ad introdurre.<\/p>\n<p>Il governo, dunque, ha detto s\u00ec allo schema di decreto legislativo che recepisce una direttiva europea per le nuove norme in materia di RCA e prevede un obbligo specifico dell\u2019assicurazione per i veicoli elettrici leggeri, tra cui i <b>monopattini<\/b>. Il testo, secondo quanto sostiene una nota del MIMIT (Ministero delle Imprese e del Made in Italy), apporta<span class=\"Apple-converted-space\">\u00a0 <\/span>modifiche al codice della Strada e al codice delle assicurazioni private, definendo i casi in cui sussiste l&#8217;<b>obbligo di copertura assicurativa<\/b>. Il provvedimento rafforza inoltre lo strumento del \u201cpreventivatore\u201d, per <b>confrontare gratuitamente i prezzi delle polizze<\/b>.<\/p>\n<p>Pi\u00f9 in dettaglio, c\u2019\u00e8 da evidenziare che il nostro Paese deve armonizzarsi con gli altri Stati membri dell\u2019Unione europea sui seguenti punti:<\/p>\n<ul>\n<li><b>tutela delle persone lese<\/b>;<\/li>\n<li>indennizzo in tutti i casi di insolvenza di compagnie straniere;<\/li>\n<li><b>aumento dei massimali<\/b>;<\/li>\n<li>rafforzamento dei controlli sui veicoli degli Stati membri;<\/li>\n<li>riconoscimento transfrontaliero degli attestati di rischio;<span class=\"Apple-converted-space\">\u00a0<\/span><\/li>\n<li>sistema di calcolo e controllo dei premi RCA mediante sistema informatizzato.<\/li>\n<\/ul>\n<p>Tra l&#8217;altro, le nuove norme rendono obbligatorio e omogeneo, in tutti i Paesi europei, l&#8217;<b>intervento risarcitorio del Fondo di garanzia<\/b> in caso d&#8217;insolvenza di un assicuratore RCA e a garantire, in caso di fallimento d&#8217;imprese estere operanti in regime di libera prestazione di servizi (LPS) o di stabilimento, il diritto di rivalsa del Fondo che ha risarcito il danneggiato nei confronti del Fondo del Paese di origine dell&#8217;impresa insolvente.<\/p>\n<p>Il ministro delle Imprese e del made in Italy,<b> Adolfo Urso<\/b>, ha spiegato che &#8220;<i>con le norme sulla Rc auto approvate in Consiglio dei ministri, obbligo di assicurazione anche per monopattini e altri mezzi elettrici leggeri e possibilit\u00e0<span class=\"Apple-converted-space\">\u00a0<\/span>di sospendere l&#8217;assicurazione fino a 9 mesi all&#8217;anno se non se ne usufruisce. Cresce la sicurezza e la <\/i><b><i>trasparenza in campo assicurativo<\/i><\/b>\u201d.<\/p>\n<h2>Nuove norme RCA: pi\u00f9 sicurezza e trasparenza su prezzi e contratti<\/h2>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%; text-align: center;\"><strong>LA NUOVA NORMATIVA RCA<\/strong><\/td>\n<td style=\"width: 50%; text-align: center;\"><strong>SPIEGAZIONE<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>Veicoli per i quali \u00e8 esteso l&#8217;obbligo di copertura assicurativa<\/strong><\/td>\n<td style=\"width: 50%;\">\n<ul>\n<li>Veicoli a prescindere dal terreno su cui sono utilizzati<\/li>\n<li>Veicoli indipendentemente che siano fermi oppure in movimento<\/li>\n<li>Veicoli in circolazione in zone il cui l&#8217;accesso \u00e8 soggetto a restrizioni <span class=\"Apple-converted-space\">\u00a0\u00a0<\/span><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>Veicoli per i quali \u00e8 escluso l&#8217;obbligo di copertura assicurativa<\/strong><\/td>\n<td style=\"width: 50%;\">\n<ul>\n<li>Veicoli non idonei all&#8217;uso come mezzo di trasporto<\/li>\n<li>Veicoli ritirati dalla circolazione (per esempio, destinati alla rottamazione o su cui vige fermo amministrativo, confisca o sequestro)<\/li>\n<li>Veicoli volontariamente sospesi dalla circolazione (per esempio, per utilizzo stagionale)<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Garantire una maggiore trasparenza nel settore delle assicurazioni auto: \u00e8 questo l\u2019obiettivo che si prefigge il rafforzamento dello strumento del \u201cpreventivatore\u201d per i consumatori con un <b>confronto fra i prezzi, le tariffe e le condizioni contrattuali<\/b> delle imprese di assicurazione, che \u00e8 consultabile\u00a0sui siti internet dell&#8217;IVASS e del Ministero delle imprese e del made in Italy.<span class=\"Apple-converted-space\">\u00a0 \u00a0<\/span><\/p>\n<p>Per quanto riguarda l&#8217;<b>obbligo di copertura assicurativa<\/b> questo \u00e8 esteso:<\/p>\n<ul>\n<li>ai veicoli a prescindere dal terreno su cui sono utilizzati;<span class=\"Apple-converted-space\">\u00a0<\/span><\/li>\n<li>ai veicoli indipendentemente dal fatto che siano fermi o in movimento;<span class=\"Apple-converted-space\">\u00a0<\/span><\/li>\n<li>ai veicoli in circolazione in zone il cui l&#8217;accesso \u00e8 soggetto a restrizioni (per esempio, mezzi che negli aeroporti trasportano i passeggeri dal gate all&#8217;aereo). <span class=\"Apple-converted-space\">\u00a0 \u00a0<\/span><\/li>\n<\/ul>\n<p>Nel provvedimento, stando a quanto si apprende, sono inserite anche alcune <b>deroghe<\/b>. In particolare, \u00e8<b> escluso l&#8217;obbligo di copertura assicurativa <\/b>per i veicoli:<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<ul>\n<li>non idonei all&#8217;uso come mezzo di trasporto;<\/li>\n<li>ritirati dalla circolazione (per esempio, destinati alla rottamazione o su cui vige fermo amministrativo, confisca o sequestro); <span class=\"Apple-converted-space\">\u00a0<\/span><\/li>\n<li>volontariamente sospesi dalla circolazione (per esempio, per utilizzo stagionale).<span class=\"Apple-converted-space\">\u00a0<\/span><\/li>\n<\/ul>\n<p>Da osservare c\u2019\u00e8 che \u00e8 l\u2019<b>assicurato<\/b> a scegliere se <b>sospendere volontariamente l&#8217;assicurazione<\/b>. Finora questa opzione era una libera scelta della compagnia assicuratrice. Infine, il termine di sospensione pu\u00f2 essere prorogato pi\u00f9 volte e non pu\u00f2 avere una durata superiore a nove mesi, rispetto all&#8217;annualit\u00e0.<\/p>\n<h2>Assicurazioni auto: le migliori offerte di Settembre 2023<\/h2>\n<p>\u00c8 possibile <b>risparmiare<\/b> sul premio assicurativo senza rinunciare a una copertura completa e in linea con le proprie esigenze. Un aiuto per trovare la soluzione pi\u00f9 conveniente arriva dal comparatore per <b>assicurazioni auto<\/b> di <b>SOStariffe.it<\/b>,<b> <\/b>il tool digitale e gratuito che consente un confronto tra<b> preventivi<\/b>.<\/p>\n<p>C\u2019\u00e8 da notare che, tramite SOStariffe.it, \u00e8 possibile fare un<b> confronto \u201csu misura\u201d del cliente<\/b>: infatti al contraente \u00e8 richiesto di inserire i seguenti dati:<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<ul>\n<li>dati anagrafici, con et\u00e0 e comune di residenza;<\/li>\n<li>dati assicurativi (per esempio, la classe di merito);<span class=\"Apple-converted-space\">\u00a0<\/span><\/li>\n<li>caratteristiche del veicolo da assicurare.<\/li>\n<\/ul>\n<p>Tutti questi dati consentono al sistema di stimare il costo della polizza auto tra differenti compagnie assicurative. Ma occorre non dimenticare che <b>non \u00e8 possibile trovare una polizza auto migliore in assoluto<\/b> ma \u00e8 sempre necessario andare a valutare, caso per caso, quali siano le opzioni pi\u00f9 convenienti sulla base dei propri dati. Occorre anche ricordare che il costo del premio RC auto dipende anche dalle garanzie accessorie che l\u2019utente intende inserire nella propria polizza. Per esempio: furto e incendio, kasko e assistenza stradale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuove norme RCA: la scadenza del 31 dicembre 2023 per recepire la direttiva UE sull\u2019assicurazione della responsabilit\u00e0 civile dell&#8217;auto si avvicina. L\u2019Italia \u00e8 al lavoro per adeguarsi, garantendo pi\u00f9 sicurezza e trasparenza. Le novit\u00e0 in arrivo sul codice delle assicurazioni private e le migliori offerte di settembre 2023 per una polizza auto su SOStariffe.it.<\/p>\n","protected":false},"author":108,"featured_media":375413,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4028],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/375392"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=375392"}],"version-history":[{"count":9,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/375392\/revisions"}],"predecessor-version":[{"id":375537,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/375392\/revisions\/375537"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/375413"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=375392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=375392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=375392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}