{"id":374658,"date":"2023-09-04T11:00:02","date_gmt":"2023-09-04T09:00:02","guid":{"rendered":"http:\/\/www.sostariffe.it\/news\/?p=374658"},"modified":"2023-09-05T09:06:22","modified_gmt":"2023-09-05T07:06:22","slug":"la-bce-alza-i-tassi-la-situazione-mutui-di-settembre-2023","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/la-bce-alza-i-tassi-la-situazione-mutui-di-settembre-2023-374658\/","title":{"rendered":"La BCE alza i tassi? La situazione mutui di Settembre 2023"},"content":{"rendered":"<p><b>BCE<\/b> in bilico se alzare ancora o meno i tassi di interesse a settembre 2023 per combattere l\u2019<b>inflazione elevata<\/b> nell\u2019Eurozona. Un aumento del costo del denaro si tradurrebbe in un nuovo <b>rialzo delle rate dei mutui a tasso variabile<\/b>. Per trovare le <b>migliori offerte <\/b>mutui, un aiuto arriva dal comparatore di <b>SOStariffe.it<\/b>.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><!--more--><\/p>\n<p>BCE indecisa sulla prossima mossa da compiere per abbassare l&#8217;inflazione che nell\u2019Eurozona ad agosto 2023 rimane stabile al 5,3%. La <b>Banca centrale europea<\/b> avverte che le prospettive per un eventuale nuovo aumento dei tassi di interesse (sarebbe il decimo di fila) restano \u201c<b>altamente incerte<\/b>\u201d e la riunione del board dell\u2019istituto di Francoforte di settembre 2023 si carica di attese.<\/p>\n<p>Una possibile ulteriore<strong> crescita del costo del denaro<\/strong>\u00a0avrebbe pesanti ricadute su famiglie e imprese. Un ritocco verso l&#8217;alto dei tassi, come fatto a luglio 2023, vorrebbe dire un altro incremento delle rate dei <b>mutui a tasso variabile<\/b>. Contro questo rischio e per trovare un mutuo conveniente, c&#8217;\u00e8 il <b>comparatore<\/b> per <b>mutui<\/b> di <b>SOStariffe.it<\/b>, che confronta le migliori soluzioni\u00a0<b>disponibili a settembre 2023<\/b>, con anche la possibilit\u00e0 di richiedere una <strong>surroga del mutuo <\/strong>in corso. Una mossa quest&#8217;ultima che aiuterebbe le famiglie ad <strong>abbassare la rata del mutuo<\/strong>.<\/p>\n<p><span class=\"Apple-converted-space\">Per saperne di pi\u00f9, clicca sul pulsante verde qui di seguito:<\/span><\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/mutui\/\" target=\"_blank\" rel=\"noopener noreferrer\">SCOPRI I MIGLIORI MUTUI <span style=\"\u201ctext-align: right\u201d;\">\u00bb<\/span><\/a><\/p>\n<h2>BCE al bivio: aumentare o meno i tassi d&#8217;interesse a Settembre 2023?<\/h2>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><\/td>\n<td style=\"width: 50%;\"><strong>I TRE PUNTI CARDINE<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">1<\/td>\n<td style=\"width: 50%;\">Ad <strong>agosto 2023<\/strong> l&#8217;inflazione nell&#8217;Eurozona era stabile al <strong>5,3%<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">2<\/td>\n<td style=\"width: 50%;\">L&#8217;obiettivo della BCE \u00e8 portare l&#8217;inflazione al <strong>2% nel 2025<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">3<\/td>\n<td style=\"width: 50%;\">Per raggiungere questo traguardo, la Banca centrale potrebbe aumentare ancora i <strong>tassi di interesse<\/strong> a <strong>settembre 2023<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>La <strong>BCE \u00e8 di fronte a un bivio<\/strong>: aumentare ancora i tassi di interesse oppure no? La risposta a questo interrogativo arriver\u00e0 dalla<strong> riunione del board della Banca centrale europea<\/strong> previsto per la met\u00e0 di settembre 2023. Per ora di certo, c&#8217;\u00e8 soltanto che l&#8217;inflazione nell&#8217;Eurozona ad agosto 2023 era ancora al 5,3%, <strong>ben lontana dal 2%<\/strong> a cui vorrebbe riportarla l&#8217;Istituto di Francoforte. E questo obiettivo giustificherebbe un eventuale ulteriore rialzo del costo del denaro.<\/p>\n<p>Nei giorni scorsi, il <strong>vicepresidente della BCE, Luis De Guindos<\/strong>, parlando a un evento all&#8217;Universit\u00e0 Menendez Pelayo di Santander (Spagna), ha affermato che l&#8217;aumento dei tassi &#8220;<em>\u00e8<span class=\"Apple-converted-space\">\u00a0<\/span><strong>una medicina amara ma necessaria<\/strong><\/em>&#8220;. Ha aggiunto: &#8220;<em>So che l&#8217;aumento dei tassi si riflette sui mutui e i prestiti ma \u00e8<span class=\"Apple-converted-space\"> l<\/span>a forma in cui il banco centrale<\/em>&#8221; combatte l&#8217;inflazione &#8220;<em>che \u00e8<span class=\"Apple-converted-space\">\u00a0<\/span>il male assoluto per la vita economica e sociale di un Paese<\/em>&#8220;.<\/p>\n<p>In quest&#8217;occasione, sempre De Guindos ha sottolineato che &#8220;<em><strong>sui tassi siamo al rettilineo finale. <\/strong>Nella riunione di settembre del consiglio BCE la decisione \u00e8<span class=\"Apple-converted-space\">\u00a0<\/span>ancora aperta<\/em>&#8220;. Ha poi spiegato che il board della Banca centrale esaminer\u00e0 i dati di inflazione ed economia e poi decider\u00e0 i passi da compiere.<\/p>\n<p>De Guindos, inoltre, ha ricordato le mosse gi\u00e0 avviate dalla BCE:<\/p>\n<ul>\n<li>crescita dei tassi;<\/li>\n<li>frenata nell&#8217;acquisto di attivi.<\/li>\n<\/ul>\n<p>Il vicepresidente ha infine evidenziato come l&#8217;economia europea &#8220;<em>negli ultimi 5 anni sia passata attraverso una serie di choc<\/em>&#8220;. &#8220;<strong>La stessa riapertura dopo il lockdown<\/strong>&#8221; provocato dalla pandemia \u00e8<span class=\"Apple-converted-space\">\u00a0<\/span>stata &#8220;<em>come passare dal congelamento al calore<\/em>&#8221; con effetti negativi, ma l&#8217;Europa e la Bce hanno reagito con misure straordinarie per far fronte a questa situazione.<\/p>\n<p>Sebbene nessun membro dell&#8217;Istituto centrale di Francoforte finora si sia sbilanciato, rimane la preoccupazione per uno scenario economico difficile. Ha spiegato, sempre nei giorni scorsi, <strong>Isabel Schnabel, del board esecutivo della BCE<\/strong>, aprendo la conferenza sull&#8217;inflazione organizzata assieme all&#8217;americana FED: &#8220;<em>Dopo oltre un anno di significativa stretta monetaria, le prospettive per l&#8217;area euro rimangono altamente incerte. L&#8217;attivit\u00e0 si\u00a0\u00e8<span class=\"Apple-converted-space\">\u00a0<\/span>visibilmente attenuata e gli indicatori segnalano una debolezza in vista<\/em>&#8220;. Ha poi aggiunto che &#8220;<em>l&#8217;inflazione complessiva \u00e8<span class=\"Apple-converted-space\">\u00a0<\/span>scesa<\/em>&#8220;, ma &#8220;<em>le pressioni di fondo sui prezzi rimangono ostinatamente elevate, con i fattori interni che ora rappresentano i principali motori dell&#8217;inflazione nell&#8217;area euro. Pertanto, una politica monetaria sufficientemente restrittiva \u00e8<span class=\"Apple-converted-space\">\u00a0<\/span>fondamentale per riportare l&#8217;inflazione al nostro obiettivo del 2% in modo tempestivo<\/em>&#8220;.<\/p>\n<p>Consultando i verbali dell&#8217;ultima riunione del board della Banca centrale, il 26-27 luglio 2023, emerge che &#8220;<em>il periodo entro il quale la BCE si aspetta di vedere<strong> l&#8217;inflazione<\/strong> ritornare al livello target si \u00e8 spostato <strong>dall&#8217;ultimo trimestre del 2024 al 2025<\/strong>&#8220;<\/em>. &#8220;<em>Anche se anticipare questa tempistica potrebbe richiedere di deprimere l&#8217;attivit\u00e0<span class=\"Apple-converted-space\">\u00a0<\/span>economica in misura non necessaria<\/em>&#8220;, i membri del board hanno ritenuto &#8220;<em>importante non allungare l&#8217;orizzonte temporale oltre il 2025<\/em>&#8220;.<\/p>\n<h2>BCE e mutui: i vantaggi di scegliere il tasso fisso a Settembre 2023<\/h2>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><strong>LE DOMANDE\u00a0<\/strong><\/td>\n<td style=\"width: 50%;\"><strong>LE RISPOSTE<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>Con l&#8217;eventuale rialzo dei tassi di interesse da parte delle BCE, meglio un mutuo a tasso fisso o variabile?<\/strong><\/td>\n<td style=\"width: 50%;\">\u00c8 consigliabile attivare un <strong>mutuo a tasso fisso<\/strong>, che mette al riparo da eventuali aumenti della rata da pagare mensilmente<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>Quanto \u00e8 attualmente la differenza fra tasso fisso e tasso variabile?<\/strong><\/td>\n<td style=\"width: 50%;\">A luglio 2023 la differenza fra tasso variabile medio e tasso fisso medio \u00e8 di oltre <b>100 punti base <\/b>a favore del tasso fisso: <strong>3,73% contro 4,74%<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>In vista di un possibile nuovo aumento dei tassi di interesse da parte della BCE, il divario fra mutui a tasso fisso e a tasso variabile \u00e8 destinato ad allargarsi ulteriormente nei prossimi mesi. Secondo i dati di luglio 2023 forniti da <b>MutuiOnline.it<\/b>, la differenza fra tasso variabile medio e tasso fisso medio era di oltre <b>100 punti base <\/b>a favore del tasso fisso: <strong>3,73% contro 4,74%<\/strong>. Risultato? Attualmente \u00e8 pi\u00f9 conveniente accendere un mutuo a tasso fisso piuttosto che tasso variabile.<\/p>\n<p>Per chi avesse invece gi\u00e0 in corso un mutuo, per esempio per l&#8217;acquisto della casa, una mossa decisamente conveniente \u00e8 quella della <a href=\"https:\/\/www.sostariffe.it\/news\/surroga-del-mutuo-come-funziona-e-quali-sono-i-vantaggi-a-settembre-2023-373261\/\"><strong>surroga del mutuo<\/strong><\/a> per provare a risparmiare sulla rata. Per <b>Alessio Santarelli, direttore generale del gruppo MutuiOnline<\/b>, &#8220;<i>la surroga, che \u00e8 lo strumento migliore per supportare i consumatori nel trasferimento del mutuo presso un altro istituto cambiandone le condizioni in maniera completamente gratuita<\/i>\u201d.<\/p>\n<p>Per le famiglie che fossero in difficolt\u00e0 economiche per una sospensione dal lavoro, o una riduzione dell&#8217;orario di lavoro, e avessero in essere un mutuo per la prima casa non superiore a 400 mila euro, c&#8217;\u00e8 la possibilit\u00e0 di accedere al Fondo di solidariet\u00e0, o <strong>Fondo<\/strong> <b>Gasparrini, <\/b>che permette beneficiare della<b> <\/b><a href=\"https:\/\/www.sostariffe.it\/news\/come-chiedere-la-sospensione-del-mutuo-ad-agosto-2023-371572\/\"><b>sospensione del mutuo<\/b><\/a><b> <\/b>per un periodo massimo di <strong>18 mesi<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BCE in bilico se alzare ancora o meno i tassi di interesse a settembre 2023 per combattere l\u2019inflazione elevata nell\u2019Eurozona. Un aumento del costo del denaro si tradurrebbe in un nuovo rialzo delle rate dei mutui a tasso variabile. Per trovare le migliori offerte mutui, un aiuto arriva dal comparatore di SOStariffe.it.\u00a0<\/p>\n","protected":false},"author":108,"featured_media":374659,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1208],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/374658"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=374658"}],"version-history":[{"count":12,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/374658\/revisions"}],"predecessor-version":[{"id":374818,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/374658\/revisions\/374818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/374659"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=374658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=374658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=374658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}