{"id":370804,"date":"2023-08-08T12:48:34","date_gmt":"2023-08-08T10:48:34","guid":{"rendered":"http:\/\/www.sostariffe.it\/news\/?p=370804"},"modified":"2023-08-08T14:12:45","modified_gmt":"2023-08-08T12:12:45","slug":"iliad-lancia-flash-180-nuova-limited-edition-da-attivare-ad-agosto-2023","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/iliad-lancia-flash-180-nuova-limited-edition-da-attivare-ad-agosto-2023-370804\/","title":{"rendered":"Iliad lancia Flash 180: nuova limited edition da attivare ad Agosto 2023"},"content":{"rendered":"<p><strong>Iliad<\/strong> rinnova la sua gamma di offerte con una <strong>nuova offerta flash<\/strong>: si tratta di <strong>Flash<\/strong> <strong>180<\/strong>. La tariffa \u00e8 la proposta pi\u00f9 completa della gamma di offerte Iliad e, con una spesa inferiore ai 10 euro al mese &#8220;per sempre&#8221;, garantisce ben 180 GB di traffico dati in 4G e 5G oltre alla possibilit\u00e0 di ottenere uno sconto sulla fibra ottica Iliad. Ecco tutti i dettagli in merito alla nuova offerta Iliad attivabile da oggi.<\/p>\n<p><!--more--><\/p>\n<p>La gamma di <strong><a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/iliad\/\">offerte Iliad<\/a> <\/strong>si rinnova con la nuova tariffa limited edition <strong>Flash<\/strong> <strong>180<\/strong>. Attivabile fino al prossimo<strong> 14 di settembre<\/strong>, questa tariffa propone minuti e SMS illimitati oltre a tanti Giga per navigare sotto rete 4G e 5G, con una spesa inferiore ai 10 euro al mese.<\/p>\n<p>La tariffa appena svelata da Iliad \u00e8 attivabile dai <strong>nuovi<\/strong> <strong>clienti<\/strong> che passano a Iliad, con o senza portabilit\u00e0 del numero (non ci sono vincoli sull&#8217;operatore di provenienza in caso di richiesta di portabilit\u00e0), ed anche dai <strong>gi\u00e0<\/strong> <strong>clienti<\/strong> <strong>Iliad<\/strong> che possono richiedere il &#8220;<em>cambio offerta<\/em>&#8220;.<\/p>\n<p>Vediamo, di seguito, tutti i dettagli:<\/p>\n<h2>Passa a Iliad con Flash 180: cosa comprende e quanto costa l&#8217;offerta limited edition<\/h2>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><\/td>\n<td style=\"width: 50%; text-align: center;\"><strong>3 COSE DA SAPERE SULLA NUOVA OFFERTA ILIAD<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">1.<\/td>\n<td style=\"width: 50%;\">\u00c8 disponibile fino al prossimo <strong>14 di settembre<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">2.<\/td>\n<td style=\"width: 50%;\">Pu\u00f2 essere attivata da <strong>nuovi<\/strong> <strong>clienti<\/strong> e da <strong>gi\u00e0 clienti Iliad<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">3.<\/td>\n<td style=\"width: 50%;\">Include<strong> 180 GB in 4G e 5G<\/strong> con un costo di <strong>9,99 euro al mese<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>La nuova <strong>Flash 180 di Iliad<\/strong>, disponibile tramite attivazione online fino al prossimo 14 di settembre, mette a disposizione il seguente bundle:<\/p>\n<ul>\n<li>minuti illimitati verso tutti i fissi e mobili nazionali<\/li>\n<li>SMS illimitati verso tutti i mobili nazionali<\/li>\n<li>minuti illimitati dall&#8217;Italia e verso oltre 60 destinazioni internazionali<\/li>\n<li><strong>180 GB in 4G e 5G ogni mese<\/strong><\/li>\n<li>tutti i servizi accessori sono inclusi nel prezzo (Mi richiami, Hotspot, Controllo credito residuo, Segreteria telefonica)<\/li>\n<li>in roaming UE: minuti ed SMS illimitati e fino a 10 GB senza costi aggiuntivi<\/li>\n<li>opzioni per avere Giga extra all&#8217;estero: 5 Giga in pi\u00f9 in UE (+3,99 euro al mese), 5 Giga in pi\u00f9 in Svizzera (+4,99 euro al mese)<\/li>\n<li>possibilit\u00e0 di acquisto a rate di uno smartphone (direttamente dal sito Iliad, con finanziamento ad anticipo zero)<\/li>\n<\/ul>\n<p>Flash 180 presenta un costo di <strong>9,99 euro al mese<\/strong> con un contributo di attivazione di 9,99 euro una tantum. L&#8217;offerta \u00e8 attivabile da tutti i nuovi clienti che passano a Iliad, con o senza portabilit\u00e0 del numero. Per attivare la promozione \u00e8 sufficiente seguire il<strong> link qui di sotto<\/strong>, in modo da raggiungere il sito Iliad.<\/p>\n<p>Baster\u00e0 premere il tasto <strong>Attiva<\/strong> per completare la procedura. L&#8217;offerta pu\u00f2 essere attivata <strong>anche con una eSIM<\/strong>, in sostituzione della SIM Card tradizionale. In questo modo, \u00e8 possibile iniziare a utilizzare subito la SIM. Tutti i dettagli sono disponibili di seguito.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=3&amp;id=11204\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva Flash 180 di Iliad <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>I <strong>gi\u00e0 clienti Iliad<\/strong> possono richiedere il cambio offerta e attivare Flash 180 direttamente tramite l&#8217;<strong>Area Personale<\/strong>. Quest&#8217;opzione \u00e8 disponibile per i clienti che hanno sottoscritto una di queste offerte:<\/p>\n<ul>\n<li>Offerta Voce, Offerta iliad a \u20ac5,99, Offerta Giga 40, Offerta Giga 50, Offerta Flash 70, Offerta Giga 70, Offerta Giga 80, Offerta Flash 100, Offerta Giga 100, Offerta Flash 100 5G, Offerta Flash 100 a \u20ac7,99, Offerta Flash 120 a \u20ac7,99, Offerta Giga 120, Offerta Flash 120, Offerta Flash 130, Offerta Flash 150, Offerta Flash 160, Offerta Giga 150.<\/li>\n<\/ul>\n<p>Attivando l&#8217;offerta Flash 180 c&#8217;\u00e8 un ulteriore bonus: i nuovi clienti che attivano un&#8217;offerta da almeno 9,99 euro al mese, come Flash 180, possono ottenere uno<strong> sconto di 5 euro sulla fibra Iliad<\/strong> che, quindi, sar\u00e0 attivabile con un canone di <strong>19,99 euro al mese<\/strong> invece che di 24,99 euro al mese. Lo sconto \u00e8 valido anche per i gi\u00e0 clienti Iliad di rete fissa e pu\u00f2 essere attivato direttamente dall&#8217;Area Personale del sito Iliad.<\/p>\n<p>L&#8217;offerta fibra di Iliad include:<\/p>\n<ul>\n<li>la linea telefonica fissa con chiamate illimitate verso tutti in Italia e verso oltre 60 destinazioni internazionali<\/li>\n<li>una<strong> connessione illimitata tramite rete in fibra ottica FTTH<\/strong> con velocit\u00e0 massima di 5 Gbps in download<\/li>\n<li>il modem Wi-Fi in comodato d&#8217;uso gratuito<\/li>\n<\/ul>\n<p>L&#8217;offerta, considerando lo sconto garantito ai clienti mobile, costa<strong> 19,99 euro al mese<\/strong> (invece che 24,99 euro al mese) con un contributo di attivazione di 39,99 euro una tantum. Per accedere alla promozione \u00e8 possibile seguire il link riportato qui di sotto.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?id=11143&amp;area=adsl\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva l&#8217;offerta fibra di Iliad <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>La <strong>nuova offerta Flash 180<\/strong> risulta essere <strong>molto conveniente<\/strong>, sia in termini di costi che di Giga inclusi, nel confronto con le tariffe proposte dagli altri operatori MNO attivi in Italia (TIM, Vodafone e WINDTRE). La<strong> tabella qui di sotto<\/strong>, diffusa direttamente da Iliad, mostra la convenienza dell&#8217;offerta.<\/p>\n<p>In ogni caso, \u00e8 possibile confrontare Flash 180 con tutte le altre proposte disponibili sul mercato grazie al<strong> comparatore di SOStariffe.it<\/strong> per <strong><a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/\">offerte di telefonia mobile<\/a><\/strong> che permette di accedere a una panoramica completa delle tariffe pi\u00f9 vantaggiose disponibili in questo momento sul mercato.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-370805\" src=\"https:\/\/www.sostariffe.it\/news\/wp-content\/uploads\/2023\/08\/ilaid-offerta.png\" alt=\"ilaid offerta\" width=\"1496\" height=\"578\" srcset=\"https:\/\/www.sostariffe.it\/news\/wp-content\/uploads\/2023\/08\/ilaid-offerta.png 1496w, https:\/\/www.sostariffe.it\/news\/wp-content\/uploads\/2023\/08\/ilaid-offerta-300x116.png 300w, https:\/\/www.sostariffe.it\/news\/wp-content\/uploads\/2023\/08\/ilaid-offerta-1024x396.png 1024w, https:\/\/www.sostariffe.it\/news\/wp-content\/uploads\/2023\/08\/ilaid-offerta-768x297.png 768w\" sizes=\"(max-width: 1496px) 100vw, 1496px\" \/><\/p>\n<h2>Le altre offerte Iliad di agosto 2023<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 96px;\">\n<tbody>\n<tr>\n<td style=\"width: 33.3333%; text-align: center;\"><strong>OFFERTA<\/strong><\/td>\n<td style=\"width: 33.3333%; text-align: center;\"><strong>MINUTI, SMS E GIGA<\/strong><\/td>\n<td style=\"width: 33.3333%; text-align: center;\"><strong>COSTO MENSILE<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 33.3333%; height: 24px;\"><strong>Giga 100<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px;\">\n<ul>\n<li>Minuti e SMS illimitati<\/li>\n<li>100 GB in 4G<\/li>\n<\/ul>\n<\/td>\n<td style=\"width: 33.3333%; height: 24px;\">\n<ul>\n<li>7,99 \u20ac\/mese<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 33.3333%; height: 24px;\"><strong>Dati 300<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px;\">\n<ul>\n<li>300 GB in 4G<\/li>\n<\/ul>\n<\/td>\n<td style=\"width: 33.3333%; height: 24px;\">\n<ul>\n<li>13,99 \u20ac\/mese<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Tra le offerte Iliad disponibili, in questo momento, continua a essere disponibile <strong>Giga<\/strong> <strong>100<\/strong>. Si tratta della tariffa di riferimento per chi vuole passare a Iliad ma intende ridurre il costo mensile (perdendo l&#8217;accesso al 5G). Ecco i dettagli dell&#8217;offerta in questione:<\/p>\n<ul>\n<li>minuti ed SMS illimitati verso tutti in Italia<\/li>\n<li>minuti illimitati dall&#8217;Italia verso oltre 60 destinazioni internazionali<\/li>\n<li><strong>100 GB in 4G\/4G\u00a0<\/strong><\/li>\n<li>minuti ed SMS illimitati e fino a 8 GB in roaming in UE<\/li>\n<li>opzioni per l&#8217;estero: 5 Giga in pi\u00f9 in UE (+3,99 euro al mese), 5 Giga in pi\u00f9 in Svizzera (+4,99 euro al mese)<\/li>\n<\/ul>\n<p>La tariffa prevede un costo di <strong>7,99 euro al mese<\/strong> con un contributo di attivazione di 9,99 euro una tantum ed \u00e8 disponibile tramite attivazione online:<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=2&amp;id=11232\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva Giga 100 di Iliad <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Da tenere d&#8217;occhio \u00e8 anche <strong>Dati 300<\/strong>. Si tratta di un&#8217;offerta solo dati che include:<\/p>\n<ul>\n<li>minuti ed SMS a consumo<\/li>\n<li><strong>300 GB in 4G\/4G+<\/strong><\/li>\n<li>fino a 13 GB in roaming in UE<\/li>\n<li>opzioni per l&#8217;estero: 5 Giga in pi\u00f9 in UE (+3,99 euro al mese), 5 Giga in pi\u00f9 in Svizzera (+4,99 euro al mese)<\/li>\n<\/ul>\n<p>Quest&#8217;offerta ha un costo di 13,99 euro al mese, con un contributo di attivazione di 9,99 euro una tantum. L&#8217;offerta garantisce anche lo sconto sulla fibra ottica.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=mobile&amp;position=5&amp;id=10097\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva Dati 300 di Iliad <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iliad rinnova la sua gamma di offerte con una nuova offerta flash: si tratta di Flash 180. La tariffa \u00e8 la proposta pi\u00f9 completa della gamma di offerte Iliad e, con una spesa inferiore ai 10 euro al mese &#8220;per sempre&#8221;, garantisce ben 180 GB di traffico dati in 4G e 5G oltre alla possibilit\u00e0 [&hellip;]<\/p>\n","protected":false},"author":47,"featured_media":370809,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[20744,9],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/370804"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=370804"}],"version-history":[{"count":3,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/370804\/revisions"}],"predecessor-version":[{"id":370815,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/370804\/revisions\/370815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/370809"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=370804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=370804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=370804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}