{"id":369681,"date":"2023-07-17T09:24:32","date_gmt":"2023-07-17T07:24:32","guid":{"rendered":"http:\/\/www.sostariffe.it\/news\/?p=369681"},"modified":"2023-07-18T16:24:14","modified_gmt":"2023-07-18T14:24:14","slug":"luce-e-gas-crollano-i-consumi-in-italia-i-dati-del-2022","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/luce-e-gas-crollano-i-consumi-in-italia-i-dati-del-2022-369681\/","title":{"rendered":"Luce e Gas: crollano i consumi in Italia, i dati del 2022"},"content":{"rendered":"<p><strong>Uno degli effetti della crisi energetica \u00e8 stato il calo dei consumi di luce e gas<\/strong>. Contenere, per quanto possibile, i consumi, evitando gli sprechi, ha permesso di attenuare gli effetti dell&#8217;aumento dei prezzi all&#8217;ingrosso dell&#8217;energia. In Italia, come confermato dalla recente<strong> Relazione Annuale di ARERA<\/strong>, si \u00e8 registrato un calo significativo, sia per l&#8217;energia elettrica che per il gas naturale. Vediamo i dettagli completi. <!--more--><\/p>\n<p>Nel corso del <strong>2022<\/strong> si \u00e8 registrato un <strong>drastico aumento dei prezzi di luce e gas<\/strong>. I rincari hanno portato ad un picco dei costi nell&#8217;estate del 2022 ma per tutto lo scorso anno si sono registrati livelli molto alti per quanto riguarda i prezzi all&#8217;ingrosso. Un primo rincari significativo \u00e8 stato registrato soltanto nel corso dei primi mesi del 2023, con le quotazioni di luce e gas che, in questo momento, sembrano essersi stabilizzate su valori pi\u00f9 accettabili (ma comunque nettamente pi\u00f9 alti dei livelli pre-crisi).<\/p>\n<p>I<strong> dati della Relazione Annuale di ARERA<\/strong> &#8220;fotografano&#8221; chiaramente l&#8217;<strong>impatto della crisi energetica sui consumi<\/strong>. Sia per la luce che per il gas si \u00e8 registrata una tendenza alla riduzione dei consumi che pu\u00f2 essere interpretata come un tentativo per ridurre al minimo l&#8217;impatto della crisi sulla spesa per l&#8217;energia. Naturalmente, la strada migliore per risparmiare resta sempre l&#8217;attivazione delle migliori offerte del Mercato Libero, facilmente individuabili tramite il <strong>comparatore di SOStariffe.it<\/strong> per<a href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/\"><strong> offerte luce e gas<\/strong><\/a>.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/\" target=\"_blank\" rel=\"noopener noreferrer\">Scopri qui le migliori offerte luce e gas <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Il <strong>calo dei consumi<\/strong>, per\u00f2, resta una <strong>risposta &#8220;naturale&#8221; da parte degli utenti finali contro la crisi energetica<\/strong>, anche per via di una maggiore attenzione al contenimento degli sprechi. I dati ARERA confermano anche un calo netto delle rinnovabili in Italia (ma con un aumento del fotovoltaico) oltre che un calo dei consumi di gas a livello europeo con una modifica radicale dei canali di approvvigionamento. Ecco i dettagli emersi dalla Relazione Annuale di ARERA che fotografa l&#8217;andamento dei consumi in Italia nel corso del 2022, in parallelo alla crisi energetica.<\/p>\n<h2>Calano i consumi di luce e gas in Italia nel 2022: i dati di ARERA<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 100px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px; text-align: center;\"><\/td>\n<td style=\"width: 50%; height: 24px; text-align: center;\"><strong>3 COSE DA SAPERE SUL CALO DEI CONSUMI DI LUCE E GAS NEL 2022<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\">1.<\/td>\n<td style=\"width: 50%; height: 24px;\">I <strong>consumi di energia elettrica <\/strong>dei <strong>clienti residenziali<\/strong> in Italia sono calati del <strong>-3,9%<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\">2.<\/td>\n<td style=\"width: 50%; height: 24px;\">\u00c8 crollato il <strong>contributo del fotovoltaico (-13,9%)<\/strong> a causa del calo dell&#8217;idroelettrico dovuto alla siccit\u00e0<\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td style=\"width: 50%; height: 28px;\">3.<\/td>\n<td style=\"width: 50%; height: 28px;\">I <strong>consumi di gas in Italia<\/strong> hanno fatto registrare un calo del<strong> -9,9%<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>La crisi energetica ha portato ad una maggiore attenzione sul consumo di luce e gas e, quindi, ad un calo complessivo dei consumi nel corso del 2022. La conferma arriva dai dati forniti da ARERA. Vediamoli nel dettaglio:<\/p>\n<h3>Energia elettrica: consumi in calo del -2,8% per i clienti residenziali<\/h3>\n<p>Secondo quanto rivelato da ARERA, in Italia si \u00e8 registrato un <strong>calo del -1,1% del consumo di energia elettrica<\/strong>. Questa flessibile \u00e8 stata nettamente pi\u00f9 marcata in ambito industriale, con un calo del -3,9%, oltre che nel <strong>settore residenziale<\/strong>, con un calo del <strong>-2,8%<\/strong>. In particolare, gli utenti residenziali sono riusciti a ridurre i consumi di energia elettrica nonostante una stagione estiva particolarmente calda che ha costretto ad un continuo ricorso ai condizionatori.<\/p>\n<p>Da notare, inoltre, che ARERA sottolinea come la <strong>domanda nazionale di energia elettrica<\/strong> sia stata soddisfatta per l&#8217;<strong>86% del totale dalla produzione nazionale<\/strong> mentre la parte restante da importazioni. La produzione nazionale di energia elettrica \u00e8 calata del -1% ma la produzione termoelettrica \u00e8 aumentata del +7,9%. Da segnalare un<strong> calo delle rinnovabili (-13,9%)<\/strong> nonostante una <strong>crescita del fotovoltaico<\/strong> (+12,3%). Il calo \u00e8 dovuto all&#8217;emergenza idrica che ha portato ad una <strong>riduzione dell&#8217;idroelettrico<\/strong> (-37,8%). Da segnalare anche un calo della generazione da bioenergie (-8,5%), da eolico (-1,8%) e da geotermico (-1,7%) rispetto al 2021.<\/p>\n<p>Le <strong>rinnovabili<\/strong> hanno contributo &#8220;solo&#8221; per il<strong> 35% alla produzione elettrica nazionale<\/strong>. Si tratta di un dato inferiore rispetto a quanto registrato nel corso del 2021 quando la quota delle rinnovabili tocc\u00f2 il 40%. Anche questo dato \u00e8 legato a doppio filo al calo dell&#8217;idroelettrico. Il dato relativo al fotovoltaico \u00e8 comunque un buon segnale in merito ad un futuro aumento della produzione di energia da fonti rinnovabili nel prossimo futuro.<\/p>\n<h3>Gas naturale: -9,9% per i consumi in Italia nel 2022<\/h3>\n<p>Per quanto riguarda il <strong>gas naturale<\/strong>, ARERA evidenzia un<strong> calo del -14% dei consumi in Europa<\/strong> (su scala globale, invece, la contrazione \u00e8 stata del -1,5%). La riduzione dei consumi di gas \u00e8 generalizzata con l&#8217;Italia che si posiziona al di sotto della media europea. Nel 2022, infatti, in <strong>Italia<\/strong> si \u00e8 registrato un calo del<strong> -9,9%<\/strong> dei consumi di gas naturale. A livello europeo, inoltre, si registra un notevole cambiamento dei sistemi di approvvigionamento di gas, con un massiccio ricorso al GNL e con la realizzazione o la programmazione di nuovi rigassificatori oltre che con l&#8217;aumento delle importazioni da gasdotti alternativi alla Russia.<\/p>\n<p>Ricordiamo che, come gi\u00e0 emerso nei mesi scorsi,<strong><a href=\"https:\/\/www.sostariffe.it\/news\/crolla-il-consumo-di-gas-in-italia-nel-2023-ecco-come-ridurre-le-bollette-362473\/\"> i consumi di gas in Italia sono crollati nella seconda met\u00e0 del 2022<\/a><\/strong>. In particolare, infatti,<strong> da settembre a dicembre<\/strong> si \u00e8 registrato un netto taglio ai consumi:<\/p>\n<ul>\n<li>settembre 2022: -17%<\/li>\n<li>ottobre 2022: -24%<\/li>\n<li>novembre 2022: -27%<\/li>\n<li>dicembre 2022: \u201324%<\/li>\n<\/ul>\n<p>Anche il 2023 \u00e8 iniziato con un calo netto: a <strong>gennaio 2023<\/strong>, infatti, \u00e8 stato consumato il <strong>22% di gas in meno.\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno degli effetti della crisi energetica \u00e8 stato il calo dei consumi di luce e gas. Contenere, per quanto possibile, i consumi, evitando gli sprechi, ha permesso di attenuare gli effetti dell&#8217;aumento dei prezzi all&#8217;ingrosso dell&#8217;energia. In Italia, come confermato dalla recente Relazione Annuale di ARERA, si \u00e8 registrato un calo significativo, sia per l&#8217;energia [&hellip;]<\/p>\n","protected":false},"author":114,"featured_media":369683,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1095,1098],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/369681"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=369681"}],"version-history":[{"count":5,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/369681\/revisions"}],"predecessor-version":[{"id":369699,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/369681\/revisions\/369699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/369683"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=369681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=369681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=369681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}