{"id":367884,"date":"2023-06-15T15:37:57","date_gmt":"2023-06-15T13:37:57","guid":{"rendered":"http:\/\/www.sostariffe.it\/news\/?p=367884"},"modified":"2023-06-15T15:38:47","modified_gmt":"2023-06-15T13:38:47","slug":"bollette-luce-e-gas-sospesi-i-pagamenti-nelle-aree-colpite-dallalluvione","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/bollette-luce-e-gas-sospesi-i-pagamenti-nelle-aree-colpite-dallalluvione-367884\/","title":{"rendered":"Bollette luce e gas: sospesi i pagamenti nelle aree colpite dall&#8217;alluvione"},"content":{"rendered":"<p>Nella giornata di oggi, <strong>ARERA<\/strong> ha annunciato la <strong>sospensione per 4 mesi dei termini di pagamento delle bollette di luce, gas, acqua e rifiuti<\/strong> per tutte le popolazioni colpite dall&#8217;<strong>alluvione in Emilia-Romagna<\/strong>. Il provvedimento segue una misura d&#8217;emergenza adottata nelle scorse settimane e rappresenta un&#8217;attuazione del &#8220;decreto alluvione&#8221; in cui viene definito l&#8217;elenco dei Comuni interessati dal provvedimento. Vediamo, di seguito, i dettagli completi. <!--more--><\/p>\n<p><strong>ARERA<\/strong> comunica in via ufficiale la<strong> sospensione per 4 mesi<\/strong> dei termini di pagamento delle bollette di luce, gas, acqua e rifiuti. Il provvedimento segue quando previsto dal cosiddetto &#8220;<strong>decreto<\/strong> <strong>alluvione<\/strong>&#8221; (decreto-legge 61\/23) e riguarda tutte le utenze situate nei Comuni colpiti, come indicato dal decreto stesso. Vediamo i dettagli completi in merito a quanto annunciato oggi da ARERA.<\/p>\n<h2>Bollette luce e gas sospese nei Comuni colpiti dall&#8217;alluvione in Emilia-Romagna: il provvedimento di ARERA<\/h2>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><\/td>\n<td style=\"width: 50%;\"><strong>COSA HA STABILITO ARERA<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">1.<\/td>\n<td style=\"width: 50%;\">Arriva la <strong>sospensione delle bollette di luce, gas, acqua e rifiuti<\/strong> per i Comuni colpiti dall&#8217;alluvione<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">2.<\/td>\n<td style=\"width: 50%;\">Il periodo di sospensione si estende <strong>fino al 31 agosto 2023<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">3.<\/td>\n<td style=\"width: 50%;\">I clienti potranno richiedere la <strong>rateizzazione in almeno 12 mesi senza interessi<\/strong> degli importi delle bollette sospese<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Il nuovo provvedimento di ARERA prevede la<strong> sospensione per 4 mesi<\/strong> dei termini di pagamento delle bollette <strong><a href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/\">luce e gas<\/a><\/strong> oltre che delle bollette relative alle forniture di acqua e ai rifiuti per i Comuni colpiti dall&#8217;alluvione in <strong>Emilia-Romagna<\/strong> (province di Reggio-Emilia, Modena, Bologna, Ferrara, Ravenna, Forl\u00ec-Cesena e Rimini). Da notare che il provvedimento si estende anche ad alcuni Comuni situati nella <strong>provincia di Pesaro e Urbino<\/strong> e nella <strong>Citt\u00e0 metropolitana di Firenze.\u00a0<\/strong><\/p>\n<p>Sono coinvolte le fatture gi\u00e0 emesse o da emettere con scadenza fissata nel <strong>quattro mesi successivi al 1\u00b0 maggio 2023.<\/strong>\u00a0 ARERA ha chiarito, inoltre, che in un successivo provvedimento potrebbe esserci un&#8217;ulteriore estensione della sospensione con l&#8217;obiettivo di assicurare tutto il sostegno necessario alla popolazione pi\u00f9 colpita dall&#8217;alluvione anche oltre i quattro mesi del provvedimento.<\/p>\n<p>Da notare, inoltre, che i clienti potranno richiedere la<strong> rateizzazione in un periodo minimo di 12 mesi<\/strong> delle bollette sospese dal provvedimento di oggi, senza applicazioni di interessi e, quindi, senza alcun costo extra. In aggiunta, in tutto il periodo di sospensione, che terminer\u00e0 il 31 agosto 2023, \u00e8 prevista la sospensione delle azioni sulla morosit\u00e0 previste da ARERA per i clienti inadempienti (anche nel caso di morosit\u00e0 pregresse).\u00a0Tutti i venditori saranno tenuti, entro 20 giorni dalla data del provvedimento di ARERA, a pubblicare sul proprio sito web tutte le misure adottate a tutela delle utenze colpite.<\/p>\n<p>In pi\u00f9, i <strong>venditori<\/strong> potranno richiedere<strong> un anticipo a titolo gratuito sugli importi non pagati<\/strong> e per i quali \u00e8 prevista la sospensione dei termini di pagamento <em>&#8220;qualora l\u2019importo delle fatture emesse dal 1\u00b0 gennaio 2023 al 1\u00b0 maggio 2023, relativamente ai soggetti beneficiari della sospensione dei termini di pagamento, con riferimento a ciascun settore, rappresenti oltre il 3% dell\u2019importo delle fatture relative alla totalit\u00e0 degli utenti e clienti serviti&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella giornata di oggi, ARERA ha annunciato la sospensione per 4 mesi dei termini di pagamento delle bollette di luce, gas, acqua e rifiuti per tutte le popolazioni colpite dall&#8217;alluvione in Emilia-Romagna. Il provvedimento segue una misura d&#8217;emergenza adottata nelle scorse settimane e rappresenta un&#8217;attuazione del &#8220;decreto alluvione&#8221; in cui viene definito l&#8217;elenco dei Comuni [&hellip;]<\/p>\n","protected":false},"author":47,"featured_media":367889,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1095,1098],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/367884"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=367884"}],"version-history":[{"count":3,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/367884\/revisions"}],"predecessor-version":[{"id":367891,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/367884\/revisions\/367891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/367889"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=367884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=367884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=367884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}