{"id":367539,"date":"2023-06-13T13:00:53","date_gmt":"2023-06-13T11:00:53","guid":{"rendered":"http:\/\/www.sostariffe.it\/news\/?p=367539"},"modified":"2023-06-25T12:52:48","modified_gmt":"2023-06-25T10:52:48","slug":"assicurazioni-auto-aumentano-i-reclami-verso-le-compagnie-estere","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/assicurazioni-auto-aumentano-i-reclami-verso-le-compagnie-estere-367539\/","title":{"rendered":"Assicurazioni auto: aumentano i reclami verso le compagnie estere"},"content":{"rendered":"<p><strong>Balzo all\u2019ins\u00f9 dei reclami<\/strong> dei consumatori contro le compagnie assicurative estere in Italia nel 2022: <strong>+26,04%<\/strong> rispetto al 2021. E il comparto <strong>RC Auto \u00e8 il pi\u00f9 bersagliato<\/strong> dalle lamentele dei clienti. L\u2019analisi del report 2022 dell\u2019Autorit\u00e0 nazionale di vigilanza delle assicurazioni (IVASS) e un focus su <strong>come trovare la miglior polizza<\/strong> per il proprio veicolo <strong>a giugno 2023<\/strong>. <!--more--><\/p>\n<p><strong>Impennata dei reclami<\/strong> contro le compagnie assicurative estere che operano in Italia: le \u201cliti\u201d tra i clienti e queste societ\u00e0 <strong>sono aumentate del 26,04%<\/strong> nel 2022 rispetto al 2021, con un balzo di circa <strong>il 59%<\/strong> nel<strong> comparto RC auto<\/strong>. Lo rivela l\u2019<strong>IVASS<\/strong>, l\u2019Istituto per la vigilanza sulle assicurazioni, nel suo report 2022.<\/p>\n<p>Prima di passare ai raggi X le cifre contenute nell\u2019analisi dell\u2019Authority italiana, \u00e8 opportuno ricordare che, per scegliere l\u2019assicurazione auto con il miglior rapporto qualit\u00e0\/prezzo di <strong>giugno 2023<\/strong>, \u00e8 bene affidarsi al confronto online dei preventivi, cos\u00ec da avere un quadro completo e dettagliato delle migliori opzioni di polizza auto attualmente sul mercato.<\/p>\n<p>Un alleato in questa ricerca \u00e8 il <strong>comparatore di SOStariffe.it<\/strong> per <strong>assicurazioni auto<\/strong>, disponibile cliccando sul link qui di sotto. Grazie a questo strumento, gratuito e digitale, \u00e8 possibile scegliere la polizza pi\u00f9 vantaggiosa.<\/p>\n<p><a class=\"green-cta\" style=\"width: 300px; height: 30px; line-height: 30px; font-size: 15px;\" href=\"https:\/\/www.sostariffe.it\/assicurazioni\/assicurazione-auto\/preventivo1.html\">Scopri la migliore polizza auto di giugno 2023<span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Il sistema funziona in modo molto intuitivo: dopo aver inserito i propri dati (anagrafici, assicurativi e del veicolo), il comparatore restituir\u00e0 una serie di preventivi, \u201cclassificandoli\u201d <strong>in base alla convenienza<\/strong> e tenendo conto dei prezzi reali delle polizze proposte dalle principali compagnie assicurative.<\/p>\n<h2>Balzo all\u2019insu per i reclami alle assicurazioni estere nel 2022: +26,04%<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 168px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 25%; height: 24px; text-align: center;\"><strong>TIPOLOGIA IMPRESE<\/strong><\/td>\n<td style=\"width: 25%; height: 24px; text-align: center;\"><strong>TOTALE RECLAMI VITA E DANNI<\/strong><\/td>\n<td style=\"width: 25%; height: 24px; text-align: center;\"><strong>TOTALE RECLAMI RC AUTO<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td style=\"width: 25%; height: 48px;\"><strong>Imprese italiane<\/strong><\/td>\n<td style=\"width: 25%; height: 48px;\">78.120 reclami nel 2022 (<strong>+0,13%<\/strong> rispetto al 2021)<\/td>\n<td style=\"width: 25%; height: 48px;\">32.149 reclami nel 2022 (<strong>+0,18%<\/strong> rispetto al 2021, quando erano stati 32.092)<\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td style=\"width: 25%; height: 48px;\"><strong>Imprese estere (UE)<\/strong><\/td>\n<td style=\"width: 25%; height: 48px;\">18.856 reclami nel 2022 (<strong>+26,04%<\/strong> rispetto al 2021)<\/td>\n<td style=\"width: 25%; height: 48px;\">9.278 reclami nel 2022 (<strong>+58,87%<\/strong>\u00a0rispetto al 2021, quando erano stati 5.840)<\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td style=\"width: 25%; height: 48px;\"><strong>Totale<\/strong><\/td>\n<td style=\"width: 25%; height: 48px;\">96.976 reclami nel 2022 (<strong>+4,3%<\/strong> rispetto al 2021)<\/td>\n<td style=\"width: 25%; height: 48px;\">41.427 reclami nel 2022 (<strong>+9,21%<\/strong> rispetto al 2021)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Secondo quanto si legge nell\u2019analisi di IVASS, nel 2022 le imprese di assicurazione operanti in Italia (sia italiane sia estere) <strong>hanno ricevuto in totale<\/strong> <strong>96.976 reclami<\/strong> da parte dei consumatori, con un incremento del <strong>4,3%<\/strong> rispetto al 2021 (quando i reclami complessivi erano stati <strong>92.975<\/strong>).<\/p>\n<p>Nel dettaglio:<\/p>\n<ul>\n<li>il <strong>42,7%<\/strong> delle rimostranze nel 2022 ha riguardato il settore <strong>RC auto<\/strong>;<\/li>\n<li>il <strong>39,8%<\/strong> dei reclami ha riguardato gli altri <strong>rami danni<\/strong>;<\/li>\n<li>il <strong>17,5%<\/strong> ha interessato i <strong>rami vita<\/strong>.<\/li>\n<\/ul>\n<p>Per quanto il numero dei reclami ricevuti dalle compagnie italiane vigilate dall\u2019Authority sia rimasto stabile nel 2022 (78.120, con un <strong>+0,13%<\/strong> rispetto ai 78.015 del 2021), le lagnanze contro le imprese assicurative estere operanti in Italia hanno subito <strong>un\u2019impennata<\/strong>, registrando<strong> una crescita del 26,04% <\/strong>nel 2022 rispetto ai dodici mesi precedenti.<\/p>\n<p>L\u2019incremento, come si legge ancora nel report, riguarda in particolare il ramo RC auto (<strong>+58,87%<\/strong>), ma interessa in maniera significativa anche gli altri rami danni (<strong>+12,58%<\/strong>). Tuttavia, per i rami vita, l&#8217;analisi delle cifre 2022 di IVASS rileva una diminuzione (<strong>-7,57%<\/strong>): i reclami nel 2022 sono stati <strong>3.162<\/strong> contro i 3.421 del 2021.<\/p>\n<p>&#8220;<em>Rispetto al 2021<\/em> &#8211; si legge nell&#8217;analisi dell&#8217;Authority &#8211; <em>si registra un incremento del 4,3%, a fronte della sostanziale stabilit\u00e0 rilevata nel periodo 2021\/2020. La tendenza all\u2019aumento appare in linea con quella gi\u00e0 evidenziata nel I semestre 2022 rispetto al I semestre 2021 e conferma in particolare la crescita dei reclami nei confronti delle imprese estere per problematiche connesse alla gestione dei sinistri RC auto&#8221;<\/em>.<\/p>\n<p>Quanto all\u2019esito del volume totale dei reclami inoltrati nel 2022:<\/p>\n<ul>\n<li><strong>circa<\/strong> <strong>il 32% \u00e8 stato accolto<\/strong>;<\/li>\n<li><strong>il 10% si \u00e8 concluso con una transazione<\/strong>;<\/li>\n<li><strong>il 58% \u00e8 stato respinto<\/strong>.<\/li>\n<\/ul>\n<p>Il tempo medio di risposta \u00e8 stato di 22 giorni, sotto la soglia normativamente prevista di 45 giorni.<\/p>\n<p>Segnaliamo ai lettori di SOStariffe.it che le imprese che entrano nel radar dell&#8217;indagine IVASS sono:<\/p>\n<ul>\n<li><strong>imprese italiane<\/strong> autorizzate dall\u2019IVASS;<\/li>\n<li><strong>rappresentanze extra UE<\/strong> autorizzate dall\u2019IVASS;<\/li>\n<li>imprese con <strong>sede legale in un Paese dell\u2019Unione Europea<\/strong> operanti in regime di <strong>stabilimento\/libera prestazione dei servizi<\/strong>.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Balzo all\u2019ins\u00f9 dei reclami dei consumatori contro le compagnie assicurative estere in Italia nel 2022: +26,04% rispetto al 2021. E il comparto RC Auto \u00e8 il pi\u00f9 bersagliato dalle lamentele dei clienti. L\u2019analisi del report 2022 dell\u2019Autorit\u00e0 nazionale di vigilanza delle assicurazioni (IVASS) e un focus su come trovare la miglior polizza per il proprio [&hellip;]<\/p>\n","protected":false},"author":108,"featured_media":367540,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4028],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/367539"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=367539"}],"version-history":[{"count":15,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/367539\/revisions"}],"predecessor-version":[{"id":367764,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/367539\/revisions\/367764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/367540"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=367539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=367539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=367539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}