{"id":365063,"date":"2023-04-28T14:00:59","date_gmt":"2023-04-28T12:00:59","guid":{"rendered":"http:\/\/www.sostariffe.it\/news\/?p=365063"},"modified":"2023-05-01T10:30:14","modified_gmt":"2023-05-01T08:30:14","slug":"poste-luce-e-gas-debutto-positivo-sul-mercato-ecco-le-offerte-di-maggio-2023","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/poste-luce-e-gas-debutto-positivo-sul-mercato-ecco-le-offerte-di-maggio-2023-365063\/","title":{"rendered":"Poste Luce e Gas: debutto positivo sul mercato, ecco le offerte di maggio 2023"},"content":{"rendered":"<p>Pi\u00f9 di <strong>200mila contratti<\/strong> per le <strong>soluzioni luce e gas di Poste Energia<\/strong>, il nuovo ramo d\u2019azienda di Poste Italiane. Caratteristiche, condizioni tariffarie e modalit\u00e0 di pagamento a <strong>maggio 2023<\/strong> e un confronto con le <strong>migliori offerte <\/strong>del Mercato Libero. <!--more--><\/p>\n<p>L\u2019offerta luce e gas retail di <strong>Poste Energia<\/strong>, il cui debutto nel <a href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/faq\/cosa-succede-se-non-si-aderisce-al-mercato-libero-luce-e-gas\"><strong>Mercato Libero<\/strong><\/a> risale a febbraio 2023, raccoglie consensi e macina nuovi contratti lungo la Penisola. Stando alle cifre rese note dal quotidiano economico <em>Milano Finanza<\/em>, in meno di tre mesi sono gi\u00e0 state superate le <strong>200mila sottoscrizioni<\/strong>. Alla fine di marzo 2023, i contratti di fornitura sottoscritti erano i <strong>150mila<\/strong>, come confermato da Matteo Del Fante, l\u2019amministratore delegato di Poste Italiane, in occasione della presentazione del bilancio 2022 avvenuta il 30 marzo 2023.<\/p>\n<p>\u201c<em>Gi\u00e0 150mila contratti, vuol dire che siamo sulla buona strada per superare i 300mila nel 2023<\/em>\u201d, aveva commentato il numero uno del gruppo in quell\u2019occasione.\u00a0Archiviato il primo (positivo) traguardo, Poste Energia (la nuova business unit di <strong>Poste Italiane<\/strong>) guarda ora al futuro: l\u2019obiettivo, secondo quanto pubblicato da Milano Finanza, \u00e8 quello di erogare energia elettrica e gas <strong>a 1,5 milioni di clienti entro il 2025<\/strong>.<\/p>\n<p>Ecco le caratteristiche della proposta commerciale di Poste Energia a maggio 2023 passate sotto la lente d\u2019ingrandimento dagli esperti di SOStariffe.it. Pi\u00f9 un confronto tra le soluzioni di Poste Energia e le migliori <a href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/\"><strong>offerte luce e gas<\/strong><\/a> del Mercato Libero attualmente attivabili.<\/p>\n<h2>Poste Luce e Gas: le offerte a prezzo bloccato a Maggio 2023<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 263px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 33.3333%; height: 24px; text-align: center;\"><strong>OFFERTE AL MICROSCOPIO<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px; text-align: center;\"><strong>FORNITURA DI ENERGIA<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px; text-align: center;\"><strong>FORNITURA DI GAS<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 33.3333%; height: 23px;\"><strong>Tipologia di tariffa<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 23px;\">Offerta a<strong> prezzo bloccato per 2 anni<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 23px;\">Offerta a <strong>prezzo bloccato per 2 anni<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 33.3333%; height: 24px;\"><strong>Costo della materia prima<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px;\"><strong>0,2475 \u20ac\/kWh<\/strong> (tariffa monoraria)<\/td>\n<td style=\"width: 33.3333%; height: 24px;\"><strong>0,894 \u20ac\/Smc<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 33.3333%; height: 24px;\"><strong>Costo fisso di commercializzazione<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px;\">69,17 euro all&#8217;anno<\/td>\n<td style=\"width: 33.3333%; height: 24px;\">63,36 euro all&#8217;anno<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 33.3333%; height: 24px;\"><strong>Sostenibilit\u00e0 delle offerte<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px;\">Energia elettrica <strong>100% green\u00a0<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 24px;\">Emissioni di <strong>CO\u2082 compensate<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 120px;\">\n<td style=\"width: 33.3333%; height: 120px;\"><strong>Metodo di pagamento<\/strong><\/td>\n<td style=\"width: 33.3333%; height: 120px;\">A scelta tra:<\/p>\n<ul>\n<li>paga quanto consumi<\/li>\n<li>rata fissa senza sorprese<\/li>\n<\/ul>\n<\/td>\n<td style=\"width: 33.3333%; height: 120px;\">A scelta tra:<\/p>\n<ul>\n<li>paga quanto consumi<\/li>\n<li>rata fissa senza sorprese<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Le offerte luce e gas di Poste Energia sono <strong>a prezzo bloccato <\/strong>per 24 mesi. Che cosa significa? Che il costo unitario della materia prima (espresso in <strong>\u20ac\/kWh<\/strong> per l\u2019elettricit\u00e0 ed <strong>\u20ac\/Smc<\/strong> per il gas) <strong>rester\u00e0 fisso<\/strong> per tutta la durata del contratto di fornitura: <strong>due anni<\/strong>.<\/p>\n<p>Ecco le condizioni tariffarie messe a punto da Poste Energia e valide per i nuovi clienti che sottoscrivano le promozioni entro il <strong>9 maggio 2023<\/strong>:<\/p>\n<ul>\n<li>l\u2019energia elettrica costa <strong>0,2475 \u20ac\/kWh<\/strong> (tariffa monoraria);<\/li>\n<li>il metano costa <strong>0,894 \u20ac\/Smc<\/strong>.<\/li>\n<\/ul>\n<p>\u00c8 previsto anche il pagamento di un contributo fisso annuale per spese di commercializzazione (indipendente quindi dal consumo) che si attesta sui <strong>69,17 euro<\/strong> per la fornitura di energia elettrica e sui <strong>63,36 euro<\/strong> per quella del gas.<\/p>\n<p>Con energia elettrica 100% green ed emissioni di CO\u2082 compensate, l\u2019offerta commerciale di Poste Energia si caratterizza anche per la <strong>duplice opzione di pagamento<\/strong>:<\/p>\n<ul>\n<li>tradizionale, ovvero basata sulla filosofia del \u201c<strong>paghi quanto consumi<\/strong>\u201d: l\u2019importo in bolletta varia in base all\u2019andamento dei consumi nel mese di riferimento;<\/li>\n<li>innovativa, cio\u00e8 <strong>a rata fissa e senza sorprese<\/strong>: in pratica, si paga lo stesso importo mensile per 12 mesi (la rata \u00e8 inizialmente calcolata analizzando i consumi dell\u2019anno precedente l\u2019attivazione dell\u2019offerta con Poste Energia). Alla fine del primo anno, la rata sar\u00e0 ricalcolata per i dodici mesi successivi, in aumento o in calo rispetto ai consumi effettivi.<\/li>\n<\/ul>\n<p>Alla sottoscrizione delle offerte luce e gas con Poste Energia (in uno dei <strong>12.800 uffici postali<\/strong>, sul sito<strong> Poste.it<\/strong> o con <strong>Postepay e BancoPosta<\/strong>) non saranno applicati costi di attivazione ed \u00e8 possibile disdire quando si vuole, senza penali. Eventuali differenze tra i consumi coperti con la rata fissa e quelli realmente effettuati in corso di fornitura saranno addebitati o accreditati in un\u2019unica soluzione nella bolletta di chiusura.<\/p>\n<h2>Poste Energia: il confronto con le migliori offerte luce e gas di Maggio 2023<\/h2>\n<p>Essendo<strong> a prezzo bloccato<\/strong>, le offerte luce e gas di Poste Energia propongono un prezzo della materia prima pi\u00f9 alto, se confrontato con le migliori <strong>tariffe a prezzo indicizzato<\/strong> del Mercato Libero.<\/p>\n<p>Le offerte indicizzate, infatti, garantiscono l\u2019accesso al <strong>prezzo all\u2019ingrosso<\/strong> della materia prima e sono legate all\u2019andamento di un indice di riferimento aggiornato mensilmente, che per l&#8217;energia elettrica \u00e8 il <a href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/faq\/cos-e-il-pun-prezzo-unico-nazionale-e-come-si-calcola\"><strong>PUN<\/strong><\/a> (Prezzo Unico Nazionale), mentre per il gas \u00e8 il <a href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/glossario\/psv\"><strong>PSV<\/strong><\/a> (Punto di Scambio Virtuale). Pi\u00f9 il valore di tali indici frena (proprio come avviene da inizio 2023), minore \u00e8 il costo della materia prima e pi\u00f9 snelle sono le bollette per i clienti finali, a parit\u00e0 di consumi effettuati.<\/p>\n<p>In questo momento in cui i prezzi dei beni energetici <strong>sono in discesa<\/strong>, le offerte che <strong>pi\u00f9 intercettano tale parabola<\/strong> sono proprio le offerte luce e gas a prezzo indicizzato. I clienti domestici che le scegliessero, potrebbero infatti ridurre il costo della materia prima fino a:<\/p>\n<ul>\n<li><strong>0,1363 \u20ac\/kWh<\/strong> per l\u2019energia elettrica (valore del PUN a marzo 2023, l&#8217;ultimo a disposizione);<\/li>\n<li><strong>0,4936 \u20ac\/Smc<\/strong> per il gas naturale (valore del PSV a marzo 2023, l&#8217;ultimo a disposizione).<\/li>\n<\/ul>\n<p>Per chi, invece, preferisca puntare sulle<strong> offerte luce e gas a prezzo fisso <\/strong>(uno scudo di protezione nel caso di improvvise impennate dei prezzi) \u00e8 possibile ridurre i costi fino a:<\/p>\n<ul>\n<li><strong>0,1975 \u20ac\/kWh<\/strong> per l\u2019energia elettrica;<\/li>\n<li><strong>0,7500 \u20ac\/Smc <\/strong>per il gas naturale;<\/li>\n<\/ul>\n<p>Sia che propongano tariffe a\u00a0<strong><a href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/faq\/prezzo-fisso-o-indicizzato-luce-e-gas-quale-scegliere\">prezzo fisso o indicizzato<\/a><\/strong>, le migliori <strong>offerte luce e gas<\/strong> del Mercato Libero possono essere individuate grazie al<strong> comparatore di SOStariffe.it<\/strong>. Per trarre il massimo vantaggio da questo tool gratuito \u00e8 necessario inserire una stima del proprio consumo annuo (tale informazione \u00e8 sempre disponibile in bolletta oppure pu\u00f2 essere stimata tramite i filtri integrati nel comparatore stesso).<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/\" target=\"_blank\" rel=\"noopener noreferrer\">SCOPRI LE MIGLIORI OFFERTE LUCE E GAS <span style=\"\u201ctext-align: right&quot;;\">\u00bb<\/span><\/a><\/p>\n<p>Una volta individuata l&#8217;offerta pi\u00f9 in linea con le proprie esigenze si pu\u00f2 procedere con l&#8217;attivazione della promozione stessa sul sito del fornitore scelto. Per completare la procedura online bastano i dati anagrafici dell\u2019intestatario e il codice identificativo della fornitura (<strong>POD<\/strong> per la luce e <strong>PDR<\/strong> per il gas).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pi\u00f9 di 200mila contratti per le soluzioni luce e gas di Poste Energia, il nuovo ramo d\u2019azienda di Poste Italiane. Caratteristiche, condizioni tariffarie e modalit\u00e0 di pagamento a maggio 2023 e un confronto con le migliori offerte del Mercato Libero.<\/p>\n","protected":false},"author":108,"featured_media":365064,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1095,1098,64],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/365063"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=365063"}],"version-history":[{"count":14,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/365063\/revisions"}],"predecessor-version":[{"id":365188,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/365063\/revisions\/365188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/365064"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=365063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=365063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=365063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}