{"id":362473,"date":"2023-03-16T10:22:58","date_gmt":"2023-03-16T09:22:58","guid":{"rendered":"http:\/\/www.sostariffe.it\/news\/?p=362473"},"modified":"2023-03-16T22:27:02","modified_gmt":"2023-03-16T21:27:02","slug":"crolla-il-consumo-di-gas-in-italia-nel-2023-ecco-come-ridurre-le-bollette","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/crolla-il-consumo-di-gas-in-italia-nel-2023-ecco-come-ridurre-le-bollette-362473\/","title":{"rendered":"Crolla il consumo di gas in Italia nel 2023: ecco come ridurre le bollette"},"content":{"rendered":"<p>Uno dei sistemi per contrastare la crisi energetica e l&#8217;aumento dei prezzi di luce e gas \u00e8 rappresentato dal taglio dei consumi. Questo stratagemma trova sempre pi\u00f9 diffusione in Italia. Nel corso degli ultimi mesi, infatti, <strong>i consumi di gas in Italia sono calati in modo netto<\/strong> nel confronto con i dati dello scorso anno. Si tratta di un trend oramai consolidato. Ecco gli ultimi numeri sulla questione e come sfruttare al massimo il taglio dei consumi per massimizzare il risparmio. <!--more--><\/p>\n<p><strong>In Italia si consuma sempre meno gas<\/strong>. Il calo dei consumi su base annuale va avanti da diversi mesi e rappresenta una <strong>chiara contromisura alla crisi energetica<\/strong> che, nel corso dell&#8217;ultimo anno e mezzo, ha spinto verso l&#8217;alto i prezzi al dettaglio dell&#8217;energia elettrica (prodotta anche tramite gas naturale) e del gas. A pesare sulla questione c&#8217;\u00e8 anche un inverno pi\u00f9 mite rispetto alle medie stagionali che ha portato ad un ricorso inferiore ai riscaldamenti.<\/p>\n<p>Ecco, quindi, i numeri sui consumi di gas in Italia:<\/p>\n<h2>Cala il consumo di gas in Italia: ecco i numeri<\/h2>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><\/td>\n<td style=\"width: 50%; text-align: center;\"><strong>3 COSE DA SAPERE SUL CALO DEI CONSUMI DI GAS IN ITALIA<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">1.<\/td>\n<td style=\"width: 50%;\">Nel <strong>2022<\/strong> si \u00e8 registrato un calo dei consumi del <strong>-10%<\/strong> rispetto al 2021<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">2.<\/td>\n<td style=\"width: 50%;\">A <strong>gennaio<\/strong> <strong>2023<\/strong> i consumi di gas sono calati del <strong>-22%<\/strong> rispetto a gennaio 2021<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">3.<\/td>\n<td style=\"width: 50%;\">La <strong>produzione<\/strong> <strong>interna<\/strong> di gas ora copre <strong>meno del 5% del fabbisogno italiano<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Dalla <strong>seconda met\u00e0 del 2022<\/strong> si registra un <strong>costante calo dei consumi di gas in Italia<\/strong>. Come chiarito dai dati riportati da IlSole24Ore, il primo semestre del 2022, infatti, ha fatto registrare consumi in linea con lo stesso periodo del 2021 (nonostante un costo medio del gas decisamente superiore). Gi\u00e0 con le prime settimane di autunno (subito dopo il picco del costo del gas all&#8217;ingrosso), per\u00f2, si \u00e8 iniziato a registrare un evidente trend in discesa.<\/p>\n<p>Ecco i dati degli <strong>ultimi quattro mesi del 2022<\/strong> nel confronto con lo stesso periodo del 2021:<\/p>\n<ul>\n<li>settembre 2022: -17%<\/li>\n<li>ottobre 2022: -24%<\/li>\n<li>novembre 2022: -27%<\/li>\n<li>dicembre 2022: &#8211;24%<\/li>\n<\/ul>\n<p>Complessivamente, <strong>nel 2022 l&#8217;Italia ha consumato 68,5 miliardi di metri cubi di gas<\/strong>, in calo del <strong>-10% rispetto al 2021<\/strong> quando il totale di gas consumato arriv\u00f2 a 76 miliardi di metri cubi all&#8217;anno.\u00a0Il trend di fine 2022 \u00e8 confermato ad inizio 2023. Nel corso del mese di <strong>gennaio<\/strong> <strong>2023<\/strong>, infatti, i consumi complessivi di gas si sono fermati a <strong>7,5 miliardi di metri cubi <\/strong>con un<strong> calo del -22%<\/strong> rispetto allo stesso periodo dello scorso anno. Il calo \u00e8 sostanzialmente in linea con quanto gi\u00e0 emerso nei mesi precedenti e conferma una tendenza chiara alla riduzione dei consumi di gas naturale in Italia.<\/p>\n<p>A spiegare il calo dei consumi \u00e8 <strong>Davide Tabarelli, presidente di Nomisma Energia<\/strong>, che sottolinea: <em>&#8220;Dai numeri di gennaio, che dovrebbero essere confermati anche dal bilancio di febbraio, l\u2019aspetto pi\u00f9 evidente \u00e8 il crollo della domanda di gas. Una tale contrazione non pu\u00f2 essere spiegata solamente con il clima pi\u00f9 mite. E neppure \u00e8 ipotizzabile un repentino efficientamento degli impianti, sia domestici che industriali. L\u2019ipotesi pi\u00f9 probabile \u00e8 che la gente abbia tagliato i consumi. Insieme a un calo dell\u2019attivit\u00e0 economica al momento nascosto dall\u2019aumento dei prezzi. Quando la tendenza a ridurre i consumi \u00e8 cos\u00ec pronunciata potrebbe portare a una recessione&#8221;.<\/em><\/p>\n<p>Da notare, invece, che \u00e8 <strong>aumentata la produzione nazionale di gas<\/strong> con un totale di <strong>279 milioni di metri cubi estratti a gennaio<\/strong>, in crescita del <strong>+7%<\/strong> rispetto allo stesso periodo dello scorso anno. Complessivamente, nel <strong>2022<\/strong> sono stati estratti <strong>3,3 miliardi di metri cubi di gas in Italia<\/strong>, con un calo del <strong>-0,8%<\/strong> rispetto al <strong>2021 <\/strong>nonostante gli sforzi per incrementare il pi\u00f9 possibile le estrazioni in modo da ridurre la dipendenza dalle importazioni<strong>. <\/strong>La <strong>produzione interna<\/strong>, quindi, <strong>copre meno del 5% del fabbisogno nazionale<\/strong> di gas naturale considerando i dati di consumo del 2022.<\/p>\n<p>[WIDGET-ENERGY]<\/p>\n<h2>Il taglio dei consumi non basta a ridurre le bollette: per risparmiare serve l&#8217;offerta giusta<\/h2>\n<p>Per <strong>massimizzare il risparmio<\/strong> in bolletta <strong>non \u00e8 sufficiente limitarsi a tagliare i consumi<\/strong>. Questo vale sia per l&#8217;energia elettrica che per il gas naturale. Il risparmio, infatti, \u00e8 legato a due fattori:<\/p>\n<ul>\n<li>il t<strong>aglio dei consumi<\/strong> che pu\u00f2 essere raggiunto riducendo gli sprechi e puntando sull&#8217;efficienza energetica<\/li>\n<li>la <strong>riduzione del costo unitario dell&#8217;energia<\/strong> accessibile solo puntando sulle <strong>migliori tariffe luce e gas<\/strong> sul mercato<\/li>\n<\/ul>\n<p>Abbinando questi due elementi si pu\u00f2 raggiungere il massimo risparmio, andando ad alleggerire le bollette senza modificare troppo le proprie abitudini e, soprattutto, senza rendere vani i sacrifici necessari per tagliare i consumi di energia elettrica e gas naturale. Si tratta di un elemento centrale per raggiungere l&#8217;obiettivo del risparmio. Seguire solo uno dei due punti non permetter\u00e0 di raggiungere il massimo risparmio.<\/p>\n<p>Per <strong>ridurre il costo dell&#8217;energia<\/strong>, quindi, \u00e8 necessario puntare sulle<strong> migliori offerte luce e gas del Mercato Libero<\/strong>. Tali offerte sono accessibili, facilmente, tramite il <strong>comparatore di SOStariffe.it.<\/strong> Basta cliccare sul link qui di sotto per accedere al tool di comparazione, gratuito e imparziale. Inserendo una<strong> stima del proprio consumo annuo<\/strong> (il dato \u00e8 riportato in bolletta ma pu\u00f2 essere calcolato anche tramite il comparatore) si acceder\u00e0 ad una panoramica completa delle tariffe pi\u00f9 vantaggiose, ordinate in base alla convenienza.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/\" target=\"_blank\" rel=\"noopener noreferrer\">Scopri qui le migliori offerte luce e gas <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Una volta scelta la tariffa giusta, quindi, si potr\u00e0 passare all&#8217;<strong>attivazione online<\/strong>, raggiungendo il sito del fornitore che la propone. Per <strong>attivare un nuovo contratto luce o gas<\/strong> \u00e8 necessario avere a disposizione:<\/p>\n<ul>\n<li>i <strong>dati anagrafici<\/strong> dell&#8217;<strong>intestatario<\/strong> della fornitura<\/li>\n<li>i <strong>dati della fornitura<\/strong> come il codice <strong>POD<\/strong> per la luce e il codice <strong>PDR<\/strong> per il gas (entrambi i codici sono riportati in bolletta)<\/li>\n<\/ul>\n<p>Per assistenza nella scelta \u00e8 possibile affidarsi al <strong>servizio di consulenza di SOStariffe.it<\/strong>, disponibile al numero <strong>02 5005 111<\/strong>. Il servizio \u00e8 gratuito e senza alcun impegno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno dei sistemi per contrastare la crisi energetica e l&#8217;aumento dei prezzi di luce e gas \u00e8 rappresentato dal taglio dei consumi. Questo stratagemma trova sempre pi\u00f9 diffusione in Italia. Nel corso degli ultimi mesi, infatti, i consumi di gas in Italia sono calati in modo netto nel confronto con i dati dello scorso anno. [&hellip;]<\/p>\n","protected":false},"author":47,"featured_media":362474,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1095,1098],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/362473"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=362473"}],"version-history":[{"count":1,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/362473\/revisions"}],"predecessor-version":[{"id":362475,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/362473\/revisions\/362475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/362474"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=362473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=362473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=362473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}