{"id":362094,"date":"2023-03-10T11:00:29","date_gmt":"2023-03-10T10:00:29","guid":{"rendered":"http:\/\/www.sostariffe.it\/news\/?p=362094"},"modified":"2023-03-12T16:10:53","modified_gmt":"2023-03-12T15:10:53","slug":"iva-su-utenze-luce-e-gas-a-quanto-ammonta-a-marzo-2023","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/iva-su-utenze-luce-e-gas-a-quanto-ammonta-a-marzo-2023-362094\/","title":{"rendered":"Iva su utenze luce e gas: a quanto ammonta a Marzo 2023?"},"content":{"rendered":"<p><strong>Iva ridotta al 5% sul gas<\/strong> e <strong>azzeramento degli oneri impropri<\/strong> delle bollette sono due misure del governo contro il caro-energia in vigore <strong>fino al 31 marzo 2023<\/strong>. Le associazioni dei consumatori in pressing sul governo: \u201cStangata in arrivo senza proroga degli sconti\u201d. <!--more--><\/p>\n<p>La <strong>riduzione dell\u2019Iva al 5%<\/strong> per il gas e <strong>l\u2019azzeramento degli oneri generali di sistema<\/strong> per le bollette sono due interventi statali che hanno contribuito a mitigare l\u2019impatto delle <a href=\"https:\/\/www.sostariffe.it\/news\/luce-e-gas-fino-a-un-quarto-dello-stipendio-medio-per-il-pagamento-delle-utenze-361743\/\"><strong>spese alle stelle per elettricit\u00e0 e metano<\/strong><\/a>\u00a0dei mesi scorsi.<\/p>\n<p>Dalla fine del 2021 e per tutto il 2022, infatti, queste misure (varate prima dal governo Draghi e poi confermate dall\u2019esecutivo Meloni) hanno aiutato le famiglie italiane a fronteggiare una crisi energetica che ha avuto e continua ad avere pesanti conseguenze sul tessuto economico e sociale del nostro Paese.<\/p>\n<p>Grazie al taglio degli oneri impropri delle bollette, \u00e8 stata di fatto <strong>eliminata una voce dalla bolletta<\/strong> per <strong>32 milioni di utenze<\/strong>, andando cos\u00ec ad assottigliare l\u2019importo finale. Anche il <strong>taglio temporaneo dell\u2019Iva al 5% per il gas<\/strong> ha contribuito a tamponare l\u2019aumento degli importi in fattura: a regime normale, infatti, l\u2019Iva si attesterebbe al 10% per le famiglie.<\/p>\n<p>Tuttavia, questi due interventi statali <strong>sono ormai in scadenza<\/strong>: la manovra di Bilancio 2023 (L.197\/2022) ne assicura l\u2019operativit\u00e0 sino al <strong>31 marzo 2023<\/strong>. Cos\u00ec, in assenza di una proroga, da aprile 2023 si torner\u00e0 alle condizioni ordinarie.<\/p>\n<p>Se dal governo le bocche sono cucite su un\u2019eventuale proroga, ad alzare la voce sono per\u00f2 le associazioni dei consumatori che lanciano l\u2019allarme per una nuova stangata all\u2019orizzonte in assenza dei rinnovi degli sconti.<\/p>\n<h2>Associazioni dei consumatori: stangata in arrivo senza una proroga degli sconti<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 200px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\"><strong>TAGLIO IVA AL 5% E ONERI DI SISTEMA: LE DOMANDE<\/strong><\/td>\n<td style=\"width: 50%; height: 24px;\"><strong>TAGLIO IVA AL 5% E ONERI DI SISTEMA: LE RISPOSTE<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 104px;\">\n<td style=\"width: 50%; height: 104px;\"><strong>Cosa prevedono queste due misure?<\/strong><\/td>\n<td style=\"width: 50%; height: 104px;\">\n<ul>\n<li><strong>Taglio temporaneo dell&#8217;Iva al 5% <\/strong>per il gas<\/li>\n<li><strong>Azzeramento degli oneri impropri<\/strong> delle bollette luce e gas<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\"><strong>Quando sono state introdotte queste misure?<\/strong><\/td>\n<td style=\"width: 50%; height: 24px;\">\n<ul>\n<li>Sono state <strong style=\"font-family: inherit; font-size: inherit;\">varate dal governo Draghi<\/strong><span style=\"font-family: inherit; font-size: inherit;\"> e confermate dall&#8217;esecutivo Meloni nella <\/span><strong style=\"font-family: inherit; font-size: inherit;\">manovra di Bilancio 2023<\/strong><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\"><strong>Quando scadono questi due interventi statali?<\/strong><\/td>\n<td style=\"width: 50%; height: 24px;\">\n<ul>\n<li>Il <strong style=\"font-family: inherit; font-size: inherit;\">31 marzo 2023<\/strong><span style=\"font-family: inherit; font-size: inherit;\">, in assenza di eventuali proroghe da parte del governo<\/span><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\"><strong>Cosa temono le associazioni dei consumatori?<\/strong><\/td>\n<td style=\"width: 50%; height: 24px;\">\n<ul>\n<li>Per <strong style=\"font-family: inherit; font-size: inherit;\">Assoutenti<\/strong><span style=\"font-family: inherit; font-size: inherit;\"> e <\/span><strong style=\"font-family: inherit; font-size: inherit;\">Unione nazionale consumatori<\/strong><span style=\"font-family: inherit; font-size: inherit;\">, il mancato rinnovo di queste due misure porter\u00e0 una <\/span><strong style=\"font-family: inherit; font-size: inherit;\">nuova stangata in bolletta<\/strong><span style=\"font-family: inherit; font-size: inherit;\"> per le famiglie italiane<\/span><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>L\u2019appello al governo \u00e8 comune. Da Assoutenti all\u2019Unc, le<strong> associazioni a tutela dei consumatori<\/strong> invocano l\u2019esecutivo di centrodestra guidato dalla premier Giorgia Meloni di prorogare, dal prossimo 31 marzo, gli sconti attualmente in vigore sulle fatture di luce e gas.<\/p>\n<p>\u201c<em>Gli oneri di sistema in bolletta pesano fino al 22% sulle bollette della luce e per circa il 5% su quelle del gas, e il loro mancato azzeramento a partire dal prossimo 31 marzo rischia di vanificare del tutto la riduzione delle tariffe registrata negli ultimi due mesi<\/em>\u201d, lancia l\u2019allarme in una nota <strong>Assoutenti<\/strong>, che teme che una nuova stangata sia all\u2019orizzonte per le famiglie italiane in assenza di un intervento del governo sul fronte delle agevolazioni.<\/p>\n<p>&#8220;<em>Il prossimo 31 marzo scadr\u00e0 l\u2019azzeramento degli oneri di sistema introdotto dal Governo per il primo trimestre del 2023<\/em> &#8211; spiega il presidente di Assoutenti, <strong>Furio Truzzi<\/strong> &#8211; <em>Questo significa che, in assenza di una proroga della misura, la tassazione sulle bollette degli italiani torner\u00e0 a salire<\/em>\u201d gi\u00e0 da aprile, \u201c<em>vanificando del tutto le riduzioni delle tariffe registrate nell&#8217;ultimo periodo<\/em>\u201d.<\/p>\n<p>Ecco perch\u00e9 Assoutenti chiede al governo la convocazione di un tavolo con <strong>i ministri Pichetto, Urso e Giorgetti<\/strong> per \u201c<em>affrontare il tema delle tariffe<\/em>\u201d e \u201c<em>prevenire una nuova impennata delle bollette operando sulla tassazione<\/em>\u201d.<\/p>\n<p>Anche per <strong>Marco Vignola<\/strong>, responsabile del settore energia dell\u2019<strong>Unione Nazionale Consumatori<\/strong> (Unc), \u201c<em>le bollette sono ben lungi dall\u2019essere tornate normali e <strong>restano da infarto per troppi italiani<\/strong><\/em>\u201d. Per queste ragioni, secondo Vignola, \u201c<em>il Governo deve rinnovare tutti gli sconti in scadenza al 31 marzo, dall\u2019azzeramento degli oneri di sistema all\u2019Iva sul gas al 5%. Sarebbe un errore fatale per il Paese non farlo, uno tsunami per le tasche degli italiani<\/em>\u201d.<\/p>\n<p>Dal governo ancora bocche cucite sui prossimi passi da compiere. Nei mesi scorsi il ministro dell&#8217;Economia, <strong>Giancarlo Giorgetti<\/strong>, aveva accennato a un lavoro da parte dei tecnici di via XX Settembre per la messa a punto di un <a href=\"https:\/\/www.sostariffe.it\/news\/nuovo-calcolo-bollette-aprile-2023-tutte-le-novita-per-risparmiare-360463\/\"><strong>nuovo sistema di calcolo delle bollette<\/strong><\/a>, sul modello tedesco, nell&#8217;ottica di uscire dal perimetro delle misure emergenziali e avviare riforme pi\u00f9 strutturali. Tuttavia, non sono stati ancora resi noti aggiornamenti su questo fronte.<\/p>\n<h2>Come alleggerire le bollette luce e gas con il Mercato Libero a Marzo 2023<\/h2>\n<p>In attesa della prossima mossa del governo, le famiglie italiane continuano ad andare a caccia di soluzioni luce e gas che permettano loro di alleggerire le spese di energia elettrica e metano. Una mossa per ricevere bollette pi\u00f9 leggere \u00e8 quella di <strong>ridurre al minimo<\/strong> il <a href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/faq\/costo-kwh-kilowattora-quanto-costa-l-energia-elettrica\"><strong>costo kWh<\/strong><\/a> per la fornitura di elettricit\u00e0 e il <a href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/faq\/quanto-costa-un-metro-cubo-smc-di-gas-metano\"><strong>costo metano al metro cubo<\/strong><\/a> per quelle del gas. Una meta che pu\u00f2 essere raggiunta scegliendo le <strong>offerte luce e gas<\/strong> pi\u00f9 competitive tra quelle proposte dai <a href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/fornitori-energetici\/\"><strong>fornitori energetici<\/strong><\/a> operanti nel <strong>Mercato Libero<\/strong>.<\/p>\n<p>Per trovare le soluzioni cucite su misura sul proprio fabbisogno energetico e con il miglior rapporto qualit\u00e0-prezzo basta affidarsi al <strong>comparatore di SOStariffe.it<\/strong>, accessibile direttamente cliccando dal link qui sotto:<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/\" target=\"_blank\" rel=\"noopener noreferrer\">SCOPRI LE MIGLIORI OFFERTE LUCE E GAS <span style=\"\u201ctext-align: right&quot;;\">\u00bb<\/span><\/a><\/p>\n<p>Questo strumento gratuito e digitale permette di confrontare le numerose proposte attivabili sul mercato a marzo 2023 a partire dal proprio consumo annuo di luce e gas. Questa informazione pu\u00f2 essere consultata nell\u2019ultima bolletta ricevuta dall\u2019attuale fornitore (nella sezione consumi), oppure stimata grazie ai filtri integrati nel <strong>comparatore di SOStariffe.it<\/strong>.<\/p>\n<p>Cliccando al link di seguito \u00e8 possibile stimare subito il proprio consumo annuo di energia elettrica:<\/p>\n<p>[WIDGET-ENERGY]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iva ridotta al 5% sul gas e azzeramento degli oneri impropri delle bollette sono due misure del governo contro il caro-energia in vigore fino al 31 marzo 2023. Le associazioni dei consumatori in pressing sul governo: \u201cStangata in arrivo senza proroga degli sconti\u201d.<\/p>\n","protected":false},"author":108,"featured_media":362095,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1095,1098],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/362094"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=362094"}],"version-history":[{"count":15,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/362094\/revisions"}],"predecessor-version":[{"id":362242,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/362094\/revisions\/362242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/362095"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=362094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=362094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=362094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}