{"id":361111,"date":"2023-02-22T11:01:33","date_gmt":"2023-02-22T10:01:33","guid":{"rendered":"http:\/\/www.sostariffe.it\/news\/?p=361111"},"modified":"2023-02-22T11:02:48","modified_gmt":"2023-02-22T10:02:48","slug":"rimodulazione-tim-prezzi-piu-alti-e-adeguamento-allinflazione-da-aprile-2023-per-alcuni-gia-clienti","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/rimodulazione-tim-prezzi-piu-alti-e-adeguamento-allinflazione-da-aprile-2023-per-alcuni-gia-clienti-361111\/","title":{"rendered":"Rimodulazione TIM: prezzi pi\u00f9 alti e adeguamento all&#8217;inflazione da aprile 2023 per alcuni gi\u00e0 clienti"},"content":{"rendered":"<p><strong>Continua il programma di rimodulazioni di TIM<\/strong> che, in queste ore, ha annunciato una nuova modifica unilaterale delle condizioni tariffarie. Questa volta tocca ad alcuni <strong>gi\u00e0 clienti di rete fissa<\/strong> che, a partire<strong> dal prossimo 1\u00b0 aprile 2023<\/strong>, registreranno un adeguamento delle condizioni economiche dell&#8217;abbonamento. Le novit\u00e0 sono due<strong>: il canone mensile aumenta di 2 euro<\/strong> e viene introdotto il <strong>meccanismo di indicizzazione all&#8217;inflazione<\/strong> che porter\u00e0 ad aggiornamenti annuali del prezzo.<\/p>\n<p><!--more--><\/p>\n<p><strong>La serie di aumenti avviata da TIM continua<\/strong>: dal prossimo <strong>1\u00b0 aprile 2023<\/strong> \u00e8 in arrivo un nuovo rincaro con annessa introduzione del meccanismo di indicizzazione all&#8217;inflazione del canone mensile, gi\u00e0 introdotto per le offerte TIM per nuovi clienti. Si tratta di una nuova modifica unilaterale delle condizioni contrattuali che riguarder\u00e0 alcuni gi\u00e0 clienti TIM di rete fissa.<\/p>\n<h2>Cosa prevede la nuova rimodulazione TIM per il fisso di aprile 2023<\/h2>\n<p>TIM ha annunciato una nuova variazione delle condizioni economiche per alcuni gi\u00e0 clienti di rete fissa. In particolare, la rimodulazione riguarda le offerte<strong> TIM Smart Premium<\/strong> e <strong>TIM Connect Premium<\/strong> (non pi\u00f9 attivabili). Per queste offerte \u00e8 previsto:<\/p>\n<ul>\n<li>un <strong>aumento del canone mensile di 2 euro<\/strong><\/li>\n<li>l&#8217;introduzione del<strong> meccanismo di indicizzazione all&#8217;inflazione del canone mensile<\/strong> che porter\u00e0 ad adeguamenti annuali del costo delle offerte<\/li>\n<\/ul>\n<p>La rimodulazione entrer\u00e0 in vigore a partire<strong> dal primo rinnovo successivo al 1\u00b0 aprile 2023<\/strong>. Come sempre, \u00e8 possibile<strong> esercitare il diritto di recesso,<\/strong> con passaggio ad altro operatore o cessazione della linea, senza costi di disattivazione. Il diritto di recesso potr\u00e0 essere esercitato in uno dei seguenti modi:<\/p>\n<ul>\n<li>chiamando il Servizio Clienti 187<\/li>\n<li>presentando richiesta dall\u2019Area Clienti MyTIM (previa registrazione)<\/li>\n<li>scrivendo all\u2019indirizzo TIM \u2013 Servizio Clienti &#8211; Casella Postale 111 &#8211; 00054 Fiumicino (Roma) o tramite PEC all\u2019indirizzo disattivazioni_clientiprivati@pec.telecomitalia.it; in questo caso \u00e8 necessario allegare una fotocopia del documento d&#8217;identit\u00e0 del titolare del contratto e specificare nell\u2019oggetto della comunicazione: \u201cModifica delle condizioni contrattuali\u201d<\/li>\n<li>recandosi in un negozio TIM<\/li>\n<\/ul>\n<p>Nella comunicazione di recesso bisogner\u00e0 <strong>specificare se si intende passare ad altro operatore oppure se si richiede la cessazione della linea.<\/strong> In ogni caso, non sono previsti costi di uscita o penali. Chi ha acquistato un dispositivo o un servizio a rate potr\u00e0 scegliere di continuare con il pagamento rateale, senza penali. Se, invece, il cliente ha un dispositivo in comodato d&#8217;uso dovr\u00e0 restituirlo a TIM seguendo le indicazioni fornite dal Servizio Clienti.<\/p>\n<p>C&#8217;\u00e8 tempo<strong> fino al 30 aprile 2023<\/strong> per esercitare il diritto di recesso.<\/p>\n<p>[WIDGET-SPEEDTEST]<\/p>\n<h2>Come funziona il meccanismo di indicizzazione all&#8217;inflazione del canone delle offerte TIM<\/h2>\n<p>Oltre all&#8217;aumento del canone, la nuova rimodulazione TIM introduce l&#8217;<strong>indicizzazione all&#8217;inflazione<\/strong>. Il nuovo meccanismo, gi\u00e0 introdotto da TIM verso fine 2022 per le tariffe riservate ai nuovi clienti, presenta le seguenti caratteristiche:<\/p>\n<ul>\n<li>il canone mensile sar\u00e0 incrementato, con cadenza annuale, in misura percentuale pari all<strong>\u2019indice di inflazione (IPCA)<\/strong> rilevato dall\u2019ISTAT, non tenendo conto di eventuali valori negativi dello stesso, <strong>maggiorato di un coefficiente pari a 3,5 punti percentuali<\/strong><\/li>\n<\/ul>\n<p>Il primo adeguamento del canone all&#8217;inflazione \u00e8 fissato per il 1\u00b0 aprile 2024, con riferimento al valore IPCA relativo all&#8217;anno solare 2023. Come evidente dalla descrizione riportata sul sito TIM per questo meccanismo, l&#8217;operatore prevede un adeguamento minimo dovuto al coefficiente di 3,5 punti che si tradurr\u00e0 in un rincaro superiore all&#8217;andamento dell&#8217;inflazione. Da notare, per\u00f2, che \u00e8 previsto <strong>un tetto massimo del 10%.<\/strong><\/p>\n<h2>Le offerte fibra alternative per evitare la rimodulazione TIM di aprile 2023<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 144px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 24.8503%; height: 24px; text-align: center;\"><strong>OFFERTA<\/strong><\/td>\n<td style=\"width: 50.1497%; height: 24px; text-align: center;\"><strong>COSA INCLUDE<\/strong><\/td>\n<td style=\"width: 25%; height: 24px; text-align: center;\"><strong>QUANTO COSTA<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 24.8503%; height: 24px;\"><strong>Fiber Evolution Full di Beactive<\/strong><\/td>\n<td style=\"width: 50.1497%; height: 24px;\">Internet illimitato fino a 1 Giga in download<\/td>\n<td style=\"width: 25%; height: 24px;\">16 euro al mese per 12 mesi, poi 23,50 euro al mese<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 24.8503%; height: 24px;\"><strong>Illumia Wifi<\/strong><\/td>\n<td style=\"width: 50.1497%; height: 24px;\">Internet illimitato fino a 1 Giga in download<\/td>\n<td style=\"width: 25%; height: 24px;\">19,99 euro al mese per 12 mesi, poi 26,99 euro al mese<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 24.8503%; height: 24px;\"><strong>PosteCasta Ultraveloce Start<\/strong><\/td>\n<td style=\"width: 50.1497%; height: 24px;\">Internet illimitato fino a 1 Giga in download<\/td>\n<td style=\"width: 25%; height: 24px;\">23,99 euro al mese<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 24.8503%; height: 24px;\"><strong>Internet Unlimited di Vodafone<\/strong><\/td>\n<td style=\"width: 50.1497%; height: 24px;\">Internet illimitato fino a 2,5 Giga in download e linea telefonica con chiamate illimitate<\/td>\n<td style=\"width: 25%; height: 24px;\">24,90 euro al mese<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 24.8503%; height: 24px;\"><strong>Sky WiFi<\/strong><\/td>\n<td style=\"width: 50.1497%; height: 24px;\">Internet illimitato fino a 1 Giga in download e linea telefonica<\/td>\n<td style=\"width: 25%; height: 24px;\">24,90 euro al mese per 18 mesi, poi 29,90 euro al mese<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Per evitare la rimodulazione TIM di aprile 2023 \u00e8 possibile esercitare il diritto di recesso e passare ad altro operatore. A disposizione degli utenti ci sono diverse offerte molto vantaggiose su cui puntare oggi per continuare ad utilizzare Internet ad alta velocit\u00e0 e ad un buon prezzo da casa. Per un quadro completo sulle offerte \u00e8 possibile consultare il comparatore di SOStariffe.it per offerte Internet casa.<\/p>\n<p>Tra le offerte pi\u00f9 interessanti del momento troviamo <strong>FiberEvolution Full di Beactive.<\/strong> L&#8217;offerta in questione consente di accedere ad Internet tramite rete in fibra ottica FTTH con velocit\u00e0 massima di 1000 Mega. Il modem \u00e8 incluso gratuitamente. Il canone \u00e8 di <strong>16 euro al mese per 12 mesi<\/strong>. Terminato il periodo promozionale, l&#8217;offerta si rinnover\u00e0 al costo di 23,50 euro al mese. \u00c8 previsto un contributo di attivazione di 27,50 euro una tantum.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=rate_widget&amp;id=11150&amp;sos_api_key=\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva FiberEvolution Full di Beactive <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Da valutare anche <strong>Illumia Wifi<\/strong> che mette a disposizione una connessione illimitata tramite fibra ottica FTTH con velocit\u00e0 massima di 1 Giga. Il costo \u00e8 di <strong>19,99 euro al mese per 12 mesi<\/strong> (poi 26,99 euro al mese). L&#8217;attivazione \u00e8 di 39,99 euro una tantum ma viene azzerata per i gi\u00e0 clienti Illumia di luce e gas. Il modem, invece, \u00e8 incluso gratuitamente per il primo anno di sottoscrizione.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=rate_widget&amp;id=9942&amp;sos_api_key=\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva Illumia Wifi <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Un&#8217;altra offerta da tenere d&#8217;occhio \u00e8<strong> PosteCasa Ultraveloce Start<\/strong>. L&#8217;offerta include una connessione illimitata tramite fibra ottica FTTH con velocit\u00e0 massima di 1 Giga. Il canone \u00e8 di<strong> 23,90 euro al mese<\/strong> ed il modem \u00e8 incluso gratuitamente. Da notare che \u00e8 previsto un contributo di attivazione di 29 euro una tantum. Per attivare l&#8217;offerta \u00e8 disponibile il link qui di sotto.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=rate_widget&amp;id=11268&amp;sos_api_key=\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva PosteCasa Ultraveloce Start <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p><strong>Internet Unlimited di Vodafone<\/strong> \u00e8 un&#8217;altra opzione da considerare per la connessione Internet di casa. L&#8217;offerta include la linea telefonica fissa con chiamate illimitate ed una connessione illimitata tramite fibra ottica FTTH fino a 2.5 Giga oppure fibra mista rame fino a 200 Mega. Il costo \u00e8 di <strong>24,90 euro al mese<\/strong> con attivazione e modem Wi-Fi gratis. L&#8217;offerta \u00e8 disponibile direttamente online:<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=rate_widget&amp;id=3029&amp;sos_api_key=\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva Internet Unlimited di Vodafone <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>C&#8217;\u00e8 anche <strong>Sky WiFi<\/strong> da considerare. L&#8217;offerta presenta un costo di <strong>24,90 euro al mese per 18 mesi<\/strong> (poi 29,90 euro al mese) con attivazione di 29 euro. A disposizione degli utenti c&#8217;\u00e8 una linea telefonica fissa con chiamate a consumo ed una connessione illimitata tramite rete in fibra ottica FTTH con velocit\u00e0 massima di 1 Giga in download oppure tramite fibra mista fino a 200 Mega.<br \/>\n<a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=rate_widget&amp;id=10035&amp;sos_api_key=\" target=\"_blank\" rel=\"noopener noreferrer\">Attiva Sky WiFi <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continua il programma di rimodulazioni di TIM che, in queste ore, ha annunciato una nuova modifica unilaterale delle condizioni tariffarie. Questa volta tocca ad alcuni gi\u00e0 clienti di rete fissa che, a partire dal prossimo 1\u00b0 aprile 2023, registreranno un adeguamento delle condizioni economiche dell&#8217;abbonamento. Le novit\u00e0 sono due: il canone mensile aumenta di 2 [&hellip;]<\/p>\n","protected":false},"author":47,"featured_media":361112,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[22322,4],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/361111"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=361111"}],"version-history":[{"count":2,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/361111\/revisions"}],"predecessor-version":[{"id":361114,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/361111\/revisions\/361114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/361112"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=361111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=361111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=361111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}