{"id":360279,"date":"2023-02-10T11:00:57","date_gmt":"2023-02-10T10:00:57","guid":{"rendered":"http:\/\/www.sostariffe.it\/news\/?p=360279"},"modified":"2023-02-10T15:37:54","modified_gmt":"2023-02-10T14:37:54","slug":"tap-cose-e-perche-e-importante-per-limportazione","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/tap-cose-e-perche-e-importante-per-limportazione-360279\/","title":{"rendered":"TAP: cos\u2019\u00e8 e perch\u00e9 \u00e8 importante per l\u2019importazione"},"content":{"rendered":"<p>Cresce il peso del <strong>metanodotto Trans Adriatico<\/strong>\u00a0nella mappa del gas in Italia: nel 2022 ha portato nel nostro Paese <strong>10 miliardi di metri cubi di gas<\/strong> in arrivo dall\u2019Azerbaigian. Ora occhi puntati sul <strong>raddoppio della sua capacit\u00e0<\/strong>: con la prima tappa dell&#8217;espansione, <strong>1,2 miliardi di metri cubi di gas<\/strong> in pi\u00f9 dal <strong>2026<\/strong>. <!--more--><\/p>\n<p>Il <strong>gasdotto Trans Adriatico TAP<\/strong> \u00e8 sempre pi\u00f9 centrale nella (nuova) <a href=\"https:\/\/www.sostariffe.it\/news\/italia-e-indipendenza-dal-gas-russo-il-punto-a-febbraio-2023-360146\/\"><strong>mappa del metano<\/strong><\/a> approntata dall\u2019Italia per sopperire ai minori flussi in arrivo dalla Russia (<strong>-52%<\/strong> nel 2022 rispetto al 2021).<\/p>\n<p>Gi\u00e0 l\u2019anno scorso questo gasdotto, che trasporta gas naturale dall\u2019area caspica in Europa, ha portato in Italia <strong>10 miliardi di metri cubi di gas<\/strong>, 3 miliardi in pi\u00f9 rispetto ai 7 miliardi del 2021. Cifre destinate ad aumentare, visto che la capacit\u00e0 di trasporto di TAP sar\u00e0 potenziata: un primo livello di espansione far\u00e0 crescere la portata di <strong>1,2 miliardi di metri cubi<\/strong> dal <strong>2026<\/strong>. Ma l&#8217;obiettivo \u00e8 il raddoppio della capacit\u00e0 a 20 miliardi di metri cubi all&#8217;anno.<\/p>\n<p>Nei paragrafi che seguono gli esperti di <strong>SOStariffe.it<\/strong> tracciano l\u2019identikit del <strong>Trans Adriatic Pipeline<\/strong>, fanno un bilancio dei flussi di gas transitati nelle sue condutture nel 2022 e illustrano le fasi dell&#8217;espansione di questa rotta di importazione su cui l&#8217;Europa e l&#8217;Italia hanno gli occhi puntati.<\/p>\n<h2>Trans Adriatic Pipeline (TAP): cosa \u00e8 e perch\u00e9 \u00e8 importante<\/h2>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%; text-align: center;\"><strong>DOMANDE SUL TRANS ADRIATIC PIPELINE (TAP)<\/strong><\/td>\n<td style=\"width: 50%; text-align: center;\"><strong>RISPOSTE SUL TRANS ADRIATIC PIPELINE (TAP)<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">Che cosa \u00e8 TAP?<\/td>\n<td style=\"width: 50%;\">\u00c8 il <strong>gasdotto transadriatico<\/strong> che trasporta gas naturale dai giacimenti azeri del <strong>Mar Caspio<\/strong> in Europa<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">Quanto \u00e8 lungo il Trans Adriatic Pipeline?<\/td>\n<td style=\"width: 50%;\">L&#8217;infrastruttura \u00e8 lunga <strong>867 chilometri<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">Da dove parte il gasdotto TAP?<\/td>\n<td style=\"width: 50%;\">Parte da <strong>Kipoi<\/strong> (al confine tra Grecia e Turchia)<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">Dove arriva il gasdotto TAP?<\/td>\n<td style=\"width: 50%;\">Arriva a <strong>Melendugno <\/strong>(Lecce) sul litorale salentino<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">Quali Paesi attraversa il gasdotto TAP?<\/td>\n<td style=\"width: 50%;\">Attraversa <strong>Grecia e Albania<\/strong> prima di arrivare in Italia<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">\u00c8 vero che TAP fa parte del cosiddetto &#8220;<strong>Corridoio meridionale del gas<\/strong>?&#8221;<\/td>\n<td style=\"width: 50%;\">S\u00ec. TAP rappresenta una parte del &#8220;Corridoio meridionale del gas&#8221;, che si snoda per 3.500 chilometri dal Mar Caspio all&#8217;Europa. Il Corridoio \u00e8 composto anche dal gasdotto transanatolico <strong>TANAP<\/strong> e da quello sud-caucasico <strong>SCP<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>TAP<\/strong> (acronimo di Trans Adriatic Pipeline) \u00e8 il metanodotto transadriatico che trasporta il <strong><a href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/faq\/che-cos-e-il-gas-naturale-e-a-cosa-serve\">gas naturale<\/a><\/strong> in Europa proveniente dai giacimenti azeri del Mar Caspio. Lungo <strong>878 chilometri<\/strong>, il gasdotto parte da <strong>Kipoi<\/strong> (al confine tra Grecia e Turchia) attraversa Grecia e Albania per approdare in Italia sulla costa adriatica. Il terminale di ricezione del gasdotto \u00e8 situato nel comune di <strong>Melendugno<\/strong> (Lecce), sul litorale salentino.<\/p>\n<p>Il metanodotto TAP \u00e8, a sua volta, collegato con il gasdotto transanatolico <strong>TANAP<\/strong> che, attraversando tutta la Turchia, costituisce la parte centrale del cosiddetto \u201c<strong>Corridoio meridionale del gas<\/strong>\u201d, una <strong>rotta cruciale<\/strong> per le importazioni di gas in Europa. Oltre a TAP e TANAP, il corridoio comprende anche il <strong>gasdotto sud-caucasico (SCP)<\/strong> tra Azerbaigian e Georgia.<\/p>\n<h2>TAP: secondo fornitore di gas per l\u2019Italia nel 2022<\/h2>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><strong>TAP: FLUSSI DI GAS NEL 2022<\/strong><\/td>\n<td style=\"width: 50%;\"><strong>TAP: FLUSSI DI GAS NEL 2021<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">10 miliardi di metri cubi di gas<\/td>\n<td style=\"width: 50%;\">7 miliardi di metri cubi di gas<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Nel 2022, l\u2019<strong>Algeria<\/strong> \u00e8 salita sul gradino pi\u00f9 alto del podio delle forniture di metano all\u2019Italia, con <strong>23,7 miliardi di metri cubi di gas<\/strong> approdati a Mazara del Vallo tramite il gasdotto Transmed (+2,5 miliardi di metri cubi rispetto al 2021).<\/p>\n<p>Alle spalle dell\u2019Algeria, si \u201cpiazza\u201d proprio la pipeline TAP, che l\u2019anno scorso ha portato in Italia <strong>10 miliardi di metri<\/strong> <strong>cubi di gas<\/strong> (3 miliardi in pi\u00f9 rispetto ai 7 miliardi del 2021), secondo le cifre rese note da Luca Schieppati, managing director TAP, in un\u2019intervista al quotidiano <em>Il Sole 24 Ore<\/em>. Nel 2022, questo flusso di gas ha coperto il <strong>15% della domanda<\/strong> di metano dell\u2019Italia.<\/p>\n<h2>Raddoppio TAP: +1,2 miliardi di metri cubi di gas l\u2019anno dal 2026<\/h2>\n<p>I numeri di questa rotta sono destinati a crescere, visto che TAP ha gi\u00e0 acceso i motori per il <strong>raddoppio della capacit\u00e0 del gasdotto<\/strong>, da 10 a <strong>20 miliardi di metri cubi all&#8217;anno<\/strong>. Il primo livello di espansione prevede di raggiungere, dal <strong>2026<\/strong>, una capacit\u00e0 aggiuntiva per <strong>1,2 miliardi di metri cubi all&#8217;anno<\/strong>.<\/p>\n<p>\u201c<em>Siamo lieti di iniziare ad espandere la capacit\u00e0 di Tap, che pu\u00f2 essere aumentata gradualmente fino ad almeno 20 miliardi di metri cubi all\u2019anno<\/em>\u201d, \u00e8 il commento di Luca Schieppati, managing director di TAP nella nota ufficiale con cui si annuncia l\u2019espansione della capacit\u00e0 del gasdotto. \u201c<em>Dopo aver chiuso la prima fase vincolante<\/em> &#8211; prosegue &#8211; <em>intendiamo avviarne un\u2019altra nella seconda met\u00e0 dell\u2019anno, con l\u2019obiettivo di rafforzare ulteriormente la sicurezza degli approvvigionamenti e la liquidit\u00e0 del mercato in Europa. Nuovi volumi di idrogeno e altri gas rinnovabili potranno inoltre essere trasportati attraverso l\u2019espansione della capacit\u00e0 di Tap, promuovendo la sostenibilit\u00e0 a lungo termine e la transizione energetica dell\u2019area\u201d<\/em>.<\/p>\n<p>A manifestare il \u201cforte interesse\u201d dell\u2019Italia al raddoppio della capacit\u00e0 di trasporto del gasdotto TAP da 10 a 20 miliardi di metri cubi di gas all\u2019anno \u00e8 stato il <strong>ministro dell\u2019Ambiente e della sicurezza energetica<\/strong>, Gilberto Pichetto, alla IX Riunione ministeriale del Consiglio Consultivo del Corridoio Meridionale del Gas (CCCMG) che si \u00e8 tenuta a Baku (Azerbaigian) lo scorso 4 febbraio 2023.<\/p>\n<p>Secondo quanto spiegato dal ministro Pichetto, il potenziamento di TAP \u201c<em>rientra perfettamente nella strategia che l\u2019Italia sta mettendo in campo per contribuire sempre di pi\u00f9 alla diversificazione delle fonti energetiche che garantiranno la sicurezza dell\u2019Italia anche in un ruolo di fornitore rispetto a molti altri paesi europei\u201d.<\/em><\/p>\n<h2>Tagliare le bollette del metano con il Mercato Libero a Febbraio 2023<\/h2>\n<p>Mentre l\u2019Italia accelera sulla diversificazione delle fonti energetiche, le famiglie sono tuttora alle prese con bollette del metano che risentono di mesi all\u2019insegna del caro prezzi.\u00a0Una mossa per ricevere bollette pi\u00f9 leggere \u00e8 quella di <strong>ridurre al minimo il costo del gas naturale al metro cubo<\/strong>. Come? Scegliendo le migliori <a href=\"https:\/\/www.sostariffe.it\/gas\/\"><strong>offerte gas<\/strong> <\/a>proposte dai <strong><a href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/fornitori-energetici\/\">gestori energetici<\/a> del<\/strong> <strong>Mercato Libero <\/strong>grazie al <strong>comparatore di SOStariffe.it<\/strong>.<\/p>\n<p>Questo strumento (online e gratuito) consente di individuare l\u2019offerta \u201ccucita\u201d sulle proprie esigenze a partire dal dato relativo al proprio consumo annuo di metano. Chi non avesse a portata di mano questo dato, sempre consultabile in bolletta, pu\u00f2 calcolarlo impostando i filtri integrati nel comparatore, accessibili dal link di seguito:<\/p>\n<p>[WIDGET-GAS]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cresce il peso del metanodotto Trans Adriatico\u00a0nella mappa del gas in Italia: nel 2022 ha portato nel nostro Paese 10 miliardi di metri cubi di gas in arrivo dall\u2019Azerbaigian. Ora occhi puntati sul raddoppio della sua capacit\u00e0: con la prima tappa dell&#8217;espansione, 1,2 miliardi di metri cubi di gas in pi\u00f9 dal 2026.<\/p>\n","protected":false},"author":108,"featured_media":360280,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1098],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/360279"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=360279"}],"version-history":[{"count":10,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/360279\/revisions"}],"predecessor-version":[{"id":360430,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/360279\/revisions\/360430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/360280"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=360279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=360279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=360279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}