{"id":359790,"date":"2023-02-03T16:00:09","date_gmt":"2023-02-03T15:00:09","guid":{"rendered":"http:\/\/www.sostariffe.it\/news\/?p=359790"},"modified":"2023-07-18T16:12:13","modified_gmt":"2023-07-18T14:12:13","slug":"bollette-gas-netto-calo-del-prezzo-in-arrivo-a-febbraio-2023-ecco-le-prime-stime","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/bollette-gas-netto-calo-del-prezzo-in-arrivo-a-febbraio-2023-ecco-le-prime-stime-359790\/","title":{"rendered":"Bollette Gas: netto calo del prezzo in arrivo a febbraio 2023, ecco le prime stime"},"content":{"rendered":"<p>Buone notizie in arrivo per le famiglie:<strong> le bollette del gas stanno per diventare pi\u00f9 leggere<\/strong>. Sia in regime di <strong>Maggior<\/strong> <strong>Tutela<\/strong> che nel <strong>Mercato Libero<\/strong>, infatti, le bollette del gas relative ai consumi di gennaio 2023 saranno molto pi\u00f9 basse (a parit\u00e0 di consumi) rispetto alle bollette dei mesi precedenti. Questa riduzione dovrebbe essere confermata anche a febbraio. Vediamo cosa sta succedendo e a quanto potrebbe ammontare il taglio sar\u00e0 annunciato soltanto ad inizio febbraio 2023.<\/p>\n<p><!--more--><\/p>\n<p><strong>Le bollette del gas diventeranno pi\u00f9 leggere<\/strong>. Il costo della materia prima \u00e8 in calo e, quindi, crescono i margini di risparmio per le famiglie, sia in regime di <strong>Tutela<\/strong> che, soprattutto, con il <strong>Mercato<\/strong> <strong>Libero<\/strong>. In particolare, i<strong> consumi relativi al mese di gennaio 2023<\/strong> che si avvia alla conclusione saranno<strong> tariffati con un costo al metro cubo nettamente pi\u00f9 basso<\/strong> rispetto a quanto registrato a dicembre con un risparmio significativo per le famiglie.<\/p>\n<h2>Bollette del gas: calo in arrivo per le famiglie, ecco i numeri<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 125px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50.0665%; height: 24px;\"><\/td>\n<td style=\"width: 49.9335%; text-align: center; height: 24px;\"><strong>LE NOVITA&#8217; IN ARRIVO PER LE BOLLETTE DI LUCE E GAS<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 53px;\">\n<td style=\"width: 50.0665%; height: 53px;\">1.<\/td>\n<td style=\"width: 49.9335%; height: 53px;\">Le quotazioni del mercato all&#8217;ingrosso (PUN per la luce e PSV per il gas) sono in calo:<strong> i prezzi di gennaio 2023 saranno pi\u00f9 bassi di quelli di dicembre 2022<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50.0665%; height: 24px;\">2.<\/td>\n<td style=\"width: 49.9335%; height: 24px;\"><strong>La spesa per il gas si riduce di oltre il 34%<\/strong> grazie al calo dell&#8217;indice PSV e coinvolge sia la Tutela che il Mercato Libero<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50.0665%; height: 24px;\">3.<\/td>\n<td style=\"width: 49.9335%; height: 24px;\">Per la <strong>luce<\/strong> \u00e8 previsto un<strong> taglio superiore al 30%<\/strong> ma <strong>solo per il Mercato Libero<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>Il calo delle bollette del gas riguarder\u00e0 sia il Mercato Libero che la Maggior Tutela<\/strong>, permettendo a tutte le famiglie italiane di beneficiare di una significativa riduzione del costo al metro cubo del gas naturale. Naturalmente, bisogna fare delle distinzioni in quanto ogni regime tariffario presenta caratteristiche ben precise e i margini di risparmio potrebbero variare caso per caso. Il trend \u00e8 comunque positivo per gli utenti.<\/p>\n<p>Per quanto riguarda il <strong>Mercato<\/strong> <strong>Tutelato si registra un calo significativo della spesa.<\/strong> Come confermato da <strong>ARERA<\/strong>, infatti, <strong><a href=\"https:\/\/www.sostariffe.it\/news\/bollette-gas-spesa-in-calo-del-342-per-i-consumi-di-gennaio-2023-per-i-clienti-in-tutela-359980\/\">per i consumi di gennaio \u00e8 prevista una spesa in calo del -34%<\/a><\/strong> rispetto a dicembre 2022 con un costo unitario del gas naturale (CMEMm) che passa<strong> da\u00a01,24 \u20ac\/Smc a 0,73 \u20ac\/Smc.<\/strong> Il nuovo prezzo \u00e8 calcolato in base alla media giornaliera, tenuta a gennaio, dall&#8217;indice <strong>PSV<\/strong>.<\/p>\n<p><strong> Calo netto anche per il Mercato Libero e<\/strong>, in particolare, per tutte le <strong>tariffe<\/strong> <strong>indicizzate<\/strong> che seguono l&#8217;andamento del PSV. Anche in questo caso, il calo di prezzo dell&#8217;indice del mercato all&#8217;ingrosso si tradurr\u00e0 in un risparmio per gli utenti che hanno attivato tariffe indicizzate che prevederanno un costo del gas naturale pari a circa 0,73 \u20ac\/Smc.<\/p>\n<p>[WIDGET-GAS]<\/p>\n<h2>Cosa succede alle bollette della luce: nessun risparmio, per ora, in Tutela mentre cala il Mercato Libero<\/h2>\n<p>Da <strong>febbraio 2023<\/strong>, invece, <strong>non ci saranno novit\u00e0 per il servizio di Maggior Tutela per l&#8217;energia elettrica.<\/strong> Il prezzo della luce \u00e8 gi\u00e0 stato fissato da ARERA e sar\u00e0 valido fino alla fine del mese di marzo. Tale prezzo, per le forniture con tariffazione monoraria, \u00e8 di circa <strong>0,36 \u20ac\/kWh<\/strong>. Sar\u00e0, quindi, necessario attendere il prossimo mese di aprile per beneficiare del calo dei prezzi all&#8217;ingrosso che si sta registrando nel corso di queste settimane.<\/p>\n<p>Situazione completamente diversa, invece, per il <strong>Mercato<\/strong> <strong>Libero<\/strong>, in particolare per chi sceglie un<strong>a tariffa a prezzo indicizzato<\/strong>. In questo caso, le <strong>offerte collegate al PUN<\/strong> possono beneficiare del calo dell&#8217;indice del mercato all&#8217;ingrosso che dovrebbe registrare un <strong>valore medio inferiore a 0,2 \u20ac\/kWh<\/strong> per il mese di gennaio garantendo condizioni di fornitura molto pi\u00f9 vantaggiose rispetto a quelle che caratterizzano il servizio di Maggior Tutela.<strong> Il calo sar\u00e0 superiore al 30%<\/strong> nel confronto con i dati di dicembre 2022 (circa 0,29 \u20ac\/kWh).<\/p>\n<p>[WIDGET-ENERGY]<\/p>\n<h2>Come tagliare subito le bollette di luce e gas<\/h2>\n<p>Il calo dei prezzi all&#8217;ingrosso di luce e gas conferma l&#8217;importanza di <strong>scegliere le migliori tariffe del Mercato Libero<\/strong>. In questo momento, infatti, le tariffe del Mercato Libero possono garantire un risparmio netto rispetto alla Tutela. La scelta migliore, in particolare, \u00e8 collegata all&#8217;attivazione delle tariffe a prezzo indicizzato che seguono l&#8217;andamento del <strong>PUN<\/strong> per la luce e del <strong>PSV<\/strong> per il gas. Le opzioni di questo tipo sul mercato sono numerose.<\/p>\n<p>Per individuare le tariffe pi\u00f9 vantaggiose \u00e8, quindi, possibile affidarsi al <strong>comparatore di SOStariffe.it<\/strong> per <strong>offerte luce e gas<\/strong>. Baster\u00e0 indicare una<strong> stima del proprio consumo annuo<\/strong> per scoprire subito le tariffe pi\u00f9 vantaggiose da attivare direttamente online, tramite il sito del fornitore. Per accedere alla comparazione \u00e8 possibile fare riferimento direttamente al link qui di sotto.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/\" target=\"_blank\" rel=\"noopener noreferrer\">Scopri qui le migliori offerte luce e gas <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Ricordiamo che per assistenza nella scelta si pu\u00f2 contattare il<strong> Servizio di Consulenza di SOStariffe.it<\/strong>, completamente gratuito e senza impegno, disponibile al numero<strong> 02 5005 111<\/strong>. Un consulente qualificato sar\u00e0 pronto ad assistere l&#8217;utente nella scelta della tariffa migliore.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buone notizie in arrivo per le famiglie: le bollette del gas stanno per diventare pi\u00f9 leggere. Sia in regime di Maggior Tutela che nel Mercato Libero, infatti, le bollette del gas relative ai consumi di gennaio 2023 saranno molto pi\u00f9 basse (a parit\u00e0 di consumi) rispetto alle bollette dei mesi precedenti. Questa riduzione dovrebbe essere [&hellip;]<\/p>\n","protected":false},"author":114,"featured_media":359793,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1095,1098],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/359790"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=359790"}],"version-history":[{"count":4,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/359790\/revisions"}],"predecessor-version":[{"id":360064,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/359790\/revisions\/360064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/359793"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=359790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=359790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=359790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}