{"id":359045,"date":"2023-01-19T10:00:39","date_gmt":"2023-01-19T09:00:39","guid":{"rendered":"http:\/\/www.sostariffe.it\/news\/?p=359045"},"modified":"2023-01-19T22:25:26","modified_gmt":"2023-01-19T21:25:26","slug":"bollette-gas-raddoppiate-le-soluzioni-di-gennaio-2023","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/bollette-gas-raddoppiate-le-soluzioni-di-gennaio-2023-359045\/","title":{"rendered":"Bollette gas raddoppiate: le soluzioni di Gennaio 2023"},"content":{"rendered":"<p>Il prezzo del gas all\u2019ingrosso <strong>\u00e8 in contrazione<\/strong> da settimane, ma a gennaio 2023 le bollette del metano <strong>crescono del +23,3%<\/strong> per i clienti della Maggior Tutela. Ecco le <strong>soluzioni gas <\/strong>del <strong>Mercato Libero<\/strong> per tenere sotto controllo i rialzi e trarre subito il massimo vantaggio dalla battuta d\u2019arresto delle quotazioni gas al <strong>TTF di Amsterdam<\/strong>. <!--more--><\/p>\n<p>Sebbene il prezzo del gas all\u2019ingrosso sia in ribasso da cinque settimane al <a href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/guide\/ttf-gas-cos-e-e-come-influenza-il-prezzo-del-gas-in-italia\"><strong>TTF di Amsterdam<\/strong><\/a>, le <strong>bollette del metano<\/strong> continuano a gravare sui bilanci delle famiglie italiane, in particolar modo su quelle ancora servite dalla Maggior Tutela. Per loro, infatti, le fatture di gennaio 2023 saranno nuovamente all\u2019insegna degli aumenti, con un prezzo gas <a href=\"https:\/\/www.sostariffe.it\/news\/bollette-gas-233-per-i-consumi-di-dicembre-2022-per-i-clienti-in-tutela-358135\/\"><strong>in crescita del +23,3%<\/strong> <\/a>sui consumi di dicembre 2022 rispetto ai consumi di novembre 2022. (<a href=\"https:\/\/www.sostariffe.it\/news\/il-prezzo-del-gas-scende-ma-le-bollette-no-perche-succede-a-gennaio-2023-358663\/\">Qui ne spieghiamo il perch\u00e9<\/a>).<\/p>\n<p>Una tregua, per\u00f2, dovrebbe arrivare da febbraio 2023: secondo una previsione di Nomisma Energia al 17 gennaio 2023, pubblicata sul quotidiano <em>Il Sole 24 Ore<\/em>, il prezzo del metano, per i clienti ancora serviti dalla Maggior Tutela, \u00e8 in <strong>calo del 29%<\/strong> al 1\u00b0 gennaio 2023 rispetto al 1\u00b0 dicembre 2022. Una contrazione che, se confermata, porterebbe un risparmio annuo di 614,3 euro per una \u201cfamiglia tipo\u201d che abbia un consumo di 1.400 metri cubi di gas nell\u2019arco di 12 mesi.<\/p>\n<p>Come fare per intercettare questo trend in flessione, <strong>massimizzando il risparmio<\/strong> in bolletta? Secondo gli esperti di <strong>SOStariffe.it<\/strong>, \u00e8 il momento giusto per puntare sulle <a href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/faq\/prezzo-fisso-o-indicizzato-luce-e-gas-quale-scegliere\"><strong>offerte a<\/strong> <strong>prezzo indicizzato<\/strong><\/a> del <strong>Mercato Libero<\/strong>. Si tratta, infatti, di soluzioni che garantiscono l\u2019accesso al prezzo del gas all\u2019ingrosso, aggiornato mensilmente. Questo permette di avere fatture sempre in linea con l\u2019andamento del mercato e trarre vantaggio delle contrazioni di prezzo gi\u00e0 nel breve periodo.<\/p>\n<p>Un valido alleato nell\u2019individuazione e nella scelta dell&#8217;opzione metano pi\u00f9 vantaggiosa \u00e8 il <strong>comparatore di SOStariffe.it <\/strong>per <strong><a href=\"https:\/\/www.sostariffe.it\/gas\/\">offerte gas<\/a><\/strong>, che permette il confronto delle innumerevoli soluzioni metano messe a punto dai <a href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/fornitori-energetici\/\">gestori energetici del Mercato Libero<\/a> a partire dal proprio consumo annuo.<\/p>\n<h2>Le offerte gas a prezzo indicizzato pi\u00f9 competitive di Gennaio 2023<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 96px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 20%; height: 24px;\"><\/td>\n<td style=\"width: 20%; height: 24px;\"><strong>NOME FORNITORE<\/strong><\/td>\n<td style=\"width: 20%; height: 24px;\"><strong>NOME OFFERTA<\/strong><\/td>\n<td style=\"width: 20%; height: 24px;\"><strong>PREZZO GAS<\/strong><\/td>\n<td style=\"width: 20%; height: 24px;\"><strong>SPESA MENSILE<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 20%; height: 24px;\">1<\/td>\n<td style=\"width: 20%; height: 24px;\"><strong>A2A Energia<\/strong><\/td>\n<td style=\"width: 20%; height: 24px;\">Easy Gas<\/td>\n<td style=\"width: 20%; height: 24px;\">1,2340 \u20ac\/Smc<\/td>\n<td style=\"width: 20%; height: 24px;\">114,68 euro<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 20%; height: 24px;\">2<\/td>\n<td style=\"width: 20%; height: 24px;\"><strong>wekiwi<\/strong><\/td>\n<td style=\"width: 20%; height: 24px;\">Gas alla Fonte<\/td>\n<td style=\"width: 20%; height: 24px;\">1,2840 \u20ac\/Smc<\/td>\n<td style=\"width: 20%; height: 24px;\">124,32 euro<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 20%; height: 24px;\">3<\/td>\n<td style=\"width: 20%; height: 24px;\"><strong>Edison Energia<\/strong><\/td>\n<td style=\"width: 20%; height: 24px;\">World Gas Plus<\/td>\n<td style=\"width: 20%; height: 24px;\">1,2340 <span style=\"font-family: inherit; font-size: inherit;\">\u20ac\/Smc<\/span><\/td>\n<td style=\"width: 20%; height: 24px;\">127,20 euro<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Come sintetizzato in tabella, ecco il podio delle soluzioni gas stilato dal <strong>comparatore di SOStariffe.it <\/strong>a gennaio 2023. Per ciascuna delle tre offerte &#8211; tutte con tariffa a prezzo indicizzato &#8211; le stime di spesa sono parametrate sul consumo di una &#8220;famiglia tipo&#8221; che utilizzi <strong>1.400 metri cubi<\/strong> di gas all&#8217;anno, con fornitura attiva nel comune di Milano.<\/p>\n<p>Chi non avesse il polso del proprio consumo annuo, pu\u00f2 calcolarlo grazie ai filtri integrati nel comparatore di SOStariffe.it. Clicca sul widget qui sotto per impostare direttamente i parametri di calcolo:<\/p>\n<p>[WIDGET-GAS]<\/p>\n<p>Il prezzo del gas elencato in tabella fa riferimento all&#8217;<a href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/glossario\/psv\">indice PSV<\/a> (Punto di Scambio Virtuale) relativo al mese di dicembre 2022 (l&#8217;ultimo attualmente disponibile). Tale valore \u00e8 eventualmente incrementato della quota aggiuntiva richiesta dal singolo fornitore.<\/p>\n<h3>Easy Gas di A2A Energia<\/h3>\n<p>L&#8217;offerta metano di <a href=\"https:\/\/www.sostariffe.it\/gas\/a2a-energia\/\"><strong>A2A Energia<\/strong><\/a> conquista la vetta della convenienza grazie a un costo del gas contenuto: i clienti, infatti, pagano la materia prima allo stesso prezzo del <strong>mercato all\u2019ingrosso<\/strong>. Inoltre, con <strong>l\u2019azzeramento<\/strong> del contributo fisso mensile (a copertura dei costi di commercializzazione) per i primi <strong>tre mesi <\/strong>di fornitura, si ottiene un extra risparmio in bolletta (pari a 37,50 euro).<\/p>\n<p>Di seguito i tratti distintivi della promozione:<\/p>\n<ul>\n<li><strong>prezzo indicizzato<\/strong> in base all\u2019indice <strong>PSV senza alcun sovrapprezzo<\/strong>;<\/li>\n<li><strong>contributo fisso mensile<\/strong> (pari a 12,50 euro) <strong>azzerato<\/strong> per i primi <strong>3 mesi<\/strong> di fornitura;<\/li>\n<li><strong>gestione online<\/strong> della fornitura con area Clienti online e App A2A;<\/li>\n<li>energia verde inclusa.<\/li>\n<\/ul>\n<p>Con l&#8217;attivazione di A2A Easy Gas, la bolletta mensile del metano per la \u201cfamiglia tipo\u201d sarebbe pari a <strong>114,68 euro<\/strong>.<\/p>\n<p>Per avere una panoramica dell\u2019offerta, clicca al link di seguito:<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=gas&amp;id=11054\" target=\"_blank\" rel=\"noopener noreferrer\">Scopri A2A Easy Gas \u00bb<\/a><\/p>\n<h3>Gas alla Fonte di wekiwi<\/h3>\n<p>Quali sono i benefici (in termini di risparmio e servizi) per i clienti domestici che si affidino alla fornitura gas proposta dalla web company <a href=\"https:\/\/www.sostariffe.it\/gas\/wekiwi\/\"><strong>wekiwi<\/strong><\/a>? La risposta \u00e8 concentrata nell&#8217;elenco puntato qui sotto:<\/p>\n<ul>\n<li><strong>prezzo <\/strong>del gas <strong>all&#8217;ingrosso <\/strong>(allineato al PSV) a cui va aggiunto un contributo al consumo di <strong>0,050 \u20ac\/Smc<\/strong>;<\/li>\n<li>costo fisso di 67 euro all\u2019anno per spese di commercializzazione (il canone mensile \u00e8 di appena 5,50 euro);<\/li>\n<li>sistema della &#8220;<strong>carica mensile<\/strong>&#8220;: il cliente sceglie l\u2019importo e la periodicit\u00e0 delle fatture in acconto, per poi ricevere conguagli solo su consumi reali;<\/li>\n<li><strong>bonus di benvenuto<\/strong> <strong>di 30 euro<\/strong> attivando l&#8217;offerta online e inserendo il codice sconto SOSW22;<\/li>\n<li><strong>sconto del 10%<\/strong> sull&#8217;acquisto dei prodotti in vendita sull\u2019e-shop wekiwi: illuminazione Led, demotica e altri gadget elettronici;<\/li>\n<li>energia verde inclusa.<\/li>\n<\/ul>\n<p>La &#8220;famiglia tipo&#8221; che scegliesse wekiwi per la fornitura metano pagherebbe <strong>124,32 euro<\/strong> al mese. Cliccando sul pulsante verde qui sotto, \u00e8 possibile consultare procedere con l&#8217;attivazione:<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/toc\/?id=5729&amp;medium=serp&amp;position=1&amp;redir=aHR0cHM6Ly93d3cuc29zdGFyaWZmZS5pdC9nYXMvZGV0YWlscy81NzI5L3dla2l3aV9nYXMtYWxsYS1mb250ZS8%2FeWVhcmx5X21jPTA%3D&amp;format=serp_result&amp;ext_params=yearly_mc%253D0&amp;direction=IN&amp;tagliawekiwi=20\" target=\"_blank\" rel=\"noopener noreferrer\">Scopri Gas alla Fonte wekiwi <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h3>World Gas Plus di Edison Energia<\/h3>\n<p>Tra le caratteristiche che rendono l&#8217;offerta di <a href=\"https:\/\/www.sostariffe.it\/gas\/edison-energia\/\"><strong>Edison Energia<\/strong>\u00a0<\/a>tra le pi\u00f9 competitive a gennaio 2023 si possono annoverare:<\/p>\n<ul>\n<li><strong>prezzo del gas all&#8217;ingrosso <\/strong>agganciato all\u2019indice <strong>PSV senza costi aggiuntivi<\/strong>;<\/li>\n<li>contributo fisso mensile <strong>scontato del 30%<\/strong>: da 20 euro a 14 euro al mese, per un totale di <strong>168 euro <\/strong>all\u2019anno;<\/li>\n<li>iniziativa <strong>Edison Cashback <\/strong>per ottenere ulteriori sconti in bolletta previa iscrizione al programma fedelt\u00e0 EdisonVille;<\/li>\n<li>accesso gratuito al servizio <strong>Edison Co.Co<\/strong>, la piattaforma anti-spreco basata sull\u2019intelligenza artificiale per monitorare i consumi degli elettrodomestici di casa;<\/li>\n<li>fornitura metano sempre a portata di smartphone grazie all&#8217;<strong>App My Edison<\/strong> e all&#8217;area Clienti online;<\/li>\n<li>energia 100% green.<\/li>\n<\/ul>\n<p>Sottoscrivendo questa promozione gas di Edison Energia, la \u201cfamiglia tipo\u201d dovrebbe preventivare un budget di spesa pari a <strong>127,20 euro<\/strong> al mese.<\/p>\n<p>Cliccando al link di seguito, informazioni sull&#8217;offerta e i passi per attivarla:<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/toc\/?id=11063&amp;medium=serp&amp;position=1&amp;redir=aHR0cHM6Ly93d3cuc29zdGFyaWZmZS5pdC9nYXMvZGV0YWlscy8xMTA2My9lZGlzb24tZW5lcmdpYV9lZGlzb24td29ybGQtZ2FzLXBsdXMvP3llYXJseV9tYz0w&amp;format=serp_result&amp;ext_params=yearly_mc%253D0&amp;direction=IN\" target=\"_blank\" rel=\"noopener noreferrer\">SCOPRI EDISON WORLD GAS PLUS <span style=\"\u201ctext-align: right&quot;;\">\u00bb<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il prezzo del gas all\u2019ingrosso \u00e8 in contrazione da settimane, ma a gennaio 2023 le bollette del metano crescono del +23,3% per i clienti della Maggior Tutela. Ecco le soluzioni gas del Mercato Libero per tenere sotto controllo i rialzi e trarre subito il massimo vantaggio dalla battuta d\u2019arresto delle quotazioni gas al TTF di [&hellip;]<\/p>\n","protected":false},"author":108,"featured_media":359046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1098],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/359045"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=359045"}],"version-history":[{"count":14,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/359045\/revisions"}],"predecessor-version":[{"id":359142,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/359045\/revisions\/359142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/359046"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=359045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=359045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=359045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}