{"id":358395,"date":"2023-01-10T10:00:37","date_gmt":"2023-01-10T09:00:37","guid":{"rendered":"http:\/\/www.sostariffe.it\/news\/?p=358395"},"modified":"2023-03-08T15:49:14","modified_gmt":"2023-03-08T14:49:14","slug":"come-ottenere-il-bonus-tv-a-gennaio-2023","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/come-ottenere-il-bonus-tv-a-gennaio-2023-358395\/","title":{"rendered":"Come ottenere il bonus TV a gennaio 2023?"},"content":{"rendered":"<p>Il <strong>bonus decoder gratis a casa per over 70<\/strong> \u00e8 l\u2019unica agevolazione per la televisione rimasta a <strong>gennaio 2023<\/strong>. Per sapere come funziona questa misura c\u2019\u00e8<strong> SOStariffe.it<\/strong>, il tool digitale e gratuito che offre anche una panoramica delle migliori offerte per la pay TV.<\/p>\n<p><!--more--><\/p>\n<p>\u00c8 ancora possibile ricevere a gennaio 2023 direttamente a casa e gratuitamente il<strong> bonus decoder<\/strong> per chi ha un\u2019et\u00e0 <strong>di 70 anni o superiore<\/strong>, ha un trattamento da assegno pensionistico non superiore a 20.000 mila euro l\u2019anno ed \u00e8 titolare di un canone d\u2019abbonamento Rai.<\/p>\n<h2>Bonus decoder over 70 a domicilio: che cos\u2019\u00e8<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 96px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\"><\/td>\n<td style=\"width: 50%; height: 24px;\"><strong>REQUISITI PER RICHIEDERLO<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\">1<\/td>\n<td style=\"width: 50%; height: 24px;\">Avere un&#8217;et\u00e0 di <strong>70 anni o superiore<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\">2<\/td>\n<td style=\"width: 50%; height: 24px;\">Essere titolare dell&#8217;<strong>abbonamento Rai<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\">3<\/td>\n<td style=\"width: 50%; height: 24px;\">Avere un reddito annuo da trattamento pensionistico non superiore a <strong>20.000 euro<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Il dispositivo, che \u00e8 consegnato a domicilio, serve per continuare a vedere la TV <a href=\"https:\/\/www.sostariffe.it\/news\/nuovo-digitale-terrestre-2023-tv-e-cosa-succede-dopo-lo-switch-off-a-gennaio-358075\/\">dopo lo switch-off dello scorso 21 dicembre 2022<\/a>, quando si \u00e8 passati alla trasmissione <strong>in alta definizione<\/strong> e, al conseguente spegnimento dei canali a bassa qualit\u00e0, cio\u00e8 dal numero 500 e oltre del telecomando.<\/p>\n<p>Grazie alla collaborazione tra il <strong>Ministero delle Imprese e del Made in Italy e Poste italiane<\/strong>, il decoder arriva a casa, senza costi, qualora si soddisfino i tre requisiti sopra indicati.<\/p>\n<p>Una volta collegato al proprio televisore, l\u2019apparecchio TV andr\u00e0 risintonizzato. Completato le due operazioni, il televisione riprender\u00e0 a funzionare regolarmente.<\/p>\n<h2>Bonus decoder a casa over 70: come richiederlo<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 120px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\"><\/td>\n<td style=\"width: 50%; height: 24px;\"><strong>DOVE RICHIEDERE IL DECODER<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\">1<\/td>\n<td style=\"width: 50%; height: 24px;\">Chiamando il numero <strong>800 776 883<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\">2<\/td>\n<td style=\"width: 50%; height: 24px;\">In un <strong>ufficio postale<\/strong> in tutta Italia<\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td style=\"width: 50%; height: 48px;\">3<\/td>\n<td style=\"width: 50%; height: 48px;\">Sul sito <strong>www.prenotazionedecodertv.it\/booking\/<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Gli aventi diritto al Bonus potranno farne richiesta e pianificare un appuntamento per la consegna del decoder nelle seguenti modalit\u00e0:<\/p>\n<ul>\n<li>attraverso il numero <strong>800 776 883<\/strong>, selezionando la sezione relativa alla consegna a domicilio dei Decoder TV (il servizio \u00e8 disponibile dal luned\u00ec al venerd\u00ec dalle ore 10 alle 18, festivi esclusi);<\/li>\n<li>andando in uno dei quasi <strong>13 mila uffici postali<\/strong> presenti in tutta Italia negli orari di apertura;<\/li>\n<li>cliccando 24 ore su 24 e 7 giorni su 7 a questo indirizzo www.prenotazionedecodertv.it\/booking\/.<\/li>\n<\/ul>\n<p>Per richiedere il riconoscimento del Bonus e prenotare la consegna del decoder TV a domicilio sar\u00e0 necessario avere a disposizione il codice fiscale e la tessera sanitaria\/documento di identit\u00e0 in corso di validit\u00e0 del titolare dell\u2019abbonamento Rai.<\/p>\n<p>All\u2019atto della prenotazione, avendo identificato il richiedente e verificato la presenza dei requisiti richiesti per ottenere l&#8217;agevolazione, potr\u00e0 essere fissata la data di consegna a casa del decoder, che il Ministero mette a disposizione gratuitamente, e che sar\u00e0 effettuata da un <strong>portalettere di Poste Italiane<\/strong>.<\/p>\n<p>Successivamente alla consegna, l\u2019utente che ne abbia la necessit\u00e0, potr\u00e0 ricevere assistenza telefonica nell\u2019 installazione e nella configurazione del decoder.<\/p>\n<p>A questo proposito, il ministero delle Imprese e del Made in Italy offre:<\/p>\n<ul>\n<li>un servizio di call center al numero <strong>06.87800262<\/strong> (attivo dal luned\u00ec al venerd\u00ec dalle 9 alle 18);<\/li>\n<li>un servizio su WhatsApp, scrivendo al numero <strong>340.1206348<\/strong>.<\/li>\n<\/ul>\n<h2>Bonus TV-decoder e Bonus Tv rottamazione a gennaio 2023<\/h2>\n<p>Non possono beneficiare della consegna gratuita del decoder i cittadini che, pur essendo in possesso dei requisiti richiesti, abbiano gi\u00e0 usufruito del <strong>Bonus TV-decoder<\/strong>.\u00a0L\u2019agevolazione \u00e8 invece<strong> cumulabile<\/strong> con il Bonus TV rottamazione sia che quest\u2019ultimo sia stato gi\u00e0 erogato, sia che si intenda richiederlo successivamente alla domanda per la consegna del decoder.<\/p>\n<p>Gli aventi diritto al Bonus potranno farne richiesta dal momento dell\u2019avvio dell\u2019iniziativa e fino ad esaurimento delle risorse disponibili. Una volta esaurite le risorse (68 milioni di euro) a disposizione non sar\u00e0 pi\u00f9 possibile richiedere il Bonus decoder TV in questa modalit\u00e0.<\/p>\n<p>Va ricordato, inoltre, che il bonus TV-decoder e il bonus TV rottamazione non sono stati <strong>rinnovati nel 2023<\/strong>, non essendo stati previsti finanziamenti nella legge di Bilancio varata dal governo Meloni.<\/p>\n<p>Pertanto, non sar\u00e0 pi\u00f9 possibile beneficiare di queste due misure che prevedevano:<\/p>\n<ul>\n<li>per il bonus TV-Decoder lo sconto era <strong>fino a 30 euro<\/strong> sul prezzo del prodotto acquistato con un ISEE inferiore a 20.000 euro e si poteva chiedere una sola volta a famiglia. A\u00a0partire da ottobre 2022, per l\u2019acquisto di decoder satellitari o di TV con decoder satellitare integrato, il Bonus poteva essere concesso fino a un importo di<strong> 50 euro<\/strong>;<\/li>\n<li>per il bonus rottamazione TV era possibile richiederlo per sostituire un televisore acquistato prima del 22 dicembre 2018. Per ottenerlo era sufficiente essere residente in Italia e in regola con il pagamento del canone Rai. Non prevedeva limiti di ISEE. Consisteva in uno sconto (<strong>fino a 100 euro<\/strong>) sul prezzo d\u2019acquisto della TV.<\/li>\n<\/ul>\n<h2>Pay TV: le migliori offerte attivabili a gennaio 2023<\/h2>\n<p>Il <strong>comparatore di SOStariffe.it<\/strong> permette di confrontare le offerte per la pay TV sia per la TV tradizionale che in streaming con una panoramica di tutte le proposte pi\u00f9 vantaggiose.<\/p>\n<p>A questo riguardo, occorre osservare che flessibilit\u00e0 e low cost sono due delle caratteristiche che stanno facendo traghettare migliaia di abbonati delle tradizionali pay TV verso le soluzioni streaming. Infatti, lo streaming permette la visione anche su supporti mobili, oltre al classico televisore, e consente anche un\u2019ampia scelta di contenuti a prezzi davvero convenienti.<\/p>\n<p>A proposito dei costi, c\u2019\u00e8 da notare che queste soluzioni sono vendute anche in abbinamento con servizi di <strong>telefonia fissa e di <a href=\"https:\/\/www.sostariffe.it\/internet-casa\/verifica-copertura\/\">ADSL o fibra<\/a><\/strong> per la connessione internet casalinga. Il funzionamento della<a href=\"https:\/\/www.sostariffe.it\/tv\/faq\/\"> streaming <\/a>tv, infatti,\u00a0dipende proprio dalla linea internet domestica o mobile.<\/p>\n<p>Le piattaforme streaming, infine, hanno cataloghi con migliaia di titoli e consentono anche la visione di eventi sportivi esclusivi. E offrono anche la disponibilit\u00e0 di visionare i contenuti acquistati su pi\u00f9 dispositivi.<\/p>\n<p>Per conoscere quali siano le <b>migliori offerte<\/b> di gennaio 2023, c\u2019\u00e8 il comparatore per <b>pay TV<\/b> di <b>SOStariffe.it<\/b>. Per saperne di pi\u00f9 sulle alternative disponibili, clicca il bottone verde qui sotto:<br \/>\n<a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/tv\/\" target=\"_blank\" rel=\"noopener noreferrer\">CONFRONTA LE OFFERTE PAY TV <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il bonus decoder gratis a casa per over 70 \u00e8 l\u2019unica agevolazione per la televisione rimasta a gennaio 2023. Per sapere come funziona questa misura c\u2019\u00e8 SOStariffe.it, il tool digitale e gratuito che offre anche una panoramica delle migliori offerte per la pay TV.<\/p>\n","protected":false},"author":108,"featured_media":358396,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[22318,1087],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/358395"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=358395"}],"version-history":[{"count":7,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/358395\/revisions"}],"predecessor-version":[{"id":358815,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/358395\/revisions\/358815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/358396"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=358395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=358395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=358395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}