{"id":358215,"date":"2023-01-05T09:39:24","date_gmt":"2023-01-05T08:39:24","guid":{"rendered":"http:\/\/www.sostariffe.it\/news\/?p=358215"},"modified":"2023-01-07T21:58:58","modified_gmt":"2023-01-07T20:58:58","slug":"crolla-il-prezzo-del-gas-allingrosso-ad-inizio-2023-ecco-come-cambieranno-le-bollette","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/crolla-il-prezzo-del-gas-allingrosso-ad-inizio-2023-ecco-come-cambieranno-le-bollette-358215\/","title":{"rendered":"Crolla il prezzo del gas all&#8217;ingrosso ad inizio 2023: ecco come cambieranno le bollette"},"content":{"rendered":"<p>L&#8217;evoluzione del mercato energetico all&#8217;ingrosso continua: c<strong>on l&#8217;inizio del 2023<\/strong>, infatti, <strong>il prezzo del gas all&#8217;ingrosso ha fatto registrato un vero crollo,<\/strong> ritornando ai <strong>livelli di inizio 2022.<\/strong> Si tratta di un vero e proprio dimezzamento rispetto alle quotazioni di inizio dicembre e di un&#8217;ottima notizia in vista dei prossimi mesi. Le <strong>bollette di luce e gas<\/strong>, infatti, potrebbero finalmente <strong>tornare su livelli pi\u00f9 sostenibili<\/strong> anche se sar\u00e0 necessario attendere le prossime settimane per avere un quadro pi\u00f9 completo sulla situazione. <!--more--><\/p>\n<p><strong>Le bollette di luce e gas potrebbero tornare su valori pi\u00f9 contenuti nel corso dei primi mesi del 2023<\/strong>. Tutto ruota intorno al recente<strong> calo del prezzo del gas all&#8217;ingrosso<\/strong> che ha registrato un vero e proprio crollo tra fine dicembre e inizio gennaio, per effetto della combinazione di vari fattori che hanno contribuito a ridurre le quotazioni dell&#8217;indice TTF. Nonostante il recente aumento del prezzo del gas in Tutela (dovuto alla crescita del prezzo all&#8217;ingrosso tra novembre e inizio dicembre), all&#8217;orizzonte potrebbe esserci una netta riduzione delle bollette nel prossimo futuro.<\/p>\n<h2>Il prezzo del gas all&#8217;ingrosso \u00e8 al minimo da inizio 2022<\/h2>\n<table style=\"border-collapse: collapse; width: 100%; height: 96px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px; text-align: center;\"><\/td>\n<td style=\"width: 50%; height: 24px; text-align: center;\"><strong>LE ULTIME SUL PREZZO DEL GAS ALL&#8217;INGROSSO<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td style=\"width: 50%; height: 48px;\">1.<\/td>\n<td style=\"width: 50%; height: 48px;\">La <strong>quotazione del gas all&#8217;ingrosso<\/strong> \u00e8 tornata ai <strong>livelli di gennaio 2022<\/strong> (circa 64 euro al megawattora)<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 50%; height: 24px;\">2.<\/td>\n<td style=\"width: 50%; height: 24px;\">A causare il calo ci sono vari fattori e, in particolare, il <strong>clima particolarmente mite<\/strong> dell&#8217;autunno e di inizio inverno<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">3.<\/td>\n<td style=\"width: 50%;\">Il calo del prezzo all&#8217;ingrosso potr\u00e0 generare un<strong> calo delle bollette<\/strong> a partire da <strong>gennaio 2023<\/strong> per il <strong>Mercato<\/strong> <strong>Libero<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Nel corso di questa settimana si \u00e8 registrato un nuovo calo del prezzo del gas all&#8217;ingrosso. L&#8217;indice <strong>TTF<\/strong> \u00e8 sceso fino ad un <strong>minimo di circa 64 euro al megawattora<\/strong>. Di fatto, siamo tornati ai valori (comunque alti) di<strong> inizio gennaio 2022<\/strong>. Il prezzo all&#8217;ingrosso del gas \u00e8 ora pari a meno della met\u00e0 di quanto registrato ad inizio dicembre 2022 ed a circa il 20% della quotazione record registrata ad agosto 2022.<\/p>\n<p>A causare questo calo \u00e8 la<strong> combinazione di diversi fattori<\/strong>. Il clima particolarmente mite, rispetto alle medie stagionali, ha permesso di ridurre drasticamente il consumo di gas in Europa. Gli stoccaggi, quindi, sono ancora molto alti e quest&#8217;elemento gioca un ruolo determinante nella riduzione del prezzo del gas all&#8217;ingrosso. Da notare che anche la riduzione delle forniture dalla Russia e la definizione di una normativa europea sul tetto al prezzo del gas potrebbero aver influenzato questo trend.<\/p>\n<h3>Quando caleranno le bollette di luce e gas?<\/h3>\n<p>Il <strong>calo del prezzo all&#8217;ingrosso del gas<\/strong> potr\u00e0 portare (se le quotazioni si stabilizzeranno su livelli contenuti) ad un<strong> calo del prezzo al dettaglio sia del gas che dell&#8217;energia elettrica<\/strong> (prodotta in larga parte tramite gas naturale). Sar\u00e0 necessario, per\u00f2, attendere alcune settimane. Per quanto riguarda le <strong>offerte del Mercato Libero con prezzo indicizzato,<\/strong> infatti, il primo calo potrebbe arrivare gi\u00e0 sulle bollette relative ai consumi di gennaio (molto dipender\u00e0 dall&#8217;andamento degli indici PUN per la luce e PSV per il gas).<\/p>\n<p>Per le<strong> offerte del Mercato Libero a prezzo bloccato,<\/strong> invece, non ci saranno modifiche. I fornitori, per\u00f2, potrebbero tornare a proporre tariffe di questo tipo nel corso delle prossime settimane, garantendo agli utenti una protezione contro i possibili rincari futuri del mercato energetico. In questo caso, la scelta giusta per individuare una nuova offerta \u00e8 rappresentata dal <strong>comparatore di SOStariffe.it per offerte luce e gas<\/strong>, accessibile dal link qui di sotto.<\/p>\n<p>Basta indicare una stima del proprio consumo per accedere subito ad una panoramica delle offerte pi\u00f9 vantaggiose. Per assistenza nella scelta, invece, \u00e8 possibile fare riferimento al <strong>servizio di consulenza di SOStariffe.it<\/strong>, disponibile, gratuitamente e senza alcun impegno, chiamando al numero <strong>02 5005 111<\/strong>.<\/p>\n<p><a class=\"green-cta\" href=\"https:\/\/www.sostariffe.it\/energia-elettrica-gas\/\" target=\"_blank\" rel=\"noopener noreferrer\">Scopri qui le migliori offerte luce e gas <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Per il <strong>Mercato Tutelato<\/strong>, invece, <strong>\u00e8 necessario aspettare.<\/strong> Il prezzo della luce in Tutela, infatti, \u00e8 fisso e bloccato fino alla fine del prossimo mese di marzo. ARERA ha annunciato alcuni giorni fa il nuovo prezzo (ancora sopra quota 50 centesimi al kWh). Per i clienti in Tutela, quindi, i possibili effetti positivi sulla bolletta legati al calo del prezzo del gas arriveranno soltanto a partire dal prossimo mese di aprile.<\/p>\n<p>Per il gas, invece, grazie al meccanismo che prevede un aggiornamento mensile del prezzo (introdotto da ARERA lo scorso ottobre) i vantaggi in bolletta potrebbero arrivare gi\u00e0 nelle prossime settimane. Tutto dipender\u00e0 dall&#8217;andamento dell&#8217;indice PSV che rappresenta il riferimento utilizzato da ARERA per definire il prezzo del gas per il Mercato Tutelato. Ne sapremo di pi\u00f9 a breve.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;evoluzione del mercato energetico all&#8217;ingrosso continua: con l&#8217;inizio del 2023, infatti, il prezzo del gas all&#8217;ingrosso ha fatto registrato un vero crollo, ritornando ai livelli di inizio 2022. Si tratta di un vero e proprio dimezzamento rispetto alle quotazioni di inizio dicembre e di un&#8217;ottima notizia in vista dei prossimi mesi. Le bollette di luce [&hellip;]<\/p>\n","protected":false},"author":47,"featured_media":358216,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1095,1098],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/358215"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=358215"}],"version-history":[{"count":1,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/358215\/revisions"}],"predecessor-version":[{"id":358217,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/358215\/revisions\/358217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/358216"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=358215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=358215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=358215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}