{"id":340030,"date":"2021-11-09T13:00:24","date_gmt":"2021-11-09T12:00:24","guid":{"rendered":"http:\/\/www.sostariffe.it\/news\/?p=340030"},"modified":"2024-02-20T09:24:44","modified_gmt":"2024-02-20T08:24:44","slug":"rete-fissa-di-iliad-le-novita-di-novembre-2021","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/rete-fissa-di-iliad-le-novita-di-novembre-2021-340030\/","title":{"rendered":"Rete fissa di Iliad: le novit\u00e0 di Novembre 2021"},"content":{"rendered":"<p>Grande attesa per la <strong>rete fissa Iliad<\/strong>. L&#8217;operatore ha annunciato il prossimo lancio di un&#8217;<strong>offerta fibra ottica<\/strong> per la <strong>FTTH<\/strong> fino a <strong>1 Gigabit<\/strong>. Le ultime novit\u00e0<!--more--><\/p>\n<p><a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/iliad\/\"><strong>Iliad<\/strong> <\/a>al suo arrivo in Italia ha annunciato che avrebbe portato una rivoluzione nel settore della <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/\"><strong>telefonia mobile<\/strong><\/a> nostrano. L&#8217;operatore francese senza ombra di dubbio \u00e8 riuscito nel suo intento. In appena tre anni \u00e8 infatti riuscito a superare la soglia di 7,8 milioni di utenti attivi e una quota di mercato superiore al 10%, che lo rende il quarto pi\u00f9 grande gestore mobile a livello nazionale. <strong>Iliad<\/strong> ora \u00e8 pronto a fare il passo successivo ed estendere la sua offerta anche alla linea fissa. L&#8217;annuncio \u00e8 arrivato l&#8217;anno scorso ma l&#8217;effettivo lancio della <strong>rete fissa Iliad<\/strong> \u00e8 stata procrastinato pi\u00f9 volte. Negli ultimi giorni per\u00f2 sono emerse voci molto interessanti in merito all&#8217;offerta per la connessione domestica dell&#8217;operatore low cost francese.<\/p>\n<h2>Rete fissa Iliad: le novit\u00e0 di novembre<\/h2>\n<p>La notizia della <strong>rete fissa Iliad<\/strong> \u00e8 arrivata durante il 2020 con l&#8217;annuncio da parte dell&#8217;azienda francese di un accordo con <strong>Open Fiber<\/strong>, tra i pi\u00f9 grandi wholesaler italiani nel settore della connessione Internet terrestre, per la realizzazione di una rete condivisa in <strong>fibra ottica<\/strong> nella tecnologia <strong>FTTH<\/strong> (Fiber to the Home). L&#8217;azienda inizialmente parlava di un ipotetico lancio della <strong>rete fissa Iliad<\/strong> nel corso del 2021 per poi annunciarne il debutto prima dell&#8217;estate scorsa.<\/p>\n<p>Nel corso della presentazione dei dati finanziari per il 2020, il CEO di <strong>Iliad<\/strong>, <strong>Thomas Reynaud<\/strong>, ha posticipato la disponibilit\u00e0 della prima offerta per la <strong>rete fissa Iliad<\/strong> a dopo l&#8217;estate ma senza indicare una data pi\u00f9 precisa. Ad agosto l&#8217;operatore ha poi annunciato un secondo accordo con <strong>FiberCop<\/strong>, societ\u00e0 che fa parte del gruppo <strong>TIM<\/strong>, sempre per lo sviluppo di una rete in fibra ottica. L&#8217;alleanza con il suo concorrente nel settore mobile non sostituisce ma si affianca a quella con <strong>Open Fiber<\/strong>. &#8220;<em>Il piano di investimenti di FiberCop<\/em> &#8211; si legge in una nota sul sito dell&#8217;operatore\u00a0&#8211; <em>assicurer\u00e0 la copertura FTTH al 75% delle aree grigie e nere nel Paese entro il 2025. TIM offrir\u00e0 inoltre a Iliad l&#8217;accesso alla rete primaria in fibra<\/em>&#8220;. Il logo di <strong>Iliad<\/strong> \u00e8 poi comparso sul sito di <strong>FiberCop<\/strong> nei primi giorni di ottobre.<\/p>\n<p>Le novit\u00e0 pi\u00f9 succose sulla <strong>rete fissa Iliad<\/strong> arrivano per\u00f2 da un articolo pubblicato su <strong>Repubblica<\/strong> la scorsa settimana. Il quotidiano afferma che l&#8217;<a href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-fibra-ottica\/\"><strong>offerta fibra ottica<\/strong><\/a> del provider francese sar\u00e0 lanciata entro al fine di novembre o comunque al massimo entro i giorni immediatamente precedenti al periodo natalizio. Repubblica va anche oltre, affermando che con il debutto di <strong>Iliad<\/strong> nel mercato della rete fissa provocher\u00e0 un effetto a catena sull&#8217;intero settore. Si vocifera infatti che anche <strong>Kena Mobile<\/strong> e <strong>ho. Mobile<\/strong>, rispettivamente marchi low cost di <strong>TIM<\/strong> e <strong>Vodafone<\/strong>, lanceranno una propria <a href=\"https:\/\/www.sostariffe.it\/internet-casa\/\"><strong>offerta Internet casa<\/strong><\/a>. Altre fonti meno autorevoli parlano anche di <strong>Very Mobile<\/strong>, operatore virtuale di <strong>WindTre<\/strong>.<\/p>\n<h2>Rete fissa Iliad, come sar\u00e0 l&#8217;offerta?<\/h2>\n<p>Ad oggi l&#8217;unica sappiamo che la<strong> rete fissa Iliad<\/strong> sar\u00e0 disponibile in tutti i principali Comuni italiani grazie alla collaborazione con <strong>OpenFiber<\/strong> e <strong>FiberCop<\/strong>. La velocit\u00e0 di navigazione sar\u00e0 fino a <strong>1 Gigabit al secondo<\/strong> in download con una connessione <strong>FTTH<\/strong>, in cui il segnale raggiunge direttamente il modem finale dell&#8217;utente. Non \u00e8 dato sapere se <strong>Iliad<\/strong> preveder\u00e0 in alternativa anche una rete con <strong>fibra mista rame<\/strong> o <strong>FTTC<\/strong> (Fiber to the Cabinet) come fanno altri operatori di rete fissa. Questa tecnologia permette di arriva fino a <strong>100\/200 Mbps<\/strong> in download a seconda della distanza dell&#8217;abitazione dalla cabina stradale. Per <a href=\"https:\/\/www.sostariffe.it\/internet-casa\/verifica-copertura\/\"><strong>verificare la copertura<\/strong><\/a> disponibile al vostro indirizzo potete utilizzare gratuitamente l&#8217;apposito strumento di <strong>SOStariffe.it<\/strong>.<\/p>\n<p><a class=\"green-cta\" style=\"width: 410px; height: 30px; line-height: 30px; font-size: 15px;\" href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-adsl\/\">Confronta le offerte Internet casa dei migliori operatori <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Per avere un&#8217;idea sulle caratteristiche e i servizi inclusi nell&#8217;offerta per la<strong> rete fissa Iliad<\/strong> si pu\u00f2 fare un paragone con la tariffa media degli altri provider e quella di <strong>Free<\/strong>, marchio con cui l&#8217;azienda propone servizi per la connessione Internet di casa in Francia. La maggior parte dei gestori in Italia prevede promozioni con <strong>chiamate, attivazione e modem incluso<\/strong>. A questi servizi \u00e8 possibile in qualche caso avere gratuitamente anche piattaforme per l&#8217;intrattenimento televisivo proprietarie (TIMVISION, Vodafone TV) o di terzi (Netflix, Amazon Prime Video, Disney+, DAZN, etc). Il prezzo mensile medio per l&#8217;offerta base \u00e8 di circa <strong>25-26 euro<\/strong>.<\/p>\n<p>Sappiamo anche che Reynaud ha confermato che quest&#8217;anno in Italia e Polonia verr\u00e0 lanciato <strong>Freebox Pop<\/strong>, un modem portatile di forma circolare incluso nelle <strong>offerte Internet casa<\/strong> di <strong>Free<\/strong>. Il dispositivo permette di connettersi alla massima velocit\u00e0 garantita dalla fibra anche con ppi\u00f9 dispositivi collegati contemporaneamente. Recentemente tra le lingue disponibili per la configurazione e gestione del router \u00e8 stata aggiunta anche l&#8217;italiano a conferma che effettivamente il terminale \u00e8 pronto ad arrivare nel nostro Paese. Non \u00e8 chiaro per\u00f2 se <strong>Freebox Pop<\/strong> avr\u00e0 le stesse carattersitiche del modello utilizzato in Francia.<\/p>\n<p>L&#8217;offerta di <strong>Free<\/strong> prevede anche <strong>Player Pop<\/strong>, un TV box con sistema operativo Android e Chromecast integrata dotato di telecomando intelligente. Il terminale dispone poi di 2 GB di RAM, 16 GB di spazio d&#8217;archiviazione per il salvataggio dei contenuti contenuti. Per una maggiore sicurezza per l&#8217;autenticazione si utilizza un QR Code. <strong>Player Pop <\/strong>inoltre supporta video in<strong> 4K <\/strong>e supporta i sistemi audio <strong>Dolby Atmos <\/strong>e<strong> Surrond 5.1<\/strong>. Il TV Box quindi offre la visione su dispositivi mobili e smart TV di film, serie TV, documentari, cartoni animati e contenuti originali trasmessi su pi\u00f9 di 200 canali di <strong>Canal+<\/strong> e permette di accedere anche ad app popolari come Netflix o Prime Video. <strong>Freebox Pop<\/strong> ha un costo di <strong>29,99 euro al mese per un anno<\/strong>, poi 39,99 euro al mese.<\/p>\n<p><strong>Iliad<\/strong> come ha fatto nel settore mobile \u00e8 probabile che proporr\u00e0 un prezzo inferiore a quello della media del mercato e non \u00e8 nemmeno da escludere che disporr\u00e0 anche di un&#8217;<strong>offerta convergente fisso-mobile<\/strong>, che includa quindi oltre alla connessione fissa anche una SIM per smartphone o tablet.<\/p>\n<p>Al momento quindi non \u00e8 possibile avere certezze su quando verr\u00e0 lanciata l&#8217;offerta <strong>rete fissa Iliad<\/strong> n\u00e9 su quali saranno i servizi inclusi e il prezzo mensile. Nel frattempo, ecco una panoramica completa sulle tariffe di telefonia mobile dell&#8217;operatore low cost. Tutte le promozioni di <strong>Iliad<\/strong> sono senza vincoli di durata n\u00e9 costi nascosti. Solo nel caso di acquisto di uno <strong>smartphone a rate<\/strong>, opzione attivabile dall&#8217;<strong>Area Personale<\/strong> da telefono o web, \u00e8 previsto un vincolo di permanenza di 30 mesi. Altrimenti, l&#8217;utente pu\u00f2 recedere dal contratto in ogni momento senza penali o sostenere costi di disattivazione. Il gestore inoltre fissa il prezzo delle offerte per sempre, in quanto non applica rimodulazioni, e non pone limiti alla velocit\u00e0 di navigazione. I gi\u00e0 clienti poi da qualche settimana possono passare gratuitamente a <strong>Giga 120<\/strong> facendo richiesta dall&#8217;<strong>Area Personale<\/strong>.<\/p>\n<h3>1. Giga 120<\/h3>\n<ul>\n<li>Minuti e SMS illimitati<\/li>\n<li>120 GB di traffico per navigare su Internet in 4G, 4G+ o 5G (6 GB in roaming in Ue)<\/li>\n<\/ul>\n<p>La tariffa ha un costo di <strong>9,99 euro al mese<\/strong> per sempre. La <strong>SIM<\/strong> ha un prezzo di <strong>9,99 euro<\/strong> una tantum.<\/p>\n<p><a class=\"green-cta\" style=\"width: 300px; height: 30px; line-height: 30px; font-size: 15px;\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=news_content&amp;id=9733\">Attiva Giga 120 <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p><strong>I<\/strong><strong>liad<\/strong> ha raggiunto una <strong>copertura<\/strong> del<strong> 99%<\/strong> della popolazione italiana in <strong>4G<\/strong>. L&#8217;operatore stando ai dati della societ\u00e0 di analisi indipendente <strong>Opensignal <\/strong>\u00e8 il secondo Download Speed Experience<strong>. <\/strong>Il gestore permette di navigare fino a <strong>855 Mbps<\/strong> in download in <a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/5g\/\"><strong>5G<\/strong><\/a> in alcune aree dei Comuni di:<\/p>\n<ul>\n<li>Alessandria<\/li>\n<li>Bari<\/li>\n<li>Bologna<\/li>\n<li>Brescia<\/li>\n<li>Cagliari<\/li>\n<li>Como<\/li>\n<li>Ferrara<\/li>\n<li>Firenze<\/li>\n<li>Genova<\/li>\n<li>La Spezia<\/li>\n<li>Latina<\/li>\n<li>Messina<\/li>\n<li>Milano<\/li>\n<li>Modena<\/li>\n<li>Padova<\/li>\n<li>Perugia<\/li>\n<li>Pesaro<\/li>\n<li>Pescara<\/li>\n<li>Piacenza<\/li>\n<li>Prato<\/li>\n<li>Ravenna<\/li>\n<li>Reggio Calabria<\/li>\n<li>Reggio Emilia<\/li>\n<li>Roma<\/li>\n<li>Torino<\/li>\n<li>Verona<\/li>\n<li>Vicenza<\/li>\n<\/ul>\n<p><strong>Iliad<\/strong> sta ampliando i dispositivi in grado di connettersi alla sua rete <strong>5G<\/strong>. I modelli attualmente compatibili sono:<\/p>\n<ul>\n<li><strong><span class=\"bold\">Huawei<\/span><\/strong>: P40, P40 Pro, P40 Pro +<\/li>\n<li><strong><span class=\"bold\">Oppo<\/span><\/strong>: Reno4 5G, Reno4 Pro 5G, Find X2 Lite, Find X2 Neo, Find X2 Pro, Find X3 Lite, Find X3 Neo<\/li>\n<li><strong><span class=\"bold\">Xiaomi<\/span><\/strong>: MI 10T Lite 5G, Mi 10, Mi 10T, Mi 10T Pro, Mi 10 Pro, Mi 11, Mi 11 Lite 5G, Mi 11i, Redmi Note 9T 5G, Redmi Note 10 5G<\/li>\n<li><strong><span class=\"bold\">Motorola<\/span><\/strong>: Edge, Edge+, Moto G 5G, Moto G 5G Plus, Moto Razr 5G, Moto g50, Moto g100<\/li>\n<li><strong><span class=\"bold\">Nokia<\/span><\/strong>: Nokia 8.3 5G, Nokia X10, Nokia X20<\/li>\n<li><strong><span class=\"bold\">Apple<\/span><\/strong>: iPhone 12, iPhone 12 mini, iPhone 12 Pro, iPhone 12 Pro Max<\/li>\n<li><strong><span class=\"bold\">Google<\/span><\/strong>: Pixel 5, Pixel 4a 5G<\/li>\n<li><strong><span class=\"bold\">OnePlus<\/span><\/strong>: OnePlus 8T, OnePlus 8T+ 5G<\/li>\n<li><strong><span class=\"bold\">Poco<\/span><\/strong>: Poco F3<\/li>\n<li><strong><span class=\"bold\">Samsung<\/span><\/strong>: Galaxy Tab S7 FE 5G, Galaxy Note20 5G, Galaxy Note20 Ultra 5G<\/li>\n<li><strong><span class=\"bold\">Sony<\/span><\/strong>: Xperia 5 II<\/li>\n<li><strong><span class=\"bold\">Vivo<\/span><\/strong>: X51 5G<\/li>\n<\/ul>\n<h3><strong>2. Giga 80<\/strong><\/h3>\n<ul>\n<li>Minuti e SMS illimitati<\/li>\n<li>80 GB di traffico per navigare su Internet in 4G o 4G+ (4 GB in roaming in Ue)<\/li>\n<\/ul>\n<p>La tariffa ha un costo di<strong> 7,99 euro al mese<\/strong> per sempre. La <strong>SIM<\/strong> ha un prezzo di<strong> 9,99 euro<\/strong> una tantum.<\/p>\n<p><a class=\"green-cta\" style=\"width: 300px; height: 30px; line-height: 30px; font-size: 15px;\" href=\"https:\/\/www.sostariffe.it\/tracker2.php?area=news_content&amp;id=9747\">Attiva Giga 80 <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h3><strong>3. Giga 40<\/strong><\/h3>\n<ul>\n<li>Minuti e SMS illimitati<\/li>\n<li>40 GB di traffico per navigare su Internet in 4G o 4G+ (4 GB in roaming in Ue)<\/li>\n<\/ul>\n<p>La tariffa ha un costo di<strong> 6,99 euro al mese<\/strong> per sempre. La <strong>SIM<\/strong> ha un prezzo di<strong> 9,99 euro<\/strong> una tantum.<\/p>\n<p>In tutte le offerte <strong>Iliad<\/strong> sono inoltre inclusi:<\/p>\n<ul>\n<li>Segreteria telefonica visiva<\/li>\n<li>Mi Richiami<\/li>\n<li>Nessuno scatto alla risposta<\/li>\n<li>Piano tariffario<\/li>\n<li>Hotspot<\/li>\n<li>Controllo credito residuo<\/li>\n<li>Disattivazione servizi a sovrapprezzo<\/li>\n<li>Visualizza numero di chiamate<\/li>\n<li>Controllo consumi<\/li>\n<li>Avviso di chiamata se numero occupato<\/li>\n<li>Blocco numeri nascosti<\/li>\n<li>Chiamate rapide<\/li>\n<li>Filtro chiamate e SMS<\/li>\n<li>Inoltro verso segreteria telefonica all&#8217;estero<\/li>\n<\/ul>\n<p>Per tutte le offerte, una volta esaurito il traffico dati incluso e previo espresso consenso, la navigazione costa <strong>90 cent ogni<\/strong> <strong>100 MB<\/strong>. In Europa si applica invece la tariffa sovrapprezzo di <strong>0,00427 euro ogni 1 MB<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grande attesa per la rete fissa Iliad. L&#8217;operatore ha annunciato il prossimo lancio di un&#8217;offerta fibra ottica per la FTTH fino a 1 Gigabit. Le ultime novit\u00e0<\/p>\n","protected":false},"author":72,"featured_media":340055,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[20744,22322],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/340030"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=340030"}],"version-history":[{"count":11,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/340030\/revisions"}],"predecessor-version":[{"id":384657,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/340030\/revisions\/384657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/340055"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=340030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=340030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=340030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}