{"id":339852,"date":"2021-11-04T14:29:32","date_gmt":"2021-11-04T13:29:32","guid":{"rendered":"http:\/\/www.sostariffe.it\/news\/?p=339852"},"modified":"2023-03-24T16:17:57","modified_gmt":"2023-03-24T15:17:57","slug":"tim-la-mail-non-funziona-le-soluzioni-di-novembre-2021","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/tim-la-mail-non-funziona-le-soluzioni-di-novembre-2021-339852\/","title":{"rendered":"TIM, la mail non funziona: le soluzioni di Novembre 2021"},"content":{"rendered":"<p><strong>TIM, la mail non funziona<\/strong>? Ecco cosa fare quando si presentano problemi con il servizio di posta elettronica dell&#8217;operatore italiano. Una guida semplice ed efficace di <strong>SOStariffe.it<\/strong><!--more--><\/p>\n<p><strong>TIM Mail<\/strong> \u00e8 il servizio di posta elettronica di <a href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-adsl-fibra-tim\/\"><strong>TIM<\/strong><\/a> disponibile per chi ha sottoscritto una delle sue<a href=\"https:\/\/www.sostariffe.it\/internet-casa\/\"><strong> offerte Internet casa<\/strong><\/a> sia da desktop sia su smartphone grazie alla nuova <strong>Mobi Mail<\/strong>. La piattaforma dell&#8217;operatore di rete fissa prevede <strong>3 GB<\/strong> di spazio d&#8217;archiviazione per i messaggi e consente di inviare allegati con dimensioni fino a <strong>2 GB<\/strong>. Il servizio inoltre integra filtri antispam e per organizzare la posta a piacimento o bloccare i mittenti indesiderati. I messaggi malevoli si cancellano ogni 20 giorni. <strong>TIM Mail<\/strong> consente di accedere con gli indirizzi <strong>@tim.it <\/strong>o<strong> @alice.it <\/strong>come webmail da tutti i principali browser su <strong>mail.tim.it\/<\/strong>\u00a0o utilizzando un <strong>client di posta<\/strong> come Outlook, Mail di Apple o Gmail. Non \u00e8 per\u00f2 previsto il backup dei dati. Per questo motivo \u00e8 opportuno fare un periodico salvataggio di recupero sul PC (la rubrica si pu\u00f2 esportare in formato CSV). A volte pu\u00f2 capitare per\u00f2 che non sia possibile effettuare il login o leggere e inviare messaggi. Nella maggior parte dei casi basta effettuare una verifica delle impostazioni per tornare a farla funzionare correttamente e non servono nemmeno particolari competenze dal lato informatico.<\/p>\n<p><a class=\"green-cta\" style=\"width: 300px; height: 30px; line-height: 30px; font-size: 15px;\" href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-adsl-fibra-tim\/\">Confronta le offerte Internet casa di TIM <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h2>TIM, la mail non funziona: problemi con il login<\/h2>\n<p>La prima cosa da fare quando non si riesce ad accedere a <strong>TIM Mail<\/strong> \u00e8 verificare che le credenziali per il login siano corrette. Nel caso in cui abbiate dimentico lo username o la password o entrambe \u00e8 sufficiente seguire una breve procedura online per recuperarle:<\/p>\n<ul>\n<li>Accedere da browser a <strong>mail.tim.it\/<\/strong><\/li>\n<li>Cliccare su <strong>recupera username e password<\/strong><\/li>\n<li>Per recuperare la password cliccare su <strong>Recupera password. <\/strong>Chi ha impostato un <strong>numero di cellulare di recupero <\/strong>ricever\u00e0 un codice via SMS da inserire sul web per impostare la nuova password. Altrimenti, vi verr\u00e0 richiesto di rispondere alla <strong>domanda scelta in fase di registrazione<\/strong>. Se risulta impossibile ritrovare la password se ne pu\u00f2 forzare il recupero inviando una fotocopia del documento d&#8217;identit\u00e0 a <strong>cambiopasswordmail@telecomitalia.it.<\/strong><\/li>\n<li>Per recuperare lo username cliccare su <strong>Recupera username<\/strong>. Tale funzione \u00e8 disponibile solo per gli indirizzi @tim.it e @alice.it. Se questi sono associati a un&#8217;offerta di <strong>telefonia mobile<\/strong> di <strong>TIM<\/strong> lo si potr\u00e0 visualizzare a video inserendo il relativo numero.\u00a0 Chi ha impostato un <strong>numero di cellulare di recupero <\/strong>ricever\u00e0 un codice via SMS da inserire sul web per visualizzare lo username. Altrimenti, vi verr\u00e0 richiesto di rispondere alla <strong>domanda scelta in fase di registrazione<\/strong>.<\/li>\n<\/ul>\n<p>Se l&#8217;account risulta<strong> bloccato<\/strong> per motivi di sicurezza o sospetto furto delle credenziali di accesso si consiglia di cambiare immediatamente la password. E&#8217; opportuno che le chiavi d&#8217;accesso contengano numeri, maiuscole e segni grafici per aumentare il livello di protezione.<\/p>\n<p>Impostare un <strong>cellulare di recupero<\/strong> rende la procedura ancora pi\u00f9 semplice. Per farlo si deve:<\/p>\n<ul>\n<li>Entrare in TIM Mail con nome utente e password della casella di posta @alice.it o @tim.it<\/li>\n<li>Cliccare in alto a destra su Impostazioni<\/li>\n<li>Password e sicurezza<\/li>\n<li>Nella sezione Per la tua sicurezza cliccare sul tasto Inserisci alla voce Cellulare di recupero. Se gi\u00e0 impostato, per modificarlo premere il tasto Modifica<\/li>\n<li>Inserire il numero da utilizzare per il recupero della password e cliccare su Salva<\/li>\n<li>Sul numero di cellulare inserito si ricever\u00e0 un SMS con un codice di verifica. Inserirlo nel pop up a video e cliccare su Prosegui<\/li>\n<li>Un messaggio di conferma vi assicurer\u00e0 che il cellulare di recupero \u00e8 stato correttamente impostato<\/li>\n<\/ul>\n<h2>TIM, la mail non funziona: errata configurazione<\/h2>\n<p>Se per accedere a <strong>TIM Mail<\/strong> utilizzate un client di posta \u00e8 possibile che risulti impossibile accedere ai messaggi perch\u00e9 non \u00e8 configurata correttamente. In questo caso i corretti parametri possono essere inseriti manualmente. E&#8217; possibile farlo anche su mobile se connessi a Internet via Wi-Fi o tramite una rete mobile:<\/p>\n<p><strong>Android<\/strong><\/p>\n<ul>\n<li>Cliccare su<strong> Impostazioni<\/strong><\/li>\n<li><strong>Email<\/strong><\/li>\n<li>Inserire l&#8217;indirizzo di posta<strong> @tim.it <\/strong>o<strong> @alice.it<\/strong> e <strong>password<\/strong><\/li>\n<li>Cliccare su<strong> CONFIG. MANUALE<\/strong><\/li>\n<li>Scegliere tra il protocollo <strong>IMAP<\/strong> o <strong>POP<\/strong>. Il primo permette di mantenere sincronizzata la mail con il serve di posta e in questo modo i messaggi vengono definitivamente cancellati solo se eliminati sul proprio telefono<\/li>\n<li>Cliccare su <strong>Accedi<\/strong><\/li>\n<\/ul>\n<p><strong>iPhone<\/strong><\/p>\n<ul>\n<li>Cliccare su <strong>Impostazioni<\/strong><\/li>\n<li><strong>Password e account<\/strong><\/li>\n<li><strong>Aggiungi account<\/strong><\/li>\n<li><strong>Altro<\/strong><\/li>\n<li>Cliccare su <strong>Aggiungi account email<\/strong> con i parametri corretti per gli indirizzi <strong>@tim.it<\/strong> e <strong>@alice.it<\/strong><\/li>\n<li>Per la configurazione dei <strong>server di posta in uscita<\/strong> cliccare su <strong>Impostazioni<\/strong><\/li>\n<li><strong>Posta, Contatti, Calendari<\/strong><\/li>\n<li>Alla voce<strong> SMTP<\/strong> verificare che sia spuntato <strong>S\u00ec<\/strong> sul server principale<\/li>\n<li>Inserire <strong>Autenticazione: password<\/strong> e <strong>Porta server: 587<\/strong><\/li>\n<li>Cliccare su <strong>Fine<\/strong><\/li>\n<\/ul>\n<p>I parametri di configurazione delle caselle di posta con dominio <strong>@tim.it<\/strong> sono:<\/p>\n<ul>\n<li>Nome utente: inserire il proprio indirizzo di posta completo del dominio @tim.it<\/li>\n<li>Server di posta in arrivo POP3: pop.tim.it<\/li>\n<li>Porta di comunicazione POP3: 110 (StartTLS)<\/li>\n<li>Server di posta in arrivo IMAP: imap.tim.it<\/li>\n<li>Porta di comunicazione IMAP: 143 (StartTLS)<\/li>\n<li>Server di posta in uscita SMTP: smtp.tim.it<\/li>\n<li>Porta di comunicazione SMTP: 587 (StartTLS)<\/li>\n<\/ul>\n<p>I parametri di configurazione delle caselle di posta con dominio <strong>@alice.it<\/strong> sono:<\/p>\n<ul>\n<li>Nome utente: inserire il proprio indirizzo di posta completo del dominio @alice.it<\/li>\n<li>Server di posta in arrivo POP3: in.alice.it<\/li>\n<li>Porta di comunicazione POP3: 110 (StartTLS)<\/li>\n<li>Server di posta in arrivo IMAP: in.alice.it<\/li>\n<li>Porta di comunicazione IMAP: 143 (StartTLS)<\/li>\n<li>Server di posta in uscita SMTP: out.alice.it<\/li>\n<li>Porta di comunicazione SMTP: 587 (StartTLS)<\/li>\n<\/ul>\n<p>I parametri di configurazione delle caselle di posta con dominio <strong>@tin.it<\/strong> sono:<\/p>\n<ul>\n<li>Nome utente: inserire il proprio indirizzo di posta completo del dominio @tin.it<\/li>\n<li>Server di posta in arrivo POP3: pops.tin.it<\/li>\n<li>Porta di comunicazione POP3: 110 (StartTLS)<\/li>\n<li>Server di posta in arrivo IMAP: imaps.tin.it<\/li>\n<li>Porta di comunicazione IMAP: 143 (StartTLS)<\/li>\n<li>Server di posta in uscita SMTP: smtps.tin.it<\/li>\n<li>Porta di comunicazione SMTP: 587 (StartTLS)<\/li>\n<\/ul>\n<p>In ogni caso, chi dispone di un indirizzo <strong>@tim.it<\/strong> dovrebbe attivare l&#8217;<strong>Autenticazione sicura<\/strong>, che offre un ulteriore livello di protezione a due fattori. Oltre a a email e password per poter effettuare il login si dovr\u00e0 inserire anche un codice PIN ricevuto via SMS. Il codice \u00e8 temporaneo e cambia ad ogni tentativo di accesso.<\/p>\n<h2><b>TIM, la mail non funziona: problemi con l&#8217;invio dei messaggi<\/b><\/h2>\n<p>A volte gli utenti ricevono i messaggi di posta ma non riescono a inviarli. Come nel caso precedente \u00e8 importante verificare che la posta sia correttamente configurata. <strong>TIM inoltre <\/strong>al fine di evitare messaggi di spam o che i propri utenti finiscano in black list non permette pi\u00f9 di inviare messaggi con mittente diverso dai domini @<b>alice.it, @tim.it <\/b>e<b> @tin.it<\/b>. Per inviare messaggi con un indirizzo differente \u00e8 quindi necessario utilizzare il server SMTP dell&#8217;altro provider mail. Sempre per una maggiore sicurezza, <b>TIM<\/b> ha stabilito un numero massimo di destinatari (A, CC e CCN) e di messaggi inviati al giorno. Superato il limite di <strong>50 contatti<\/strong> e<strong> 200 messaggi inviati<\/strong>\u00a0si visualizzer\u00e0 un pop up informativo.<\/p>\n<p><strong>TIM Mail <\/strong>risulta inaccessibile\u00a0anche quando si viene <strong>inseriti in una blacklist<\/strong>. In questo caso riceverete una notifica di mancato recapito ogni volta che tentate di inviare un messaggio. Solitamente basta attendere 48 ore per esserne cancellati automaticamente da queste liste ma si pu\u00f2 comunque effettuare una verifica su siti come <strong>www.spamhaus.org\/pbl<\/strong>, <strong>www.senderscore.org\/rtbl<\/strong> e <strong>psbl.org\/<\/strong>. Per evitare di finire in balcklist basta seguire alcune semplici regole:<\/p>\n<ul>\n<li>Aprire poche sessioni SMTP simultanee (es: 4\/6) dallo stesso IP sorgente verso il target<\/li>\n<li>Inviare a non pi\u00f9 di 20\/25 destinatari per singolo messaggio e per ogni sessione SMTP<\/li>\n<li>Contenere il numero di messaggi sulla singola transazione SMTP<\/li>\n<li>Mantenere pulite le proprie mailing list eliminando account inesistenti e\/o che generano bounce\/DNS perenni (time delivey expired, mailbox full, message size exceeded, etc.)<\/li>\n<\/ul>\n<p>E&#8217; inoltre opportuno effettuare una scansione con un antivirus per verificare il PC sono sia stato infettato da spyware o malware. Se invece si visualizza il messaggio di errore &#8220;<strong>Le seguenti caselle di posta elettronica non sono disponibili o \u00e8 impossibile trovarle: xxxxxxx@xxxx.xxx<\/strong>&#8221; si devono seguire questi passaggi:<\/p>\n<ul>\n<li>Inserire il <strong>cellulare di recupero password<\/strong> al posto della domanda e risposta<\/li>\n<li>Effettuare il reset e\/o cambio password con una pi\u00f9 sicura (composta da lettere, numeri e caratteri speciali)<\/li>\n<li>Controllare, nelle impostazioni della webmail , che nel campo mittente non siano presenti indirizzi mail strani o non impostati\/conosciuti (\u00e8 corretto che il campo sia vuoto o che sia presente la propria mail)<\/li>\n<\/ul>\n<h2>TIM, la mail non funziona: come aprire una segnalazione<\/h2>\n<p>Se <strong>TIM Mail<\/strong> ancora non funziona nonostante tutte le verifiche effettuate non resta che richiedere assistenza al <strong>Servizio Clienti<\/strong> dell&#8217;operatore chiamando il <strong>187<\/strong>. Si pu\u00f2 richiedere supporto anche via chat su <strong>WhatsApp<\/strong> al numero <strong>335 123 7272 <\/strong>o interagendo con <strong>Angie<\/strong>, l&#8217;assistente personale dell&#8217;operatore, sul sito nell&#8217;<strong>area MyTIM<\/strong> o dall&#8217;<strong>app MyTIM<\/strong>. Se nonostante l&#8217;aiuto degli esperti dell&#8217;operatore non si riesce a utilizzare <strong>TIM Mail<\/strong> in modo corretto si pu\u00f2 aprire una\u00a0segnalazione online all&#8217;<strong>Assistenza Tecnica <\/strong>sempre dal sito o da app. Tramite <strong>Angie<\/strong> si pu\u00f2 controllare lo stato di lavorazione del ticket, aggiornarlo con le proprie osservazioni, inviare un sollecito e infine confermarne la chiusura dopo aver verificato il corretto funzionamento del servizio di posta. Chi ha poca dimestichezza con la tecnologia o desidera un supporto ancora pi\u00f9 completo pu\u00f2 attivare\u00a0il servizio<strong> doctorTIM HOME<\/strong> che include:<\/p>\n<ul>\n<li>Consultazione di pi\u00f9 caselle mail da un unico accesso<\/li>\n<li>Inport\/export della rubrica<\/li>\n<li>Sincronizzazione di rubriche e calendario<\/li>\n<li>Configurazione di filtri antispam e anti-phishing per la protezione dei dati personali<\/li>\n<\/ul>\n<p>Per ricevere <strong>assistenza telefonica<\/strong> il costo \u00e8 di <strong>29,95 euro<\/strong> mentre per un <strong>intervento a domicilio<\/strong> il prezzo \u00e8 di <strong>94,95 euro<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TIM, la mail non funziona? Ecco cosa fare quando si presentano problemi con il servizio di posta elettronica dell&#8217;operatore italiano. Una guida semplice ed efficace di SOStariffe.it<\/p>\n","protected":false},"author":72,"featured_media":339866,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[22322,4],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/339852"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=339852"}],"version-history":[{"count":7,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/339852\/revisions"}],"predecessor-version":[{"id":363062,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/339852\/revisions\/363062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/339866"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=339852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=339852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=339852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}