{"id":309323,"date":"2020-06-29T11:54:23","date_gmt":"2020-06-29T09:54:23","guid":{"rendered":"https:\/\/www.sostariffe.it\/news\/?p=309323"},"modified":"2023-07-06T10:32:33","modified_gmt":"2023-07-06T08:32:33","slug":"attivazioni-online-conti-correnti-dal-2019-crescono-del-54-anche-grazie-al-lockdown","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/attivazioni-online-conti-correnti-dal-2019-crescono-del-54-anche-grazie-al-lockdown-309323\/","title":{"rendered":"Attivazioni online conti correnti: dal 2019 crescono del 54%, anche grazie al lockdown"},"content":{"rendered":"<p>Nel passaggio dal 2019 al 2020 si registra un<strong> incremento del numero di utenti che ricorre a tool di comparazione tariffe per risparmiare sui costi bancari<\/strong>. Ad utilizzare questo particolare strumento per sottoscrivere un nuovo conto corrente sono soprattutto i giovani uomini (tra 25 e 34 anni) che vivono in grandi citt\u00e0 come Napoli o Bologna. L<strong>&#8216;ultimo osservatorio di SOStariffe.it<\/strong> \u00e8 analizzato l&#8217;uso del comparatore conti correnti nell&#8217;ultimo anno prendendo in considerazione i dati in arrivo da nove diverse citt\u00e0 italiane. <!--more--><\/p>\n<p><strong>L&#8217;utilizzo dei comparatori per individuare i migliori conti corrent<\/strong>i da attivare e risparmiare sui costi bancari sta registrando una <strong>crescita significativa<\/strong>. L&#8217;ultima indagine di SOStariffe.it mette in evidenza come, rispetto allo scorso anno, nel 2020 si registri una crescita del <strong>+51%<\/strong> dei risparmiatori che si affidano ai tool di comparazione per sottoscrivere un conto online pi\u00f9 conveniente.<\/p>\n<p>In particolare, la crescita percentuale si riferisce al numero di utenti che hanno usato il comparatore per individuare il conto migliore e poi hanno scelto di continuare con la procedura di attivazione online, una soluzione sempre pi\u00f9 richiesta anche per via degli effetti del lockdown.<\/p>\n<p>I dati raccolti da SOStariffe.it confermano che <strong>l&#8217;identikit<\/strong> dell&#8217;utente che si affida alla comparazione online per individuare il conto migliore \u00e8 un <strong>giovane uomo con et\u00e0 compresa tra 25 e 34 anni.<\/strong>\u00a0Anche le donne, in misura minore, si affidano ai tool di comparazione sul web che rappresentano un punto di riferimento per la fascia di et\u00e0 compresa tra 25 e 44 anni.<\/p>\n<p>L&#8217;osservatorio di SOStariffe.it ha messo in evidenza come \u00e8 cambiata la propensione ad aprire un conto corrente dopo aver effettuato una comparazione delle opzioni a propria disposizione nel corso degli ultimi 12 mesi. La tabella qui di sotto riassume i risultati individuati dall&#8217;indagine evidenziando la sostanziale crescita dell&#8217;utilizzo della comparazione online.<\/p>\n<p><a href=\"https:\/\/www.sostariffe.it\/news\/wp-content\/uploads\/2020\/06\/Conti-Correnti-dal-confronto-online-all\u2019acquisto-e1593374087548.png\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-309339\" src=\"https:\/\/www.sostariffe.it\/news\/wp-content\/uploads\/2020\/06\/Conti-Correnti-dal-confronto-online-all\u2019acquisto-e1593374087548.png\" alt=\"\" width=\"734\" height=\"693\" srcset=\"https:\/\/www.sostariffe.it\/news\/wp-content\/uploads\/2020\/06\/Conti-Correnti-dal-confronto-online-all\u2019acquisto-e1593374087548.png 734w, https:\/\/www.sostariffe.it\/news\/wp-content\/uploads\/2020\/06\/Conti-Correnti-dal-confronto-online-all\u2019acquisto-e1593374087548-300x283.png 300w\" sizes=\"(max-width: 734px) 100vw, 734px\" \/><\/a><\/p>\n<h2><strong>La comparazione bancaria funziona: +51,34% coloro che dopo acquistano<\/strong><\/h2>\n<p>Uno dei punti centrali del<strong> nuovo report di SOStariffe.it<\/strong> riguarda il numero di utenti che, dopo essersi affidato alla comparazione online, sceglie di attivare un nuovo conto corrente. Le rilevazioni del mese di maggio 2020 sono state poste a confronto con quelle del mese di maggio del 2019.<\/p>\n<p>Grazie ai dati raccolti dal comparatore di offerte <a href=\"https:\/\/www.sostariffe.it\/conto-corrente\/\"><strong>conti correnti<\/strong>,<\/a>\u00a0 si registra una sostanziale crescita del numero di utenti che si affidano alla comparazione online per scegliere il conto corrente per poi procedere con l&#8217;attivazione online. Nel confronto tra il 2019 ed il 2020, infatti, la crescita registrata dall&#8217;indagine \u00e8 del <strong>+51,34%.\u00a0<\/strong><\/p>\n<p>A spingere la ricerca dei migliori conti online e la successiva attivazione ci sono vari fattori come, ad esempio, la convenienza delle proposte disponibili online, rispetto a quelle &#8220;tradizionali&#8221;, e gli effetti del lockdown che spinge gli utenti ad utilizzare, sempre di pi\u00f9, gli strumenti online.<\/p>\n<h2><strong>Nelle grandi citt\u00e0 si prova a risparmiare di pi\u00f9<\/strong><\/h2>\n<p>I dati raccolti da SOStariffe.it confermano che gli utenti che vanno a caccia di offerte pi\u00f9 convenienti sono situati, prevalentemente, nelle grandi citt\u00e0. Non c&#8217;\u00e8, invece, particolare differenza tra Nord, Centro e Sud del Paese. A <strong>Bologna,<\/strong> ad esempio, si registra un +76% per le sottoscrizioni online mentre a <strong>Napoli<\/strong> e <strong>Milano<\/strong> la crescita \u00e8, rispettivamente, del +65% e +64%.<\/p>\n<p>Dati in crescita anche per <strong>Roma<\/strong> (+50,92%), <strong>Torino<\/strong> (+ 44,17%), <strong>Bari<\/strong> (+ 41,40%) e <strong>Catania<\/strong> (+ 39,77%). Solo una leggera crescita per\u00a0<strong>Firenze<\/strong> (+8,20%) mentre <strong>Palermo<\/strong> \u00e8 l&#8217;unica citt\u00e0 in controtendenza rispetto all&#8217;andamento generale (-8,20%).<\/p>\n<h2><strong>La comparazione online conquista i giovani<\/strong><\/h2>\n<p>Per quanto riguarda la fascia di et\u00e0, invece, gli utenti che si mostrano pi\u00f9 inclini a scegliere ed attivare il conto corrente tramite la comparazione online sono i <strong>giovani adulti (25-34 anni).<\/strong> Per questa categoria si registra una crescita del <strong>+74%<\/strong> nel confronto con i dati dell&#8217;anno precedente.<\/p>\n<p>Dati in forte crescita anche per i ragazzi (18-24 anni) che fanno registrare una crescita del +52% e per la fascia d&#8217;et\u00e0 35-44 anni che cresce del +51%. Da segnalare anche lo scorso interesse per la comparazione online, almeno per quanto riguarda il conto corrente, da parte della fascia di et\u00e0 45-54 anni (-6%) e 55-64 anni (-14%). Dati in calo anche per gli over 65 (-36%).<\/p>\n<p>Per quanto riguarda il sesso, sono gli uomini che mostrano un interesse maggiore per la comparazione online come strumento per la scelta del conto corrente (+59%). Le donne, invece, registrano una crescita meno marcata (+38%).<\/p>\n<h2><strong>I vantaggi di un conto corrente online<\/strong><\/h2>\n<p>La <strong>scelta del conto corrente online<\/strong>, rispetto ad uno tradizionale, pu\u00f2 garantire un gran numero di vantaggi per gli utenti, sia in termini di <strong>servizi inclusi<\/strong> che per quanto riguarda i<strong> costi di gestione del conto<\/strong> stesso e di tutti gli strumenti collegati. Nella maggior parte dei casi, infatti, ci troviamo di fronte a conti a zero spese, <strong>senza canone mensile e commissioni<\/strong> per le varie operazioni.<\/p>\n<p>Gli istituti bancari che propongono i conti online puntano tutto sui servizi di <strong>Internet banking,<\/strong> una scelta che permette di abbattere i costi necessari e, quindi, di offrire condizioni economiche pi\u00f9 vantaggiose ai clienti. I conti online, grazie a sistemi di protezione e autenticazione sempre pi\u00f9 sofisticati, sono al top anche per quanto riguarda la sicurezza per gli utenti.<\/p>\n<p>Ricordiamo che \u00e8 possibile scoprire le offerte pi\u00f9 vantaggiose delle varie banche grazie al<strong> comparatore di SOStariffe.it per conti correnti,<\/strong> disponibile cliccando sul box qui di sotto oppure accessibile tramite l&#8217;<strong><a href=\"https:\/\/www.sostariffe.it\/\">App di SOStariffe.it<\/a><\/strong>, scaricabile gratuitamente su smartphone Android e iOS.<\/p>\n<p><a class=\"green-cta\" style=\"width: 300px; height: 30px; line-height: 30px; font-size: 15px;\" href=\"https:\/\/www.sostariffe.it\/conto-corrente\/\">Scopri il conto corrente pi\u00f9 adatto alle tue esigenze <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel passaggio dal 2019 al 2020 si registra un incremento del numero di utenti che ricorre a tool di comparazione tariffe per risparmiare sui costi bancari. Ad utilizzare questo particolare strumento per sottoscrivere un nuovo conto corrente sono soprattutto i giovani uomini (tra 25 e 34 anni) che vivono in grandi citt\u00e0 come Napoli o [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":309341,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3889,1104,6],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/309323"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=309323"}],"version-history":[{"count":3,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/309323\/revisions"}],"predecessor-version":[{"id":309385,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/309323\/revisions\/309385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/309341"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=309323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=309323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=309323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}