{"id":302333,"date":"2020-03-13T14:12:54","date_gmt":"2020-03-13T13:12:54","guid":{"rendered":"https:\/\/www.sostariffe.it\/news\/?p=302333"},"modified":"2024-02-11T18:08:43","modified_gmt":"2024-02-11T17:08:43","slug":"google-meet-google-classroom-e-come-funzionano-altri-metodi-di-lavoro-e-studio-a-distanza","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/google-meet-google-classroom-e-come-funzionano-altri-metodi-di-lavoro-e-studio-a-distanza-302333\/","title":{"rendered":"Google Meet, Google Classroom e come funzionano altri metodi di lavoro e studio a distanza"},"content":{"rendered":"<p>A causa dell&#8217;emergenza\u00a0<strong>Coronavirus<\/strong>\u00a0i contatti umani sono stati ridotti al minimo e quindi per lavorare e studiare servono strumenti che permettono di svolgere queste attivit\u00e0 a distanza. Ecco i migliori software per\u00a0<strong>smart working<\/strong>\u00a0e\u00a0<strong>smart study<\/strong>\u00a0e come funzionano<!--more--><\/p>\n<p>Il Governo italiano nel pieno dell&#8217;emergenza\u00a0<strong>Coronavirus<\/strong>\u00a0ha deciso di bloccare\u00a0tutte le attivit\u00e0 non essenziali per contenere il contagio. Molti uffici, cos\u00ec come scuole e universit\u00e0, sono chiusi ma l&#8217;infezione non pu\u00f2 fermare la necessit\u00e0 di lavorare n\u00e9 quella di studiare. Lo\u00a0<strong>smart working<\/strong>, pratica prima molto sottostimata in Italia, \u00e8 quindi diventato essenziale.<\/p>\n<p>Software come\u00a0<strong>Google Hangouts Meet<\/strong>\u00a0oggi ci consentono di svolgere da casa molte delle attivit\u00e0 lavorative quotidiane. Gli studenti tramite gli appositi strumenti come\u00a0<strong>Google Classroom<\/strong>\u00a0possono invece interagire a distanza tra loro per formare gruppi di studio e partecipare alle lezioni senza muoversi dalla propria abitazione. Serve solamente una connessione\u00a0<strong>Internet<\/strong>. Ecco descritti nel dettaglio i pi\u00f9 utili\u00a0<strong>metodi di lavoro e studio a distanza<\/strong>.<br \/>\n<a class=\"green-cta\" style=\"width: 300px; height: 30px; line-height: 30px; font-size: 15px;\" href=\"https:\/\/www.sostariffe.it\/ct\/c\/10259?sub=0\">Scopri le migliori tariffe per la connessione Internet di casa<span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h2>Google Hangouts Meet<\/h2>\n<p><strong>Google Hangouts Meet<\/strong>\u00a0\u00e8 un\u2019app gratuita che consente di creare e gestire videochiamate di gruppo fino ad un massimo di 25 partecipanti. Da iPhone, iPad, telefoni e tablet Android o browser (Chrome, Safari, Vista) \u00e8 possibile solo partecipare alla riunione virtuale tramite autorizzazione o invito su Calendar. Non \u00e8 invece consentito l\u2019accesso via telefono. La possibilit\u00e0 di inviare messaggi \u00e8 limitata alla piattaforma web e con la versione gratuita non \u00e8 possibile registrare la riunione, in modo di consentire a chi non ha potuto partecipare di tenersi aggiornato.<\/p>\n<p><strong>Google Hangouts Meet<\/strong>\u00a0consente comunque di condividere documenti inviando la propria schermata o una finestra specifica e di organizzare le idee dei vari membri del team su una lavagna virtuale, anche se solo in bassa risoluzione.<\/p>\n<p>Se le vostre esigenze lavorative richiedono qualcosa in pi\u00f9 rispetto alla versione base o dovete mettere in contatto un maggior numero di persone (si pu\u00f2 arrivare a 250),\u00a0<strong>Google Hangouts Meet<\/strong>\u00a0pu\u00f2 essere arricchito in termini di funzioni sottoscrivendo un abbonamento\u00a0<strong>G Suite<\/strong>\u00a0nelle sue varie declinazioni (Basic, for Education, Business, Enterprise ed Enterprise for Education).<\/p>\n<h2>Google Classroom<\/h2>\n<p><strong>Google Classroom<\/strong>\u00a0\u00e8 incluso nella\u00a0<strong>G Suite for Education<\/strong>\u00a0e si tratta di uno strumento per facilitare il lavoro dei docenti e studenti. L&#8217;app \u00e8 disponibile per iPhone, iPad, telefoni e tablet Android e PC. Per sfruttare tutte le sue funzioni \u00e8 necessario dotarsi di un\u00a0<strong>account Google<\/strong>, operazione gratuita e che richiede pochi e semplici passi. Gli insegnanti possono aggiungere i propri studenti direttamente o tramite la condivisione di un codice per tutta la classe. Da qui i docenti hanno la possibilit\u00e0 di accedere ai compiti, fornire materiale didattico e rispondere in tempo reale alle domande degli studenti.<\/p>\n<p>Quest&#8217;ultimi possono essere sempre aggiornati sui nuovi contenuti condivisi sulla piattaforma tramite un puntuale sistema di notifiche. Tutti i file, documenti, video, immagini, presentazioni o altro vengono archiviati automaticamente all&#8217;interno di cartelle su\u00a0<strong>Google Drive<\/strong>.<\/p>\n<h2>Altre app per smart working e studio a distanza<\/h2>\n<h3>1. Teamviewer (iOS e Android)<\/h3>\n<p>L&#8217;app permette di controllare da remoto altri dispositivi come smartphone, tablet e PC per condividere la schermata, gestirne le funzioni a distanza o trasferire file. Si tratta di un ottimo strumento per coloro che necessitano di supporto e assistenza a distanza o vogliono mostrare contenuti in tempo reale.<\/p>\n<h3>2. Expensify (iOS e Android)<\/h3>\n<p>L&#8217;app consente di archiviare scontrini e ricevute per le spese aziendali per facilitare la richiesta di rimborso e la contabilit\u00e0. Basta scattare una foto con il proprio smartphone per creare le copie digitali da presentare poi in ufficio.<\/p>\n<h3>3. Camscanner\u00a0(iOS e Android)<\/h3>\n<p>L&#8217;app permette di scannerizzare qualsiasi documento cartaceo creandone una copia in formato PDF. Il file pu\u00f2 poi essere condiviso via email, app di messaggistica o altri servizi online.<\/p>\n<h3>4. Happeo\u00a0(iOS e Android)<\/h3>\n<p>L&#8217;app ideale per migliorare la condivisione di documenti, relazioni, presentazioni o altro materiale all&#8217;interno della rete interna all&#8217;azienda. Solo i dipendenti possono accedere alla piattaforma per garantire la sicurezza dei dati aziendali.<\/p>\n<h3>5. We Transfer<\/h3>\n<p>Il sito consente di trasferire gratuitamente file di grandi dimensioni a colleghi o altri studenti. Il ricevente potr\u00e0 accedere ai file tramite un link all&#8217;interno di un&#8217;email o allegato.<\/p>\n<h3><strong>6. Mindomo<\/strong><\/h3>\n<p>L&#8217;app permette di creare mappe concettuali per organizzare i propri appunti in modo pi\u00f9 produttivo e facilitare il ripasso degli argomenti studiati. I professionisti possono sfruttarla per sessioni di brainstorming da condividere con il proprio team.<\/p>\n<h3>7. Skype for Business<\/h3>\n<p>La versione professionale di\u00a0<strong>Skype<\/strong>\u00a0di\u00a0<strong>Microsoft<\/strong>\u00a0integra strumenti avanzati per lo smart working. Ad esempio, \u00e8 possibile interagire in contemporanea su note, presentazioni PowerPoint o condividere app e il desktop. Il software consente ovviamente anche di creare delle riunioni virtuali con un numero elevato di partecipanti e creare sondaggi per una votazione a distanza tra i partecipanti alla sessione.<\/p>\n<h3>8. App per videoconferenze<\/h3>\n<p>Altre app molto utili per mettersi in contatto con pi\u00f9 colleghi da remoto sono\u00a0<strong>FaceTime<\/strong>, integrata su tutti i dispositivi Apple con\u00a0<strong>iOS 12.1<\/strong>\u00a0o versioni successive, e\u00a0<strong>WhatsApp<\/strong>. L&#8217;app di messaggistica di propriet\u00e0 di\u00a0<strong>Facebook<\/strong>\u00a0dispone anche di una\u00a0<strong>versione desktop &#8211;\u00a0 <\/strong>leggi la guida <strong>&#8220;<a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/guide\/whatsapp-web-come-utilizzare-l-app-di-messaggistica-da-desktop\">Come usare Whatsapp Web<\/a>&#8221; <\/strong>per saperne di pi\u00f9<strong>.<\/strong><\/p>\n<p><strong>Teleskill<\/strong>\u00a0\u00e8 molto utilizzata in ambito accademico e si integra con diverse piattaforme di e-learning come\u00a0<strong>Docebo<\/strong>\u00a0e\u00a0<strong>CMS<\/strong>\u00a0come\u00a0<strong>WordPress<\/strong>. L&#8217;app permette anche di salvare lezioni e riunioni per seguirle in seguito.\u00a0<strong>Zoom<\/strong>\u00a0nella sua versione base permette di creare meeting fino a 100 partecipanti della durata massima di 40 minuti mentre\u00a0<strong>Slack\u00a0<\/strong>\u00e8 pi\u00f9 simile ad una chat per professionisti, in quanto permette di svolgere in contemporanea conversazioni in privato e di gruppo.<\/p>\n<h2>Le migliori offerte di telefonia mobile<\/h2>\n<p>Per sostenere il telelavoro o lo studio a distanza \u00e8 necessario disporre di una connessione Internet stabile e veloce sia per quanto riguarda la\u00a0<strong>rete fissa<\/strong>\u00a0sia per quella\u00a0<strong>mobile<\/strong>. Per coloro che intendono utilizzare soprattutto il PC di casa, con il comparatore di\u00a0<strong>SosTariffe.it<\/strong>\u00a0potete confrontare le diverse offerte\u00a0<a href=\"https:\/\/www.sostariffe.it\/internet-casa\/\"><strong>Internet casa<\/strong><\/a>\u00a0per\u00a0<a href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-adsl\/\"><strong>ADSL<\/strong><\/a>\u00a0o\u00a0<a href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-fibra-ottica\/\"><strong>fibra ottica<\/strong><\/a>\u00a0in modo da trovare la tariffa migliore per le vostre attivit\u00e0 quotidiane.<\/p>\n<p><a class=\"green-cta\" style=\"width: 300px; height: 30px; line-height: 30px; font-size: 15px;\" href=\"https:\/\/www.sostariffe.it\/internet-casa\/offerte-adsl\/\">Confronta le offerte Internet casa <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Lo stesso si pu\u00f2 fare anche per le promozioni di\u00a0<a href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/\"><strong>telefonia mobile<\/strong><\/a>, prediligendo, ad esempio, le proposte con Gigabyte illimitati o comunque una quantit\u00e0 di traffico dati particolarmente cospicua. Il consiglio \u00e8 comunque sempre quello di connettersi ad Internet su\u00a0<strong>smartphone<\/strong>\u00a0e\u00a0<strong>tablet<\/strong>\u00a0sfruttando una rete\u00a0<strong>Wi-Fi<\/strong>\u00a0quando disponibile.<\/p>\n<p><a class=\"green-cta\" style=\"width: 300px; height: 30px; line-height: 30px; font-size: 15px;\" href=\"https:\/\/www.sostariffe.it\/tariffe-cellulari\/\">Confronta le offerte di telefonia mobile <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<p>Trovare l&#8217;offerta migliore \u00e8 semplicissimo. Basta inserire i giusti parametri per costruire il proprio profilo di consumo ideale e in pochi secondi vedrete comparire in ordine di convenienza le\u00a0<strong>tariffe fisso e mobile<\/strong>\u00a0pi\u00f9 adatte alle vostre esigenze. Non solo,\u00a0<strong>SosTariffe.it<\/strong>\u00a0consente gratuitamente di\u00a0<a href=\"https:\/\/www.sostariffe.it\/internet-casa\/verifica-copertura\/\"><strong>verificare la copertura<\/strong><\/a>\u00a0offerta nel vostro Comune e di misurare in tempo reale la velocit\u00e0 della connessione sia in download sia in upload tramite l&#8217;apposito\u00a0<a href=\"https:\/\/www.sostariffe.it\/internet-casa\/test-velocita\/\"><strong>speed test<\/strong><\/a>, in modo da avere la certezza di poter disporre del massimo delle performance e continuare a lavorare e studiare da casa cos\u00ec come avviene in ufficio o sui banchi di scuola.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A causa dell&#8217;emergenza\u00a0Coronavirus\u00a0i contatti umani sono stati ridotti al minimo e quindi per lavorare e studiare servono strumenti che permettono di svolgere queste attivit\u00e0 a distanza. Ecco i migliori software per\u00a0smart working\u00a0e\u00a0smart study\u00a0e come funzionano<\/p>\n","protected":false},"author":72,"featured_media":302337,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[22322,9],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/302333"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=302333"}],"version-history":[{"count":21,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/302333\/revisions"}],"predecessor-version":[{"id":383964,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/302333\/revisions\/383964"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/302337"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=302333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=302333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=302333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}