{"id":302017,"date":"2020-03-10T16:13:38","date_gmt":"2020-03-10T15:13:38","guid":{"rendered":"https:\/\/www.sostariffe.it\/news\/?p=302017"},"modified":"2024-08-07T11:51:42","modified_gmt":"2024-08-07T09:51:42","slug":"pagamento-utenze-e-affitti-e-coronavirus-sospensione-bollette-gas-luce-e-cosa-sapere","status":"publish","type":"post","link":"https:\/\/www.sostariffe.it\/news\/pagamento-utenze-e-affitti-e-coronavirus-sospensione-bollette-gas-luce-e-cosa-sapere-302017\/","title":{"rendered":"Pagamento utenze e affitti e Coronavirus: sospensione bollette gas, luce e cosa sapere"},"content":{"rendered":"<p>Aumentano i contagi\u00a0e il Governo vara il decreto Cura Italia per cercare di porre un freno alle conseguenze economiche per cittadini e imprese. Ecco quali saranno le nuove disposizioni su provvedimenti fiscali\u00a0 e di supporto a famiglie e imprese per far fronte all&#8217;emergenza coronavirus e chi sar\u00e0 interessato dalla sospensione del pagamento delle bollette di luce, gas e utenze<\/p>\n<p><!--more--><\/p>\n<p>Le notizie sul coronavirus si rincorrono e cresce la preoccupazione dei cittadini, i timori non riguardano purtroppo solo la salute. Carceri in rivolta, aziende costrette alla chiusura, l&#8217;Italia sottoposta a misure di contenimento del contagio sempre pi\u00f9 stringenti. Il bollettino\u00a0fornito ieri ha visto salire a <strong>31.506 i casi di contagio<\/strong> e i <strong>morti<\/strong> per l&#8217;infezione da <strong>Covid-19<\/strong> sono arrivati a <strong>2.503<\/strong>. I guariti sono 2.941. In tutto questo per\u00f2 aumentano anche i dubbi dei cittadini per quel che riguarda il pagamento di tributi e utenze.<br \/>\n<a class=\"green-cta\" style=\"width: 300px; height: 30px; line-height: 30px; font-size: 15px;\" href=\"https:\/\/www.sostariffe.it\/ct\/c\/10263?sub=0\">Scopri come risparmiare sulle bollette di luce e gas <span style=\"text-align: right;\">\u00bb<\/span><\/a><\/p>\n<h2>Coronavirus, sintomi e numeri utili<\/h2>\n<p>Le prescrizioni mediche e di prevenzione del contagio consigliano di mantenere una distanza di un metro tra le persone, di lavarsi spesso le mani con saponi o igienizzanti, di pulire con alcol e candeggina le superfici, di tossire o starnutire nel gomito o in un fazzoletto usa e getta, di evitare i luoghi affollati. Se si ha febbre o tosse non recarsi nei pronto soccorso o dal proprio medico ma telefonare al dottore e chiedere istruzioni o chiamare i numeri per le emergenze.<\/p>\n<p>I sintomi del Covid-19 a cui prestare attenzione sono: febbre alta, tosse secca, fiato corto, mal di testa. Se si hanno dubbi i numeri da contattare sono il 1500 per informazioni o il 112 per emergenze sanitarie. Sono stati attivati anche degli appositi numeri verdi in ciascuna regione:<\/p>\n<ul>\n<li>Abruzzo:\u00a0800 860 146<\/li>\n<li>Calabria: 800 76 76 76<\/li>\n<li>Campania: 800 90 96 99<\/li>\n<li>Emilia-Romagna: 800 033 033<\/li>\n<li>Friuli Venezia Giulia: 800 500 300<\/li>\n<li>Lazio: 800 11 88 00<\/li>\n<li>Lombardia: 800 89 45 45<\/li>\n<li>Marche: 800 93 66 77<\/li>\n<li>Piemonte: 800 333 444<\/li>\n<li>Provincia autonoma di Trento: 800 86 73 88<\/li>\n<li>Sicilia: 800 45 87 87<\/li>\n<li>Toscana: 800 55 60 60<\/li>\n<li>Trentino Alto Adige: 800 751 751<\/li>\n<li>Umbria: 800 63 63 63<\/li>\n<li>Val d\u2019Aosta: 800 122 121<\/li>\n<li>Veneto: 800 46 23 40<\/li>\n<\/ul>\n<h2>Covid-19: nuovi provvedimenti del Governo<\/h2>\n<p>Visto lo stop forzato di molte attivit\u00e0 o gli incassi praticamente azzerati in tanti si stanno chiedendo come riusciranno a pagare le bollette, le rate dei mutui e gli affitti alla fine del mese. Il decreto dell&#8217;11 Marzo ha allargato le restrizioni su spostamenti e chiusure di negozi, bar e ristoranti a tutta la Penisola. Questo ampliamento della zona rossa per\u00f2 ha reso ancora pi\u00f9 confuse le misure di supporto annunciate dal Governo, come la sospensione del pagamento delle utenze.<\/p>\n<p>Il decreto del 28 Febbraio 2020 ha riscritto le scadenze fiscali di quest&#8217;anno <strong>posticipando il 730 al 30 Settembre 2020<\/strong>. Nei giorni scorsi sono state<strong> sospese le attivit\u00e0 dell&#8217;Agenzia delle Entrate<\/strong> e sono stati chiusi gli sportelli, le pratiche quindi avranno delle proroghe. In ogni caso i termini di riscossioni e contenziosi sono stati sospesi fino a fine Maggio.<\/p>\n<p>Il provvedimento denominato Cura Italia ha poi dato seguito agli annunci di sospensione o posticipo dei versamenti IVA di Marzo.\u00a0Per i settori martoriati dal coronavirus \u00e8 stata disposta la sospensioni del versamento dei contributi, delle rate assicurative e delle ritenute d&#8217;acconto. Le categorie ritenute pi\u00f9 colpite e che quindi potranno avere accesso a questo stop\u00a0delle scadenze IVA sono quelle turistico-alberghiere e dell&#8217;intrattenimento, insieme organizzazione eventi e fiere e anche ai centri scommesse.<\/p>\n<p>Chi non dovesse rientrare nei settori riconosciuti come pi\u00f9 svantaggiati avr\u00e0 solo un posticipo delle scadenze dal 16 Marzo al 20. Per <strong>societ\u00e0 sportive e dilettantistiche<\/strong> sono stati rimandati fino al <strong>31 Maggio 2020 i versamenti<\/strong> dei<strong> canoni di locazio<\/strong>ne degli impianti. I lavoratori domestici potranno pagare i contributi entro il 10 Giugno 2020.<\/p>\n<h2>Il decreto per le zone rosse e la sospensione dei tributi<\/h2>\n<p>Uno dei punti centrali per i cittadini per\u00f2 resta piuttosto oscuro, la sospensione dei tributi annunciata a pi\u00f9 riprese e gi\u00e0 deliberata nel decreto del 28 Febbraio per le prime zone rosse in Lombardia e Veneto \u00e8 stata estesa? No, la risposta al momento \u00e8 questa. Il <strong>pagamento di acqua, luce, gas e tributi \u00e8 stato sospeso solo nei 14 comuni<\/strong> che sono stati interessati dalle misure restrittive pi\u00f9 stringenti nelle prime settimane di emergenza e durer\u00e0 <strong>solo\u00a0fino al 30 Aprile<\/strong>.<\/p>\n<p>I comuni dunque a cui sar\u00e0 applicata questa misura straordinaria restano\u00a0Bertonico, Casalpusterlengo, Castelgerundo, Castiglione D\u2019Adda, Codogno, Fombio, Maleo, San Fiorano, Somaglia, Terranova dei Passerini e V0\u2019 Euganeo. I pagamenti di bollette sono solo sospesi, non cancellati, sar\u00e0 dunque poi necessario capire quali saranno le condizioni con cui si ritorner\u00e0 alla normalit\u00e0 e si recupereranno tributi e utenze. Lo ripetiamo si tratta di una sospensione e non di una cancellazione delle bollette e delle tasse.<\/p>\n<p>Inizialmente era circolata la notizia che questa misura straordinaria avrebbe potuto liberare da scadenze e pagamento delle bollette gli utenti per 6 mesi, poi il tutto \u00e8 stato ridimensionato e nel testo approvato il termine della sospensione \u00e8 stato fissato a 2 mesi circa. Tra le bufale che si stanno diffondendo c&#8217;\u00e8 anche chi sostiene che la sospensione vada avanti per tutto l&#8217;anno. Si tratta di notizie false. Invece \u00e8 confermato che sar\u00e0 incluso nella sospensione anche il <strong>pagamento del Canone Rai<\/strong>, lo si pagher\u00e0 con la prima bolletta post sospensione e sar\u00e0 versato in un&#8217;unica rata.<\/p>\n<h2>L&#8217;Arera e la gestione del blocco delle bollette di luce e gas<\/h2>\n<p>L&#8217;Arera ha avuto mandato di gestire questa situazione straordinaria. Non \u00e8 di certo il primo caso di sospensione delle fatture, ma come \u00e8 stato ricordato anche dal Presidente dell&#8217;Autorit\u00e0, Stefano Besseghini, negli altri casi si trattava di eventi diversi. Questa misura ad esempio \u00e8 stata applicata in caso di calamit\u00e0 naturali e per sismi come quello che colp\u00ec il Centro Italia, in quella situazione particolare la sospensione \u00e8 andata avanti dal 2016 al 2020.<\/p>\n<p>Come ha riportato il Corriere della Sera, Besseghini ha sottolineato come\u00a0qualsiasi\u00a0misura per contrastare il Covid-19 &#8220;si applichi nei confronti di consumatori e imprese, infatti, produce effetti sull&#8217;equilibrio complessivo del sistema, che vanno previsti e misurati.\u2009A differenza di altre emergenze, come alluvioni e terremoti, non ci sono danni strutturali alle utenze e la continuit\u00e0 del servizio \u00e8 assicurata. L\u2019elemento da valutare in questi casi, come si sta facendo, \u00e8 limitato ai\u00a0rapporti contrattuali tra gestori e utenti\u00a0e alle misure di riconoscimento della parte economica&#8221;.<\/p>\n<p>L&#8217;Arera nel frattempo ha<strong> sospeso le interruzioni di servizio per morosit\u00e0<\/strong> per clienti in bassa tensione e con non superino un consumo di 200.000 smc. Ci sono anche state compagnie come l&#8217;Acea, Iren, A2a e Hera che hanno attivato degli speciali piani di rateizzazione dei pagamenti per gli utenti in difficolt\u00e0 e che hanno provveduto a sospendere eventuali interruzioni per mancati pagamenti.<\/p>\n<h2>Le misure a sostegno di imprese e famiglie<\/h2>\n<p>Nel Decreto Cura Italia sono state istituite molte delle misure di supporto straordinario di cui si parlava nelle scorse settimane.\u00a0Per le famiglie\u00a0\u00e8\u00a0prevista una <strong>sospensione sui mutui per la prima casa<\/strong>\u00a0tramite il sostegno garantito dal Fondo solidariet\u00e0 mutui prima casa. Questa misura \u00e8 estesa <strong>anche ai liberi professionisti<\/strong> che possano accertare un calo pi\u00f9 alto del 33% del proprio fatturato al 21 Febbraio 2020.<\/p>\n<p>Sono garantiti fino ad un massimo di <strong>600 euro<\/strong> per i genitori\u00a0che hanno figli minori e che sono comunque costretti a recarsi al lavoro di <strong>voucher baby-sitter<\/strong>.\u00a0 Viene anche concessa l&#8217;opzione di 12 giorni, eventualmente prorogabili se la chiusura degli istituti dovesse andare avanti, di <strong>congedo parentale<\/strong>.<\/p>\n<p>Sono anche contenute nel decreto delle importanti decisioni in merito ad ammortizzatori sociali e le azioni straordinarie a livello fiscale e tributario, come visto. Nel decreto vengono stabiliti i criteri per accedere alla cassa integrazione e ai Fondi speciali, come il Fondo di integrazione salariale. Restano da chiarire i provvedimenti presi per lavoratori autonomi e stagionali.<\/p>\n<p>La cassa integrazione in deroga \u00e8 stata allargata a tutte le aziende, anche quelle con meno di 5 dipendenti, che abbiano subito un brusco calo di lavoro a causa dell&#8217;emergenza. Il periodo massimo per questo strumento \u00e8 di 9 settimane.<\/p>\n<p>Anche <strong>partite Iva e lavoratori autonomi<\/strong> riceveranno un contributo per sostenere i disagi e le forti crisi di settore che stanno affrontando per la situazione creatasi con il contagio Covid-19. Nel Cura Italia \u00e8 stato previsto un <strong>bonus di 600 euro<\/strong> per i lavoratori stagionali, autonomi, P.IVA, per i dipendenti a con contratti co.co.co., per tutte le figure di lavori di impianti come terme e del settore turistico stagionale.<\/p>\n<p>Anche per lavoratori autonomi del<strong> mondo dello spettacolo, del cinema, dei teatri, e gli addetti del mondo della cultura<\/strong> \u00e8 valido il bonus da 600 euro. In questo caso \u00e8 previsto un limite di reddito per poter accedere al contributo statale, si devono percepire meno di 50 mila euro l&#8217;anno.<\/p>\n<p>Per <strong>chi \u00e8 costretto a recarsi a lavoro<\/strong> sar\u00e0 aggiunto un<strong> bonus di 100 euro<\/strong> alla busta paga e sar\u00e0 un contributo non sottoposto al conteggio fiscale. Non sono inclusi i lavoratori in smart working.<\/p>\n<h2>I divieti a cui attenersi per contenere i contagi<\/h2>\n<p>Il decreto diffuso il 9 Marzo nel frattempo ha posto dei precisi divieti e delle norme di comportamento indispensabili per cercare di uscire il pi\u00f9 rapidamente possibile dallo stato d&#8217;emergenza in cui il Paese \u00e8 venuto a trovarsi. Ecco in breve cosa \u00e8 permesso fare e cosa no in tutta Italia:<\/p>\n<ul>\n<li>divieto di assembramento\u00a0in luoghi pubblici o aperti al pubblico<\/li>\n<li>tutti i centri commerciali e i mercati dovranno restare chiusi nei giorni festivi e prefestivi. Nei normali giorni di lavoro si dovr\u00e0 rispettare la condizione del metro di distanza tra persone e all&#8217;interno dei centri commerciali potranno essere aperti solo supermercati, farmacie e tabacchi<\/li>\n<li>farmacie, parafarmacie e negozi di beni alimentari saranno regolarmente aperte, vi si dovr\u00e0 rispettare il metro di distanza e dovranno essere rispettate le severe norme igieniche<\/li>\n<li>chiuse le palestre, i pub, i centri ricreativi, spa, piscine, centri sociali e culturali<\/li>\n<li>solo i centri termali hanno delle deroghe per trattamenti sanitari<\/li>\n<li>tutti gli eventi e le competizioni sportive sono sospese, anche quelli che finora si sono tenuti a porte chiuse come le partite del campionato di calcio. Sono consentite solo le competizioni organizzate da organismi internazionali ma dovranno svolgersi senza pubblico e in impianti a porte chiuse<\/li>\n<li>gli impianti sportivi potranno essere utilizzati per allenamenti di professionisti e non professionisti che il Comitato olimpico e le federazioni riterranno necessari e di interesse nazionali per la partecipazioni ai giochi olimpici<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Aumentano i contagi\u00a0e il Governo vara il decreto Cura Italia per cercare di porre un freno alle conseguenze economiche per cittadini e imprese. Ecco quali saranno le nuove disposizioni su provvedimenti fiscali\u00a0 e di supporto a famiglie e imprese per far fronte all&#8217;emergenza coronavirus e chi sar\u00e0 interessato dalla sospensione del pagamento delle bollette di [&hellip;]<\/p>\n","protected":false},"author":79,"featured_media":302021,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1095,1098,1208],"tags":[21833,21835,21837],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/302017"}],"collection":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/users\/79"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/comments?post=302017"}],"version-history":[{"count":6,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/302017\/revisions"}],"predecessor-version":[{"id":303393,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/posts\/302017\/revisions\/303393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media\/302021"}],"wp:attachment":[{"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/media?parent=302017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/categories?post=302017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sostariffe.it\/news\/wp-json\/wp\/v2\/tags?post=302017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}